{"id":112937,"date":"2022-04-25T08:00:00","date_gmt":"2022-04-25T06:00:00","guid":{"rendered":"https:\/\/e326.greatsolution.dev\/?p=112937"},"modified":"2022-04-26T07:27:36","modified_gmt":"2022-04-26T05:27:36","slug":"cloud-financial-officer","status":"publish","type":"post","link":"https:\/\/e326.greatsolution.dev\/de\/cloud-financial-officer\/","title":{"rendered":"Cloud Financial Officer"},"content":{"rendered":"\n<p>Abermals muss die Frage gestellt werden: Kann SAP auch Cloud Computing? SAP ist erfolgreich im Cloud Business. Aber diese Antwort ist zu allgemein. Worin genau liegt das SAP\u2019sche Erfolgspotenzial des Cloud Computing?<\/p>\n\n\n\n<p>Die \u00fcberzeugendsten Cloud-Zahlen lieferte in der Vergangenheit regelm\u00e4\u00dfig der SAP-CFO Luka Mucic. Der Umsatz wuchs regelm\u00e4\u00dfig und manche Cloud-Zahlen aus der Bilanz \u00fcberraschten sogar Finanzanalysten. Hingegen h\u00f6rte die SAP-Community von den Vorst\u00e4nden Thomas Saueressig und J\u00fcrgen M\u00fcller nur sehr wenig bez\u00fcglich Cloud-Applikationen und Cloud-Technik.<\/p>\n\n\n\n<p>Ganz offensichtlich besitzt SAP keine Cloud-Kompetenz im wissenschaftlichen und technischen Bereich. Die von Klein-Vorg\u00e4nger Bill McDermott zugekauften Cloud-Apps erweisen sich \u00fcberwiegend als brauchbar. Eine hinreichende Integration in den ERP-Core stellt auch viele SAP-Bestandskunden zufrieden. Aber w\u00e4hrend Luka Mucic regelm\u00e4\u00dfig leuchtende Augen bekommt, wenn er \u00fcber die SAP\u2019schen Cloud-Erfolge berichten darf, bleiben seine Vorstandskollegen, Saueressig und M\u00fcller, sehr unscheinbar und stumm.<\/p>\n\n\n\n<p>Mit guten Gr\u00fcnden kann SAP-Vorstandsmitglied Luka Mucic als Cloud Financial Officer bezeichnet werden. Er hat mit geschickter Hand in den vergangenen Jahren viele SAP-Ums\u00e4tze in die Wolke gehoben \u2013 ein Verdienst, den auch Professor Hasso Plattner erw\u00e4hnt und als Alleinstellungsmerkmal im Raum stehen l\u00e4sst. So, als h\u00e4tte Luka Mucic in seinen 26 Jahren bei SAP sonst nichts geleistet.<\/p>\n\n\n\n<p><em>\u201eWir sind Luka Mucic f\u00fcr seine 26-j\u00e4hrige T\u00e4tigkeit und sein Engagement f\u00fcr das Unternehmen sehr dankbar\u201c<\/em>, sagte Hasso Plattner, Vorsitzender des Aufsichtsrats der SAP. <em>\u201eW\u00e4hrend seiner Amtszeit als CFO ist der Cloud-Umsatz der SAP von einer Milliarde Euro auf \u00fcber neun Milliarden Euro gewachsen. Luka und sein F\u00fchrungsteam waren ein Eckpfeiler der erfolgreichen Cloud-Transformation der SAP. Ich bin sicher, dass sie auch w\u00e4hrend der kommenden \u00dcbergangsphase weiterhin hervorragende Arbeit leisten werden.\u201c<\/em><\/p>\n\n\n\n<p>Luka Mucic war also flei\u00dfig und hat den Cloud-Umsatz der SAP vervielfacht. Kein Wort von Plattner zu dem tadellosen Finanzmanagement w\u00e4hrend der internationalen Finanzkrise 2008, zu der finanziellen Absicherung w\u00e4hrend der SAP-Reorganisation, zu dem Management der zahlreichen Zuk\u00e4ufe w\u00e4hrend der Herrschaft von Bill McDermott und zu dem erfolgreichen B\u00f6rsengang von Qualtrics sowie zu der hervorragenden Mitarbeit bei Sapphire Venture. Und vielem mehr.<\/p>\n\n\n\n<p>Der Cloud Financial Officer geht also von Board: Die SAP hat Mitte M\u00e4rz bekannt gegeben, dass der Aufsichtsrat und Luka Mucic sich einvernehmlich darauf verst\u00e4ndigt haben, dass er das Unternehmen zum 31. M\u00e4rz kommenden Jahres verl\u00e4sst. Der Aufsichtsrat hat die Suche nach einem Nachfolger eingeleitet. Mucic ist der dritte CFO in der 50-j\u00e4hrigen Geschichte des Unternehmens. Er \u00fcbernahm die Position im Jahr 2014 von Werner Brandt, als er in den Vorstand berufen wurde. Mucic begann seine Karriere bei SAP im Jahr 1996 als Mitglied der Rechtsabteilung. <\/p>\n\n\n\n<p>Nachdem er von 2008 bis 2012 als CFO der DACH-Region t\u00e4tig war, wurde er 2013 zum Head of Global Finance und Mitglied des Global Managing Board der SAP ernannt. Mucic leitet au\u00dferdem die Nachhaltigkeitsbem\u00fchungen der SAP und ist f\u00fcr die Gesch\u00e4ftsbereiche Taulia und SAP Signavio verantwortlich. Taulia und Signavio stehen noch nicht auf eigenen Beinen. Mucic\u2019 langj\u00e4hrige Erfahrung und das Wissen um die SAP-Tradition werden diesen beiden Bereichen bei ihrer Emanzipation fehlen.<\/p>\n\n\n\n<p>SAP-Chef Christian Klein kann einem leidtun. Der junge CEO verliert seinen erfahrenen CFO und Cloud-Mitstreiter. Das zuk\u00fcnftige Cloud-Gesch\u00e4ft bei SAP ist in seiner Entwicklung massiv gef\u00e4hrdet. Luka Mucic hat nicht nur zehn Jahre mehr Berufserfahrung, sondern kennt auch die SAP-Entwicklung aus eigener Anschauung. Selten gab es in einem Dax-Konzern eine \u00e4hnlich reibungslose und erfolgreiche Staffel\u00fcbergabe wie zwischen dem Ex-CFO Werner Brandt und Luka Mucic.<\/p>\n\n\n\n<p>Technikvorstand J\u00fcrgen M\u00fcller und Applikationsvorstand Thomas Saueressig sind keine Unterst\u00fctzung f\u00fcr Klein. Marketingvorstand Julia White hat in den ersten 100 Tagen ihrer Amtszeit nichts geliefert und wird auch f\u00fcr den Rest ihrer Vorstandst\u00e4tigkeit bei SAP ein unbeschriebenes Blatt bleiben. Bez\u00fcglich Erfahrung, Intellekt und K\u00f6nnen bietet sich lediglich Sabine Bendiek, Chief People and Operating Officer, als Partnerin und Mentorin f\u00fcr Christian Klein an \u2013 vielleicht eine R\u00fcckbesinnung auf eine SAP-Doppelspitze.<\/p>\n\n\n\n<p><em>\u201eLuka war w\u00e4hrend meiner gesamten Laufbahn bei SAP ein wunderbarer Mentor\u201c<\/em>, sagte Christian Klein anl\u00e4sslich der neuen Situation. <em>\u201eSein Intellekt und seine Gro\u00dfz\u00fcgigkeit, sein auf Grunds\u00e4tzen beruhender F\u00fchrungsstil und sein Einsatz f\u00fcr SAP und unsere Kunden waren nicht nur f\u00fcr mich pers\u00f6nlich ein enormer Gewinn, sondern auch f\u00fcr die von ihm geleiteten Teams, f\u00fcr unser Wachstum sowie unseren Erfolg als Unternehmen.\u201c<\/em><\/p>\n\n\n\n<p><strong><em>Hinweis zum aktuellen E-3 Cover April 2022: <\/em><\/strong>Power of Orange ist das Leitmotiv des SAP-Partners cbs und keine politische Aussage. Aufgrund des in jeder Hinsicht zu verurteilenden Kriegs in der Ukraine durch den russischen Aggressor Wladimir Putin erscheint der E-3 Redaktion dieser Hinweis vor dem Hintergrund der Orangen Revolution von 2004 zur Klarstellung wichtig.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CFO Luka Mucic verl\u00e4sst SAP kommendes Jahr. Das Vorstandsmitglied und CFO hat mit dem Aufsichtsrat seinen R\u00fccktritt ausgehandelt, um sich beruflich neu zu positionieren. Zahlreiche Aufsichtsratsposten warten.<\/p>\n","protected":false},"author":2,"featured_media":4146,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[8,40563],"tags":[1114,15484,6389,8855],"coauthors":[27825],"class_list":["post-112937","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-editorial","category-mag-22-04","tag-cfo","tag-editorial","tag-luka-mucic","tag-peter-faerbinger","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479.jpg",1000,400,false],"thumbnail":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479-150x150.jpg",150,150,true],"medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479-400x160.jpg",400,160,true],"medium_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479-768x307.jpg",768,307,true],"large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479.jpg",1000,400,false],"image-100":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479-100x40.jpg",100,40,true],"image-480":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479-480x192.jpg",480,192,true],"image-640":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479-640x256.jpg",640,256,true],"image-720":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479-720x288.jpg",720,288,true],"image-960":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479-960x384.jpg",960,384,true],"image-1168":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479.jpg",1000,400,false],"image-1440":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479.jpg",1000,400,false],"image-1920":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479.jpg",1000,400,false],"1536x1536":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479.jpg",1000,400,false],"2048x2048":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479.jpg",1000,400,false],"trp-custom-language-flag":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479-18x7.jpg",18,7,true],"bricks_large_16x9":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479.jpg",1000,400,false],"bricks_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479.jpg",1000,400,false],"bricks_large_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479.jpg",1000,400,false],"bricks_medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479-600x240.jpg",600,240,true],"bricks_medium_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479-600x400.jpg",600,400,true],"profile_24":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479-24x24.jpg",24,24,true],"profile_48":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479-48x48.jpg",48,48,true],"profile_96":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479-96x96.jpg",96,96,true],"profile_150":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479-150x150.jpg",150,150,true],"profile_300":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>CFO Luka Mucic verl\u00e4sst SAP kommendes Jahr. Das Vorstandsmitglied und CFO hat mit dem Aufsichtsrat seinen R\u00fccktritt ausgehandelt, um sich beruflich neu zu positionieren. Zahlreiche Aufsichtsratsposten warten.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e326.greatsolution.dev\/de\/category\/meinung\/editorial\/\" rel=\"category tag\">Editorial<\/a>, <a href=\"https:\/\/e326.greatsolution.dev\/de\/category\/mag-22-04\/\" rel=\"category tag\">Mag 22-04<\/a>","author_info_v2":{"name":"Peter M. F\u00e4rbinger, E3-Magazin","url":"https:\/\/e326.greatsolution.dev\/de\/author\/peter-m-faerbinger-e-3-magazin\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/posts\/112937","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/comments?post=112937"}],"version-history":[{"count":0,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/posts\/112937\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/media\/4146"}],"wp:attachment":[{"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/media?parent=112937"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/categories?post=112937"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/tags?post=112937"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/coauthors?post=112937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}