{"id":113775,"date":"2022-06-07T08:00:00","date_gmt":"2022-06-07T06:00:00","guid":{"rendered":"https:\/\/e326.greatsolution.dev\/?p=113775"},"modified":"2022-06-07T11:59:40","modified_gmt":"2022-06-07T09:59:40","slug":"die-zukunft-der-lizenzierung","status":"publish","type":"post","link":"https:\/\/e326.greatsolution.dev\/de\/die-zukunft-der-lizenzierung\/","title":{"rendered":"Die Zukunft der Lizenzierung"},"content":{"rendered":"\n<p>Das Interesse an Rise with SAP ist derzeit gro\u00df. Als All-in-One-Angebot erhalten Kunden Softwarelizenzen, Application- und System-Management, Infrastruktur, Betriebssysteme, Implementierungs- sowie Prozessberatung \u2013 alles aus SAP-Hand. Damit kombiniert Rise eine bereits bestehende S\/4 Hana Cloud mit zus\u00e4tzlichen Komponenten. Darin beinhaltet sind kostenlose Schnupper- beziehungsweise Starterpakete, mit denen sich auf den ersten Blick Kosten reduzieren lassen. Auf den zweiten Blick decken diese Pakete den kompletten Bedarf aber oft nicht ab. Ein Beispiel: Vergleicht man den Listenpreis mit den Jahreskosten einer 1000-User-Installation, liegen diese unter f\u00fcnf Prozent des j\u00e4hrlichen S\/4-Abonnementpreises.<\/p>\n\n\n\n<p>Hier gilt es im Vorfeld zu pr\u00fcfen, ob nicht doch versteckte Kosten lauern und die Pakete wirklich einen Mehrwert bieten. Wen der errechnete ROI \u00fcberzeugt und wer seinem Softwarehersteller entspannt die Verantwortung f\u00fcr die Infrastruktur und Prozessoptimierung \u00fcbertragen m\u00f6chte, der ist bei Rise richtig.<\/p>\n\n\n\n<p>Bei der j\u00e4hrlichen Lizenzvermessung werden die User-Transaktionen, also die tats\u00e4chliche Nutzung, ermittelt. Jedoch gibt es seitens der SAP keine sinnvolle Dokumentation mit Lizenztypen f\u00fcr bestimmte Nutzungsumf\u00e4nge. Dabei ist seit 2018 im neuen USMM die Option zur \u201eLizenzvergabe nach Berechtigung\u201c integriert. Zun\u00e4chst hatte diese Funktion rein informellen Charakter. Stand heute haben immer mehr Unternehmen die neue Vermessungsart gew\u00e4hlt \u2013 ob monet\u00e4r sinnvoll oder nicht, sei dahingestellt. Sie alle stehen aber vor der Herausforderung, Berechtigungsrollen und Rollenzuweisungen vor der n\u00e4chsten Vermessung auf ein Minimum zu reduzieren. Andernfalls wird bei zu weitreichenden Berechtigungen, sogenannten Monsterrollen, eine teure Professional- oder gar Developer-Lizenz notwendig. M\u00f6chten Unternehmen nach Berechtigungen lizenzieren, sollten sie dem bew\u00e4hrten Grundsatz \u201eSo wenig wie m\u00f6glich, so viel wie n\u00f6tig\u201c folgen. Rollen und ihre Zuordnungen lassen sich schnell und automatisiert schrumpfen. Ratsam ist zudem, das Berechtigungskonzept vor der n\u00e4chsten Lizenzvermessung zu \u00fcberarbeiten, um den Monsterrollen entgegenzuwirken.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Gut vorbereitet in die Verhandlung gehen<\/h3>\n\n\n\n<p>Schon vor vielen Jahren hat die SAP das Zusammenspiel von SAP und Third-Party-Systemen kostenpflichtig gestellt. Sofern nicht vertraglich anders geregelt, fallen bei Fremdzugriffen auf SAP-Systeme Kosten an. Fortan wird die SAP versuchen, Unternehmen auf die sogenannten 9 Documents hin zu vermessen. Das hei\u00dft: Neu angelegte, wertsch\u00f6pfende Datenbankeintr\u00e4ge einer bestimmten Kategorie werden teuer. Bei 1000 Eintr\u00e4gen bel\u00e4uft sich der Preis auf 500 Euro zuz\u00fcglich Wartung. Oft liegen die angelegten Eintr\u00e4ge in Millionenh\u00f6he und stellen Unternehmen vor existenzielle Herausforderungen.&nbsp;<\/p>\n\n\n\n<p>Empfehlenswert ist, das Digital Access Adoption Program (DAAP) in Anspruch zu nehmen. Die SAP bietet Sonderkonditionen, wenn Kunden proaktiv \u2013 ergo: vor der Vermessung \u2013 auf das dokumentenbasierte Lizenzmodell umsteigen. Das DAAP gew\u00e4hrt einen Rabatt von 90 Prozent und entbindet von r\u00fcckwirkenden Wartungszahlungen. Hierbei ist es ratsam, eine korrekte Analyse und Z\u00e4hlung durch einen Lizenzierungsmanager durchzuf\u00fchren. Die Herkunft und Anzahl der Dokumente sind entscheidend und werden mit Bordmitteln gegebenenfalls nicht richtig vermessen.<\/p>\n\n\n\n<p>Unternehmen sollten sich nicht erst mit dem Lizenzmanagement auseinandersetzen, wenn der Vermessungstermin kurz vor der T\u00fcr steht oder die Migration schon vertraglich geregelt ist. Um auf Augenh\u00f6he verhandeln zu k\u00f6nnen, braucht es ausreichend zeitlichen Vorlauf und fundierte Informationen zu den wirklich notwendigen Lizenzierungen sowie damit verbundenen Kosten.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/e326.greatsolution.dev\/partners\/sivis-gmbh\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"112\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/08\/Sivis.jpg\" alt=\"https:\/\/e326.greatsolution.dev\/partners\/sivis-gmbh\/\" class=\"wp-image-54441\" title=\"Die zukunft der lizenzierung\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/08\/Sivis.jpg 1000w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/08\/Sivis-768x86.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/08\/Sivis-100x11.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/08\/Sivis-480x54.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/08\/Sivis-640x72.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/08\/Sivis-720x81.jpg 720w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/08\/Sivis-960x108.jpg 960w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>SAP-Lizenzierungsm\u00f6glichkeiten und -kosten \u00e4ndern sich regelm\u00e4\u00dfig. Kein Wunder, dass Verantwortliche den \u00dcberblick verlieren und Zusatzkosten entstehen. Aktuell werden Rise, DAAP und die Lizenzvergabe nach Berechtigung hei\u00df diskutiert.<\/p>\n","protected":false},"author":2437,"featured_media":2453,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[11,40660],"tags":[269,39933,15850],"coauthors":[39849],"class_list":["post-113775","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lizenz-kolumne","category-mag-22-05","tag-lizenzen","tag-lizenzkolumne","tag-sivis","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/Lizenzen.jpg",1000,432,false],"thumbnail":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/Lizenzen-150x150.jpg",150,150,true],"medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/Lizenzen.jpg",400,173,false],"medium_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/Lizenzen-768x332.jpg",768,332,true],"large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/Lizenzen.jpg",1000,432,false],"image-100":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/Lizenzen-100x43.jpg",100,43,true],"image-480":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/Lizenzen-480x207.jpg",480,207,true],"image-640":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/Lizenzen-640x276.jpg",640,276,true],"image-720":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/Lizenzen-720x311.jpg",720,311,true],"image-960":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/Lizenzen-960x415.jpg",960,415,true],"image-1168":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/Lizenzen.jpg",1000,432,false],"image-1440":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/Lizenzen.jpg",1000,432,false],"image-1920":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/Lizenzen.jpg",1000,432,false],"1536x1536":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/Lizenzen.jpg",1000,432,false],"2048x2048":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/Lizenzen.jpg",1000,432,false],"trp-custom-language-flag":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/Lizenzen.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/Lizenzen.jpg",1000,432,false],"bricks_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/Lizenzen.jpg",1000,432,false],"bricks_large_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/Lizenzen.jpg",1000,432,false],"bricks_medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/Lizenzen.jpg",600,259,false],"bricks_medium_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/Lizenzen.jpg",600,259,false],"profile_24":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/Lizenzen-24x24.jpg",24,24,true],"profile_48":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/Lizenzen-48x48.jpg",48,48,true],"profile_96":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/Lizenzen-96x96.jpg",96,96,true],"profile_150":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/Lizenzen-150x150.jpg",150,150,true],"profile_300":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/Lizenzen-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>SAP-Lizenzierungsm\u00f6glichkeiten und -kosten \u00e4ndern sich regelm\u00e4\u00dfig. Kein Wunder, dass Verantwortliche den \u00dcberblick verlieren und Zusatzkosten entstehen. Aktuell werden Rise, DAAP und die Lizenzvergabe nach Berechtigung hei\u00df diskutiert.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e326.greatsolution.dev\/de\/category\/meinung\/lizenz-kolumne\/\" rel=\"category tag\">Lizenz-Kolumne<\/a>, <a href=\"https:\/\/e326.greatsolution.dev\/de\/category\/mag-22-05\/\" rel=\"category tag\">Mag 22-05<\/a>","author_info_v2":{"name":"Andreas Knab, Sivis","url":"https:\/\/e326.greatsolution.dev\/de\/author\/andreas-knab\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/posts\/113775","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/users\/2437"}],"replies":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/comments?post=113775"}],"version-history":[{"count":0,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/posts\/113775\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/media\/2453"}],"wp:attachment":[{"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/media?parent=113775"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/categories?post=113775"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/tags?post=113775"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/coauthors?post=113775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}