{"id":120240,"date":"2022-12-22T10:00:00","date_gmt":"2022-12-22T09:00:00","guid":{"rendered":"https:\/\/e326.greatsolution.dev\/?p=120240"},"modified":"2024-01-19T11:27:16","modified_gmt":"2024-01-19T10:27:16","slug":"reise-nach-jerusalem","status":"publish","type":"post","link":"https:\/\/e326.greatsolution.dev\/de\/reise-nach-jerusalem\/","title":{"rendered":"Reise nach Jerusalem"},"content":{"rendered":"\n<p>Die Reise nach Jerusalem ist ein spannendes Spiel auf Kinderpartys. Es gibt immer einen Sessel weniger als anwesende Personen. H\u00f6rt die Musik auf zu spielen, muss sich jeder der Anwesenden schnell einen Platz suchen. Wer keinen Platz findet, der scheidet aus.<\/p>\n\n\n\n<p>Vorteilhaft bei diesem Spiel sind ein gutes Geh\u00f6r und schnelle Reaktion. Beides vermissen die Bestandskunden aktuell an SAP. Die F\u00e4higkeit, zuzuh\u00f6ren und nach dem Geh\u00f6rten das eigene Handeln auszurichten, ist der SAP in den vergangenen Jahren zunehmend abhandengekommen, siehe Illustration.<\/p>\n\n\n\n<p>SAP kommt regelm\u00e4\u00dfig mit interessanten Innovationen auf den Markt, diese entsprechen aber nur selten den Kundenw\u00fcnschen. Hana ist eine Datenbankinnovation, wie sie sich in der Informatik vielleicht nur alle 20 Jahre ereignet. Mit IBM DB2, MS-SQL-Server und Oracle waren die SAP-Bestandskunden aber auch sehr zufrieden. Es bestand keine Not, um eine neue und exklusive Datenbank zu platzieren. Sanfter Druck auf die Anbieter h\u00e4tte gen\u00fcgt, um diese zu besserer Leistung zu motivieren. Die Hana-Disruption war f\u00fcr viele SAP-Bestandskunden ein Kulturschock und nicht das Ergebnis ihrer W\u00fcnsche.<\/p>\n\n\n\n<p>Weil aber SAP die Stimme der Bestandskunden immer weniger h\u00f6rt und ber\u00fccksichtigt, findet SAP auch immer weniger Platz in den IT-Herzen ihrer Anwender. Es scheint fast eine selbsterf\u00fcllende Prophezeiung zu werden: Wenn SAP nicht h\u00f6rt und liefert, was die Anwender wollen und brauchen, werden andere IT-Anbieter den Platz von SAP einnehmen.<\/p>\n\n\n\n<p>Beim Thema CRM scheint SAP soeben ihren Platz zu verlieren. Hier ist die Reise nach Jerusalem zugunsten von Salesforce ausgegangen. Und die Musik spielt schon wieder weiter, sodass SAP eventuell die n\u00e4chste Runde an ServiceNow verliert. Wer jemals auf einem Kinderfest das Spiel gesehen hat, der wei\u00df, dass es ein brutales Spiel ist.<\/p>\n\n\n\n<p>Die Situation ist ambivalent, weil nicht eindeutig: Die Innovationen der SAP zeugen von hoher Entwicklerst\u00e4rke, umfassendem Wissen und nachhaltigem Durchhalteverm\u00f6gen \u2013 aber immer \u00f6fters gehen die SAP\u2019schen Erfindungen an den Marktbed\u00fcrfnissen vorbei. Rise with SAP ist ein innovativer Ansatz \u2013 nur, braucht das jemand in der SAP-Community? Die Qualit\u00e4ten von Rise gereichen einem durchschnittlichen SAP-Bestandskunden nicht zum Vorteil. Der Anwender will den Berg nicht schnell umrunden, sondern schnell auf dem Gipfel einen Platz f\u00fcr sich erobern, bevor die Musik aufh\u00f6rt zu spielen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"536\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2022\/11\/Platzgummer_Feb14_dltz.jpg\" alt=\"Platzgummer Feb 2014\" class=\"wp-image-120242\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2022\/11\/Platzgummer_Feb14_dltz.jpg 800w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2022\/11\/Platzgummer_Feb14_dltz-768x515.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2022\/11\/Platzgummer_Feb14_dltz-100x67.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2022\/11\/Platzgummer_Feb14_dltz-480x322.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2022\/11\/Platzgummer_Feb14_dltz-640x429.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2022\/11\/Platzgummer_Feb14_dltz-720x482.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption class=\"wp-element-caption\"><em>Erstmals wurde die Karikatur von Robert Platzgummer (1975 bis 2016) in der E-3 Ausgabe Februar 2014 verwendet. Schon damals gl\u00e4nzte SAP mit beachtenswerten Innovationen. Hier machen Ex-SAP-Chef Bill McDermott und Ex-Technikvorstand Vishal Sikka einem Bestandskunden Hana schmackhaft.<\/em><\/figcaption><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>SAP h\u00f6rt die Stimmen &#8211; die Musik &#8211; aus der Community nicht und alle Pl\u00e4tze f\u00fcr die Reise in die Zukunft sind besetzt. SAP bleibt zur\u00fcck. <\/p>\n","protected":false},"author":2,"featured_media":4954,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[41922,25],"tags":[5245,41924,39824,236,1633,5246],"coauthors":[27825],"class_list":["post-120240","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mag-22-11","category-satire-das-letzte","tag-das-letzte","tag-mag-22-11","tag-pmf","tag-sap","tag-sap-community","tag-satire","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-Letzte-Satire.jpg",1000,431,false],"thumbnail":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-Letzte-Satire-150x150.jpg",150,150,true],"medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-Letzte-Satire.jpg",400,172,false],"medium_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-Letzte-Satire-768x331.jpg",768,331,true],"large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-Letzte-Satire.jpg",1000,431,false],"image-100":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-Letzte-Satire-100x43.jpg",100,43,true],"image-480":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-Letzte-Satire-480x207.jpg",480,207,true],"image-640":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-Letzte-Satire-640x276.jpg",640,276,true],"image-720":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-Letzte-Satire-720x310.jpg",720,310,true],"image-960":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-Letzte-Satire-960x414.jpg",960,414,true],"image-1168":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-Letzte-Satire.jpg",1000,431,false],"image-1440":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-Letzte-Satire.jpg",1000,431,false],"image-1920":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-Letzte-Satire.jpg",1000,431,false],"1536x1536":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-Letzte-Satire.jpg",1000,431,false],"2048x2048":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-Letzte-Satire.jpg",1000,431,false],"trp-custom-language-flag":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-Letzte-Satire.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-Letzte-Satire.jpg",1000,431,false],"bricks_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-Letzte-Satire.jpg",1000,431,false],"bricks_large_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-Letzte-Satire.jpg",1000,431,false],"bricks_medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-Letzte-Satire.jpg",600,259,false],"bricks_medium_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-Letzte-Satire.jpg",600,259,false],"profile_24":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-Letzte-Satire-24x24.jpg",24,24,true],"profile_48":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-Letzte-Satire-48x48.jpg",48,48,true],"profile_96":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-Letzte-Satire-96x96.jpg",96,96,true],"profile_150":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-Letzte-Satire-150x150.jpg",150,150,true],"profile_300":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-Letzte-Satire-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>SAP h\u00f6rt die Stimmen &#8211; die Musik &#8211; aus der Community nicht und alle Pl\u00e4tze f\u00fcr die Reise in die Zukunft sind besetzt. SAP bleibt zur\u00fcck. <\/p>\n","category_list_v2":"<a href=\"https:\/\/e326.greatsolution.dev\/de\/category\/mag-22-11\/\" rel=\"category tag\">Mag 22-11<\/a>, <a href=\"https:\/\/e326.greatsolution.dev\/de\/category\/meinung\/satire-das-letzte\/\" rel=\"category tag\">Satire: Das Letzte<\/a>","author_info_v2":{"name":"Peter M. F\u00e4rbinger, E3-Magazin","url":"https:\/\/e326.greatsolution.dev\/de\/author\/peter-m-faerbinger-e-3-magazin\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/posts\/120240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/comments?post=120240"}],"version-history":[{"count":1,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/posts\/120240\/revisions"}],"predecessor-version":[{"id":137484,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/posts\/120240\/revisions\/137484"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/media\/4954"}],"wp:attachment":[{"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/media?parent=120240"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/categories?post=120240"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/tags?post=120240"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/coauthors?post=120240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}