{"id":1856,"date":"2016-11-25T02:00:55","date_gmt":"2016-11-25T01:00:55","guid":{"rendered":"https:\/\/e326.greatsolution.dev\/?p=1856"},"modified":"2022-02-05T23:55:31","modified_gmt":"2022-02-05T22:55:31","slug":"koenigsweg-zum-golden-record","status":"publish","type":"post","link":"https:\/\/e326.greatsolution.dev\/de\/koenigsweg-zum-golden-record\/","title":{"rendered":"K\u00f6nigsweg zum Golden Record"},"content":{"rendered":"<h3>Was sind die Erfolgsfaktoren f\u00fcr eine Stammdateninitiative?<\/h3>\n<p><strong>Marco Wittigayer<\/strong>: Eine Stammdatenmanagementinitiative ist kein in erster Linie technologisches und daher auch kein reines <span id=\"urn:local-text-annotation-seeunwp8dwf9hu0j0h5uz3pwekl54yv9\" class=\"textannotation disambiguated wl-thing\">IT<\/span>-Thema. Sie muss in <span id=\"urn:local-text-annotation-3syrx4v3vr41dwhrtzoegfhy2cesywh2\" class=\"textannotation disambiguated wl-thing\">Unternehmen<\/span> gemeinsam von den Fachbereichen und von der <span id=\"urn:local-text-annotation-bdduv9w87ck09pp8y73pqne1bi29llzr\" class=\"textannotation disambiguated wl-thing\">IT<\/span> getrieben werden.<\/p>\n<p>Laut einer PwC-Studie geh\u00f6ren unter anderem die Unterst\u00fctzung durch das <span id=\"urn:local-text-annotation-n2hbn8k2vqrfaz66pe8qwkff9h0fzlv3\" class=\"textannotation disambiguated wl-thing\">Management<\/span>, strukturierte und zielgerichtete Data Governance sowie Prozessoptimierung zu den Erfolgsfaktoren.<\/p>\n<p>Sie sollten nicht irgendwo im <span id=\"urn:local-text-annotation-3qo2ou99y5y2pkqwvpesy9nv68wdhq62\" class=\"textannotation disambiguated wl-thing\">Unternehmen<\/span> angesiedelt sein, sondern beim Top-<span id=\"urn:local-text-annotation-23cmczn1licjeu9xq8pynibhafdcps3o\" class=\"textannotation disambiguated wl-thing\">Management<\/span>. Nur so kann sichergestellt werden, dass die Bedeutung hoher Stammdatenqualit\u00e4t f\u00fcr die Gesch\u00e4fts- und Kostenentwicklung von allen <span id=\"urn:local-text-annotation-pirad4lzq7nhuqc2obpa0xyercgqp29c\" class=\"textannotation disambiguated wl-thing\">Mitarbeitern<\/span> verstanden wird.<\/p>\n<p>Unternehmensinterne Richtlinien f\u00fcr den Umgang mit <span id=\"urn:local-text-annotation-s1v1hyjpf6s517c7di1twrcofjf2rae1\" class=\"textannotation disambiguated wl-thing\">Daten<\/span> sind zwingend erforderlich. Die Data Governance definiert einheitliche Regeln, Prozesse und Verantwortlichkeiten f\u00fcr Dateneingabe, -freigabe und -pflege sowie Datenqualit\u00e4ts-KPIs.<\/p>\n<p>Dabei sind nicht nur die Kernprozesse im <span id=\"urn:local-text-annotation-xggaft1zeamx02fh6wi7be9x2igs34cg\" class=\"textannotation disambiguated wl-thing\">Unternehmen<\/span> zu ber\u00fccksichtigen, wie <span id=\"urn:local-text-annotation-pn1xrm332slbh35tncd8466gpkzi7i53\" class=\"textannotation disambiguated wl-thing\">Einkauf<\/span>, Produktion oder Vertrieb. Auch die Stammdatenprozesse rund um das Anlegen, Pflegen oder L\u00f6schen von <span id=\"urn:local-text-annotation-vy2sccfv8xgtbb5g91494j3xuq5mxhjx\" class=\"textannotation disambiguated wl-thing\">Daten<\/span> m\u00fcssen optimiert werden.<\/p>\n<h3><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/Screenshot-2016-11-23-um-10.56.52.png\"><img loading=\"lazy\" decoding=\"async\" title=\"K\u00f6nigsweg zum golden record\" class=\"alignleft wp-image-1930\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/Screenshot-2016-11-23-um-10.56.52.png\" alt=\"ZetVisions\" width=\"169\" height=\"541\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/Screenshot-2016-11-23-um-10.56.52.png 362w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/Screenshot-2016-11-23-um-10.56.52-100x320.png 100w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/><\/a>Ist daf\u00fcr viel \u00dcberzeugungsarbeit bei den <span id=\"urn:local-text-annotation-onewsp1yl1fleuxz9b8duz85aqc9epzh\" class=\"textannotation disambiguated wl-thing\">Mitarbeitern<\/span> notwendig?<\/h3>\n<p><strong>Wittigayer<\/strong>: Eine Stammdateninitiative greift in \u00fcberkommene Strukturen, Prozesse und Hoheitsgebiete ein.<\/p>\n<p>Daher geh\u00f6rt ein begleitendes Change <span id=\"urn:local-text-annotation-gsgnngio1p47fuvfpathfc9cl079q1lg\" class=\"textannotation disambiguated wl-thing\">Management<\/span> zu den Erfolgsfaktoren, um die Betroffenen zu Beteiligten zu machen und sie in die neue Welt \u201emitzunehmen\u201c.<\/p>\n<p>Eine professionelle Softwarel\u00f6sung schlie\u00dflich kann stets nur unterst\u00fctzend wirken. Erst nachdem Prozesse und Befugnisse f\u00fcr die Datenpflege und -freigabe klar definiert sind, kann eine <span id=\"urn:local-text-annotation-jnhivtn6ghf9ckzxz9gu7m445cbv2tms\" class=\"textannotation disambiguated wl-thing\">IT<\/span>-Unterst\u00fctzung erfolgen.<\/p>\n<h3>Wie sollten <span id=\"urn:local-text-annotation-lcwm7nab1zbxven1vyypr581jsvkevm4\" class=\"textannotation disambiguated wl-thing\">Unternehmen<\/span> bei einer Stammdateninitiative vorgehen?<\/h3>\n<p>Wittigayer: Wir empfehlen, nicht gleich mit allen Stammdatendom\u00e4nen \u2013 <span id=\"urn:local-text-annotation-ix08plrbl86ch0z71r7kwmuh8rjos4jn\" class=\"textannotation disambiguated wl-thing\">Kunden<\/span>, Lieferanten, Material, Produkte, Finanzen etc. \u2013 zu starten, sondern erst einmal nur mit einer Dom\u00e4ne.<\/p>\n<p>F\u00fcr die Auswahl gibt es verschiedene M\u00f6glichkeiten.<\/p>\n<p>Man kann die Dom\u00e4ne mit den gr\u00f6\u00dften Qualit\u00e4tsproblemen zuerst angehen oder die, die entweder die gr\u00f6\u00dfte Bedeutung f\u00fcr das <span id=\"urn:local-text-annotation-y7lnbz1mr6lv44kq1d9u5md24m815bf2\" class=\"textannotation disambiguated wl-thing\">Unternehmen<\/span> besitzt oder die schnellsten Erfolgserlebnisse verspricht. Das ist eine individuelle Entscheidung.<\/p>\n<p>Nach dem Start mit einer Dom\u00e4ne erfolgt der Ausbau der Stammdateninitiative auf die weiteren Dom\u00e4nen, also z.B. erst die Kundenstammdaten, dann die Lieferantenstammdaten usw. So ergibt sich eine durchaus sinnvolle Aufteilung des Gesamtprojekts auf mehrere Phasen.<\/p>\n<h3>Welche MDM-L\u00f6sung ist aus Ihrer Sicht wirkungsvoller: Single- oder Multi-Domain?<\/h3>\n<p><strong>Wittigayer<\/strong>: Unabh\u00e4ngig von unserer Empfehlung, zun\u00e4chst mit einer Dom\u00e4ne zu starten, sollten <span id=\"urn:local-text-annotation-i9kpuuc1ppe1jkbuvqpx7u8jg5xw5ohy\" class=\"textannotation disambiguated wl-thing\">Unternehmen<\/span> eine Multi-\u00adDomain-MDM-L\u00f6sung einsetzen.<\/p>\n<p>Dabei handelt es sich um eine <span id=\"urn:local-text-annotation-e36qoob2khipjc5qbeljhkmmpe2t1pvn\" class=\"textannotation disambiguated wl-thing\">Stammdaten<\/span>-L\u00f6sung, die mehrere Stammdatendom\u00e4nen abdeckt und das gesamte Master Data Management in einer Plattform zentralisiert. Alle relevanten <span id=\"urn:local-text-annotation-wg1rplu3a96qe493zbq0ty0bwiiiglnq\" class=\"textannotation disambiguated wl-thing\">Daten<\/span> vom <span id=\"urn:local-text-annotation-wxlsuxsq0gsd2dkykhhh9q39q0mbiite\" class=\"textannotation disambiguated wl-thing\">Einkauf<\/span> bis zum Verkauf laufen in einem zentralen System zusammen und k\u00f6nnen von dort an beliebige Zielsysteme verteilt werden.<\/p>\n<p>Das er\u00f6ffnet neue Perspektiven f\u00fcr den <span id=\"urn:local-text-annotation-n4khtbih654mmwb6f8enrmgk5una3myb\" class=\"textannotation disambiguated wl-thing\">Gesch\u00e4ftsprozess<\/span>. Unternehmensweite Zusammenh\u00e4nge und Wechselwirkungen werden sichtbar \u2013 und damit nicht selten ein betr\u00e4chtliches Einsparpotenzial bei Zeit und Kosten.<\/p>\n<p>Bringt man zugeh\u00f6rige <span id=\"urn:local-text-annotation-9wl6edx0zuslm1eym64hg9pfd6kyqgft\" class=\"textannotation disambiguated wl-thing\">Stammdaten<\/span> einer Dom\u00e4ne zusammen, l\u00e4sst sich ein \u201eGolden Record\u201c f\u00fcr beispielsweise <span id=\"urn:local-text-annotation-kknauyj794nk0cjf639cls7np0zbx6na\" class=\"textannotation disambiguated wl-thing\">Kunden<\/span>, Produkte, Lieferanten bilden und lassen sich Wechselwirkungen zwischen diesen Dom\u00e4nen erkennen. Man erh\u00e4lt einen Rundumblick auf die <span id=\"urn:local-text-annotation-k7q4l2t4tllrn4sm7nm4nsrviwtjj1gh\" class=\"textannotation disambiguated wl-thing\">Stammdaten<\/span> \u00fcber alle Dom\u00e4nen hinweg.<\/p>\n<p>Ein Multi-Domain-MDM schafft somit die \u201eeine Wahrheit\u201c f\u00fcr unterschiedliche Stammdatendom\u00e4nen \u00fcber den gesamten <span id=\"urn:local-text-annotation-o1jwv5rklaopbp5rs3tv4bckanst3yrw\" class=\"textannotation disambiguated wl-thing\">Gesch\u00e4ftsprozess<\/span>.<\/p>\n<h3>Welche Vorteile bieten Multi-Domain-L\u00f6sungen noch?<\/h3>\n<p><strong>Wittigayer<\/strong>: Neben der integrierten unternehmensweiten Datenhaltung k\u00f6nnen Multi-Domain-MDM-Systeme mit Datenqualit\u00e4tsregeln und Lebenszyklusprozessen auch Data Governance unterst\u00fctzen, also einheitliche und verbindliche Rahmenbedingungen, Workflows und Verantwortlichkeiten f\u00fcr den Umgang mit <span id=\"urn:local-text-annotation-vez0rsxpfkdyeuqqrfmgy82n3srf8z08\" class=\"textannotation disambiguated wl-thing\">Daten<\/span>, ihre Pflege, Verteilung etc. Bei der Nutzung von diversen Single-Domain-Datensilos ist es naturgem\u00e4\u00df schwierig, die unternehmensweite Einhaltung definierter Standards sicherzustellen.<\/p>\n<p>Gibt es dagegen nur eine Quelle f\u00fcr <span id=\"urn:local-text-annotation-qhbobund9yng8tgsb0y9jcm9oimx3toq\" class=\"textannotation disambiguated wl-thing\">Stammdaten<\/span>, haben die Nutzer erheblich weniger Autonomie bei der Entwicklung von Definitionen und Regeln f\u00fcr Daten, da die dom\u00e4nen\u00fcbergreifende Datenarchitektur verbindlich und transparent ist.<\/p>\n<p>Das Ergebnis: wirksame Governance-Prinzipien und funktions\u00fcbergreifende Zusammenarbeit zwischen <span id=\"urn:local-text-annotation-65ru70twgkmjfanpguo7lhkhusz40xbc\" class=\"textannotation disambiguated wl-thing\">Abteilungen<\/span>. Beides zusammen f\u00fchrt zu mehr Prozesseffizienz und besserer Ressourcenallokation.<\/p>\n<h3>Wie ist Ihre Vorgehensweise bei einem Stammdatenprojekt?<\/h3>\n<p><strong>Wittigayer<\/strong>: Wir gehen in f\u00fcnf Schritten vor, wobei jede Phase mit einem Meilenstein abgeschlossen wird, bevor die n\u00e4chste Projektphase beginnt.<\/p>\n<p>Innerhalb der Projektvorbereitungsphase wird in Abstimmung mit dem <span id=\"urn:local-text-annotation-bcm9prdsmttzaxkt3xbpgptbqcxkbdze\" class=\"textannotation disambiguated wl-thing\">Kunden<\/span> der Projektumfang spezifiziert und ein detaillierter Projektplan erstellt. Ein Kick-off-Meeting inklusive Teamtraining holt alle Beteiligten ins Boot.<\/p>\n<p>In der anschlie\u00dfenden Sollkonzept-Phase, die den Grundstein f\u00fcr den Erfolg eines Stammdatenprojekts legt und somit die wichtigste Phase darstellt, definieren wir in Workshops und Gespr\u00e4chen individuelle Zielsetzungen; zudem erarbeiten wir ein bedarfsgerechtes <span id=\"urn:local-text-annotation-358gz3tu6bpl9976ty4qkheyyt95pjua\" class=\"textannotation disambiguated wl-thing\">Konzept<\/span> f\u00fcr die <span id=\"urn:local-text-annotation-sp9tm0rlwyisq5mw9cndf9926y57ewue\" class=\"textannotation disambiguated wl-thing\">IT<\/span>-gest\u00fctzte Abbildung der unternehmensspezifischen Data-Gover\u00adnance-Aspekte, Berechtigungen und die damit verbundenen Prozesse.<\/p>\n<p>Auch die Definition der Datenmodelle sowie der Schnittstellen (Datentransfers) erfolgt in dieser Phase. Die Entscheidung, welche <span id=\"urn:local-text-annotation-qzs9q3j3fzcbdjia5sq28quhgquewujs\" class=\"textannotation disambiguated wl-thing\">Stammdaten<\/span> im zentralen System gef\u00fchrt werden sollen, ist ebenfalls Bestandteil dieser Phase.<\/p>\n<p>Parallel dazu installieren wir ZetVisions SPoT auf der Systemlandschaft des <span id=\"urn:local-text-annotation-pg92630ww4iz2ne43vczhqzrap6d9ebc\" class=\"textannotation disambiguated wl-thing\">Kunden<\/span>.<\/p>\n<h3>Was passiert nach dieser Phase?<\/h3>\n<p><strong>Wittigayer<\/strong>: In der darauf folgenden Implementierungsphase werden die einzelnen Fachkonzepte in die Tat umgesetzt. Gegebenenfalls bereiten wir hier auch eine initiale Daten\u00fcbernahme in SPoT vor.<\/p>\n<p>Weiterhin erhalten <span id=\"urn:local-text-annotation-pftlptsbmab6v78uqz57oeovegqpp0re\" class=\"textannotation disambiguated wl-thing\">Kunden<\/span> nun die Gelegenheit, die Einstellungen oder Anpassungen des neuen Systems ausgiebig zu testen.<\/p>\n<p>W\u00e4hrend der Produktionsvorbereitung unterst\u00fctzt ZetVisions den <span id=\"urn:local-text-annotation-2pmoro4lboruqadzasdnyk8pja0n1ajt\" class=\"textannotation disambiguated wl-thing\">Kunden<\/span> bei der Go-live-Planung. Dazu geh\u00f6rt selbstverst\u00e4ndlich auch die Schulung der <span id=\"urn:local-text-annotation-yepjsl1rb7pafrte4mg4kn5m5xqhch49\" class=\"textannotation disambiguated wl-thing\">Mitarbeiter<\/span>. Sie sollen das System nicht nur handhaben k\u00f6nnen, sondern in der Lage sein, selbst Anpassungen am System (<span id=\"urn:local-text-annotation-3ed0nf4rzljt1qoof6vmzbvxbvuh24zv\" class=\"textannotation disambiguated wl-thing\">Customizing<\/span>) durchzuf\u00fchren.<\/p>\n<p>In der finalen Go-live-Phase geht ZetVisions SPoT an die Arbeit. Nach erfolgreichem Abschluss des Projekts erfolgt die \u00dcbergabe an unser <span id=\"urn:local-text-annotation-iwqqmx7sykymx3hdswpm6iu862y7uk37\" class=\"textannotation disambiguated wl-thing\">Support<\/span>-Team.<\/p>\n<h3>Wie sieht Ihr Schulungskonzept aus?<\/h3>\n<p><strong>Wittigayer<\/strong>: Wir verfolgen von Projektbeginn an ein Train-the-Trainer-<span id=\"urn:local-text-annotation-k9ped4hy4kre1blotackzhvcp4yz102o\" class=\"textannotation disambiguated wl-thing\">Konzept<\/span>. Im Mittelpunkt steht dabei das Team, das in den ersten beiden Projektphasen das <span id=\"urn:local-text-annotation-93q4vvh5d3rqqsexh9hka2vscu272b5f\" class=\"textannotation disambiguated wl-thing\">Customizing<\/span> definiert und vollst\u00e4ndigen Zugang zum System erh\u00e4lt.<\/p>\n<p>Schon innerhalb einer Administratorschulung implementieren die Administratoren des <span id=\"urn:local-text-annotation-7wdumkosuvmiitotkajsfzhvy85fc7tq\" class=\"textannotation disambiguated wl-thing\">Kunden<\/span> mit unserer Unterst\u00fctzung das System und k\u00f6nnen es selbstst\u00e4ndig customizen.<\/p>\n<p>Das hei\u00dft: Der Kunde kann auf die hauseigene <span id=\"urn:local-text-annotation-9dzg40joh1cmf7bbdb362cryj85h0lju\" class=\"textannotation disambiguated wl-organization\">SAP<\/span>-Basis\u00adexpertise zugreifen, um z. B. das SPoT-<span id=\"urn:local-text-annotation-jzriclkxesoea7tm453fyv3cacrwp2xw\" class=\"textannotation disambiguated wl-thing\">Customizing<\/span> und das Berechtigungsmanagement vorzunehmen.<\/p>\n<p>Dar\u00fcber hinaus werden in der zweiten Phase des Projekts weitere Schulungen zu einzelnen Aspekten des Systems durchgef\u00fchrt.<\/p>\n<h3>Was ist das Ziel der Schulungen?<\/h3>\n<p>Wittigayer: Die Teilnehmer entwickeln w\u00e4hrend der Schulungen ein grundlegendes Verst\u00e4ndnis f\u00fcr die Funktionsweise von SPoT und machen erste Erfahrungen mit der Dateneingabe und -auswertung.<\/p>\n<p>Ziel des Train-the-Trainer-Konzepts ist es, neben der L\u00f6sungseinf\u00fchrung den Projektmitarbeiter zu bef\u00e4higen, eigenst\u00e4ndig Schulungen zu leiten. Nach Projektabschluss k\u00f6nnen <span id=\"urn:local-text-annotation-1p761uftisp6lby3zlzprb1fhu7w1h60\" class=\"textannotation disambiguated wl-thing\">Kunden<\/span> die Endanwender in einer nachgelagerten Schulungsphase in das System einf\u00fchren.<\/p>\n<p>Bei Bedarf bietet auch ZetVisions solche Anwenderschulungen zu den gew\u00fcnschten Themen an oder unterst\u00fctzt bei der Durchf\u00fchrung.<\/p>\n<h3>Was passiert nach der Implementierung bzw. nach dem Projekt?<\/h3>\n<p><strong>Wittigayer<\/strong>: Nat\u00fcrlich bleiben wir auch nach der Einf\u00fchrung von ZetVisions SPoT an der Seite unserer <span id=\"urn:local-text-annotation-s06xaq1hgpoxnrd8b38fn29nd72q7sgd\" class=\"textannotation disambiguated wl-thing\">Kunden<\/span>.<\/p>\n<p>Nach dem Go-live steht unser <span id=\"urn:local-text-annotation-x0fq6iphuxl7ia04edoigmc0271yaxck\" class=\"textannotation disambiguated wl-thing\">Support<\/span> nicht nur w\u00e4hrend der Hypercare-Phase direkt nach Inbetriebnahme, sondern auch dar\u00fcber hinaus f\u00fcr alle Fragen, W\u00fcnsche und Probleme zur Verf\u00fcgung.<\/p>\n<p>Die Intensit\u00e4t der Betreuung wird dabei allein durch die Anforderungen unserer <span id=\"urn:local-text-annotation-pqf6utg0509wt2htssqviolth8vwkliz\" class=\"textannotation disambiguated wl-thing\">Kunden<\/span> bestimmt.<\/p>\n<h3>Was sind Ihre pers\u00f6nlichen \u201elessons \u00adlearned\u201c aus Stammdatenprojekten?<\/h3>\n<p><strong>Wittigayer<\/strong>: Neben der Beachtung der oben beschriebenen Erfolgsfaktoren kommt es darauf an, erst einmal die richtigen Fragen zu stellen. Das hat uns nicht nur die Erfahrung aus zahlreichen Kundenprojekten gezeigt, sondern auch die Implementierung unserer L\u00f6sung f\u00fcr Kundenstammdaten im eigenen Haus.<\/p>\n<p>Die Ausgangssituation war gekennzeichnet durch drei verschiedene Datenpools, in denen die internen <span id=\"urn:local-text-annotation-kph5z9wus7d5mpyvlkrdqdozbzhfa5qs\" class=\"textannotation disambiguated wl-thing\">Abteilungen<\/span> Kundendaten, wie beispielsweise Name, Adresse, Kontaktpersonen, f\u00fcr ihre Zwecke und damit mehrfach angelegt haben.<\/p>\n<p>Informationen, die in einem \u201eDatentopf\u201c ankamen, wurden nicht immer an die anderen weitergereicht, die sie aber auch h\u00e4tten kennen m\u00fcssen. Das klingt zun\u00e4chst unspektakul\u00e4r, ist aber leider der Nukleus f\u00fcr die typischen, generalisierbaren Probleme beim <span id=\"urn:local-text-annotation-ahww893588lyat482ngdi8is4gzvxhd5\" class=\"textannotation disambiguated wl-thing\">Management<\/span> von <span id=\"urn:local-text-annotation-yqdqqa1fknmzqap7jlcdmmyyvn0kke85\" class=\"textannotation disambiguated wl-thing\">Stammdaten<\/span>.<\/p>\n<h3>Wie gelingt die Zusammenarbeit zwischen den Abteilungsgrenzen hinweg?<\/h3>\n<p><strong>Wittigayer<\/strong>: Zun\u00e4chst mussten sich die Fachbereiche \u00fcber die Definition austauschen und w\u00e4hrend des Projekts ein einheitliches Wording festlegen.<\/p>\n<p>Zum Beispiel sprach die Finanzabteilung von \u201eDebitoren, <span id=\"urn:local-text-annotation-1u2174ulqgmp9ar8vjzta8ad84jcwbe1\" class=\"textannotation disambiguated wl-thing\">Kunden<\/span>\u201c, wohingegen Sales &amp; Marketing von \u201eAccounts\u201c sprachen.<\/p>\n<p>Allein die Frage \u201eWann ist jemand <span id=\"urn:local-text-annotation-2ycm3ls3j7gul013cwj3jh6svdn1np4t\" class=\"textannotation disambiguated wl-thing\">Kunde<\/span>?\u201c hat einige Diskussionen ausgel\u00f6st.<\/p>\n<p>Vor diesem durchaus verallgemeinerungsf\u00e4higen Hintergrund geh\u00f6ren zu den typischen Fragen, die sich vor und w\u00e4hrend eines Stammdatenprojekts stellen:<\/p>\n<ul>\n<li>Was bedeuten <span id=\"urn:local-text-annotation-wmxh4524yo989n31bbuo5x3dhht1whtd\" class=\"textannotation disambiguated wl-thing\">Stammdaten<\/span> in unserem Kontext?<\/li>\n<li>Wie werden diese <span id=\"urn:local-text-annotation-nyzzg56v43wmievuql2d95rsmf6ptxzw\" class=\"textannotation disambiguated wl-thing\">Stammdaten<\/span> definiert?<\/li>\n<li>Welche <span id=\"urn:local-text-annotation-85z2aayetyfyn2ysebu5mlwnklwupc8l\" class=\"textannotation disambiguated wl-thing\">Stammdaten<\/span> m\u00fcssen angeglichen, welche sollen \u00fcberhaupt initial \u00fcbernommen werden?<\/li>\n<li>Was sind globale oder lokale <span id=\"urn:local-text-annotation-7ptsclb6c1bmdm81gryrcsfufq8j00f7\" class=\"textannotation disambiguated wl-thing\">Stammdaten<\/span>?<\/li>\n<li>Welches System hat die beste <span id=\"urn:local-text-annotation-km0gj35nlfnp53mkb3urzlz9vvg31jjd\" class=\"textannotation disambiguated wl-thing\">Datenqualit\u00e4t<\/span> f\u00fcr die initiale Daten\u00fcbernahme in ZetVisions SPoT?<\/li>\n<li>Welche \u00dcberschneidungen dieser <span id=\"urn:local-text-annotation-ogth7c1huhaovkgalxmklt75ayjr9pks\" class=\"textannotation disambiguated wl-thing\">Stammdaten<\/span> mit den bestehenden Datenpools gibt es?<\/li>\n<li>Was sind die technischen Besonderheiten der Systeme?<\/li>\n<li>Wie soll der Soll-Prozess aussehen?<\/li>\n<li>Wer ist f\u00fcr Dateneingabe und -pflege verantwortlich?<\/li>\n<li>Wie sollen die Freigabeprozesse aufgebaut sein?<\/li>\n<li>Welche Systeme sollen angebunden werden?<\/li>\n<\/ul>\n<p>Im Ergebnis f\u00fchrt die Beantwortung dieser Fragen im Wege der Implementierung einer Stammdatenmanagement-L\u00f6sung zu einer deutlich besseren Data Governance durch klar definierte Verantwortlichkeiten und kontrollierte Prozesse f\u00fcr Dateneingabe und -freigabe sowie kontrollierte und zentralisierte Datenverteilung an alle Empf\u00e4ngersysteme.<\/p>\n<h3>Wie wirkt sich das auf die Fehlerquellen aus?<\/h3>\n<p><strong>Wittigayer<\/strong>: Potenzielle Fehlerquellen werden reduziert, weil definiert ist, wer welche Informationen wo pflegen \u2013 oder eben nicht pflegen \u2013 darf.<\/p>\n<p>Da alle Systeme dieselbe Version der <span id=\"urn:local-text-annotation-9q0ngqeis24w6i7k8qpnrls3bk1suf21\" class=\"textannotation disambiguated wl-thing\">Stammdaten<\/span> nutzen, wird die <span id=\"urn:local-text-annotation-bdcdj7x4jeb5oqz3c4mkaix5tarwzidg\" class=\"textannotation disambiguated wl-thing\">Datenqualit\u00e4t<\/span> \u201eautomatisch\u201c besser, die richtigen <span id=\"urn:local-text-annotation-s38u7heni719xn8bzhzdjqkgv8exw7b4\" class=\"textannotation disambiguated wl-thing\">Daten<\/span> liegen stets tagesaktuell vor.<\/p>\n<p>Schlanke Prozesse ohne redundante, manuelle Dateneingabe in den verschiedenen Systemen \u2013 und dem damit verbundenen Abstimmungsaufwand zwischen den <span id=\"urn:local-text-annotation-aipzoqq7kmdfxrzfmt0vhro0479nlgfc\" class=\"textannotation disambiguated wl-thing\">Abteilungen<\/span> \u2013 reduzieren Komplexit\u00e4t und Kosten.<\/p>\n<p>Dieses Res\u00fcmee l\u00e4sst sich auf jedes andere Stammdatenmanagement-Thema \u00fcbertragen.<\/p>\n<h3>Danke f\u00fcr das Gespr\u00e4ch!<\/h3>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wenn die Datenqualit\u00e4t in Ihrem Unternehmen nicht stimmt, hat das negative Auswirkungen auf Ihre gesamte betriebliche Struktur. Dr. Marco Wittigayer zeigt im E-3 Exklusivinterview, was Unternehmen alles beachten m\u00fcssen, damit Stammdateninitiativen erfolgreich werden.<\/p>\n","protected":false},"author":38,"featured_media":4944,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[741,740],"tags":[618,143,437,750,619,608],"coauthors":[19920],"class_list":["post-1856","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coverstory1612","category-mag1612","tag-kunde","tag-management","tag-mitarbeiter","tag-spot","tag-support","tag-unternehmen","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/E3-Interview.jpg",1000,685,false],"thumbnail":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/E3-Interview-150x150.jpg",150,150,true],"medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/E3-Interview.jpg",400,274,false],"medium_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/E3-Interview-768x526.jpg",768,526,true],"large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/E3-Interview.jpg",1000,685,false],"image-100":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/E3-Interview-100x69.jpg",100,69,true],"image-480":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/E3-Interview-480x329.jpg",480,329,true],"image-640":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/E3-Interview-640x438.jpg",640,438,true],"image-720":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/E3-Interview-720x493.jpg",720,493,true],"image-960":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/E3-Interview-960x658.jpg",960,658,true],"image-1168":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/E3-Interview.jpg",1000,685,false],"image-1440":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/E3-Interview.jpg",1000,685,false],"image-1920":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/E3-Interview.jpg",1000,685,false],"1536x1536":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/E3-Interview.jpg",1000,685,false],"2048x2048":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/E3-Interview.jpg",1000,685,false],"trp-custom-language-flag":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/E3-Interview.jpg",18,12,false],"bricks_large_16x9":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/E3-Interview.jpg",985,675,false],"bricks_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/E3-Interview.jpg",1000,685,false],"bricks_large_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/E3-Interview.jpg",1000,685,false],"bricks_medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/E3-Interview.jpg",600,411,false],"bricks_medium_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/E3-Interview.jpg",600,411,false],"profile_24":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/E3-Interview-24x24.jpg",24,24,true],"profile_48":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/E3-Interview-48x48.jpg",48,48,true],"profile_96":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/E3-Interview-96x96.jpg",96,96,true],"profile_150":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/E3-Interview-150x150.jpg",150,150,true],"profile_300":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/E3-Interview-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Wenn die Datenqualit\u00e4t in Ihrem Unternehmen nicht stimmt, hat das negative Auswirkungen auf Ihre gesamte betriebliche Struktur. Dr. Marco Wittigayer zeigt im E-3 Exklusivinterview, was Unternehmen alles beachten m\u00fcssen, damit Stammdateninitiativen erfolgreich werden.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e326.greatsolution.dev\/de\/category\/coverstorys\/coverstory1612\/\" rel=\"category tag\">Coverstory 16-12<\/a>, <a href=\"https:\/\/e326.greatsolution.dev\/de\/category\/mag1612\/\" rel=\"category tag\">MAG 16-12<\/a>","author_info_v2":{"name":"E-3 Magazin","url":"https:\/\/e326.greatsolution.dev\/de\/author\/e-3-magazin\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/posts\/1856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/comments?post=1856"}],"version-history":[{"count":0,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/posts\/1856\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/media\/4944"}],"wp:attachment":[{"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/media?parent=1856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/categories?post=1856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/tags?post=1856"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/coauthors?post=1856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}