{"id":60885,"date":"2016-05-02T10:31:49","date_gmt":"2016-05-02T08:31:49","guid":{"rendered":"https:\/\/e326.greatsolution.dev\/?p=60885"},"modified":"2019-07-11T10:35:29","modified_gmt":"2019-07-11T08:35:29","slug":"social-media-recruiting-active-sourcing-und-co","status":"publish","type":"post","link":"https:\/\/e326.greatsolution.dev\/de\/social-media-recruiting-active-sourcing-und-co\/","title":{"rendered":"Social Media Recruiting, Active Sourcing und Co"},"content":{"rendered":"<p>\u00dcber 4500 Gesch\u00e4ftsf\u00fchrer, HR-Entscheider, Personalentwickler und Gesundheitsbeauftragte nutzten in diesem Jahr die Personal Swiss, Fachmesse f\u00fcr HRM, Recruiting Solutions, Trainings to Business und Corporate Health in der Messe Z\u00fcrich, um sich zu informieren, um sich weiterzubilden und auszutauschen.<\/p>\n<p>Hinzu kamen die fast 850 Besucher der angeschlossenen Workplace Strategy Expo, die innovative L\u00f6sungen und Konzepte f\u00fcr die Entwicklung moderner B\u00fcros und Headquarter auf dem Programm hatte.<\/p>\n<p><em>\u201eDie Personal Swiss: ein Muss f\u00fcr alle HR-Verantwortlichen, die ihr Unternehmen auch in Zukunft auf dem richtigen Weg halten m\u00f6chten\u201c<\/em><\/p>\n<p>res\u00fcmiert die Projektleiterin der Personal Swiss, Kamila Slowacka, und f\u00fcgt hinzu:<\/p>\n<p><em>\u201eWir haben auch in diesem Jahr wieder die T\u00fcr aufgesto\u00dfen und unseren Besuchern den Blick auf die Entwicklungen der Zukunft geboten!\u201c<\/em><\/p>\n<p>Der Messeveranstalter B\u00f8rding Exposition plant im kommenden Jahr, die Themenbereiche Rekrutierung und Employer Branding an der TalentPro, Fachmesse f\u00fcr Recruiting Solutions und Employer Branding, in der Halle 3 der Messe Z\u00fcrich zu b\u00fcndeln.<\/p>\n<p><em>\u201eSo erhalten wir in den Hallen 5 und 6 den n\u00f6tigen Platz, den wir f\u00fcr das weitere Wachstum in den Bereichen HR-Software, Talentmanagement, Trainings to Business und Corporate Health ben\u00f6tigen. Und wir k\u00f6nnen die Messe strukturierter ausbauen\u201c<\/em><\/p>\n<p>f\u00fcgt B\u00f8rding-Gesch\u00e4ftsf\u00fchrer Alexander R. Petsch hinzu.<\/p>\n<p><em>\u201eAu\u00dferdem unterstreichen wir mit der eigenen Messe f\u00fcr die Recruiting-Themen die wachsende Bedeutung, die richtigen Talente f\u00fcr die eigene Organisation zu gewinnen.\u201c<\/em><\/p>\n<p>Die TalentPro richte sich auch an Firmen, die international t\u00e4tig sind, sowie Fachbesucher aus anderen L\u00e4ndern, die die neuesten Trends und Technologien im Recruiting suchen.<\/p>\n<p><em>\u201eEin Vortragsstrang der Messe wird ausschlie\u00dflich Vortr\u00e4ge in Englisch auf dem Programm haben.\u201c<\/em><\/p>\n<p>Gro\u00dfen Besucherandrang und teilweise nur noch Stehpl\u00e4tze gab es bei den Keynote-Speakern, die etwa ihre Visionen zur Arbeitswelt 4.0, zur F\u00fchrungskr\u00e4fteentwicklung, zum Social Learning uns zum betrieblichen Gesundheitsmanagement teilten.<\/p>\n<p>Technologie als Enabler<\/p>\n<p>Keynote-Speakerin Petra Jenner, ehemalige CEO von Microsoft Switzerland, gab zu bedenken:<\/p>\n<p><em>\u201eIch finde, dass das Thema Digitalisierung bzw. Arbeit 4.0 viel zu sehr von der technologischen Seite diskutiert wird.\u201c<\/em><\/p>\n<p>Die Technologie sei zwar letztendlich der \u201eEnabler\u201c f\u00fcr viele ver\u00e4nderte Arbeitsprozesse und Arbeitsstrukturen.<\/p>\n<p><em>\u201eAber die wirkliche Innovation ist, dass die Wertsch\u00f6pfungskette, der Wertbeitrag verschiedener Gesch\u00e4ftsbereiche sich ver\u00e4ndert: Es gibt bestimmte Gesch\u00e4ftsbereiche, die auf einmal mit ganz anderen Branchen zusammenarbeiten werden.\u201c<\/em><\/p>\n<h3>Ausblick 2017<\/h3>\n<p>Im n\u00e4chsten Jahr findet der HR-Gipfel am 4. und 5. April wie gewohnt in der Messe Z\u00fcrich in den Hallen 5 und 6 statt. Auch die international ausgerichtete Workplace Strategy Expo ist wieder am Start.<\/p>\n<p>Den Themen Recruiting und Employer Branding widmet der Messeveranstalter in der Halle 3 mit der TalentPro einen eigenen Bereich. Als weiteres neues Messe-Event h\u00e4lt am 5. und 6. April 2017 die IT-expo.ch, Fachmesse f\u00fcr Business Software, Security &amp; Document Solutions, Einzug in die Messe Z\u00fcrich.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wie viel Gespr\u00e4chs- und Diskussionsbedarf zu Social Media Recruiting, Active Sourcing und Co in der HR-Branche herrscht, zeigten die vielen Programmbeitr\u00e4ge in den Praxisforen der Personal Swiss.<\/p>\n","protected":false},"author":38,"featured_media":60767,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[13318],"tags":[1104],"coauthors":[19920],"class_list":["post-60885","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coverstory-1605","tag-hr","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016.jpg",1000,387,false],"thumbnail":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016-150x150.jpg",150,150,true],"medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016.jpg",400,155,false],"medium_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016-768x297.jpg",768,297,true],"large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016.jpg",1000,387,false],"image-100":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016-100x39.jpg",100,39,true],"image-480":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016-480x186.jpg",480,186,true],"image-640":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016-640x248.jpg",640,248,true],"image-720":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016-720x279.jpg",720,279,true],"image-960":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016-960x372.jpg",960,372,true],"image-1168":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016.jpg",1000,387,false],"image-1440":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016.jpg",1000,387,false],"image-1920":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016.jpg",1000,387,false],"1536x1536":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016.jpg",1000,387,false],"2048x2048":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016.jpg",1000,387,false],"trp-custom-language-flag":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016.jpg",18,7,false],"bricks_large_16x9":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016.jpg",1000,387,false],"bricks_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016.jpg",1000,387,false],"bricks_large_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016.jpg",1000,387,false],"bricks_medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016.jpg",600,232,false],"bricks_medium_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016.jpg",600,232,false],"profile_24":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016-24x24.jpg",24,24,true],"profile_48":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016-48x48.jpg",48,48,true],"profile_96":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016-96x96.jpg",96,96,true],"profile_150":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016-150x150.jpg",150,150,true],"profile_300":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Wie viel Gespr\u00e4chs- und Diskussionsbedarf zu Social Media Recruiting, Active Sourcing und Co in der HR-Branche herrscht, zeigten die vielen Programmbeitr\u00e4ge in den Praxisforen der Personal Swiss.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e326.greatsolution.dev\/de\/category\/coverstorys\/coverstory-1605\/\" rel=\"category tag\">Coverstory 16-05<\/a>","author_info_v2":{"name":"E-3 Magazin","url":"https:\/\/e326.greatsolution.dev\/de\/author\/e-3-magazin\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/posts\/60885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/comments?post=60885"}],"version-history":[{"count":0,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/posts\/60885\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/media\/60767"}],"wp:attachment":[{"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/media?parent=60885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/categories?post=60885"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/tags?post=60885"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/coauthors?post=60885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}