{"id":65760,"date":"2020-04-09T08:00:34","date_gmt":"2020-04-09T06:00:34","guid":{"rendered":"https:\/\/e326.greatsolution.dev\/?p=65760"},"modified":"2020-03-30T10:56:56","modified_gmt":"2020-03-30T08:56:56","slug":"ich-will-eine-pizza-mit-doenerfleisch","status":"publish","type":"post","link":"https:\/\/e326.greatsolution.dev\/de\/ich-will-eine-pizza-mit-doenerfleisch\/","title":{"rendered":"Ich will eine Pizza mit D\u00f6nerfleisch"},"content":{"rendered":"\r\n<p>Das Wirtschaftsmagazin \u201ebrand eins\u201c widmet seine diesj\u00e4hrige Februar-Ausgabe dem Schwerpunkt \u201eKommunikation\u201c. Und brand-eins-Starautor Wolf Lotter schreibt: <em>\u201eKommunikation bedeutet: miteinander reden \u2013 nicht gegeneinander.\u201c<\/em> In seinem Leitartikel hat Lotter noch viele gute und richtige S\u00e4tze, die man alle gro\u00df an Hausw\u00e4nde projizieren sollte.<\/p>\r\n\r\n\r\n\r\n<p>Seit Jennifer Morgan und Christian Klein an der Spitze von SAP stehen, h\u00f6rt man als Bestandskunde oft die S\u00e4tze <em>\u201eWir m\u00fcssen auf unsere Kunden h\u00f6ren\u201c<\/em> und <em>\u201eDie W\u00fcnsche der Kunden sind wichtig und zu respektieren\u201c<\/em>. Die Presse ist voll des Lobes f\u00fcr SAP, endlich h\u00f6rt der ERP-Konzern auf seine Kunden!<\/p>\r\n\r\n\r\n\r\n<p>Als Betroffener, als Bestandskunde, stellt sich die Situation aber anders dar: Sollen nun die Bestandskunden die Arbeit der SAP machen? Forschen, verifizieren und nachdenken, was sinnvoll und notwendig ist? Die SAP-Bestandskunden bezahlen SAP f\u00fcr \u201eAntworten\u201c und nicht f\u00fcr \u201eFragen\u201c \u2013 nach dem Motto: W\u00fcnsch dir was.<\/p>\r\n\r\n\r\n\r\n<p>Es erscheint kontraproduktiv, sich mit einer un\u00fcbersichtlichen Preisliste (PKL) und zahlreichen sich widersprechenden und an- sowie abgek\u00fcndigten Produkten vor dem Bestandskunden zu positionieren und nun von diesem zu fordern, Ordnung in das Chaos zu bringen und endlich zu artikulieren, was der ERP-Anwender denn wirklich wolle.<\/p>\r\n\r\n\r\n\r\n<p>Wenn der Erfinder von standardisierten Gesch\u00e4ftsprozessen nicht mehr wei\u00df, was notwendig und sinnvoll ist, woher soll es dann der Bestandskunde wissen? Umgekehrt k\u00f6nnte der Anwender zu SAP gehen und fragen: Was soll ich produzieren? Was soll ich verkaufen?<\/p>\r\n\r\n\r\n\r\n<p>In einem Sterne-Restaurant will ich vom Chefkoch nicht h\u00f6ren: Was soll ich kochen? Ganz im Gegenteil! Ich nehme das Tagesmen\u00fc und den Hauswein, weil ich mich auf die Kompetenz des Restaurants verlasse.<\/p>\r\n\r\n\r\n\r\n<p>Ich habe ja bewusst diesen Ort gew\u00e4hlt, weil ich von der Qualit\u00e4t der K\u00fcche und des Kellners \u00fcberzeugt bin. \u00c4hnlich ergeht es den meisten SAP-Bestandskunden:<\/p>\r\n\r\n\r\n\r\n<p>Diese haben SAP nicht gew\u00e4hlt aufgrund des Logos, der Programmiersprache Abap oder der Liebe zu Cloud, sondern aufgrund der betriebswirtschaftlichen Expertise, der standardisierten Gesch\u00e4ftsprozesse sowie der ganzheitlichen Probleml\u00f6sungskompetenz.<\/p>\r\n\r\n\r\n\r\n<p>SAP muss auf seine Kunden h\u00f6ren: <em>\u201eIch will eine Pizza mit D\u00f6nerfleisch.\u201c<\/em> Und SAP muss qualifizierte Antworten geben:<em> \u201eNein, willst du nicht.\u201c<\/em> SAP ist der Community nicht eine ausufernde PKL, sondern verifizierte Digitalisierung schuldig. SAP muss liefern: Strate\u00adgien, Umsetzung, Klarheit und Planbarkeit.<\/p>\r\n\r\n\r\n\r\n<p><em>\u201eAufrichtig miteinander reden bedeutet echte Neugier statt des Versuchs, den anderen von der eigenen Position zu \u00fcberzeugen. Aufrichtig hei\u00dft auch, dass man wirklich wissen will, warum die anderen so ticken, wie man es selbst nicht tut\u201c<\/em><\/p>\r\n\r\n\r\n\r\n<p>schreibt Wolf Lotter auf Seite 41 der \u201ebrand eins\u201c-Ausgabe Februar 2020.<\/p>\r\n\r\n\r\n\r\n<p>Wolf Lotter schreibt das mit leichter Feder. In der SAP\u2019schen Realit\u00e4t wird es schwierig zum Umsetzen sein. Aber es kann gelingen. Die jungen Co-CEOs, Jennifer Morgan und Christian Klein, haben die Gene daf\u00fcr. Es bleibt eine Gratwanderung zwischen Strategie, Erwartungshaltung, PKL, Roadmaps und Vertrauen.<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Antwort: Nein, willst du nicht. Forderung und Antwort in der Form eines imagin\u00e4ren Tweets sind auf dem Cover des Wirtschaftsmagazins \u201ebrand eins\u201c vom Februar dieses Jahres zu finden. Besser k\u00f6nnte man das SAP-Desaster \u201eWir m\u00fcssen auf unsere Kunden h\u00f6ren\u201c nicht ausdr\u00fccken.<\/p>\n","protected":false},"author":38,"featured_media":4147,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[7,9,37393],"tags":[73,7656,236],"coauthors":[19920],"class_list":["post-65760","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-meinung","category-hausmitteilung","category-mag-2003","tag-erp","tag-pkl","tag-sap","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1.jpg",1000,431,false],"thumbnail":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1-150x150.jpg",150,150,true],"medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1.jpg",400,172,false],"medium_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1-768x331.jpg",768,331,true],"large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1.jpg",1000,431,false],"image-100":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1-100x43.jpg",100,43,true],"image-480":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1-480x207.jpg",480,207,true],"image-640":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1-640x276.jpg",640,276,true],"image-720":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1-720x310.jpg",720,310,true],"image-960":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1-960x414.jpg",960,414,true],"image-1168":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1.jpg",1000,431,false],"image-1440":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1.jpg",1000,431,false],"image-1920":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1.jpg",1000,431,false],"1536x1536":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1.jpg",1000,431,false],"2048x2048":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1.jpg",1000,431,false],"trp-custom-language-flag":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1.jpg",1000,431,false],"bricks_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1.jpg",1000,431,false],"bricks_large_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1.jpg",1000,431,false],"bricks_medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1.jpg",600,259,false],"bricks_medium_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1.jpg",600,259,false],"profile_24":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1-24x24.jpg",24,24,true],"profile_48":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1-48x48.jpg",48,48,true],"profile_96":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1-96x96.jpg",96,96,true],"profile_150":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1-150x150.jpg",150,150,true],"profile_300":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Antwort: Nein, willst du nicht. Forderung und Antwort in der Form eines imagin\u00e4ren Tweets sind auf dem Cover des Wirtschaftsmagazins \u201ebrand eins\u201c vom Februar dieses Jahres zu finden. Besser k\u00f6nnte man das SAP-Desaster \u201eWir m\u00fcssen auf unsere Kunden h\u00f6ren\u201c nicht ausdr\u00fccken.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e326.greatsolution.dev\/de\/category\/meinung\/\" rel=\"category tag\">Die Meinung der SAP-Community<\/a>, <a href=\"https:\/\/e326.greatsolution.dev\/de\/category\/meinung\/hausmitteilung\/\" rel=\"category tag\">Hausmitteilung<\/a>, <a href=\"https:\/\/e326.greatsolution.dev\/de\/category\/mag-2003\/\" rel=\"category tag\">MAG 20-03<\/a>","author_info_v2":{"name":"E-3 Magazin","url":"https:\/\/e326.greatsolution.dev\/de\/author\/e-3-magazin\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/posts\/65760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/comments?post=65760"}],"version-history":[{"count":0,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/posts\/65760\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/media\/4147"}],"wp:attachment":[{"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/media?parent=65760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/categories?post=65760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/tags?post=65760"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/coauthors?post=65760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}