{"id":69199,"date":"2020-10-01T12:00:00","date_gmt":"2020-10-01T10:00:00","guid":{"rendered":"https:\/\/e326.greatsolution.dev\/?p=69199"},"modified":"2020-09-28T09:56:51","modified_gmt":"2020-09-28T07:56:51","slug":"nicht-zuhoeren-sondern-handeln","status":"publish","type":"post","link":"https:\/\/e326.greatsolution.dev\/de\/nicht-zuhoeren-sondern-handeln\/","title":{"rendered":"Nicht zuh\u00f6ren, sondern handeln"},"content":{"rendered":"\n<p>Ich denke nicht, dass irgendein SAP-Bestandskunde dem CEO Christian Klein ins Ohr gefl\u00fcstert hat, bringe Qualtrics an die B\u00f6rse, um etwas Schadensbegrenzung zu erlangen. Qualtrics ist ein Desaster f\u00fcr die SAP, die Partner und allen voran die Bestandskunden, die mit den hohen Cloud- und On-premises-Lizenzgeb\u00fchren den Totalschaden finanzieren m\u00fcssen. <\/p>\n\n\n\n<p>Wahrscheinlich war es die kalkulierende Um- und Weitsicht von Finanzvorstand Luka Mucic. Er hat schon eine Excel-Tabelle, die den B\u00f6rsengewinn und Deckungsbeitrag gegen den weit \u00fcberzogenen Kaufpreis aufrechnet. Seit vielen Jahren ist Mucic mit seinem Sinn f\u00fcr die Geldvermehrung der SAP-Felsen in der IT-Brandung. Mag Hana sexy sein und S\/4 innovativ, der SAP-Finanzvorstand ist solide, weitdenkend und hat eine sehr geschickte Hand f\u00fcrs liebe Geld.<\/p>\n\n\n\n<p>In einem aktuellen SAP-Community-Call bezeichnete Vorstand Thomas Saueressig die Funktionen der Qualtrics-Software als wichtigen Bestandteil seiner Anwendungsentwicklung. Auch zuk\u00fcnftig soll nach Meinung von Saueressig diese zugekaufte Cloud-Software die anderen Komponenten des SAP-Universums erg\u00e4nzen und dadurch ein integrierter Teil in den End-to-End-Prozessen sein. Unabh\u00e4ngig davon ist das Vorhaben, Qualtrics als selbstst\u00e4ndiges und b\u00f6rsennotiertes Unternehmen in den USA zu positionieren.<\/p>\n\n\n\n<p>Experten sprechen von Schadensminimierung: Urspr\u00fcngliche Sch\u00e4tzungen billigten Qualtrics bei einem m\u00f6glichen B\u00f6rsengang einen Marktwert von vier bis f\u00fcnf Milliarden US-Dollar zu. SAP kaufte Qualtrics f\u00fcr etwa acht Milliarden US-Dollar. Aus Sicht von SAP ist es verst\u00e4ndlich, dass nach der gescheiterten Integration und vereitelter Konsolidierung in das SAP-One-Domain-Modell zumindest die finanzielle Situation verbessert werden muss. Ein offensichtlicher B\u00f6rsengang von Qualtrics k\u00f6nnte SAP ein paar Milliarden US-Dollar als Wiedergutmachung bescheren.<\/p>\n\n\n\n<p>In dem Community-Call wurde SAP-Vorstand Thomas Saueressig auch gefragt, ob es noch eine Chance g\u00e4be, Qualtrics auf die Hana-Datenbank zu bringen und somit eine Integration und Konsolidierung auf dieser Plattform zu erzielen. Trotz Wiederholung durch den Moderator \u00fcberging Saueressig diese offensichtlich f\u00fcr SAP peinliche Frage.<\/p>\n\n\n\n<p>Hintergrund: Die meisten anderen Cloud-Zuk\u00e4ufe haben nach vielen Jahren der Unsicherheit mittlerweile den Weg auf die Hana-Plattform gefunden. SAP-CEO Christian Klein hat vor einem Jahr vermutet, dass Qualtrics sich nicht auf Hana bringen l\u00e4sst \u2013 und er hat recht behalten. Daf\u00fcr betonte Thomas Saueressig mehrfach im SAP-Community-Call: <em>\u201eQualtrics ist Teil der SAP-Familie.\u201c<\/em><\/p>\n\n\n\n<p>Tricksen ist erlaubt, aber bitte auf intelligente Art! Sich gem\u00fctlich im Chefsessel zur\u00fccklehnen und auf Zurufe der SAP-Community warten, ist letztendlich zu billig. Es ist erb\u00e4rmlich, wenn der SAP-Chef und seine Vorstandskollegen den Bestandskunden und Partnern zuh\u00f6ren m\u00fcssen, um zu erfahren, wo die Bits und Bytes in Unordnung sind, wo die Integration scheitert und welche Bereiche besser weiterverkauft werden, siehe auch SDI (SAP Digital Interconnect, eine ehemalige Sybase-Abteilung, die SAP 2010 aufkaufte).<\/p>\n\n\n\n<p>Christian Klein, Thomas Saueressig und J\u00fcrgen M\u00fcller haben zahlreiche Experten und Top-Executives um sich geschart, die ihnen jederzeit und sehr pr\u00e4zise sagen sollten, wo die Baustellen sich befinden. In einem Akt gespielter Gro\u00dfz\u00fcgigkeit nun die SAP-Bestandskunden in Geiselhaft zu nehmen und von diesen zu verlangen, die Strategie zu definieren, ist perfide! Nicht sich zur\u00fccklehnen und passiv den Ausf\u00fchrungen einzelner Bestandskunden und Partner lauschen, sondern aktiv reparieren, instand setzen und erforschen, was der IT-Markt und die SAP-Community brauchen. Der SAP-Vorstand muss aus seiner passiven Lethargie in ein aktives Wollen kommen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Was will SAP-Chef Christian Klein von seinen Kunden h\u00f6ren, was er im tiefsten Herzen nicht schon wei\u00df? Es ist ein rhetorischer Trick, wenn Klein sagt, jetzt h\u00f6ren wir auf unsere Bestandskunden.<\/p>\n","protected":false},"author":2,"featured_media":4146,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[7,8,38075],"tags":[243,27907,236],"coauthors":[27825],"class_list":["post-69199","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-meinung","category-editorial","category-mag-2009","tag-boerse","tag-qualtrics","tag-sap","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479.jpg",1000,400,false],"thumbnail":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479-150x150.jpg",150,150,true],"medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479-400x160.jpg",400,160,true],"medium_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479-768x307.jpg",768,307,true],"large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479.jpg",1000,400,false],"image-100":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479-100x40.jpg",100,40,true],"image-480":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479-480x192.jpg",480,192,true],"image-640":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479-640x256.jpg",640,256,true],"image-720":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479-720x288.jpg",720,288,true],"image-960":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479-960x384.jpg",960,384,true],"image-1168":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479.jpg",1000,400,false],"image-1440":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479.jpg",1000,400,false],"image-1920":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479.jpg",1000,400,false],"1536x1536":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479.jpg",1000,400,false],"2048x2048":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479.jpg",1000,400,false],"trp-custom-language-flag":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479-18x7.jpg",18,7,true],"bricks_large_16x9":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479.jpg",1000,400,false],"bricks_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479.jpg",1000,400,false],"bricks_large_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479.jpg",1000,400,false],"bricks_medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479-600x240.jpg",600,240,true],"bricks_medium_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479-600x400.jpg",600,400,true],"profile_24":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479-24x24.jpg",24,24,true],"profile_48":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479-48x48.jpg",48,48,true],"profile_96":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479-96x96.jpg",96,96,true],"profile_150":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479-150x150.jpg",150,150,true],"profile_300":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Was will SAP-Chef Christian Klein von seinen Kunden h\u00f6ren, was er im tiefsten Herzen nicht schon wei\u00df? Es ist ein rhetorischer Trick, wenn Klein sagt, jetzt h\u00f6ren wir auf unsere Bestandskunden.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e326.greatsolution.dev\/de\/category\/meinung\/\" rel=\"category tag\">Die Meinung der SAP-Community<\/a>, <a href=\"https:\/\/e326.greatsolution.dev\/de\/category\/meinung\/editorial\/\" rel=\"category tag\">Editorial<\/a>, <a href=\"https:\/\/e326.greatsolution.dev\/de\/category\/mag-2009\/\" rel=\"category tag\">MAG 20-09<\/a>","author_info_v2":{"name":"Peter M. F\u00e4rbinger, E3-Magazin","url":"https:\/\/e326.greatsolution.dev\/de\/author\/peter-m-faerbinger-e-3-magazin\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/posts\/69199","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/comments?post=69199"}],"version-history":[{"count":0,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/posts\/69199\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/media\/4146"}],"wp:attachment":[{"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/media?parent=69199"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/categories?post=69199"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/tags?post=69199"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/coauthors?post=69199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}