{"id":70645,"date":"2021-02-04T08:00:00","date_gmt":"2021-02-04T07:00:00","guid":{"rendered":"https:\/\/e326.greatsolution.dev\/?p=70645"},"modified":"2021-02-01T10:33:52","modified_gmt":"2021-02-01T09:33:52","slug":"never-change-a-running-system","status":"publish","type":"post","link":"https:\/\/e326.greatsolution.dev\/de\/never-change-a-running-system\/","title":{"rendered":"Never change a running system"},"content":{"rendered":"\n<p>Die SAP-ERP-Version S\/4 wurde am 3. Februar 2015 an der New Yorker B\u00f6rse vom damaligen Chef Bill McDermott, dem Ex-CTO Bernd Leukert sowie von Professor Hasso Plattner pr\u00e4sentiert. Mehr als f\u00fcnf Jahre sp\u00e4ter haben etwa 15.100 SAP-Kunden eine S\/4-Hana-Lizenz erworben, davon haben aber nur 8100 Kunden ein lauff\u00e4higes und produktives S\/4-System. Diese Transformation innerhalb von f\u00fcnf Jahren f\u00fcr einen anstehenden ERP-Versionswechsel ist besorgniserregend.<\/p>\n\n\n\n<p>In einer Presseaussendung schreibt der Verein DSAG: Der Wechsel an sich ist f\u00fcr viele Unternehmen ein erheblicher Kraftakt, der mit einer Reihe weiterer Ver\u00e4nderungen einhergeht.<\/p>\n\n\n\n<p><em>\u201eDenn\u201c<\/em>, so der DSAG-Technologievorstand Steffen Pietsch, \u201e<em>eine S\/4-Hana-Migration ist kein minimalinvasiver Eingriff, sondern ein umfangreiches Change-Projekt auf prozessualer, organisatorischer und technischer Ebene.\u201c <\/em><\/p>\n\n\n\n<p>Ver\u00e4nderungen betreffen vielfach nicht nur das ERP-System selbst, sondern f\u00fchren auch zu Anpassungen in integrierten Umsystemen oder der Einf\u00fchrung neuer Softwarel\u00f6sungen.<\/p>\n\n\n\n<p>Wer sich noch nicht mit hybrider oder cloudbasierter Software und deren Integration in eine SAP-Landschaft befasst hat, steht vor gro\u00dfen Herausforderungen. Letztendlich ist es dann ein technischer Versionswechsel ohne Gesch\u00e4ftsprozessvorteile. Es ist mehr als verst\u00e4ndlich, dass nur die H\u00e4lfte der stolzen S\/4-Lizenzbesitzer auch ein Customizing wagte: never change a running system.<\/p>\n\n\n\n<p>Technisch und organisatorisch hat SAP-Chef Christian Klein fast alles richtig gemacht. Transformationsprozesse brauchen aber Zeit. Die Wahrscheinlichkeit einer weiteren Wartungsverl\u00e4ngerung \u00fcber 2030 hinaus ist demnach hoch, weil eine S\/4-Migration keinen minimalinvasiven Eingriff, sondern ein umfangreiches Change-Projekt darstellt.<\/p>\n\n\n\n<p>SAP-Aufsichtsrat, Vorstand und die Partner-Community zeigen mit Hana und S\/4 eine bl\u00fchende Zukunft. Sie vergessen aber, die Gr\u00fcnde zu nennen, warum der SAP-Bestandskunde seine existierende Business Suite 7 mit AnyDB verschrotten soll. Das Neue m\u00f6ge besser sein, das Alte ist aber auch nicht schlecht, oder?<\/p>\n\n\n\n<p>Es gibt in der SAP-Community viele Proofs of Concept bez\u00fcglich Hana und S\/4, aber wenig Vertrauen in einen nachhaltigen Mehrwert. Eine DSAG-Umfrage zeigt, dass viele SAP-Bestandskunden auf dem Weg in Richtung Hana und S\/4 sind, aber SAP weigert sich, Antworten betreffend Transformation zu geben und vertrauensbildende Ma\u00dfnahmen zu setzen: <\/p>\n\n\n\n<p>Wie geht es nach 2025 mit AnyDB in Richtung Hana und sp\u00e4ter auf S\/4 weiter? Die Beantwortung dieser Frage wurde Anfang dieses Jahres auf den DSAG-Technologietagen von SAP-Vorstand J\u00fcrgen M\u00fcller angek\u00fcndigt. Bis heute gibt es keine SAP-Antworten.<\/p>\n\n\n\n<p>Der DSAG-Technologievorstand Steffen Pietsch fordert von SAP passende L\u00f6sungen und Hilfestellungen wie eine klare Einordnung zur Informationssicherheit und DSGVO-konformen Verarbeitung personenbezogener Daten, geeignete Qualifizierungsprogramme, mehr Planungssicherheit bez\u00fcglich erforderlicher Komponenten und Lizenzen f\u00fcr hybride Szenarien sowie Integrationsf\u00e4higkeit als Kernforderung. Dies ist eine wesentliche Voraussetzung, um den Weg zu S\/4 und in eine hybride Zukunft zu meistern. <\/p>\n\n\n\n<p><em>\u201eSAP ist auf einem guten Weg und hat auch bereits wichtige Meilensteine erreicht, aber es sind noch einige H\u00fcrden zu nehmen\u201c<\/em>, so Pietsch.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Was tun mit der neuen ERP-Generation S\/4? Selbst der Anwenderverein DSAG warnt vor einem Schnellschuss, denn der Wechsel ist ein Kraftakt. Und 8100 produktive S\/4-Systeme nach f\u00fcnf Jahren sind nicht ermutigend.<\/p>\n","protected":false},"author":2,"featured_media":4147,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[7,9,38469],"tags":[273,73,28334,1632],"coauthors":[27825],"class_list":["post-70645","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-meinung","category-hausmitteilung","category-mag-20-12","tag-dsag","tag-erp","tag-faerbinger","tag-hausmitteilung","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1.jpg",1000,431,false],"thumbnail":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1-150x150.jpg",150,150,true],"medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1.jpg",400,172,false],"medium_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1-768x331.jpg",768,331,true],"large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1.jpg",1000,431,false],"image-100":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1-100x43.jpg",100,43,true],"image-480":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1-480x207.jpg",480,207,true],"image-640":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1-640x276.jpg",640,276,true],"image-720":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1-720x310.jpg",720,310,true],"image-960":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1-960x414.jpg",960,414,true],"image-1168":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1.jpg",1000,431,false],"image-1440":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1.jpg",1000,431,false],"image-1920":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1.jpg",1000,431,false],"1536x1536":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1.jpg",1000,431,false],"2048x2048":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1.jpg",1000,431,false],"trp-custom-language-flag":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1.jpg",1000,431,false],"bricks_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1.jpg",1000,431,false],"bricks_large_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1.jpg",1000,431,false],"bricks_medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1.jpg",600,259,false],"bricks_medium_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1.jpg",600,259,false],"profile_24":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1-24x24.jpg",24,24,true],"profile_48":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1-48x48.jpg",48,48,true],"profile_96":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1-96x96.jpg",96,96,true],"profile_150":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1-150x150.jpg",150,150,true],"profile_300":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Hausmitteilung-1-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Was tun mit der neuen ERP-Generation S\/4? Selbst der Anwenderverein DSAG warnt vor einem Schnellschuss, denn der Wechsel ist ein Kraftakt. Und 8100 produktive S\/4-Systeme nach f\u00fcnf Jahren sind nicht ermutigend.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e326.greatsolution.dev\/de\/category\/meinung\/\" rel=\"category tag\">Die Meinung der SAP-Community<\/a>, <a href=\"https:\/\/e326.greatsolution.dev\/de\/category\/meinung\/hausmitteilung\/\" rel=\"category tag\">Hausmitteilung<\/a>, <a href=\"https:\/\/e326.greatsolution.dev\/de\/category\/mag-20-12\/\" rel=\"category tag\">MAG 20-12<\/a>","author_info_v2":{"name":"Peter M. F\u00e4rbinger, E3-Magazin","url":"https:\/\/e326.greatsolution.dev\/de\/author\/peter-m-faerbinger-e-3-magazin\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/posts\/70645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/comments?post=70645"}],"version-history":[{"count":0,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/posts\/70645\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/media\/4147"}],"wp:attachment":[{"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/media?parent=70645"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/categories?post=70645"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/tags?post=70645"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/coauthors?post=70645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}