{"id":70875,"date":"2021-02-11T08:00:00","date_gmt":"2021-02-11T07:00:00","guid":{"rendered":"https:\/\/e326.greatsolution.dev\/?p=70875"},"modified":"2021-02-08T11:39:37","modified_gmt":"2021-02-08T10:39:37","slug":"mit-open-source-in-der-krise-effektiv-zusammenarbeiten","status":"publish","type":"post","link":"https:\/\/e326.greatsolution.dev\/de\/mit-open-source-in-der-krise-effektiv-zusammenarbeiten\/","title":{"rendered":"Mit Open Source in der Krise effektiv zusammenarbeiten"},"content":{"rendered":"\n<p>Corona macht es \u00fcberdeutlich: Die Skalierung etablierter Prozesse und Organisationsstrukturen und der Wechsel zur Zusammenarbeit an verschiedenen Standorten stellen Akteure in den verschiedensten Branchen vor erhebliche Heraus\u00adforderungen. Beh\u00f6rden wie Unternehmen m\u00fcssen Wege finden, wie ihre Teams jenseits des B\u00fcros effizient auf Informationen zugreifen, miteinander kommunizieren und gemeinsam Aufgaben bearbeiten k\u00f6nnen. Ihre IT-Abteilungen m\u00fcssen durch den Wechsel ins Homeoffice einen sprunghaften Anstieg der zu verwaltenden Ger\u00e4te sowie verzeichneten Sicherheitsvorf\u00e4lle bew\u00e4ltigen.<\/p>\n\n\n\n<p>Markantes Beispiel f\u00fcr die Schwierigkeiten, die entstehen k\u00f6nnen, wenn Prozesse skaliert und in verteilte Umgebungen \u00fcbertragen werden: das sommerliche Testdebakel an Grenzen und Flugh\u00e4fen. In Windeseile wurden die behelfsm\u00e4\u00dfigen Teststationen aus dem Boden gestampft. Doch die zusammengestrickte Kombination aus analogen und digitalen Prozessen erwies sich als fehleranf\u00e4llig. Wichtige Testergebnisse wurden zu sp\u00e4t, nicht richtig oder \u00fcberhaupt nicht an die Betroffenen kommuniziert.<\/p>\n\n\n\n<p>Mit einem Open-Source-Ticketsystem wie Otobo w\u00e4ren diese Probleme vermeidbar gewesen. Das webbasierte System ist schnell eingef\u00fchrt: Es wird nur einmal an zentraler Stelle installiert. Dann greifen alle Beteiligten einfach via Browser darauf zu. Weil alle Informationen verschl\u00fcsselt \u00fcbertragen und nur auf dem zentralen Server gespeichert werden, k\u00f6nnen dazu sogar Privatger\u00e4te zum Einsatz kommen.<\/p>\n\n\n\n<p>Die Vorz\u00fcge zeigen sich \u00fcberall, wo verschiedene Personen gemeinsam Vorf\u00e4lle und Anfragen bearbeiten. Bei der Zusammenarbeit von Au\u00dfen- und Innendienst, der Betreuung von Mitarbeitern im Homeoffice durch den IT-Support, beim Informationsaustausch zwischen Krankenh\u00e4usern oder \u00c4rzten und Laboren etc.<\/p>\n\n\n\n<p>Die zentrale Vorgangsverwaltung stellt sicher, dass jede Anfrage nur einmal bearbeitet wird und alle Beteiligten immer auf dem aktuellen Stand sind. Textbausteine, Vorlagen und automatisierte Prozesse sparen Zeit. Benachrichtigungen und Eskalationen verhindern, dass F\u00e4lle \u00fcbersehen werden. Die zentrale Knowledgebase dient intern als Wissensspeicher und bietet extern in den FAQs direkte Antwort auf h\u00e4ufige Fragestellungen. <\/p>\n\n\n\n<p>\u00dcber Schnittstellen k\u00f6nnen Daten \u2013 auch automatisiert \u2013 mit anderen Systemen ausgetauscht werden. Mit Testlaboren beispielsweise oder dem Robert-Koch-Institut. Berichte und \u00dcbersichten vermitteln einen \u00dcberblick \u00fcber die Auslastung des Teams und erm\u00f6glichen, schnell einzugreifen und gegenzusteuern, wenn es zu Engp\u00e4ssen kommt.<\/p>\n\n\n\n<p>Speziell f\u00fcr IT-Abteilungen halten ITSM-f\u00e4hige Systeme einen weiteren Vorteil bereit: Alle zu verwaltenden Ger\u00e4te k\u00f6nnen in einer zentralen Datenbank (Configuration Management Database, CMDB) erfasst werden. Die bietet einen \u00dcberblick \u00fcber alle Assets, deren Status sowie Abh\u00e4ngigkeiten und Zugeh\u00f6rigkeiten. <\/p>\n\n\n\n<p>Bei Otobo ist sie eng mit den Servicedesk-Funktionen verwoben, sodass die Informationen direkt zur Bearbeitung von Supportanfragen zur Verf\u00fcgung stehen. OS-Ticketsysteme sind also vielerorts untersch\u00e4tzte Allzweckwaffen, deren Nutzen weit \u00fcber die klassischen Einsatzszenarien im IT-Support hinausgeht. In der aktuellen Lage wird das besonders deutlich.<\/p>\n\n\n\n<p>Lange scheuten sich Unternehmen, OS-Systeme in gr\u00f6\u00dferem Ma\u00dfstab einzusetzen. Sie wurden als Bastel- und Nischenl\u00f6sung wahrgenommen, deren Betrieb nur mit erheblicher Manpower gestemmt werden konnte. Doch es geht anders: mit einem OS-Ticketsystem, dessen Hersteller Business Services zur L\u00f6sung anbietet. <\/p>\n\n\n\n<p>Mit einem Partner, der sich um Einrichtung, Anpassung, Support und sogar um den Betrieb k\u00fcmmert, k\u00f6nnen Organisationen sicher sein, alle Vorteile auszusch\u00f6pfen, und bleiben dabei flexibel. Unterschiede gibt es nicht zuletzt beim Verst\u00e4ndnis dessen, was Open-Source-Software ausmacht. Deshalb lohnt ein genauer Blick auf Businessmodelle und Preisstrukturen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wie freie OS-Ticketsysteme Organisationen in der Krise dabei unterst\u00fctzen, ihre Prozesse sicher, effizient und nachverfolgbar zu gestalten, und Teams in die Lage versetzen, standortunabh\u00e4ngig produktiv zusammenzuarbeiten.<\/p>\n","protected":false},"author":2246,"featured_media":2685,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[7,38469,22],"tags":[506],"coauthors":[38593],"class_list":["post-70875","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-meinung","category-mag-20-12","category-open-source","tag-open-source","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source.jpg",1000,435,false],"thumbnail":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source-150x150.jpg",150,150,true],"medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source.jpg",400,174,false],"medium_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source-768x334.jpg",768,334,true],"large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source.jpg",1000,435,false],"image-100":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source-100x44.jpg",100,44,true],"image-480":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source-480x209.jpg",480,209,true],"image-640":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source-640x278.jpg",640,278,true],"image-720":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source-720x313.jpg",720,313,true],"image-960":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source-960x418.jpg",960,418,true],"image-1168":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source.jpg",1000,435,false],"image-1440":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source.jpg",1000,435,false],"image-1920":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source.jpg",1000,435,false],"1536x1536":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source.jpg",1000,435,false],"2048x2048":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source.jpg",1000,435,false],"trp-custom-language-flag":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source.jpg",1000,435,false],"bricks_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source.jpg",1000,435,false],"bricks_large_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source.jpg",1000,435,false],"bricks_medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source.jpg",600,261,false],"bricks_medium_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source.jpg",600,261,false],"profile_24":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source-24x24.jpg",24,24,true],"profile_48":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source-48x48.jpg",48,48,true],"profile_96":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source-96x96.jpg",96,96,true],"profile_150":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source-150x150.jpg",150,150,true],"profile_300":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Wie freie OS-Ticketsysteme Organisationen in der Krise dabei unterst\u00fctzen, ihre Prozesse sicher, effizient und nachverfolgbar zu gestalten, und Teams in die Lage versetzen, standortunabh\u00e4ngig produktiv zusammenzuarbeiten.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e326.greatsolution.dev\/de\/category\/meinung\/\" rel=\"category tag\">Die Meinung der SAP-Community<\/a>, <a href=\"https:\/\/e326.greatsolution.dev\/de\/category\/mag-20-12\/\" rel=\"category tag\">MAG 20-12<\/a>, <a href=\"https:\/\/e326.greatsolution.dev\/de\/category\/meinung\/open-source\/\" rel=\"category tag\">Open Source Kolumne<\/a>","author_info_v2":{"name":"Stefan Rother, Rother OSS","url":"https:\/\/e326.greatsolution.dev\/de\/author\/stefan-rother-rother-oss\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/posts\/70875","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/users\/2246"}],"replies":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/comments?post=70875"}],"version-history":[{"count":0,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/posts\/70875\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/media\/2685"}],"wp:attachment":[{"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/media?parent=70875"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/categories?post=70875"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/tags?post=70875"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/coauthors?post=70875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}