{"id":74031,"date":"2021-06-11T08:00:00","date_gmt":"2021-06-11T06:00:00","guid":{"rendered":"https:\/\/e326.greatsolution.dev\/?p=74031"},"modified":"2021-05-20T09:23:44","modified_gmt":"2021-05-20T07:23:44","slug":"zieht-der-deutsche-mittelstand-mit","status":"publish","type":"post","link":"https:\/\/e326.greatsolution.dev\/de\/zieht-der-deutsche-mittelstand-mit\/","title":{"rendered":"Zieht der deutsche Mittelstand mit?"},"content":{"rendered":"\n<p>So pr\u00e4sent die Begriffe \u201eDeep Learning\u201c, \u201eProcess Mining\u201c oder \u201eNatural Language Processing\u201c in der Arbeitswelt mittlerweile auch sein m\u00f6gen, der deutsche Mittelstand misst k\u00fcnstlicher Intelligenz (KI) keine besonders hohe strategische Relevanz zu. F\u00fcr ihre aktuelle Studie hat Deloitte \u00fcber 300 F\u00fchrungskr\u00e4fte mittelst\u00e4ndischer Unternehmen zu den Herausforderungen, Chancen und Risiken von KI im Mittelstand befragt. <\/p>\n\n\n\n<p>64 Prozent messen KI eine lediglich mittlere bis niedrige Relevanz f\u00fcr den Mittelstand als Ganzes bei. Auch in Bezug auf das eigene Gesch\u00e4ftsmodell sprechen ihr 58 Prozent eine niedrige Bedeutung zu. Werfen die Befragten den Blick in die Zukunft, \u00e4ndert sich das Meinungsbild: 59 Prozent sind davon \u00fcberzeugt, dass die Bedeutung von KI zunehmen wird.<\/p>\n\n\n\n<p>KI-Technologien stehen reihenweise bereit \u2013 doch welche haben f\u00fcr den Mittelstand die gr\u00f6\u00dfte Bedeutung? 45 Prozent der Befragten sehen regelbasierte Systeme in Sachen Relevanz an erster Stelle, gefolgt von Machine Learning (41 Prozent) und Deep Learning (36 Prozent). Diese Priorisierung deckt sich mit den Potenzialen, die sich die Unternehmen vom KI-Einsatz am ehesten versprechen, n\u00e4mlich die Automatisierung von Prozessen (77 Prozent), die effiziente Nutzung von Daten (72 Prozent) und die Beschleunigung von Prozessen (66 Prozessen). <\/p>\n\n\n\n<p>Lediglich 43 Prozent erhoffen sich von KI die Entwicklung neuer Gesch\u00e4ftsmodelle. Entsprechend gering f\u00e4llt mit 26 Prozent auch der Anteil der Unternehmen aus, die Anwendungen selbst entwickeln \u2013 34 Prozent der Befragten nutzen KI als Produkt, 30 Prozent als Service.<\/p>\n\n\n\n<p>Geht es um die idealen KI-Einsatzgebiete im Unternehmen, nennt eine Mehrheit von 65 Prozent den IT-Bereich als pr\u00e4destinierte Abteilung. Auch in der Logistik und in der Material- und Produktionswirtschaft machen die Teilnehmenden hohe Potenziale f\u00fcr den Gebrauch aus. <\/p>\n\n\n\n<p>\u00dcberraschend: Gerade solche Bereiche, in denen sich durch etablierte KI-Technologien vergleichsweise rasche und unkompliziert realisierbare Effizienzsteigerungen erzielen lassen \u2013 etwa im Controlling oder Rechnungswesen \u2013, stufen die meisten Befragten als deutlich weniger KI-geeignet ein. <\/p>\n\n\n\n<p>Die ambivalente Haltung des Mittelstands zu KI spiegelt sich auch in dessen Einsch\u00e4tzungen zu m\u00f6glichen Anwendungsrisiken wider: Ganze 47 Prozent der Unternehmen f\u00fcrchten falsche Rahmenbedingungen f\u00fcr deren Einsatz \u2013 wie etwa ungen\u00fcgende Datenqualit\u00e4t oder auch einfach fehlende Daten. 45 Prozent haben Bedenken, dass Aufwand und Ertrag nicht zusammenpassen. Weitere 44 Prozent sehen das Risiko intransparenter Entscheidungen oder Entscheidungswege.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">KI ist Chefsache<\/h3>\n\n\n\n<p>Wer hat im Unternehmen den KI-Hut auf? Bei knapp \u00fcber der H\u00e4lfte der Teilnehmenden ist die organisatorische Verantwortung derzeit bei Abteilungen unterhalb der Gesch\u00e4ftsleitung angesiedelt, beispielsweise bei der IT oder den operativen Bereichen, die KI direkt anwenden (jeweils 16 Prozent). Eine eigene KI-Abteilung kann nur ein Prozent der Befragten vorweisen. 48 Prozent hingegen verorten die Verantwortung bereits beim Topmanagement. <\/p>\n\n\n\n<p>Eine \u00e4hnliche Zweiteilung l\u00e4sst sich auch beim Thema Budget ablesen: Zwar betr\u00e4gt bei der gesamten Stichprobe der Median f\u00fcr KI-Investitionen rund 250.000 Euro pro Jahr. Allerdings investieren 41 Prozent sogar 500.000 Euro und mehr, w\u00e4hrend 48 Prozent der Unternehmen unterhalb des Medians bleiben. Bei elf Prozent liegt das KI-Finanzvolumen sogar bei unter 50.000 Euro j\u00e4hrlich. Immerhin: 38 Prozent der Befragten rechnen mit einem starken bzw. sehr starken Anstieg der KI-Budgets f\u00fcr die Zukunft.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der deutsche Mittelstand scheint KI-Technologien noch verhalten gegen\u00fcberzustehen \u2013 das zeigt die aktuelle Studie \u201eK\u00fcnstliche Intelligenz im Mittelstand\u201c.<\/p>\n","protected":false},"author":38,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[2,39280],"tags":[625,624,3442],"coauthors":[19920],"class_list":["post-74031","post","type-post","status-publish","format-standard","hentry","category-sap-nachrichten","category-mag-21-05","tag-ai","tag-ki","tag-mittelstand","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","image-100":"","image-480":"","image-640":"","image-720":"","image-960":"","image-1168":"","image-1440":"","image-1920":"","1536x1536":"","2048x2048":"","trp-custom-language-flag":"","bricks_large_16x9":"","bricks_large":"","bricks_large_square":"","bricks_medium":"","bricks_medium_square":"","profile_24":"","profile_48":"","profile_96":"","profile_150":"","profile_300":""},"post_excerpt_stackable_v2":"<p>Der deutsche Mittelstand scheint KI-Technologien noch verhalten gegen\u00fcberzustehen \u2013 das zeigt die aktuelle Studie \u201eK\u00fcnstliche Intelligenz im Mittelstand\u201c.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e326.greatsolution.dev\/de\/category\/sap-nachrichten\/\" rel=\"category tag\">Community Nachrichten<\/a>, <a href=\"https:\/\/e326.greatsolution.dev\/de\/category\/mag-21-05\/\" rel=\"category tag\">MAG 21-05<\/a>","author_info_v2":{"name":"E-3 Magazin","url":"https:\/\/e326.greatsolution.dev\/de\/author\/e-3-magazin\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/posts\/74031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/comments?post=74031"}],"version-history":[{"count":0,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/posts\/74031\/revisions"}],"wp:attachment":[{"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/media?parent=74031"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/categories?post=74031"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/tags?post=74031"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/coauthors?post=74031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}