{"id":92955,"date":"2021-08-31T08:00:00","date_gmt":"2021-08-31T06:00:00","guid":{"rendered":"https:\/\/e326.greatsolution.dev\/?p=92955"},"modified":"2021-08-06T10:42:03","modified_gmt":"2021-08-06T08:42:03","slug":"wichtiges-digitalisierungswerkzeug","status":"publish","type":"post","link":"https:\/\/e326.greatsolution.dev\/de\/wichtiges-digitalisierungswerkzeug\/","title":{"rendered":"Wichtiges Digitalisierungswerkzeug"},"content":{"rendered":"\n<p>Dank neuartiger Ans\u00e4tze in den Bereichen k\u00fcnstliche Intelligenz, kognitive Automatisierung und Machine Learning entwickeln sich Enterprise-Service-Management-L\u00f6sungen (ESM) zu einem der wichtigsten Mittel, um servicebasierte Gesch\u00e4ftsprozesse unternehmens\u00fcbergreifend zu digitalisieren. <\/p>\n\n\n\n<p>Obwohl die Grundidee, die Organisationsprinzipien des IT-Servicemanagements (ITSM) auch auf die Gestaltung von Nicht-IT-Abl\u00e4ufen anzuwenden, erst wenige Jahre alt ist, verzeichnet der ESM-Markt bereits jetzt \u00fcberdurchschnittlich hohe Wachstumsraten. Haupttreiber ist einmal mehr die Coronapandemie, die insbesondere Gro\u00dfunternehmen dazu veranlasst, das Management gesch\u00e4ftskritischer Dienstleistungsprozesse auf ortsunabh\u00e4ngig nutzbare Webportale zu verlagern. <\/p>\n\n\n\n<p>Vor diesem Hintergrund birgt der ESM-Markt hohe Wachstumschancen sowohl f\u00fcr Tool-Anbieter als auch f\u00fcr Beratungsh\u00e4user. Dies meldet die neue Vergleichsstudie ISG Provider Lens Enterprise Service Management Germany 2021. <\/p>\n\n\n\n<p>\u201e<em>Funktionierende ESM-Plattformen l\u00f6sen eines der Kardinalprobleme vieler Digitalisierungsprojekte. Dieses besteht darin, nicht konsistent genug auf aktuelle Datenbest\u00e4nde zugreifen zu k\u00f6nnen. Vor allem an dieser Stelle der IT-Wertsch\u00f6pfung sorgt Enterprise Service Management wirksam f\u00fcr Abhilfe<\/em>\u201c, sagt Heiko Henkes, Director und Principal Analyst bei der Information Services Group (ISG), und erl\u00e4utert: \u201e<em>Mit hochautomatisierten Ende-zu-Ende-Abl\u00e4ufen etabliert ESM einen vielseitig nutzbaren Gestaltungsrahmen, um Mitarbeitern, Partnern und Kunden ausreichende Interaktionsm\u00f6glichkeiten zu bieten. Und zwar organisations\u00fcbergreifend entlang der gesamten Wertsch\u00f6pfungskette. So zum Beispiel in den Bereichen Einkauf, Geb\u00e4udemanagement, Kundendienst, Personalverwaltung und Rechnungswesen.<\/em>\u201c <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2021\/07\/HeikoHenkes.jpg\" alt=\"\" class=\"wp-image-92963\"\/><figcaption>&#8220;<em>Funktionierende ESM-Plattformen l\u00f6sen eines der Kardinalprobleme vieler Digitalisierungsprojekte.<\/em>&#8221; &#8211; <em><br><strong>Heiko Henkes,<\/strong> Principal Analyst bei ISG<\/em><\/figcaption><\/figure>\n\n\n\n<p>Die wachsende Nachfrage f\u00fchre jedoch zu divergierenden Marktentwicklungen aufseiten der unterschiedlichen ESM-Anbieter. Im Software-bereich verzeichne man, so ISG, einen stark zunehmenden Konsolidierungsdruck. Aktuell vergehe kaum noch ein Tag ohne \u00dcbernahmen und Zusammenschl\u00fcsse von Tool-Anbietern. <\/p>\n\n\n\n<p>Ziel sei es, die funktionale Reichweite des eigenen Produktportfolios permanent weiter auszudehnen. Demgegen\u00fcber b\u00f6te der Beratermarkt ausreichendes Wachstumspotenzial f\u00fcr wesentlich mehr Unternehmen, so ISG weiter.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>W\u00e4hrend der \u00dcbernahmedruck im Bereich Enterprise-Service-Management-Tools weiter zunimmt, bietet der Berater<\/p>\n","protected":false},"author":38,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[2,39637],"tags":[601,4944,39413],"coauthors":[19920],"class_list":["post-92955","post","type-post","status-publish","format-standard","hentry","category-sap-nachrichten","category-mag-21-07","tag-digitalisierung","tag-enterprise-service-management","tag-isg-one","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","image-100":"","image-480":"","image-640":"","image-720":"","image-960":"","image-1168":"","image-1440":"","image-1920":"","1536x1536":"","2048x2048":"","trp-custom-language-flag":"","bricks_large_16x9":"","bricks_large":"","bricks_large_square":"","bricks_medium":"","bricks_medium_square":"","profile_24":"","profile_48":"","profile_96":"","profile_150":"","profile_300":""},"post_excerpt_stackable_v2":"<p>W\u00e4hrend der \u00dcbernahmedruck im Bereich Enterprise-Service-Management-Tools weiter zunimmt, bietet der Berater<\/p>\n","category_list_v2":"<a href=\"https:\/\/e326.greatsolution.dev\/de\/category\/sap-nachrichten\/\" rel=\"category tag\">Community Nachrichten<\/a>, <a href=\"https:\/\/e326.greatsolution.dev\/de\/category\/mag-21-07\/\" rel=\"category tag\">MAG 21-07<\/a>","author_info_v2":{"name":"E-3 Magazin","url":"https:\/\/e326.greatsolution.dev\/de\/author\/e-3-magazin\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/posts\/92955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/comments?post=92955"}],"version-history":[{"count":0,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/posts\/92955\/revisions"}],"wp:attachment":[{"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/media?parent=92955"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/categories?post=92955"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/tags?post=92955"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/de\/wp-json\/wp\/v2\/coauthors?post=92955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}