{"id":126202,"date":"2023-04-20T11:30:00","date_gmt":"2023-04-20T09:30:00","guid":{"rendered":"https:\/\/e326.greatsolution.dev\/?p=126202"},"modified":"2024-01-19T12:41:42","modified_gmt":"2024-01-19T11:41:42","slug":"el-polo-de-la-comunidad","status":"publish","type":"post","link":"https:\/\/e326.greatsolution.dev\/es\/el-polo-de-la-comunidad\/","title":{"rendered":"Los polos de la comunidad"},"content":{"rendered":"<h2 class=\"wp-block-heading\">Declaraci\u00f3n de misi\u00f3n bipolar: ALM<\/h2>\n\n\n\n<p>En la actualidad, SAP plantea grandes exigencias a la competencia de los clientes y socios existentes. Por un lado, hay que completar un cambio de versi\u00f3n t\u00e9cnica de ECC a S\/4 en un tiempo r\u00e9cord; por otro, hay que adaptar innovaciones como IIoT, blockchain, machine learning, miner\u00eda de procesos y computaci\u00f3n en la nube. El producto SAP <a href=\"https:\/\/e326.greatsolution.dev\/es\/categoria\/opinion\/alm\/\" target=\"_blank\" rel=\"noreferrer noopener\">ALM<\/a>La gesti\u00f3n del ciclo de vida de las aplicaciones es un buen paradigma de este enorme abanico: en un polo se encuentra la innovadora herramienta de Signavio para la reingenier\u00eda de los procesos empresariales, en el polo opuesto, una herramienta inform\u00e1tica para las pruebas operativas y automatizadas. Un cliente responsable de SAP debe enfrentarse a estos retos bipolares. La tarea consiste en organizar la simultaneidad de la miner\u00eda de procesos y las pruebas automatizadas con SAP ALM.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Clave: Automatizaci\u00f3n<\/h3>\n\n\n\n<p>Una soluci\u00f3n en la base de SAP para gestionar los distintos flujos es la automatizaci\u00f3n. Nunca antes tantos socios de SAP hab\u00edan abordado este tema. El tema de la automatizaci\u00f3n y la supervisi\u00f3n no s\u00f3lo puede garantizar la seguridad de las operaciones SAP, sino tambi\u00e9n amortiguar la actual escasez de competencias inform\u00e1ticas. Para preparar el art\u00edculo de portada de E-3 de junio, los socios de SAP Avantra y <a href=\"https:\/\/e326.greatsolution.dev\/es\/socios\/nagarro\/\" target=\"_blank\" rel=\"noreferrer noopener\">Nagarro<\/a>Automatizando el proceso, el responsable del CCC puede ahorrar dos tercios o m\u00e1s del tiempo necesario para la personalizaci\u00f3n b\u00e1sica. Desde el punto de vista operativo, hay una gran diferencia entre que el responsable del CCC tenga que planificar 15 o solo 5 d\u00edas-hombre. <br><br>Encontrar\u00e1 m\u00e1s informaci\u00f3n sobre la automatizaci\u00f3n en SAP Basis en la direcci\u00f3n <strong>1 y 2 de junio en Salzburgo<\/strong> en el <a href=\"https:\/\/e326.greatsolution.dev\/es\/summit-cc\/\" target=\"_blank\" rel=\"noreferrer noopener\">Cumbre de Centros de Competencia<\/a>. El evento de seguimiento del legendario Foro CCC ofrece todas las respuestas para el \u00e9xito de las operaciones SAP.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">ALM y Steampunk<\/h3>\n\n\n\n<p>La propia SAP baila en estos momentos sobre muchas mareas altas. Con ALM y Steampunk, el l\u00edder mundial del mercado ERP muestra todo el ancho de banda entre el polo operativo y el innovador. Toda la comunidad SAP trabaja en esta hoja de ruta bipolar. Con herramientas de TI como las pruebas automatizadas, la supervisi\u00f3n y la medici\u00f3n de licencias en un polo y el desarrollo de aplicaciones innovadoras en la BTP, Business Technology Platform, con low-code\/no-code y steampunk, el Abap integrado, en el otro polo, SAP, los socios y los clientes existentes est\u00e1n intentando hacer justicia a la transformaci\u00f3n digital.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">De extremo a extremo<\/h3>\n\n\n\n<p>Suerte en la desgracia. Si adem\u00e1s existe un desaf\u00edo bipolar, los dos polos no se repelen. Quienes sepan armonizar lo operativo con lo estrat\u00e9gico cosechar\u00e1n un valor a\u00f1adido. Como ocurre a menudo en la comunidad SAP, es necesario orquestar diferentes corrientes, tendencias, visiones y polos. El reto reside en la complejidad de una base de datos Hana y un sistema ERP S\/4. Aquellos que puedan conectar los dos polos de extremo a extremo podr\u00e1n utilizar la transformaci\u00f3n digital en su beneficio.<\/p>","protected":false},"excerpt":{"rendered":"<p>Actualmente existen dos corrientes en la comunidad SAP. En un polo est\u00e1 SAP con muchas innovaciones empresariales, en el otro los clientes y socios existentes con herramientas inform\u00e1ticas para endurecer la infraestructura y la arquitectura ERP, un reto bipolar.<\/p>","protected":false},"author":2,"featured_media":72570,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[27840],"tags":[13335,13334,39926,73,8855,517,236,38983],"coauthors":[27825],"class_list":["post-126202","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chefredakteur-blog","tag-alm","tag-application-lifecycle-management","tag-chefredakteurblog","tag-erp","tag-peter-faerbinger","tag-s4","tag-sap","tag-signavio","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2021\/03\/ChefredakteurFin.jpg",1000,450,false],"thumbnail":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2021\/03\/ChefredakteurFin-150x150.jpg",150,150,true],"medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2021\/03\/ChefredakteurFin.jpg",400,180,false],"medium_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2021\/03\/ChefredakteurFin-768x346.jpg",768,346,true],"large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2021\/03\/ChefredakteurFin.jpg",1000,450,false],"image-100":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2021\/03\/ChefredakteurFin-100x45.jpg",100,45,true],"image-480":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2021\/03\/ChefredakteurFin-480x216.jpg",480,216,true],"image-640":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2021\/03\/ChefredakteurFin-640x288.jpg",640,288,true],"image-720":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2021\/03\/ChefredakteurFin-720x324.jpg",720,324,true],"image-960":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2021\/03\/ChefredakteurFin-960x432.jpg",960,432,true],"image-1168":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2021\/03\/ChefredakteurFin.jpg",1000,450,false],"image-1440":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2021\/03\/ChefredakteurFin.jpg",1000,450,false],"image-1920":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2021\/03\/ChefredakteurFin.jpg",1000,450,false],"1536x1536":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2021\/03\/ChefredakteurFin.jpg",1000,450,false],"2048x2048":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2021\/03\/ChefredakteurFin.jpg",1000,450,false],"trp-custom-language-flag":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2021\/03\/ChefredakteurFin.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2021\/03\/ChefredakteurFin.jpg",1000,450,false],"bricks_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2021\/03\/ChefredakteurFin.jpg",1000,450,false],"bricks_large_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2021\/03\/ChefredakteurFin.jpg",1000,450,false],"bricks_medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2021\/03\/ChefredakteurFin.jpg",600,270,false],"bricks_medium_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2021\/03\/ChefredakteurFin.jpg",600,270,false],"profile_24":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2021\/03\/ChefredakteurFin-24x24.jpg",24,24,true],"profile_48":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2021\/03\/ChefredakteurFin-48x48.jpg",48,48,true],"profile_96":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2021\/03\/ChefredakteurFin-96x96.jpg",96,96,true],"profile_150":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2021\/03\/ChefredakteurFin-150x150.jpg",150,150,true],"profile_300":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2021\/03\/ChefredakteurFin-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Aktuell gibt es zwei Str\u00f6mungen in der SAP-Community. An einem Pol befindet sich SAP mit vielen Business-Innovationen, am anderen Ende die Bestandskunden und Partner mit IT-Werkzeugen, um Infrastruktur und ERP-Architektur zu h\u00e4rten, eine bipolare Herausforderung.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e326.greatsolution.dev\/es\/categoria\/blog-del-jefe-redactor-2\/\" rel=\"category tag\">Chefredakteur-Blog<\/a>","author_info_v2":{"name":"Peter M. F\u00e4rbinger, E3 Magazine","url":"https:\/\/e326.greatsolution.dev\/es\/author\/peter-m-faerbinger-e-3-magazin\/"},"comments_num_v2":"0 comentarios","_links":{"self":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/126202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/comments?post=126202"}],"version-history":[{"count":1,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/126202\/revisions"}],"predecessor-version":[{"id":137615,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/126202\/revisions\/137615"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/media\/72570"}],"wp:attachment":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/media?parent=126202"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/categories?post=126202"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/tags?post=126202"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/coauthors?post=126202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}