{"id":130874,"date":"2023-07-21T14:00:00","date_gmt":"2023-07-21T12:00:00","guid":{"rendered":"https:\/\/e326.greatsolution.dev\/?p=130874"},"modified":"2024-01-19T14:47:32","modified_gmt":"2024-01-19T13:47:32","slug":"datasfera-alternativa","status":"publish","type":"post","link":"https:\/\/e326.greatsolution.dev\/es\/datasfera-alternativa\/","title":{"rendered":"Alternativa a Datasphere"},"content":{"rendered":"<p>SAO lleva muchos a\u00f1os experimentando con la entrega \u00f3ptima de datos corporativos. El primer intento fue SAP Data Hub, que era un buen concepto, pero consum\u00eda demasiados recursos y, por tanto, no resultaba econ\u00f3mico. En la actualidad, SAP lo est\u00e1 intentando con el complej\u00edsimo concepto Datasphere, v\u00e9ase tambi\u00e9n la p\u00e1gina 48. Pero hay otro camino, como nos cuentan Richard Brouwer, Especialista Principal en Ingenier\u00eda de Ventas para SAP en Fivetran, y Benedikt Engel, Arquitecto de Soluciones para EMEA en Snowflake, en una entrevista doble exclusiva de E-3.<\/p>\n\n\n\n<p><strong>E-3:<\/strong> Copo de Nieve y Fivetran, \u00bfqu\u00e9 los uni\u00f3 y qu\u00e9 los conecta?<\/p>\n\n\n\n<p><strong>Richard Brouwer,<\/strong> <strong>Fivetran:<\/strong> Snowflake y Fivetran son socios desde hace aproximadamente una d\u00e9cada, y tambi\u00e9n somos clientes el uno del otro. -Fivetran est\u00e1 considerado uno de los socios tecnol\u00f3gicos de \u00e9lite de Snowflake y es Data Integration Partner of the Year 2022. Ambas empresas se han propuesto sacar los datos de los silos, y juntas ofrecemos una soluci\u00f3n que lo consigue. Normalmente, los datos no proceden de Snowflake, sino de otros sistemas. Fivetran ofrece canalizaciones listas para usar y totalmente gestionadas que alimentan Snowflake con datos. Al hacerlo, nuestra capacidad \u00fanica para replicar datos SAP tambi\u00e9n nos convierte en el socio de integraci\u00f3n preferido para Snowflake. Muchos clientes de SAP saben que la entrega de datos SAP a Snowflake es engorrosa. Fivetran entrega estos datos de forma sencilla y eficaz casi en tiempo real. Nuestro objetivo es introducir los datos en Snowflake como una r\u00e9plica perfecta de la fuente. Snow-flake sirve entonces como repositorio \u00fanico y de confianza para todos los datos.&nbsp;<\/p>\n\n\n\n<p><strong>\u00c1ngeles:<\/strong> Mientras tanto, ya no se dice que \"los datos son el nuevo petr\u00f3leo\", sino que \"el tiempo es el nuevo petr\u00f3leo\". De esto tambi\u00e9n tratan Snowflake y Fivetran: Snowflake como plataforma de datos y Fivetran como ELT que permite disponer de datos de innumerables fuentes casi en tiempo real. Con Snowflake, los datos se armonizan y analizan, lo que proporciona informaci\u00f3n valiosa y supone un enorme aumento de la eficiencia y la eficacia. Como resultado, ahora podemos abordar nuevos problemas para los que antes la relaci\u00f3n coste-beneficio no era la adecuada.&nbsp;<\/p>\n\n\n\n<p><strong>E-3:<\/strong> Y concretamente, \u00bfd\u00f3nde se complementan?<\/p>\n\n\n\n<p><strong>Brouwer:<\/strong> Con m\u00e1s de 400 conectores, Fivetran proporciona datos de una amplia gama de fuentes en un formato que permite a los clientes sacar el m\u00e1ximo partido de sus datos en la plataforma Snowflake. Por ejemplo, en Salesforce, los datos de SAP pueden conectarse a m\u00e1s de 460 fuentes de terceros. Dado que los datos est\u00e1n disponibles en el formato adecuado y con la frecuencia \u00f3ptima, su valor es mucho m\u00e1s f\u00e1cil de aprovechar con las capacidades de la plataforma Snowflake que con otras soluciones. Incluso cuando la cantidad de datos y el n\u00famero de fuentes crecen exponencialmente, nuestros clientes de Snowflake siempre tienen todos sus datos al alcance de la mano.&nbsp;<\/p>\n\n\n\n<p><strong>Benedikt Engel,<\/strong> <strong>Copo de nieve:<\/strong> A continuaci\u00f3n, Snowflake proporciona la funcionalidad necesaria para analizar los datos y enriquecerlos con m\u00e1s datos a trav\u00e9s de Snowflake Market-place, o los rentabiliza de otras formas para que los clientes puedan tomar las decisiones correctas.<\/p>\n\n\n\n<p><strong>E-3:<\/strong> Desde la perspectiva de un cliente SAP existente con ECC o S\/4, \u00bfqu\u00e9 puede ofrecer usted que SAP no pueda?<\/p>\n\n\n\n<p><strong>\u00c1ngeles:<\/strong> Una plataforma de datos nativa en la nube escalable y rentable con una arquitectura f\u00e1cil de usar, agn\u00f3stica respecto a la nube y caracterizada por el aislamiento de las cargas de trabajo gracias a la separaci\u00f3n de los recursos de c\u00e1lculo y almacenamiento e inform\u00e1tica. Nuestros clientes pueden solicitar cl\u00fasteres de computaci\u00f3n de forma flexible, que se suministran por segundos y se abonan mediante un sistema de pago por uso: una aut\u00e9ntica soluci\u00f3n SaaS.<\/p>\n\n\n\n<p><strong>Brouwer:<\/strong> Nuestra completa oferta incluye una gama de soluciones superiores para que los clientes de SAP con sistemas ECC o S\/4 repliquen sus datos SAP. Con nuestra eficiente replicaci\u00f3n de datos en m\u00faltiples nubes, les permitimos replicar sin problemas en diferentes plataformas en la nube y les ofrecemos la flexibilidad de elegir el entorno m\u00e1s adecuado. Nuestro enfoque totalmente gestionado garantiza una replicaci\u00f3n sin complicaciones, mientras que el procesamiento de datos en las instalaciones mejora el rendimiento y proporciona informaci\u00f3n en tiempo real. Con una migraci\u00f3n y replicaci\u00f3n de datos seguras y pr\u00e1cticamente en tiempo real, minimizamos el impacto en los sistemas de origen y los clientes pueden cargar sus datos SAP en Snowflake de forma rentable.<\/p>\n\n\n\n<p><strong>E-3: <\/strong>\u00bfCu\u00e1l es su relaci\u00f3n con SAP?<\/p>\n\n\n\n<p><strong>Brouwer:<\/strong> Fivetran es socio de SAP y el primer conector certificado estar\u00e1 disponible en breve.&nbsp;<\/p>\n\n\n\n<p><strong>\u00c1ngeles:<\/strong> En lo que respecta a la plataforma anal\u00edtica, Snowflake suele tener clientes comunes con SAP. A menudo se desarrollan sinergias: SAP ERP es una de las fuentes de datos, mientras que Snowflake ayuda a los clientes a hacer realidad casos de uso que antes eran dif\u00edcilmente viables, o solo con mucho esfuerzo. Nuestra plataforma se utiliza para analizar datos SAP y no SAP, a veces ampliados con datos de Snowflake Marketplace o datos en streaming de dispositivos IoT.&nbsp;<\/p>\n\n\n\n<p><strong>E-3:<\/strong> En el sentido m\u00e1s amplio, usted trabaja en el campo de la gesti\u00f3n de datos.<\/p>\n\n\n\n<p>Existen excelentes bases de datos SQL, \u00bfd\u00f3nde ve exactamente el reto actual en la gesti\u00f3n de datos corporativos?<\/p>\n\n\n\n<p><strong>\u00c1ngeles:<\/strong> Muchos clientes eligen Snowflake para resolver los siguientes problemas: En primer lugar, sus datos existen en muchas copias, algunas de las cuales son incoherentes. El resultado es la redundancia de datos. Como consecuencia, distintos an\u00e1lisis de los mismos datos suelen arrojar resultados diferentes, lo que hace pr\u00e1cticamente imposible gestionar la empresa en funci\u00f3n de los datos. En segundo lugar, debido a limitaciones f\u00edsicas o a diferentes responsabilidades en materia de datos, \u00e9stos se encuentran en bases de datos completamente distintas, es decir, en silos de datos.&nbsp;<\/p>\n\n\n\n<p>Esto significa que los datos no pueden combinarse. Por tanto, su utilidad es limitada. Si pueden combinarse, los procesos de aprobaci\u00f3n opacos y las diferentes opciones dentro del sistema respectivo dificultan una gobernanza uniforme, lo que r\u00e1pidamente genera problemas de seguridad. Y en tercer lugar, vemos que las soluciones existentes no crecen con la empresa: palabra clave: escalabilidad limitada. A menudo, los sistemas deben planificarse para una utilizaci\u00f3n m\u00e1xima porque no son el\u00e1sticos. Si se aplica la amortizaci\u00f3n habitual en cinco a\u00f1os, a menudo es demasiado arriesgado iniciar un proyecto porque los costes y beneficios son dif\u00edciles de estimar.&nbsp;<\/p>\n\n\n\n<p><strong>E-3:<\/strong> Fivetran dice en su sitio web: \"La plataforma automatizada de movimiento de datos\", y Snowflake tambi\u00e9n ofrece distribuci\u00f3n de datos. Hay que mover los datos?&nbsp;<\/p>\n\n\n\n<p><strong>Brouwer:<\/strong> S\u00ed, y con vol\u00famenes y fuentes de datos cada vez mayores, automatizar el movimiento de datos es la \u00fanica forma de tener \u00e9xito. La creaci\u00f3n manual de estas canalizaciones plantea muchos problemas. Encontrar ingenieros de datos cualificados que puedan crear las canalizaciones es cada vez m\u00e1s dif\u00edcil. Adem\u00e1s, es necesario mantenerlos y mejorarlos continuamente. El movimiento de datos es especialmente necesario cuando hay que vincular datos de distintas fuentes. Si est\u00e1n en una sola plataforma, se obtienen respuestas mucho m\u00e1s r\u00e1pidas y eficientes.&nbsp;<\/p>\n\n\n\n<p><strong>E-3:<\/strong> \u00bfAs\u00ed que se trata de movimiento y transformaci\u00f3n de datos?<\/p>\n\n\n\n<p><strong>Brouwer:<\/strong> Cuando comparamos el movimiento de datos con la distribuci\u00f3n de datos, estamos hablando de diferentes formas de movimiento de datos. Fivetran mueve principalmente datos brutos o datos de origen. Dichos datos necesitan ser movidos porque normalmente necesitan ser combinados con otras fuentes. Esto incluye tambi\u00e9n la transformaci\u00f3n de los datos. Transformar estos datos y enriquecerlos con otras fuentes de datos es mucho m\u00e1s eficiente en Snowflake. Cuando hablamos de distribuci\u00f3n de datos, se trata m\u00e1s bien de productos de datos. Este tipo de datos se adapta mejor a los datos de copia cero en Snowflake.&nbsp;<\/p>\n\n\n\n<p><strong>\u00c1ngeles:<\/strong> Snowflake pretende acabar con los silos de datos almacen\u00e1ndolos una sola vez y permitiendo que cualquiera pueda acceder a ellos. Esto se consigue gracias a nuestra arquitectura \u00fanica, que incluye la separaci\u00f3n de la inform\u00e1tica y el almacenamiento. Esto nos proporciona una escalabilidad ilimitada en almacenamiento y computaci\u00f3n.&nbsp;<\/p>\n\n\n\n<p><strong>E-3:<\/strong> Entonces, \u00bfd\u00f3nde est\u00e1 el origen de Copito de Nieve?<\/p>\n\n\n\n<p><strong>\u00c1ngeles:<\/strong> Snowflake tiene sus or\u00edgenes en la nube, uno de los pilares fundamentales de la arquitectura Snowflake. Al hacer que Snowflake est\u00e9 disponible en AWS, GCP y Azure y vincular las cuentas entre s\u00ed, creamos lo que llamamos nuestra Snowgrid, que nos permite ofrecer a nuestros clientes un intercambio de datos de copia cero, replicaci\u00f3n y conmutaci\u00f3n por error. Esto permite a nuestros clientes entrar en un intercambio directo con otros clientes y compartir sus datos directamente, no solo dentro de los l\u00edmites de la empresa, sino tambi\u00e9n con otras organizaciones, socios, terceros y otras industrias. Con este enfoque, rompemos los silos de datos, geogr\u00e1ficamente y tambi\u00e9n entre proveedores de nube. Los datos siempre est\u00e1n vivos, no hay copias innecesarias. Pero primero hay que llevar los datos a Snowflake y, para ello, Fivetran, con sus numerosos conectores, es la soluci\u00f3n elegida. &nbsp;<\/p>\n\n\n\n<p><strong>E-3:<\/strong> SAP ha desarrollado un concepto con el Data Hub para que los datos se queden donde est\u00e1n almacenados, \u00bfno?&nbsp;<\/p>\n\n\n\n<p><strong>Brouwer:<\/strong> Es cierto, pero, por regla general, los datos no est\u00e1n disponibles en el formato que la empresa necesita ni con la frecuencia necesaria. Para crear un centro de datos, tambi\u00e9n es necesario configurar el sistema SAP. Adem\u00e1s, los datos de SAP son muy valiosos. Para poder utilizar este valor, debe combinarse con otras fuentes de datos. Snow-flake es una plataforma mucho mejor para ello. Esto se debe a que Data Hub se basa en el concepto de visualizaci\u00f3n de datos. Para combinar datos de diferentes fuentes, todav\u00eda hay que mover grandes cantidades de datos. As\u00ed pues, SAP Data Hub es bueno para examinar datos, pero no es ideal para un entorno de producci\u00f3n.<\/p>\n\n\n\n<p><strong>E-3:<\/strong> Elevator Pitch: \u00bfPara qu\u00e9 retos deber\u00eda ponerse en contacto con usted un cliente de SAP?&nbsp;<\/p>\n\n\n\n<p><strong>\u00c1ngeles:<\/strong> Si no puede o s\u00f3lo puede aplicar con dificultad los requisitos de los departamentos especializados, ya sea por la relaci\u00f3n precio-rendimiento, porque faltan funcionalidades en la plataforma o porque la escalabilidad de la arquitectura no es suficiente en el punto para soportar cargas de trabajo adicionales.<\/p>\n\n\n\n<p><strong>Brouwer:<\/strong> Si los datos SAP no est\u00e1n disponibles a tiempo o en el formato o nivel de detalle adecuados, es el momento de recurrir a Snowflake y Fivetran. Permitimos a los clientes extraer no s\u00f3lo datos SAP, sino tambi\u00e9n datos importantes o cr\u00edticos para el negocio de otras fuentes de datos externas y combinarlos en un almac\u00e9n de datos central. As\u00ed es como rompemos los silos de datos y posibilitamos las decisiones basadas en datos.<\/p>\n\n\n\n<p><strong>E-3:<\/strong> \u00bfD\u00f3nde y c\u00f3mo complementa su oferta de forma \u00f3ptima una arquitectura ECC o S\/4?<\/p>\n\n\n\n<p><strong>Brouwer: <\/strong>En la replicaci\u00f3n eficiente, rentable y r\u00e1pida de datos de SAP. Tambi\u00e9n damos soporte a casos de uso peque\u00f1os y grandes desde ECC o S\/4 a Snowflake. Gracias a las capacidades \u00fanicas de CDC de Fivetran, las transformaciones en Snowflake tambi\u00e9n se ejecutan de forma eficiente y r\u00e1pida, entregando los datos casi en tiempo real o por lotes. Al vincular datos SAP con datos de otras fuentes, los clientes pueden obtener mucho m\u00e1s valor de sus datos SAP.<\/p>\n\n\n\n<p><strong>\u00c1ngeles:<\/strong> Aqu\u00ed es exactamente donde entra Snowflake: Generamos informaci\u00f3n a partir de todos los datos de todas las fuentes vinculadas. En ese sentido, nos sentamos encima de los sistemas fuente de ECC.&nbsp;<\/p>\n\n\n\n<p><strong>E-3:<\/strong> Gracias por la entrevista.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.fivetran.com\/?_gl=11twq9th_gaMjA5MzgzNzc5Ny4xNjg5ODYxNjU1_ga_NE72Z5F3GB*MTY4OTg2MTY1NC4xLjAuMTY4OTg2MTY1Ni41OC4wLjA.\" target=\"_blank\" rel=\"noopener\">fivetran.com<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/www.snowflake.com\/en\/\" target=\"_blank\" rel=\"noopener\">snowflake.com<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>La disponibilidad de datos no es s\u00f3lo una cuesti\u00f3n de arquitectura, sino tambi\u00e9n de tiempo.<br \/>\nSi la entrega se retrasa, el valor a\u00f1adido es cero.<br \/>\nEl tiempo real es, por tanto, un componente estrat\u00e9gico de la gesti\u00f3n de datos.<\/p>","protected":false},"author":38,"featured_media":130879,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[2,161],"tags":[516,5015,1283,606,3224,14065,8689,245,21219,117,799],"coauthors":[19920],"class_list":["post-130874","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sap-nachrichten","category-szene","tag-aws","tag-azure","tag-data-hub","tag-daten","tag-enterprise-resource-planning","tag-gcp","tag-governance","tag-interview","tag-s-4","tag-sicherheit","tag-transformation","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/07\/Daten-1.jpg",1000,450,false],"thumbnail":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/07\/Daten-1-150x150.jpg",150,150,true],"medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/07\/Daten-1-400x180.jpg",400,180,true],"medium_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/07\/Daten-1-768x346.jpg",768,346,true],"large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/07\/Daten-1.jpg",1000,450,false],"image-100":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/07\/Daten-1-100x45.jpg",100,45,true],"image-480":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/07\/Daten-1-480x216.jpg",480,216,true],"image-640":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/07\/Daten-1-640x288.jpg",640,288,true],"image-720":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/07\/Daten-1-720x324.jpg",720,324,true],"image-960":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/07\/Daten-1-960x432.jpg",960,432,true],"image-1168":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/07\/Daten-1.jpg",1000,450,false],"image-1440":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/07\/Daten-1.jpg",1000,450,false],"image-1920":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/07\/Daten-1.jpg",1000,450,false],"1536x1536":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/07\/Daten-1.jpg",1000,450,false],"2048x2048":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/07\/Daten-1.jpg",1000,450,false],"trp-custom-language-flag":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/07\/Daten-1-18x8.jpg",18,8,true],"bricks_large_16x9":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/07\/Daten-1.jpg",1000,450,false],"bricks_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/07\/Daten-1.jpg",1000,450,false],"bricks_large_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/07\/Daten-1.jpg",1000,450,false],"bricks_medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/07\/Daten-1-600x270.jpg",600,270,true],"bricks_medium_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/07\/Daten-1-600x450.jpg",600,450,true],"profile_24":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/07\/Daten-1-24x24.jpg",24,24,true],"profile_48":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/07\/Daten-1-48x48.jpg",48,48,true],"profile_96":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/07\/Daten-1-96x96.jpg",96,96,true],"profile_150":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/07\/Daten-1-150x150.jpg",150,150,true],"profile_300":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/07\/Daten-1-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Datenverf\u00fcgbarkeit ist nicht nur eine Architektur-, sondern auch eine Zeitfrage.<br \/>\nWenn die Anlieferung zu sp\u00e4t kommt, ist der Mehrwert gleich null.<br \/>\nRealtime ist somit eine strategische Komponente beim Datenmanagement.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e326.greatsolution.dev\/es\/categoria\/noticias-sap\/\" rel=\"category tag\">Community Nachrichten<\/a>, <a href=\"https:\/\/e326.greatsolution.dev\/es\/categoria\/escena\/\" rel=\"category tag\">Szene<\/a>","author_info_v2":{"name":"Revista E-3","url":"https:\/\/e326.greatsolution.dev\/es\/author\/e-3-magazin\/"},"comments_num_v2":"0 comentarios","_links":{"self":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/130874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/comments?post=130874"}],"version-history":[{"count":12,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/130874\/revisions"}],"predecessor-version":[{"id":130900,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/130874\/revisions\/130900"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/media\/130879"}],"wp:attachment":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/media?parent=130874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/categories?post=130874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/tags?post=130874"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/coauthors?post=130874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}