{"id":150180,"date":"2025-04-07T07:00:00","date_gmt":"2025-04-07T05:00:00","guid":{"rendered":"https:\/\/e326.greatsolution.dev\/?p=150180"},"modified":"2025-04-04T09:26:11","modified_gmt":"2025-04-04T07:26:11","slug":"e3-entrevista-exclusiva-quo-vadis-sap-basis","status":"publish","type":"post","link":"https:\/\/e326.greatsolution.dev\/es\/e3-entrevista-exclusiva-quo-vadis-sap-basis\/","title":{"rendered":"Entrevista exclusiva con E3 Magazine: \u00bfQuo vadis, SAP Basis?"},"content":{"rendered":"<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-8cf370e7 wp-block-group-is-layout-flex\">\n<p><strong>E3: Los clientes de SAP conf\u00edan en SAP Basis o en la automatizaci\u00f3n de la infraestructura de SAP desde hace unos 20 a\u00f1os. En qu\u00e9 punto nos encontramos hoy? \u00bfHacia d\u00f3nde se dirige el viaje?<\/strong><\/p>\n\n\n\n<p><strong>Marcus Bogenst\u00e4tter, Empirius\u200e:\u200e<\/strong>Las interfaces estandarizadas para SAP R\/3, incluidas las de supervisi\u00f3n, copia de seguridad y programaci\u00f3n de trabajos, permitieron a SAP crear buenas opciones para automatizar los procesos empresariales y el funcionamiento del sistema SAP desde el principio. A lo largo de los a\u00f1os, las empresas han seguido optimizando y perfeccionando las operaciones por su cuenta, con el SAP Solution Manager y con la ayuda de productos de terceros. Desde 2005, tambi\u00e9n nos hemos especializado en un tema de automatizaci\u00f3n, a saber, la creaci\u00f3n automatizada de copias del sistema SAP; m\u00e1s adelante (nota del editor: 2021), el radio se ampli\u00f3 a la gesti\u00f3n automatizada del sistema como \"punto central de gesti\u00f3n\" con la suite o plataforma Epos. Por ejemplo, con el \u00e1rea de tareas de actualizaciones del n\u00facleo SAP o de cualquier base de datos, incluido el arranque\/parada automatizados de los sistemas SAP. O simplemente el reinicio concertado de varios servidores, teniendo en cuenta las dependencias de los sistemas SAP que se ejecutan en ellos. Esto significa que el equipo de SAP Basis responsable del funcionamiento de los sistemas SAP puede ahora gestionar, controlar y supervisar autom\u00e1ticamente diversas tareas y actividades importantes requeridas por un usuario de SAP desde un punto central y una interfaz de usuario web. Todo ello teniendo en cuenta las necesidades individuales. Sin embargo, la estrategia de SAP en la nube, incluido SAP Rise, est\u00e1 asociada a un cambio en este sentido. Sin embargo, seg\u00fan nuestras conclusiones, esto a\u00fan no se ha concretado del todo. O dicho de otro modo: Todav\u00eda quedan cabos sueltos.<\/p>\n<\/div>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-stackable-image stk-block-image stk-block stk-02c9462\" data-block-id=\"02c9462\"><style>.stk-02c9462 .stk-img-figcaption{text-align:center !important;}.stk-02c9462 .stk-img-wrapper{width:70% !important;}.stk-02c9462 .stk-img-wrapper img{object-position:53% 34% !important;}<\/style><figure><span class=\"stk-img-wrapper stk-image--shape-stretch\"><img loading=\"lazy\" decoding=\"async\" class=\"stk-img wp-image-150188\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/Empirius_Marcus-Bogenstaetter-scaled.jpg\" width=\"2560\" height=\"2047\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/Empirius_Marcus-Bogenstaetter-scaled.jpg 1351w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/Empirius_Marcus-Bogenstaetter-400x320.jpg 400w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/Empirius_Marcus-Bogenstaetter-1200x959.jpg 1200w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/Empirius_Marcus-Bogenstaetter-768x614.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/Empirius_Marcus-Bogenstaetter-100x80.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/Empirius_Marcus-Bogenstaetter-480x384.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/Empirius_Marcus-Bogenstaetter-640x512.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/Empirius_Marcus-Bogenstaetter-720x576.jpg 720w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/Empirius_Marcus-Bogenstaetter-960x768.jpg 960w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/Empirius_Marcus-Bogenstaetter-1168x934.jpg 1168w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/Empirius_Marcus-Bogenstaetter-1440x1151.jpg 1440w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/Empirius_Marcus-Bogenstaetter-1536x1228.jpg 1536w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/Empirius_Marcus-Bogenstaetter-2048x1638.jpg 1350w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/Empirius_Marcus-Bogenstaetter-15x12.jpg 15w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/Empirius_Marcus-Bogenstaetter-600x480.jpg 600w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/span><figcaption class=\"stk-img-figcaption\">\"Si Rise se refiere a la nube y, por tanto, al funcionamiento del sistema SAP, los clientes deber\u00edan integrar su propia base SAP\".  <br><strong>Marcus Bogenst\u00e4tter<\/strong>Director de Tecnolog\u00eda, Empirius<\/figcaption><\/figure><\/div>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-8cf370e7 wp-block-group-is-layout-flex\">\n<p><strong>E3: \u00bfQu\u00e9 significa el cambio en t\u00e9rminos concretos? \u00bfQu\u00e9 significa en t\u00e9rminos del futuro papel de SAP Basis?<\/strong><\/p>\n\n\n\n<p><strong>Bogenst\u00e4tter:\u200e<\/strong>Debido al fin de la vida \u00fatil de SAP Business Suite a finales de 2027, muchos clientes est\u00e1n migrando actualmente al sucesor tecnol\u00f3gico S\/4 Hana, a menudo al mismo tiempo que se trasladan a la nube de SAP, es decir, a SAP Rise. El cambio consiste en que SAP se hace cargo de una parte m\u00e1s o menos grande de las actividades rutinarias de SAP Basis con su oferta en la nube Rise, pero ni mucho menos de todas. La coordinaci\u00f3n de los tiempos de inactividad sigue estando en manos de Basis del cliente, adem\u00e1s de las actividades que siguen estando en Basis de todos modos. Ser\u00eda importante que los clientes conservaran una visi\u00f3n global y el control de todas las tareas relacionadas con SAP Basis. Ejemplo concreto: \u00bfC\u00f3mo podemos planificar y minimizar los tiempos de inactividad en la nube, por ejemplo durante una actualizaci\u00f3n del kernel con parada e inicio del sistema, incluida la base de datos, de acuerdo con los requisitos y con precisi\u00f3n milim\u00e9trica?<\/p>\n<\/div>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-8cf370e7 wp-block-group-is-layout-flex\">\n<p><strong>E3: \u00bfEn qu\u00e9 medida influye SAP Rise with Cloud en el uso de las soluciones de automatizaci\u00f3n SAP Basis y, por tanto, en las actividades de los proveedores de dichas soluciones?<\/strong><\/p>\n\n\n\n<p><strong>Bogenst\u00e4tter:\u200e<\/strong>El futuro lo demostrar\u00e1. Si los proveedores de soluciones de automatizaci\u00f3n de SAP Basis no tienen acceso a los par\u00e1metros relevantes para SAP Basis debido a las especificaciones de SAP, ya sea por motivos t\u00e9cnicos o de licencias, el reto es grande. Sin embargo, a\u00fan quedan las actividades que no est\u00e1n incluidas en SAP Rise. Ejemplos: Gesti\u00f3n de certificados, notas de seguridad, supervisi\u00f3n de par\u00e1metros o comprobaciones de conformidad. En la actualidad, algunos clientes de SAP han firmado un contrato con SAP Rise, pero la transici\u00f3n a Rise a\u00fan no se ha completado. Tambi\u00e9n hay que reconocer que un cierto n\u00famero de clientes de SAP S\/4 siguen utilizando su entorno local. Parece que las cosas est\u00e1n actualmente en un estado de flujo. No estamos en alerta roja. Nuestras ventas de licencias Epos est\u00e1n aumentando.<\/p>\n<\/div>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-8cf370e7 wp-block-group-is-layout-flex\">\n<p><strong>E3: Pero Empirius sigue vigilando de cerca el asunto de la subida del SAP, \u00bfno?<\/strong><\/p>\n\n\n\n<p><strong>Bogenst\u00e4tter:\u200e<\/strong>Por supuesto. Tambi\u00e9n estamos haciendo esfuerzos concretos para fomentar el di\u00e1logo con una visi\u00f3n orientada a las soluciones junto con SAP. Nuestro objetivo es encontrar y utilizar una interfaz compatible con la licencia para que los clientes puedan utilizar nuestra plataforma Epos y apoyar as\u00ed a los equipos de SAP Basis con soluciones de automatizaci\u00f3n para los distintos requisitos. Desde nuestro punto de vista, en realidad hay tres niveles diferentes en el complejo de resoluci\u00f3n de problemas: SAP, los clientes y nosotros.<\/p>\n<\/div>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-8cf370e7 wp-block-group-is-layout-flex\">\n<p><strong>E3: \u00bfQu\u00e9 recomienda Empirius a los equipos y clientes de SAP Basis?<\/strong><\/p>\n\n\n\n<p><strong>Bogenst\u00e4tter:\u200e<\/strong>Cuando se trata de la nube y, por tanto, del funcionamiento del sistema SAP en relaci\u00f3n con Rise, los clientes deber\u00edan implicar definitivamente a su propia SAP Basis. O bien SAP Basis deber\u00eda esforzarse por participar en las negociaciones contractuales relativas a la prestaci\u00f3n o asunci\u00f3n de los niveles de servicio que deben proporcionarse.<\/p>\n<\/div>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-8cf370e7 wp-block-group-is-layout-flex\">\n<p><strong>E3: Independientemente de SAP Rise, \u00bfcu\u00e1l es la estrategia de producto futura de Empirius?<\/strong><\/p>\n\n\n\n<p><strong>Bogenst\u00e4tter:\u200e<\/strong>Partimos de la base de que el tema de SAP Rise y SAP Cloud puede, por decirlo sin rodeos, aclararse. Seguimos centr\u00e1ndonos en nuestra plataforma Epos como soluci\u00f3n de \"punto central de gesti\u00f3n\" con 14 aplicaciones actuales que pueden utilizarse para automatizar un gran n\u00famero de tareas de SAP Basis. La versi\u00f3n 24.9 incorpora una importante innovaci\u00f3n para nosotros y nuestros clientes: el motor de administraci\u00f3n. Ampliaremos gradualmente este motor para peque\u00f1as tareas ad hoc de SAP Basis. Con una automatizaci\u00f3n de SAP Basis a\u00fan m\u00e1s flexible, que aportar\u00e1 m\u00e1s ventajas de eficiencia. Tambi\u00e9n tenemos previsto que Epos est\u00e9 disponible para SAP, pero tambi\u00e9n para entornos que no sean SAP. Por ejemplo, para clientes de SAP que deseen utilizar SAP para ERP on-prem o con un proveedor de servicios SAP, pero que utilicen Salesforce para CRM, Workday para RRHH o Kinaxis como sustituto de APO. La gesti\u00f3n de identidades es otra \u00e1rea en la que llevamos tiempo trabajando. En concreto, la gesti\u00f3n de identidades a nivel de aplicaci\u00f3n.<\/p>\n<\/div>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Al directorio de socios:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><a href=\"https:\/\/e326.greatsolution.dev\/es\/socios\/empirius-gmbh\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"300\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/11\/Empirius-Logo-mit-Slogan-2023.png\" alt=\"\" class=\"wp-image-134537\" style=\"width:300px\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/11\/Empirius-Logo-mit-Slogan-2023.png 800w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/11\/Empirius-Logo-mit-Slogan-2023-400x150.png 400w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/11\/Empirius-Logo-mit-Slogan-2023-768x288.png 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/11\/Empirius-Logo-mit-Slogan-2023-100x38.png 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/11\/Empirius-Logo-mit-Slogan-2023-480x180.png 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/11\/Empirius-Logo-mit-Slogan-2023-640x240.png 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/11\/Empirius-Logo-mit-Slogan-2023-720x270.png 720w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/11\/Empirius-Logo-mit-Slogan-2023-18x7.png 18w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/11\/Empirius-Logo-mit-Slogan-2023-600x225.png 600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/figure>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Essenziell f\u00fcr SAP-Kunden: Hoheit und Kontrolle \u00fcber SAP-Systeme \u2013 mit einer zuverl\u00e4ssigen Basis.<br \/>\nIn den vergangenen 20 Jahren wurde mit SAP-Basis-Automatisierung viel erreicht. Welchen Einfluss haben SAPs Cloud-Strategie und Rise? Dazu Empirius-Technik-Chef Marcus Bogenst\u00e4tter. <\/p>","protected":false},"author":2368,"featured_media":150192,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[2,44114],"tags":[14545,245,43815,41850],"coauthors":[39720],"class_list":["post-150180","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sap-nachrichten","category-mag-25-04","tag-empirius","tag-interview","tag-rise","tag-sap-basis","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/shutterstock_2255988053_.jpg",1000,450,false],"thumbnail":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/shutterstock_2255988053_-150x150.jpg",150,150,true],"medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/shutterstock_2255988053_-400x180.jpg",400,180,true],"medium_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/shutterstock_2255988053_-768x346.jpg",768,346,true],"large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/shutterstock_2255988053_.jpg",1000,450,false],"image-100":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/shutterstock_2255988053_-100x45.jpg",100,45,true],"image-480":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/shutterstock_2255988053_-480x216.jpg",480,216,true],"image-640":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/shutterstock_2255988053_-640x288.jpg",640,288,true],"image-720":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/shutterstock_2255988053_-720x324.jpg",720,324,true],"image-960":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/shutterstock_2255988053_-960x432.jpg",960,432,true],"image-1168":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/shutterstock_2255988053_.jpg",1000,450,false],"image-1440":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/shutterstock_2255988053_.jpg",1000,450,false],"image-1920":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/shutterstock_2255988053_.jpg",1000,450,false],"1536x1536":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/shutterstock_2255988053_.jpg",1000,450,false],"2048x2048":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/shutterstock_2255988053_.jpg",1000,450,false],"trp-custom-language-flag":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/shutterstock_2255988053_-18x8.jpg",18,8,true],"bricks_large_16x9":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/shutterstock_2255988053_.jpg",1000,450,false],"bricks_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/shutterstock_2255988053_.jpg",1000,450,false],"bricks_large_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/shutterstock_2255988053_.jpg",1000,450,false],"bricks_medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/shutterstock_2255988053_-600x270.jpg",600,270,true],"bricks_medium_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/shutterstock_2255988053_-600x450.jpg",600,450,true],"profile_24":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/shutterstock_2255988053_-24x24.jpg",24,24,true],"profile_48":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/shutterstock_2255988053_-48x48.jpg",48,48,true],"profile_96":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/shutterstock_2255988053_-96x96.jpg",96,96,true],"profile_150":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/shutterstock_2255988053_-150x150.jpg",150,150,true],"profile_300":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/shutterstock_2255988053_-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Essenziell f\u00fcr SAP-Kunden: Hoheit und Kontrolle \u00fcber SAP-Systeme \u2013 mit einer zuverl\u00e4ssigen Basis.<br \/>\nIn den vergangenen 20 Jahren wurde mit SAP-Basis-Automatisierung viel erreicht. Welchen Einfluss haben SAPs Cloud-Strategie und Rise? Dazu Empirius-Technik-Chef Marcus Bogenst\u00e4tter. <\/p>\n","category_list_v2":"<a href=\"https:\/\/e326.greatsolution.dev\/es\/categoria\/noticias-sap\/\" rel=\"category tag\">Community Nachrichten<\/a>, <a href=\"https:\/\/e326.greatsolution.dev\/es\/categoria\/mag-25-04\/\" rel=\"category tag\">MAG 25-04<\/a>","author_info_v2":{"name":"E3 Magazine","url":"https:\/\/e326.greatsolution.dev\/es\/author\/e3_magazin\/"},"comments_num_v2":"0 comentarios","_links":{"self":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/150180","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/users\/2368"}],"replies":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/comments?post=150180"}],"version-history":[{"count":9,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/150180\/revisions"}],"predecessor-version":[{"id":150191,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/150180\/revisions\/150191"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/media\/150192"}],"wp:attachment":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/media?parent=150180"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/categories?post=150180"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/tags?post=150180"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/coauthors?post=150180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}