{"id":154113,"date":"2025-08-21T12:41:40","date_gmt":"2025-08-21T10:41:40","guid":{"rendered":"https:\/\/e326.greatsolution.dev\/?p=154113"},"modified":"2025-08-21T16:07:12","modified_gmt":"2025-08-21T14:07:12","slug":"ki-no-es-un-modelo-de-negocio-de-savia","status":"publish","type":"post","link":"https:\/\/e326.greatsolution.dev\/es\/ki-no-es-un-modelo-de-negocio-de-savia\/","title":{"rendered":"La IA no es un modelo de negocio SAP"},"content":{"rendered":"<h2 class=\"wp-block-heading\">El dilema de un innovador en IA<\/h2>\n\n\n\n<p><\/p>\n\n\n\n<p>La IA en los \u00e1mbitos del aprendizaje por refuerzo, los modelos ling\u00fc\u00edsticos grandes (LLM) y los agentes de IA est\u00e1 produciendo una sensaci\u00f3n t\u00e9cnica tras otra. Miles de start-ups se superan unas a otras con experimentos innovadores y espect\u00e1culos tecnol\u00f3gicos maravillosos, pero muy a menudo carecen de un concepto empresarial y organizativo. Las empresas que se han beneficiado economicamente con la IA son escasas. De todas las empresas tecnol\u00f3gicas, la que produce hardware es la que se convirti\u00f3 en ganadora con la IA. Nvidia se ha convertido en la empresa m\u00e1s valiosa del mundo con chips de IA. Ninguna empresa de software ha sido capaz de crecer tan r\u00e1pida y espectacularmente con la IA.<\/p>\n\n\n\n<p>Marlon Bonazzi escribe en la revista virtual alemana WirtschaftsWoche: \"Importante rev\u00e9s para los valores tecnol\u00f3gicos tras el bombo de la IA [...] Pero los valores de software como SAP tambi\u00e9n est\u00e1n bajo presi\u00f3n. Las acciones de la empresa alemana de software SAP, por ejemplo, llevan meses debilit\u00e1ndose a pesar de que el Dax se mantiene firme. Las acciones de Salesforce tambi\u00e9n se han visto muy afectadas, cayendo de 360 a poco menos de 250 d\u00f3lares en apenas unos meses. A los inversores les preocupa que el software de gesti\u00f3n de relaciones con los clientes de Salesforce pueda ser sustituido por la IA. Esto sigue siendo un sue\u00f1o distante, pero el mercado de valores busca constantemente el equilibrio adecuado en el bombo que rodea a la IA.\" (Fuente: <a href=\"https:\/\/www.wiwo.de\/finanzen\/boerse\/palantir-aktie-nvidia-aktie-co-ruecksetzer-fuer-tech-aktien-nach-ki-hype\/100149382.html\" target=\"_blank\" rel=\"noreferrer noopener\">WirtschaftsWoche<\/a>)<\/p>\n\n\n\n<p>SAP est\u00e1 muy comprometida con la IA, pero a\u00fan no hay signos de sostenibilidad. La inversi\u00f3n no se ha traducido en ning\u00fan nuevo ERP, ni en nuevos conocimientos empresariales, ni en ingresos significativos. SAP est\u00e1 haciendo IA sin un plan, mientras que la computaci\u00f3n en nube est\u00e1 vertiendo mucho dinero en las arcas de SAP. Sin embargo, actualmente es muy incierto cu\u00e1nto tiempo podr\u00e1 seguir patrocinando el negocio de la nube los costosos experimentos de IA.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La computaci\u00f3n en nube patrocina la IA<\/h2>\n\n\n\n<p><\/p>\n\n\n\n<p>La IA impresiona por su espectacular tecnolog\u00eda, pero tiene la desagradable caracter\u00edstica de ser muy compleja y cara. Por lo tanto, es razonable suponer que muchos proveedores de software realizan subvenciones cruzadas: La nube aporta el dinero, la IA la reputaci\u00f3n. Sin embargo, este c\u00e1lculo se ve amenazado por una tendencia actual, como informa el portal online en alem\u00e1n CIO.<\/p>\n\n\n\n<p>\"Los directores de inform\u00e1tica han empezado a replantearse su dependencia de la nube p\u00fablica para la IA y otras cargas de trabajo, y han renovado su inter\u00e9s en la nube privada y los entornos locales. Aunque la nube p\u00fablica ofrece la flexibilidad necesaria para poner en marcha un gran n\u00famero de GPUs para experimentos de IA, a medida que sus estrategias de IA maduran, los CIOs buscan entornos de nube privada o locales para limitar el gasto y garantizar la protecci\u00f3n de los datos.\" (Fuente: <a href=\"https:\/\/www.cio.de\/article\/4024939\/cios-uberdenken-public-cloud-angesichts-ihrer-ki-strategie.html\" target=\"_blank\" rel=\"noreferrer noopener\">CIO<\/a>)<\/p>\n\n\n\n<p>En la comunidad SAP se observa una tendencia similar desde hace muchos meses. Con un creciente nivel de madurez, los procesos de TI procedentes de la computaci\u00f3n en nube y la b\u00fasqueda de la soberan\u00eda de TI, las instalaciones de ERP on-premise vuelven a estar en alta demanda. Muchos modelos operativos de ERP se basan en el alojamiento, la externalizaci\u00f3n y las nubes privadas. Sin embargo, esto pone en peligro el modelo de negocio de SAP con Rise with SAP y Grow with SAP a largo plazo. Queda por ver si la cotizaci\u00f3n de SAP, que lleva semanas cayendo, es ya una se\u00f1al de ello.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Exageraciones sobre la IA en la comunidad SAP<\/h2>\n\n\n\n<p><\/p>\n\n\n\n<p>La euforia por la IA tambi\u00e9n es real en la comunidad SAP, pero hasta ahora nadie ha obtenido beneficios financieros significativos de ella. Cada vez hay m\u00e1s sistemas de IA t\u00e9cnicamente maduros. Lo que falta es un concepto marco de negocio. Mientras que la computaci\u00f3n en nube se convirti\u00f3 r\u00e1pidamente en un modelo de negocio e impuls\u00f3 el precio de las acciones de SAP, no se han hecho observaciones similares con la IA. Al contrario: la IA parece estar corrompiendo el modelo de negocio de SAP: el precio de las acciones lleva semanas cayendo.<\/p>\n\n\n\n<p>Los resultados de muchos experimentos de IA son espectaculares. El aprendizaje autom\u00e1tico, los modelos ling\u00fc\u00edsticos grandes y los agentes de IA pueden conseguir cosas asombrosas. Servicios y tareas sencillas de gesti\u00f3n y organizaci\u00f3n empresarial son sustituibles f\u00e1cilmente por IA. SAP est\u00e1 tratando de equipar su propio ERP para el futuro con cientos de m\u00f3dulos de IA. Pero nadie sabe ad\u00f3nde nos llevar\u00e1 el viaje, \u00bfverdad?<\/p>","protected":false},"excerpt":{"rendered":"<p>La IA ofrece resultados cada vez m\u00e1s espectaculares y est\u00e1 penetrando en cada vez m\u00e1s \u00e1reas de negocio, pero las cotizaciones de los proveedores de TI que deber\u00edan beneficiarse de este bombo publicitario de la IA est\u00e1n cayendo. Qu\u00e9 est\u00e1 fallando en la inteligencia artificial?<\/p>","protected":false},"author":2,"featured_media":132122,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[27840],"tags":[],"coauthors":[27825],"class_list":["post-154113","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chefredakteur-blog","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/09\/Chefredakteur-neu.jpeg",1000,450,false],"thumbnail":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/09\/Chefredakteur-neu-150x150.jpeg",150,150,true],"medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/09\/Chefredakteur-neu-400x180.jpeg",400,180,true],"medium_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/09\/Chefredakteur-neu-768x346.jpeg",768,346,true],"large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/09\/Chefredakteur-neu.jpeg",1000,450,false],"image-100":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/09\/Chefredakteur-neu-100x45.jpeg",100,45,true],"image-480":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/09\/Chefredakteur-neu-480x216.jpeg",480,216,true],"image-640":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/09\/Chefredakteur-neu-640x288.jpeg",640,288,true],"image-720":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/09\/Chefredakteur-neu-720x324.jpeg",720,324,true],"image-960":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/09\/Chefredakteur-neu-960x432.jpeg",960,432,true],"image-1168":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/09\/Chefredakteur-neu.jpeg",1000,450,false],"image-1440":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/09\/Chefredakteur-neu.jpeg",1000,450,false],"image-1920":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/09\/Chefredakteur-neu.jpeg",1000,450,false],"1536x1536":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/09\/Chefredakteur-neu.jpeg",1000,450,false],"2048x2048":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/09\/Chefredakteur-neu.jpeg",1000,450,false],"trp-custom-language-flag":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/09\/Chefredakteur-neu-18x8.jpeg",18,8,true],"bricks_large_16x9":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/09\/Chefredakteur-neu.jpeg",1000,450,false],"bricks_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/09\/Chefredakteur-neu.jpeg",1000,450,false],"bricks_large_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/09\/Chefredakteur-neu.jpeg",1000,450,false],"bricks_medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/09\/Chefredakteur-neu-600x270.jpeg",600,270,true],"bricks_medium_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/09\/Chefredakteur-neu-600x450.jpeg",600,450,true],"profile_24":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/09\/Chefredakteur-neu-24x24.jpeg",24,24,true],"profile_48":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/09\/Chefredakteur-neu-48x48.jpeg",48,48,true],"profile_96":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/09\/Chefredakteur-neu-96x96.jpeg",96,96,true],"profile_150":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/09\/Chefredakteur-neu-150x150.jpeg",150,150,true],"profile_300":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/09\/Chefredakteur-neu-300x300.jpeg",300,300,true]},"post_excerpt_stackable_v2":"<p>KI liefert immer spektakul\u00e4rere Ergebnisse und dringt in immer mehr Gesch\u00e4ftsfelder vor, aber die B\u00f6rsenkurse der IT-Anbieter, die von diesem KI-Hype profitieren sollten, sinken. Was l\u00e4uft falsch mit der k\u00fcnstlichen Intelligenz?<\/p>\n","category_list_v2":"<a href=\"https:\/\/e326.greatsolution.dev\/es\/categoria\/blog-del-jefe-redactor-2\/\" rel=\"category tag\">Chefredakteur-Blog<\/a>","author_info_v2":{"name":"Peter M. F\u00e4rbinger, E3 Magazine","url":"https:\/\/e326.greatsolution.dev\/es\/author\/peter-m-faerbinger-e-3-magazin\/"},"comments_num_v2":"0 comentarios","_links":{"self":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/154113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/comments?post=154113"}],"version-history":[{"count":4,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/154113\/revisions"}],"predecessor-version":[{"id":154149,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/154113\/revisions\/154149"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/media\/132122"}],"wp:attachment":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/media?parent=154113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/categories?post=154113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/tags?post=154113"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/coauthors?post=154113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}