{"id":2017,"date":"2016-12-08T02:00:26","date_gmt":"2016-12-08T01:00:26","guid":{"rendered":"https:\/\/e326.greatsolution.dev\/?p=2017"},"modified":"2022-02-06T14:42:07","modified_gmt":"2022-02-06T13:42:07","slug":"mobile-natives-out-in-the-field","status":"publish","type":"post","link":"https:\/\/e326.greatsolution.dev\/es\/mobile-natives-out-in-the-field\/","title":{"rendered":"Nativos m\u00f3viles sobre el terreno"},"content":{"rendered":"<h3>El m\u00f3vil a\u00fan no es algo habitual<\/h3>\n<p>Tambi\u00e9n en el <span id=\"urn:local-text-annotation-ndmqx81z6fsd994c7sd6o1lrfg79xi54\" class=\"textannotation disambiguated wl-thing\">Vida profesional<\/span> un dispositivo m\u00f3vil con acceso a Internet pertenece a la mayor\u00eda de nosotros, que seguimos la <span id=\"urn:local-text-annotation-ajy4lsng7w4ei13aubrrdc8hjv3edh61\" class=\"textannotation disambiguated wl-thing\">Generaci\u00f3n<\/span> Los inmigrantes m\u00f3viles forman parte de la vida cotidiana desde hace a\u00f1os.<\/p>\n<p>Pero todav\u00eda hay <span id=\"urn:local-text-annotation-i2uiezhuaedz3at7o6dpef9m5hzvfsym\" class=\"textannotation disambiguated wl-thing\">Industrias<\/span> y zonas de trabajo donde esto no es algo habitual. Sin embargo, esto est\u00e1 cambiando ahora con los nativos m\u00f3viles, cada vez m\u00e1s numerosos en el <span id=\"urn:local-text-annotation-7q7egox58jw0d8busfbivmrsi9tbtgqf\" class=\"textannotation disambiguated wl-thing\">Vida profesional<\/span> convertirse.<\/p>\n<p><span id=\"urn:local-text-annotation-lavo07pvwqbvcpt9eoic5l4o7xoqu6to\" class=\"textannotation disambiguated wl-place\">Mercanc\u00edas<\/span> Hace unos a\u00f1os, el personal de campo o los t\u00e9cnicos de servicio a\u00fan se mostraban esc\u00e9pticos cuando se trataba de sustituir el papel por una soluci\u00f3n m\u00f3vil, ahora se dice cada vez con m\u00e1s frecuencia cuando los compa\u00f1eros m\u00e1s j\u00f3venes empiezan en una nueva empresa:<\/p>\n<p><em>\"\u00bfPor qu\u00e9 no tenemos todav\u00eda una soluci\u00f3n m\u00f3vil para esto? \u00bfY d\u00f3nde est\u00e1 mi tableta con la que puedo tramitar los pedidos?\".<\/em><\/p>\n<p>Por tanto, las empresas tambi\u00e9n tienen que considerarse empleadoras de las generaciones m\u00e1s j\u00f3venes. <span id=\"urn:local-text-annotation-ek8lcn1n4w7m58z1jmpfqpfgskx9ehdd\" class=\"textannotation disambiguated wl-thing\">Generaci\u00f3n<\/span> quieren seguir siendo atractivas, con aplicaciones m\u00f3viles para <span id=\"urn:local-text-annotation-j313p2alkxtmka6tm0vngklwo9mkxr5s\" class=\"textannotation disambiguated wl-thing\">Procesos empresariales<\/span> tratar con.<\/p>\n<p>Y esto tambi\u00e9n concierne sobre todo a <span id=\"urn:local-text-annotation-2jj1w2zceqqiccrzlhdymxp98y12snqn\" class=\"textannotation disambiguated wl-thing\">Industrias<\/span> y sectores que han sido reacios a hacerlo en el pasado, como los proveedores de energ\u00eda o la industria t\u00e9cnica. <span id=\"urn:local-text-annotation-sc1oi7v3kijdyosldv5dawymvk3oyc0n\" class=\"textannotation disambiguated wl-thing\">Servicio de campo<\/span>.<\/p>\n<h3>El m\u00f3vil aumenta la motivaci\u00f3n<\/h3>\n<p>En los pr\u00f3ximos a\u00f1os, los m\u00f3viles actuales <span id=\"urn:local-text-annotation-kedj3nvkwp5h0m14sdcypsz5ety9lrme\" class=\"textannotation disambiguated wl-thing\">Tendencias<\/span> la mecanizaci\u00f3n en la <span id=\"urn:local-text-annotation-jsqrxhj30rkqyglpxkjdmre5da01ibrs\" class=\"textannotation disambiguated wl-thing\">Servicio de campo<\/span> y en el <span id=\"urn:local-text-annotation-y5v8myvjwxjfjda1spc5pcy63ugpkqr2\" class=\"textannotation disambiguated wl-thing\">Mantenimiento<\/span> avanzar m\u00e1s.<\/p>\n<p>Por un lado, esto permite a los <span id=\"urn:local-text-annotation-jo39l5gd5cnosxm5wxv0kqdsk6vygokx\" class=\"textannotation disambiguated wl-thing\">Confort<\/span> y el <span id=\"urn:local-text-annotation-i41b5fcosxv2ezlbfetjo3po78q2msi5\" class=\"textannotation disambiguated wl-thing\">Motivaci\u00f3n<\/span> de los t\u00e9cnicos de servicio sobre el terreno y, por otro, aumentar la calidad del servicio al cliente.<\/p>\n<p>Tomemos el ejemplo de los wearables: En <span id=\"urn:local-text-annotation-5rvz03psw8maszxwi2o83pi8gr61be20\" class=\"textannotation disambiguated wl-thing\">Consumidores<\/span>-Los ordenadores port\u00e1tiles, como los smartwatches, hace tiempo que llegaron al mercado.<\/p>\n<p>En el mundo profesional siguen siendo un <span id=\"urn:local-text-annotation-shaiajgn4uf8zd3ornf7gngr5cv1eihl\" class=\"textannotation disambiguated wl-thing\">Tendencia<\/span>ya que hasta ahora las aplicaciones han sido la excepci\u00f3n y no la regla. Pero aqu\u00ed tambi\u00e9n hay potencial.<\/p>\n<p>En el futuro, el t\u00e9cnico de servicio podr\u00eda recibir un impulso a trav\u00e9s de su smartwatch cuando le llamen para una aver\u00eda urgente, en lugar de recibir un SMS o una llamada en su tel\u00e9fono m\u00f3vil como hasta ahora.<\/p>\n<p>As\u00ed, los wearables pueden mejorar la satisfacci\u00f3n del cliente y la calidad de vida gracias a tiempos de respuesta y reparaci\u00f3n m\u00e1s r\u00e1pidos. <span id=\"urn:local-text-annotation-6jtxzneo7mw8h8qwoeqq9pgbe380mlzc\" class=\"textannotation disambiguated wl-thing\">Motivaci\u00f3n<\/span> el <span id=\"urn:local-text-annotation-x5wznd6afsm5zzr6e4aeztwf1tc4jl4n\" class=\"textannotation disambiguated wl-thing\">T\u00e9cnico<\/span> aumentar.<\/p>\n<p>El volumen de mercado previsto en el sector de los wearables es enorme. El instituto de estudios de mercado Abi Research espera que se vendan 485 millones de dispositivos a finales de 2018.<\/p>\n<h3>Realidad aumentada<\/h3>\n<p>El tema de la realidad aumentada tambi\u00e9n encuentra cada vez m\u00e1s aplicaciones en \u00e1mbitos profesionales.<\/p>\n<p><span id=\"urn:local-text-annotation-tfsdg6hmkps2f0un5bxfktm9ka5etos7\" class=\"textannotation disambiguated wl-place\">Mercanc\u00edas<\/span> Vasos de datos para <span id=\"urn:local-text-annotation-zold5bi5fozi3zltdxr0jw0sjp4y621d\" class=\"textannotation disambiguated wl-thing\">Consumidores<\/span> m\u00e1s bien un fracaso hasta ahora, abren posibilidades completamente nuevas a los t\u00e9cnicos de servicio sobre el terreno.<\/p>\n<p>Muestran al usuario informaci\u00f3n adicional en forma de mapas, despieces e im\u00e1genes, lo que le permite realizar sus tareas con mayor profesionalidad y rapidez.<\/p>\n<p>Hoy en d\u00eda, por ejemplo, un instalador del sector de los servicios p\u00fablicos podr\u00eda ver literalmente el trazado de la tuber\u00eda de gas, agua o electricidad en sus gafas de datos accediendo a un sistema de geoinformaci\u00f3n, aunque la tuber\u00eda se encuentre a cinco metros bajo la superficie.<\/p>\n<p>En el futuro, tambi\u00e9n se pueden concebir varios escenarios en el \u00e1mbito de la ingenier\u00eda de instalaciones. Por ejemplo, un montador de ascensores podr\u00eda visualizar el despiece del ascensor a trav\u00e9s de las gafas de datos y tendr\u00eda las dos manos libres para realizar las reparaciones. <span id=\"urn:local-text-annotation-d52h3ugiaj4gsrq9uexb5e6outeamg2j\" class=\"textannotation disambiguated wl-thing\">gratis<\/span>.<\/p>\n<p>Hoy en d\u00eda, sin embargo, esto sigue siendo una quimera, ya que a\u00fan faltan datos en 3D para este escenario.<\/p>\n<h3>Manos libres<\/h3>\n<p>El espectacular aumento de la potencia inform\u00e1tica y la capacidad de almacenamiento de los dispositivos m\u00f3viles en los \u00faltimos a\u00f1os tambi\u00e9n permite una <span id=\"urn:local-text-annotation-1e2thn9ueau9htjdi6mznfryres6zfyh\" class=\"textannotation disambiguated wl-thing\">Confort<\/span> durante la interacci\u00f3n.<\/p>\n<p>Los actuales tel\u00e9fonos inteligentes o tabletas reconocen el habla natural sin mucho entrenamiento previo por parte del usuario, incluso en entornos desfavorables con ruido de fondo.<\/p>\n<p>Esto facilita el funcionamiento en situaciones en las que el <span id=\"urn:local-text-annotation-crk6d6f4rmfh4qx4a4fsf27ikkrve4b9\" class=\"textannotation disambiguated wl-thing\">T\u00e9cnico<\/span> o m\u00e1s en forma ambas manos <span id=\"urn:local-text-annotation-ljmfsddixht61w2rzpdleisrlmuh0z3t\" class=\"textannotation disambiguated wl-thing\">gratis<\/span> debe tener, como en la recogida de datos de medici\u00f3n.<\/p>\n<p>De estos ejemplos se desprende que el futuro est\u00e1 en el campo del servicio t\u00e9cnico de campo y <span id=\"urn:local-text-annotation-tom5mxjs2wsatd8rtdsheje2pismuf5w\" class=\"textannotation disambiguated wl-thing\">Mantenimiento<\/span> radica en las aplicaciones m\u00f3viles que contribuyen a ello, <span id=\"urn:local-text-annotation-9lalobf6ic79fq3i8sioj8qfgv7hb1dk\" class=\"textannotation disambiguated wl-thing\">Procesos empresariales<\/span> en las empresas de forma m\u00e1s r\u00e1pida, c\u00f3moda y sencilla.<\/p>\n<p>El nuevo <span id=\"urn:local-text-annotation-ehm006n58frrftul9h5hq40tp7xppmyc\" class=\"textannotation disambiguated wl-thing\">Generaci\u00f3n<\/span> el <span id=\"urn:local-text-annotation-mb9at2gil259ma2rbsrmeys39719wgkc\" class=\"textannotation disambiguated wl-thing\">T\u00e9cnico<\/span> contribuir\u00e1 a impulsar esta iniciativa gracias a su experiencia digital y su afinidad con la telefon\u00eda m\u00f3vil.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/es\/socios\/mobilex-ag\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" title=\"Nativos m\u00f3viles en exteriores\" class=\"aligncenter wp-image-11371 size-full\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/03\/CI-MOBILEx.jpg\" alt=\"https:\/\/e326.greatsolution.dev\/partners\/mobilex-ag\/\" width=\"1000\" height=\"112\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/03\/CI-MOBILEx.jpg 1000w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/03\/CI-MOBILEx-768x86.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/03\/CI-MOBILEx-100x11.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/03\/CI-MOBILEx-480x54.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/03\/CI-MOBILEx-640x72.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/03\/CI-MOBILEx-720x81.jpg 720w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/03\/CI-MOBILEx-960x108.jpg 960w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>El acceso a Internet, a la informaci\u00f3n y al entretenimiento, as\u00ed como el intercambio constante con los amigos dondequiera que se encuentre: esto caracteriza a la generaci\u00f3n de nativos m\u00f3viles que crecen o han crecido con tel\u00e9fonos inteligentes y tabletas.<\/p>","protected":false},"author":63,"featured_media":4163,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[10,7,740],"tags":[90,89,651,656],"coauthors":[21836],"class_list":["post-2017","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-das-aktuelle-stichwort","category-meinung","category-mag1612","tag-apps","tag-mobil","tag-mobile","tag-modernisierung","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",1000,431,false],"thumbnail":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort-150x150.jpg",150,150,true],"medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",400,172,false],"medium_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort-768x331.jpg",768,331,true],"large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",1000,431,false],"image-100":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort-100x43.jpg",100,43,true],"image-480":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort-480x207.jpg",480,207,true],"image-640":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort-640x276.jpg",640,276,true],"image-720":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort-720x310.jpg",720,310,true],"image-960":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort-960x414.jpg",960,414,true],"image-1168":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",1000,431,false],"image-1440":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",1000,431,false],"image-1920":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",1000,431,false],"1536x1536":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",1000,431,false],"2048x2048":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",1000,431,false],"trp-custom-language-flag":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",1000,431,false],"bricks_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",1000,431,false],"bricks_large_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",1000,431,false],"bricks_medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",600,259,false],"bricks_medium_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",600,259,false],"profile_24":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort-24x24.jpg",24,24,true],"profile_48":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort-48x48.jpg",48,48,true],"profile_96":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort-96x96.jpg",96,96,true],"profile_150":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort-150x150.jpg",150,150,true],"profile_300":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Der Zugriff aufs Internet, auf Informationen und Unterhaltung sowie der st\u00e4ndige Austausch mit Freunden, wo auch immer man sich gerade befindet \u2013 das charakterisiert die Generation der Mobile Na\u00adtives, die mit Smartphones und Tablets aufwachsen bzw. aufgewachsen sind.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e326.greatsolution.dev\/es\/categoria\/opinion\/la-palabra-clave-actual\/\" rel=\"category tag\">Das aktuelle Stichwort<\/a>, <a href=\"https:\/\/e326.greatsolution.dev\/es\/categoria\/opinion\/\" rel=\"category tag\">Die Meinung der SAP-Community<\/a>, <a href=\"https:\/\/e326.greatsolution.dev\/es\/categoria\/le-gusta1612\/\" rel=\"category tag\">MAG 16-12<\/a>","author_info_v2":{"name":"Hannes Heckner, MobileX","url":"https:\/\/e326.greatsolution.dev\/es\/author\/hannes-heckner\/"},"comments_num_v2":"0 comentarios","_links":{"self":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/2017","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/comments?post=2017"}],"version-history":[{"count":0,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/2017\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/media\/4163"}],"wp:attachment":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/media?parent=2017"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/categories?post=2017"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/tags?post=2017"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/coauthors?post=2017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}