{"id":28943,"date":"2017-09-28T00:01:06","date_gmt":"2017-09-27T22:01:06","guid":{"rendered":"https:\/\/e326.greatsolution.dev\/?p=28943"},"modified":"2019-03-11T11:51:33","modified_gmt":"2019-03-11T10:51:33","slug":"buenas-practicas-de-codigo-abierto-incluso-para-empresas-que-no-lo-utilizan","status":"publish","type":"post","link":"https:\/\/e326.greatsolution.dev\/es\/buenas-practicas-de-codigo-abierto-incluso-para-empresas-que-no-lo-utilizan\/","title":{"rendered":"\u00bfLa mejor pr\u00e1ctica para el c\u00f3digo abierto tambi\u00e9n para las empresas que no utilizan \"ninguno\"?"},"content":{"rendered":"<p>Eso me sorprende, porque los expertos informan de que los componentes de c\u00f3digo abierto se encuentran en cerca del 99% de las auditor\u00edas de software. Los motivos de estas auditor\u00edas son las negociaciones con revendedores como SAP, las absorciones de empresas, las rondas de financiaci\u00f3n estrat\u00e9gica o los controles de conformidad y seguridad.<\/p>\n<p>Por regla general, se encuentran cientos, a veces miles, de componentes de c\u00f3digo abierto diferentes. Los expertos de los analistas llevan tiempo informando de que hoy en d\u00eda normalmente un tercio del c\u00f3digo de las aplicaciones est\u00e1 formado por componentes de c\u00f3digo abierto.<\/p>\n<p>Esto tambi\u00e9n se aplica a la comunidad SAP, donde Android, Apache, Git, Java, Linux, Maven, OpenStack, Spring y cientos de otros componentes m\u00e1s peque\u00f1os o m\u00e1s grandes desempe\u00f1an un papel cada vez m\u00e1s importante en TI.<\/p>\n<p>As\u00ed que me pregunto c\u00f3mo debo interpretar la declaraci\u00f3n en respuesta a mi pregunta inicial. \u00bfMi interlocutor no tiene una visi\u00f3n general del desarrollo interno de software, la empresa no es consciente o es indiferente a lo que hacen sus desarrolladores de software? \u00bfRealmente no se utiliza el c\u00f3digo abierto y, por tanto, no se aprovecha el importante potencial de innovaci\u00f3n y ahorro de costes?<\/p>\n<p>\u00bfPor qu\u00e9 es importante saber si se utiliza el c\u00f3digo abierto y en qu\u00e9 medida? El dicho \"lo que no s\u00e9 no me hace da\u00f1o\" no protege ni a las empresas ni a los directivos en caso de problemas cr\u00edticos. Mientras no se sepa si se est\u00e1 utilizando c\u00f3digo abierto, d\u00f3nde y qu\u00e9, no puede haber una protecci\u00f3n eficaz.<\/p>\n<p>\u00bfPor qu\u00e9 es necesario? Los componentes de c\u00f3digo abierto pueden contener tipos de licencia poco claros o incluso virales, que en algunos casos ya han provocado costosas disputas legales con los desarrolladores de c\u00f3digo abierto.<\/p>\n<p>Mientras tanto, al igual que ocurre con las patentes, existen los llamados trolls que atacan a las empresas y \"ganan\" millones con ello. Dado que m\u00e1s de la mitad de las auditor\u00edas revelan tipos de licencia desconocidos para la direcci\u00f3n en cuesti\u00f3n o componentes con licencias GPL cr\u00edticas, el riesgo potencial es muy alto.<\/p>\n<p>Tambi\u00e9n se conocen casos en los que adquisiciones de empresas, inversiones o acuerdos OEM han \"reventado\" o el valor de las empresas ha ca\u00eddo dr\u00e1sticamente. A diferencia de las aplicaciones m\u00f3viles, los usuarios de c\u00f3digo abierto no suelen ser informados autom\u00e1ticamente de las nuevas versiones.<\/p>\n<p>Como consecuencia, las empresas suelen utilizar versiones obsoletas que contienen errores cr\u00edticos y lagunas de seguridad conocidas desde hace tiempo. Los desarrolladores tienen que ser activos ellos mismos y averiguar laboriosamente las actualizaciones. Los piratas inform\u00e1ticos tambi\u00e9n lo hacen y utilizan la informaci\u00f3n de bases de datos como OWASP.org para realizar ataques selectivos a trav\u00e9s de componentes inseguros.<\/p>\n<h3>Evite riesgos con las mejores pr\u00e1cticas<\/h3>\n<p>Es importante establecer primero el alcance del uso, aunque no se utilice \"oficialmente\" ning\u00fan c\u00f3digo abierto. Las empresas deben definir un proceso en el que se regule el uso y, si es posible, se supervise autom\u00e1ticamente sin obstaculizar el desarrollo.<\/p>\n<p>Empresas como SAP, Seeburger y Xing demuestran que esto es posible sin problemas asegurando la implantaci\u00f3n mediante procesos \u00e1giles y software de supervisi\u00f3n. Esto protege frente a riesgos comerciales, as\u00ed como a la hora de cumplir requisitos legales como la Ley de Seguridad Inform\u00e1tica.<\/p>\n<p>Mientras tanto, existen algunas soluciones comerciales propietarias, sobre todo de EE.UU. e Israel, pero esto parece algo parad\u00f3jico para la supervisi\u00f3n del software de c\u00f3digo abierto.<\/p>\n<p>Soluciones como VersionEye de Mannheim adoptan aqu\u00ed un enfoque diferente, son ellas mismas 100 por cien de c\u00f3digo abierto (licencia Apache) y tambi\u00e9n pueden utilizarse gratuitamente para una supervisi\u00f3n totalmente autom\u00e1tica en lo que respecta a versiones, licencias y posibles riesgos de seguridad.<\/p>","protected":false},"excerpt":{"rendered":"<p>A menudo, cuando pregunto a los directores generales o ejecutivos del ecosistema SAP hasta qu\u00e9 punto se utiliza el c\u00f3digo abierto en su empresa, obtengo la respuesta: \"\u00a1NOSOTROS no utilizamos ninguno!\" <\/p>","protected":false},"author":1984,"featured_media":2685,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[22,7,17703],"tags":[104,797,92,67,506,301,236],"coauthors":[37235],"class_list":["post-28943","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-open-source","category-meinung","category-mag-1710","tag-android","tag-apache","tag-java","tag-linux","tag-open-source","tag-openstack","tag-sap","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source.jpg",1000,435,false],"thumbnail":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source-150x150.jpg",150,150,true],"medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source.jpg",400,174,false],"medium_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source-768x334.jpg",768,334,true],"large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source.jpg",1000,435,false],"image-100":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source-100x44.jpg",100,44,true],"image-480":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source-480x209.jpg",480,209,true],"image-640":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source-640x278.jpg",640,278,true],"image-720":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source-720x313.jpg",720,313,true],"image-960":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source-960x418.jpg",960,418,true],"image-1168":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source.jpg",1000,435,false],"image-1440":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source.jpg",1000,435,false],"image-1920":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source.jpg",1000,435,false],"1536x1536":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source.jpg",1000,435,false],"2048x2048":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source.jpg",1000,435,false],"trp-custom-language-flag":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source.jpg",1000,435,false],"bricks_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source.jpg",1000,435,false],"bricks_large_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source.jpg",1000,435,false],"bricks_medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source.jpg",600,261,false],"bricks_medium_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source.jpg",600,261,false],"profile_24":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source-24x24.jpg",24,24,true],"profile_48":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source-48x48.jpg",48,48,true],"profile_96":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source-96x96.jpg",96,96,true],"profile_150":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source-150x150.jpg",150,150,true],"profile_300":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Open-Source-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Oft erhalte ich auf meine Frage an SAP-Ecosystem-Gesch\u00e4ftsf\u00fchrer oder F\u00fchrungskr\u00e4fte, in welchem Umfang in ihrem Unternehmen Open Source genutzt wird, die Antwort: \u201eWIR setzen keine ein!\u201c <\/p>\n","category_list_v2":"<a href=\"https:\/\/e326.greatsolution.dev\/es\/categoria\/opinion\/codigo-abierto\/\" rel=\"category tag\">Open Source Kolumne<\/a>, <a href=\"https:\/\/e326.greatsolution.dev\/es\/categoria\/opinion\/\" rel=\"category tag\">Die Meinung der SAP-Community<\/a>, <a href=\"https:\/\/e326.greatsolution.dev\/es\/categoria\/mag-1710\/\" rel=\"category tag\">MAG 17-10<\/a>","author_info_v2":{"name":"Ralf Meyer, Synomic","url":"https:\/\/e326.greatsolution.dev\/es\/author\/ralf-meyer-synomic\/"},"comments_num_v2":"0 comentarios","_links":{"self":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/28943","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/users\/1984"}],"replies":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/comments?post=28943"}],"version-history":[{"count":0,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/28943\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/media\/2685"}],"wp:attachment":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/media?parent=28943"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/categories?post=28943"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/tags?post=28943"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/coauthors?post=28943"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}