{"id":36608,"date":"2018-02-23T08:33:19","date_gmt":"2018-02-23T07:33:19","guid":{"rendered":"https:\/\/e326.greatsolution.dev\/?p=32990"},"modified":"2025-07-12T16:17:44","modified_gmt":"2025-07-12T14:17:44","slug":"desmantelamiento-sap-aplicaciones","status":"publish","type":"post","link":"https:\/\/e326.greatsolution.dev\/es\/desmantelamiento-sap-aplicaciones\/","title":{"rendered":"Desmantelamiento de aplicaciones SAP"},"content":{"rendered":"<p>Las empresas siempre han estado interesadas en desmantelar los sistemas SAP en cuanto ya no necesitan estar constantemente disponibles para los procesos de la empresa. El desmantelamiento siempre va de la mano de la expectativa de una reducci\u00f3n de costes: se pueden ahorrar costes operativos y de licencias. Por ejemplo, cuando se venden empresas o partes de empresas o cuando se reorganizan empresas. Pero tambi\u00e9n cuando se cambia de R\/2 a R\/3 o ERP ECC, o ahora cada vez m\u00e1s cuando se cambia al S\/4 basado en Hana.<\/p>\n<p>Si se sustituye un sistema heredado por un nuevo entorno de sistemas basado en un enfoque greenfield, pr\u00e1cticamente siempre existe la necesidad de conservar determinados datos tras el desmantelamiento del sistema y ponerlos a disposici\u00f3n para diversos fines de an\u00e1lisis. Por ejemplo, para auditor\u00edas fiscales, auditor\u00edas de la seguridad social, auditor\u00edas internas y an\u00e1lisis de datos, responsabilidad por productos defectuosos, etc.<\/p>\n<p>Determinar qu\u00e9 datos de una base de datos y\/o de un sistema de archivo deben seguir estando disponibles en detalle tras el cierre de un sistema SAP es una tarea ardua. Por regla general, un equipo de diferentes departamentos es responsable de un proyecto de este tipo en una empresa, en el que posiblemente tambi\u00e9n participe una empresa de consultor\u00eda externa que aporte amplios conocimientos o experiencia en el desmantelamiento\/definici\u00f3n de sistemas SAP. Extraer todos los datos de un sistema SAP que se va a dar de baja para poder utilizarlo m\u00e1s adelante o seguir utiliz\u00e1ndolo no es muy conveniente por razones de coste y esfuerzo.<\/p>\n<p>El esfuerzo o la duraci\u00f3n de un desmantelamiento de un sistema SAP de este tipo puede variar enormemente. Hay proyectos que pueden realizarse en unos diez d\u00edas, pero tambi\u00e9n pueden requerir 100 d\u00edas-hombre o m\u00e1s, en funci\u00f3n del n\u00famero de sociedades que se tengan en cuenta o de la diversidad de los datos SAP que deban extraerse. En cualquier caso, esto deber\u00eda considerarse en una fase temprana, preferiblemente cuando se decida desmantelar aplicaciones SAP o antes del plan real para cambiar a S\/4 Hana, por ejemplo.<\/p>\n<h3>A la medida de SAP<\/h3>\n<p>PBS Software es probablemente el \u00fanico socio de SAP en el mundo que lleva muchos a\u00f1os ofreciendo una soluci\u00f3n complementaria espec\u00edfica para el desmantelamiento de sistemas SAP como parte de su cartera de productos de gesti\u00f3n del ciclo de vida de la informaci\u00f3n. Como todas las soluciones complementarias de SAP, es distribuida por PBS y sus socios o utilizada por empresas asociadas o consultoras en proyectos de desmantelamiento relacionados con SAP.<\/p>\n<p>Se trata de una soluci\u00f3n est\u00e1ndar \u00e1gil y econ\u00f3mica. Es una alternativa a la soluci\u00f3n SAP ILM con la que SAP cubre el tema del desmantelamiento de SAP. Con la soluci\u00f3n SAP se pueden llevar a cabo incluso las mayores necesidades de desmantelamiento, pero para ello siguen siendo necesarias aplicaciones SAP en funcionamiento, como ERP y BW. En cambio, la soluci\u00f3n PBS ya no requiere un sistema SAP en funcionamiento tras el desmantelamiento.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/01\/Detlev-Steinbinder.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-32994\" title=\"Desmantelamiento de aplicaciones sap\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/01\/Detlev-Steinbinder.jpg\" alt=\"Detlev Steinbinder, PBS\" width=\"800\" height=\"356\" \/><\/a><\/p>\n<p>La soluci\u00f3n PBS consta esencialmente de dos componentes: Por un lado, el denominado PBS Content Extractor (CONEX) garantiza que los datos puedan extraerse\/liberarse de los sistemas SAP en un formato transparente; por otro lado, el segundo componente, el PBS Enterprise Content Store basado en PC\/Windows, garantiza que los datos extra\u00eddos puedan gestionarse, protegerse, filtrarse, visualizarse o tambi\u00e9n utilizarse con fines de an\u00e1lisis a trav\u00e9s de vistas especialmente preparadas seg\u00fan sea necesario.<\/p>\n<p>Una de las principales ventajas de la soluci\u00f3n es que ofrece funciones f\u00e1ciles de usar para manejar o evaluar datos SAP y, por tanto, la posibilidad de que los usuarios que no son de SAP realicen b\u00fasquedas de datos de forma sencilla.<\/p>\n<h3>Transparencia a raudales<\/h3>\n<p>\u00bfQu\u00e9 significa software est\u00e1ndar en este contexto? \u00bfQu\u00e9 tiene de especial la soluci\u00f3n PBS para el desmantelamiento de sistemas SAP? Por un lado, utiliza un procedimiento estandarizado y probado para extraer datos que pueden rastrearse en cualquier momento. Los objetos de extracci\u00f3n se crean y utilizan para que coincidan con los respectivos datos de aplicaci\u00f3n en el entorno SAP. En concreto, se generan o crean objetos especialmente utilizables, por ejemplo, un documento FI, un documento SD u objetos dedicados para datos de producci\u00f3n.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/01\/Grafik-PBS-infra-1802.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-33004\" title=\"Desmantelamiento de aplicaciones sap\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/01\/Grafik-PBS-infra-1802.jpg\" alt=\"Gr\u00e1fico PBS Infra 1802\" width=\"700\" height=\"447\" \/><\/a><\/p>\n<h3>Objetos personalizados - Tablas Z<\/h3>\n<p>Tambi\u00e9n pueden crearse objetos personalizados. Esto significa que pueden incluirse en la extracci\u00f3n tablas adicionales, especialmente tablas espec\u00edficas de clientes, las denominadas \"tablas Z\". Tambi\u00e9n es posible integrar ficheros de archivo SAP (ADK) en la extracci\u00f3n. Las empresas tambi\u00e9n tienen la opci\u00f3n de integrar o transferir informaci\u00f3n no estructurada, como documentos y listas de impresi\u00f3n de un sistema DMS existente por referencia, adem\u00e1s de los datos de la tabla. Esta informaci\u00f3n tambi\u00e9n estar\u00e1 disponible en el PBS Enterprise Content Store para su uso en an\u00e1lisis tras una parada del sistema SAP.<\/p>\n<h3>Ficheros SAP DART para auditor\u00edas de empresas<\/h3>\n<p>ECS tambi\u00e9n puede utilizarse para importar y procesar archivos SAP DART. Muchos clientes utilizan DART para generar extractos de datos para la transferencia de datos relevantes para los impuestos en el contexto de las auditor\u00edas fiscales. El PBS Enterprise Content Store ofrece muchas m\u00e1s funcionalidades que un sistema de archivo est\u00e1ndar. Con esta soluci\u00f3n de PBS, no s\u00f3lo se pueden visualizar y navegar en tablas SAP o datos SAP, sino que tambi\u00e9n se pueden seguir procesando o utilizar para una amplia variedad de prop\u00f3sitos.<\/p>\n<p>Por ejemplo, para imprimir, para crear archivos Excel, para la visualizaci\u00f3n de documentos SAP de tipo transaccional basados en transacciones SAP o con fines anal\u00edticos (tambi\u00e9n con vistas predefinidas para la evaluaci\u00f3n de datos SAP o en conexi\u00f3n con herramientas de an\u00e1lisis como SAP Crystal Reports o SQL Server Business Intelligence).<\/p>\n<p>Por supuesto, tambi\u00e9n existen funciones de comprobaci\u00f3n o prueba que garantizan que las extracciones de datos realizadas se corresponden exactamente con las acordadas, adem\u00e1s de una administraci\u00f3n de usuarios y un control de acceso de gran alcance (a documentos SAP, listas de impresi\u00f3n y extractos).<\/p>\n<h3>Adecuado a las necesidades<\/h3>\n<p>Est\u00e1 en la naturaleza de lo que es el desmantelamiento del sistema SAP: despu\u00e9s de una extracci\u00f3n de datos\/extracci\u00f3n de datos completada de un sistema SAP heredado con un uso \u00fanico de facto durante un cierto periodo de tiempo, el componente para la extracci\u00f3n de datos (Content Extractor) no se necesita de forma permanente. Precisamente por eso se ofrece tambi\u00e9n como software de alquiler.<\/p>\n<p>La situaci\u00f3n es diferente para el otro componente, el sistema de almacenamiento de contenidos empresariales basado en PC, incluida la base de datos SQL a la que se importaron los datos de SAP. Se utiliza o se pone en funcionamiento mientras sea necesario almacenar los datos correspondientes. Si algunos de los datos dejan de ser necesarios, basta con borrarlos de la base de datos. La regla general es: cuanto m\u00e1s tiempo se almacenen los datos, mejor. Al fin y al cabo, nunca se sabe cu\u00e1nto tiempo se van a necesitar determinados datos. Por cierto, PBS est\u00e1 evaluando la posibilidad de ofrecer este componente como una soluci\u00f3n en la nube en el futuro.<\/p>\n<p>En principio, la soluci\u00f3n est\u00e1ndar para el desmantelamiento de sistemas SAP presentada es apta para su uso en todos los sistemas o m\u00f3dulos de aplicaci\u00f3n SAP (incluidas las soluciones sectoriales) y ya ha demostrado su eficacia en numerosos proyectos nacionales e internacionales.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/es\/socios\/pbs-software-gmbh\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-25154 size-full\" title=\"Desmantelamiento de aplicaciones sap\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/07\/PBS-CI-Banner.jpg\" alt=\"https:\/\/e326.greatsolution.dev\/partners\/pbs-software-gmbh\/\" width=\"1000\" height=\"112\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/07\/PBS-CI-Banner.jpg 1000w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/07\/PBS-CI-Banner-768x86.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/07\/PBS-CI-Banner-100x11.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/07\/PBS-CI-Banner-480x54.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/07\/PBS-CI-Banner-640x72.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/07\/PBS-CI-Banner-720x81.jpg 720w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/07\/PBS-CI-Banner-960x108.jpg 960w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n<p><em>Cierre concreto de SAP:<\/em><\/p>\n<h3><span style=\"color: #a86500;\">Venta de una unidad de negocio<\/span><\/h3>\n<p>Pr\u00e1cticamente con la decisi\u00f3n de una empresa mediana (unos 200 empleados, alrededor de 50 millones de euros de facturaci\u00f3n) de vender una divisi\u00f3n de negocio, se trataba de dar de baja un sistema SAP ECC. Al mismo tiempo, la empresa fabricante, que no desea ser nombrada, ten\u00eda la obligaci\u00f3n de eliminar del sistema los datos SAP relevantes. \u00c9stos deb\u00edan seguir estando disponibles durante cierto tiempo despu\u00e9s del desmantelamiento. Principalmente por motivos de conservaci\u00f3n. Todo sali\u00f3 seg\u00fan lo previsto. Aproximadamente 40.000 documentos de facturaci\u00f3n de un DMS, unos 700 registros maestros de personal y varios miles de recibos de viaje (datos de RR.HH.) se extrajeron o transfirieron al PBS Enterprise Content Store mediante la soluci\u00f3n CONEX de PBS. El proyecto s\u00f3lo requiri\u00f3 diez d\u00edas-hombre, lo que permiti\u00f3 mantener los costes de implantaci\u00f3n dentro de los l\u00edmites presupuestarios establecidos.<\/p>","protected":false},"excerpt":{"rendered":"<p>El desmantelamiento del sistema SAP se est\u00e1 convirtiendo en un problema cada vez m\u00e1s importante debido al cambio de Business Suite a S\/4. En el proceso, los datos deben extraerse de un sistema heredado y poder utilizarse seg\u00fan sea necesario. Recurrir a una soluci\u00f3n est\u00e1ndar especialmente desarrollada aporta ventajas.<\/p>","protected":false},"author":1375,"featured_media":36793,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[5,20361],"tags":[15595,65,4067,20856,450,21219],"coauthors":[21842],"class_list":["post-36608","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-it-management","category-mag-1802","tag-erp-ecc","tag-hana","tag-pbs","tag-r-2","tag-r3","tag-s-4","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/shutterstock_665898385.jpg",1000,460,false],"thumbnail":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/shutterstock_665898385-150x150.jpg",150,150,true],"medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/shutterstock_665898385.jpg",400,184,false],"medium_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/shutterstock_665898385-768x353.jpg",768,353,true],"large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/shutterstock_665898385.jpg",1000,460,false],"image-100":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/shutterstock_665898385-100x46.jpg",100,46,true],"image-480":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/shutterstock_665898385-480x221.jpg",480,221,true],"image-640":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/shutterstock_665898385-640x294.jpg",640,294,true],"image-720":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/shutterstock_665898385-720x331.jpg",720,331,true],"image-960":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/shutterstock_665898385-960x442.jpg",960,442,true],"image-1168":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/shutterstock_665898385.jpg",1000,460,false],"image-1440":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/shutterstock_665898385.jpg",1000,460,false],"image-1920":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/shutterstock_665898385.jpg",1000,460,false],"1536x1536":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/shutterstock_665898385.jpg",1000,460,false],"2048x2048":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/shutterstock_665898385.jpg",1000,460,false],"trp-custom-language-flag":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/shutterstock_665898385.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/shutterstock_665898385.jpg",1000,460,false],"bricks_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/shutterstock_665898385.jpg",1000,460,false],"bricks_large_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/shutterstock_665898385.jpg",1000,460,false],"bricks_medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/shutterstock_665898385.jpg",600,276,false],"bricks_medium_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/shutterstock_665898385.jpg",600,276,false],"profile_24":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/shutterstock_665898385-24x24.jpg",24,24,true],"profile_48":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/shutterstock_665898385-48x48.jpg",48,48,true],"profile_96":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/shutterstock_665898385-96x96.jpg",96,96,true],"profile_150":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/shutterstock_665898385-150x150.jpg",150,150,true],"profile_300":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/shutterstock_665898385-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>SAP-Systemstilllegungen werden durch den Umstieg von der Business Suite zu S\/4 immer mehr zum Thema. Dabei m\u00fcssen Daten aus einem Altsystem extrahiert werden und bedarfsgerecht genutzt werden k\u00f6nnen. Der R\u00fcckgriff auf eine eigens entwickelte Standardl\u00f6sung bringt Vorteile.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e326.greatsolution.dev\/es\/categoria\/gestion-informatica\/\" rel=\"category tag\">IT-Management<\/a>, <a href=\"https:\/\/e326.greatsolution.dev\/es\/categoria\/mag-1802\/\" rel=\"category tag\">MAG 18-02<\/a>","author_info_v2":{"name":"Prof. Dr. Detlev Steinbinder, PBS","url":"https:\/\/e326.greatsolution.dev\/es\/author\/detlev-steinbinder\/"},"comments_num_v2":"1 comentario","_links":{"self":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/36608","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/users\/1375"}],"replies":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/comments?post=36608"}],"version-history":[{"count":2,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/36608\/revisions"}],"predecessor-version":[{"id":152427,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/36608\/revisions\/152427"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/media\/36793"}],"wp:attachment":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/media?parent=36608"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/categories?post=36608"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/tags?post=36608"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/coauthors?post=36608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}