{"id":4872,"date":"2016-11-01T00:14:15","date_gmt":"2016-10-31T23:14:15","guid":{"rendered":"https:\/\/e326.greatsolution.dev\/?p=4872"},"modified":"2022-02-06T14:42:59","modified_gmt":"2022-02-06T13:42:59","slug":"s4-hana-as-digital-backbone","status":"publish","type":"post","link":"https:\/\/e326.greatsolution.dev\/es\/s4-hana-as-digital-backbone\/","title":{"rendered":"S\/4 Hana como columna vertebral digital"},"content":{"rendered":"<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Sarah-Leichtweis-info.jpg\"><img loading=\"lazy\" decoding=\"async\" title=\"S\/4 hana como columna vertebral digital\" class=\"wp-image-4876 alignright\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Sarah-Leichtweis-info.jpg\" alt=\"Sarah Leichtweis, Pikon\" width=\"201\" height=\"387\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Sarah-Leichtweis-info.jpg 246w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Sarah-Leichtweis-info-100x193.jpg 100w\" sizes=\"auto, (max-width: 201px) 100vw, 201px\" \/><\/a>En el debate sobre <span id=\"urn:local-text-annotation-j6gt5jtart03d1yzjhmlkw2bksjaf8b9\" class=\"textannotation disambiguated wl-thing\">S\/4<\/span> A Hana le interesan sobre todo las siguientes preguntas: \u00bfQu\u00e9 valor a\u00f1adido, o mejor dicho, qu\u00e9 beneficio concreto aporta <span id=\"urn:local-text-annotation-nhwt1b0vs7ijbn12b8iem7n2kpfg7y9r\" class=\"textannotation disambiguated wl-thing\">S\/4<\/span> \u00bfHana? \u00bfEn qu\u00e9 plazo se amortizan las inversiones en licencias y hardware? \u00bfCu\u00e1ndo es el momento adecuado para el cambio? \u00bfCu\u00e1l es el escenario adecuado para el cambio: greenfield o brownfield? \u00bfCu\u00e1les son los efectos en los sistemas adyacentes (por ejemplo, almac\u00e9n empresarial, CRM, etc.)?<\/p>\n<p>Las respuestas a estas preguntas son tan variadas como las empresas en las que se plantean. En nuestra opini\u00f3n, sin embargo, hay algo que es igual en todas las empresas: las respuestas no solo deben darse desde el punto de vista de las funciones y posibilidades del nuevo sistema inform\u00e1tico S\/4 Hana.<\/p>\n<p>\u00bfQu\u00e9 queremos decir con esto? La propia SAP, en el curso de su comunicaci\u00f3n sobre <span id=\"urn:local-text-annotation-m6js18iqprrj8oy6eaat960hreaz9i9y\" class=\"textannotation disambiguated wl-thing\">S\/4<\/span> Hana el t\u00e9rmino \"<span id=\"urn:local-text-annotation-3zy1c39s3nt45s7ssrcaxje3oaaoj2kw\" class=\"textannotation disambiguated wl-thing\">ERP<\/span> como la \"columna vertebral digital\" de una empresa. Y creo que es un t\u00e9rmino extraordinariamente correcto y acertado.<\/p>\n<p>Un sistema ERP mapea casi toda la estructura organizativa de una empresa en sus diversas unidades contables legalmente independientes, ubicaciones de producci\u00f3n y almac\u00e9n y su organizaci\u00f3n de ventas (por nombrar s\u00f3lo algunas). Tambi\u00e9n contiene toda la informaci\u00f3n central sobre socios comerciales y productos.<\/p>\n<p>Sin embargo, lo m\u00e1s importante es la <span id=\"urn:local-text-annotation-9i3v2tcex0stto0yhrppfjn3pesgc3p7\" class=\"textannotation disambiguated wl-thing\">Procesos<\/span> de la empresa se mapean en el sistema. El abanico de posibilidades que ofrece la personalizaci\u00f3n es enorme, \u00a1ya hoy!<\/p>\n<p>Esto nos lleva a la idea central: el beneficio de una <span id=\"urn:local-text-annotation-p0lsdyx9o9eqj02m4l5uwpunh2oav3ip\" class=\"textannotation disambiguated wl-thing\">ERP<\/span>-sistema depende no s\u00f3lo de las estructuras y funciones del sistema, sino tambi\u00e9n de la <span id=\"urn:local-text-annotation-vt9yvr0c4ffkjby6hfajtnpqyf5zosts\" class=\"textannotation disambiguated wl-thing\">Calidad<\/span> la introducci\u00f3n, la <span id=\"urn:local-text-annotation-gx6yy4mwe6rpoyzjmmaltw6mnfiavh0m\" class=\"textannotation disambiguated wl-thing\">Calidad<\/span> el <span id=\"urn:local-text-annotation-hnbiag1g8tui6ress0z68lvingaak30u\" class=\"textannotation disambiguated wl-thing\">Datos<\/span> y el <span id=\"urn:local-text-annotation-13tqji9a506fdv57b4kno0u4bjucghjy\" class=\"textannotation disambiguated wl-thing\">Calidad<\/span> el propio uso. No basta con ocuparse del aqu\u00ed y ahora. Lo decisivo es c\u00f3mo las estructuras, <span id=\"urn:local-text-annotation-ld6igm68l7ncohu9ke8npxapzzhi9o86\" class=\"textannotation disambiguated wl-thing\">Datos<\/span> y <span id=\"urn:local-text-annotation-tk2pgoflvrb8hpkofhdvxrjn66xw40zp\" class=\"textannotation disambiguated wl-thing\">Procesos<\/span> a prueba de futuro.<\/p>\n<p>Me gustar\u00eda ilustrar estos puntos utilizando como ejemplo tres temas de gesti\u00f3n empresarial.<\/p>\n<h3><span id=\"urn:local-text-annotation-4h2ktup96i5tdkssslqm8rdsjhhpke4q\" class=\"textannotation disambiguated wl-thing\">Tama\u00f1o del lote<\/span> 1<\/h3>\n<p>Detr\u00e1s de esto est\u00e1 el deseo de muchos clientes de tener productos individuales. En casos extremos, cada producto se fabrica una sola vez, por lo que <span id=\"urn:local-text-annotation-8l94zm5bogu94uyl51hytpahsch7avi8\" class=\"textannotation disambiguated wl-thing\">Tama\u00f1o del lote<\/span> 1. para los clientes industriales en el negocio B2B, se trata de diferenciarse en la competencia. Es un punto fuerte cl\u00e1sico de las grandes empresas medianas de la regi\u00f3n DACH reaccionar con flexibilidad a estos deseos de los clientes.<\/p>\n<p>Sin embargo, esta flexibilidad es al mismo tiempo un gran reto organizativo, porque surgen muchas variantes de productos diferentes, con enormes efectos sobre los datos y los procesos. En este sentido, es crucial seleccionar el \"escenario de proceso\" adecuado en el <span id=\"urn:local-text-annotation-23r3j70u19ropd4gafmnelqlcy90mpsg\" class=\"textannotation disambiguated wl-thing\">ERP<\/span>-sistema. En SAP, por ejemplo, se dispone de los escenarios configuraci\u00f3n de variantes, fabricaci\u00f3n sobre pedido y fabricaci\u00f3n de proyectos. Para muchas empresas, esto ofrece un gran potencial para optimizar el dise\u00f1o de sus procesos de producci\u00f3n. <span id=\"urn:local-text-annotation-8wwxml6wm32l3iju0ogs5izd95fupxii\" class=\"textannotation disambiguated wl-thing\">Procesos<\/span>.<\/p>\n<p>En Pikon hemos desarrollado el llamado \u00cdndice de Puntuaci\u00f3n de Complejidad. Lo utilizamos para evaluar la complejidad de las variantes de productos y, a continuaci\u00f3n, derivar el escenario adecuado junto con nuestros clientes. Para muchas empresas que a\u00fan no han pensado en estos escenarios de proceso, existe un considerable potencial de mejora.<\/p>\n<h3>Proceso de oferta<\/h3>\n<p>Ser capaz de presentar r\u00e1pidamente una oferta competitiva en respuesta a una consulta de un cliente es una cuesti\u00f3n competitivamente cr\u00edtica importante para casi todas las empresas. Para ello, debe optimizarse la interacci\u00f3n entre ventas, dise\u00f1o\/ingenier\u00eda y producci\u00f3n. En definitiva, un documento atractivo debe llegar al coraz\u00f3n de la propuesta.<\/p>\n<p>Todo esto s\u00f3lo puede lograrse si las reglas empresariales correspondientes para la fijaci\u00f3n de precios, las comprobaciones de disponibilidad y el control de textos y mensajes funcionan en todos los m\u00f3dulos y departamentos. Los datos de los clientes deben almacenarse de forma transparente y sin redundancias en el sistema, y las estructuras modulares de los productos son importantes para poder cubrir las necesidades espec\u00edficas de los clientes (v\u00e9ase tambi\u00e9n el punto \"<span id=\"urn:local-text-annotation-twfjotdh0akrjlnnfwfjqfvf9d5pifqq\" class=\"textannotation disambiguated wl-thing\">Tama\u00f1o del lote<\/span> 1\").<\/p>\n<p>Estos aspectos en la <span id=\"urn:local-text-annotation-425y72osaq869d5zp90204pxfamooziu\" class=\"textannotation disambiguated wl-thing\">ERP<\/span>-sistema forman la columna vertebral digital en este punto, por as\u00ed decirlo. Adem\u00e1s, muchas empresas apuestan aqu\u00ed por funciones muy individuales para diferenciarse de la competencia y poder reaccionar con flexibilidad a los deseos de los clientes.<\/p>\n<p>El abanico de posibilidades para una presentaci\u00f3n electr\u00f3nica de productos con selecci\u00f3n de opciones de producto y suministro de informaci\u00f3n adicional sobre el producto o el proceso de venta es diverso. Se tienen en cuenta tanto las soluciones en l\u00ednea como fuera de l\u00ednea. La oferta de plataformas digitales y medios sociales tambi\u00e9n desempe\u00f1a un papel cada vez m\u00e1s importante. Estos aspectos individuales se aplican cada vez m\u00e1s en sistemas ajenos a la <span id=\"urn:local-text-annotation-9h9g2hklltcfu4jk70ehhvnxnx7vfo3c\" class=\"textannotation disambiguated wl-thing\">ERP<\/span>-La columna vertebral de SAP se asigna como complementos integrados de SAP o como sistemas independientes integrados (por ejemplo, CRM o sistemas externos para la configuraci\u00f3n de productos).<\/p>\n<h3>Modernizaci\u00f3n de las finanzas<\/h3>\n<p>En el transcurso de la <span id=\"urn:local-text-annotation-hlt9fu62ioqckp63xiltoprzbtgtsqk6\" class=\"textannotation disambiguated wl-thing\">Digitalizaci\u00f3n<\/span> Cada vez surgen m\u00e1s requisitos para un sistema financiero moderno y eficiente. Para muchas empresas, esto incluye la adaptaci\u00f3n paralela a distintas normas contables, como las NIIF o el HGB. Pero el tema de la aceleraci\u00f3n tambi\u00e9n desempe\u00f1a un papel importante. Por ejemplo, en el \u00e1mbito del cierre del ejercicio. Al menos eso es lo que sugieren los resultados de un estudio del Institute of Management Accountants (IMA).<\/p>\n<p>De los 2.000 directores financieros encuestados, m\u00e1s de la mitad afirmaron que acelerar los cierres de ejercicio ayudar\u00eda significativamente a aumentar la productividad de sus equipos. El requisito previo es la eficiencia <span id=\"urn:local-text-annotation-hvhglw5zg3ckq774149ze4khae43dyaj\" class=\"textannotation disambiguated wl-thing\">Procesos<\/span> y su ilustraci\u00f3n en un <span id=\"urn:local-text-annotation-p26o5akc5c87cf40genywss9r2dyf4c8\" class=\"textannotation disambiguated wl-thing\">ERP<\/span>-sistema.<\/p>\n<h3>El camino hacia <span id=\"urn:local-text-annotation-q8daeco7ofi8lthvd8bhwj2fic18ycs8\" class=\"textannotation disambiguated wl-thing\">S\/4<\/span> Hana<\/h3>\n<p>Los tres ejemplos de las \u00e1reas <span id=\"urn:local-text-annotation-tv9ak4a4y1mvroilii3of8o7s9r6xsjr\" class=\"textannotation disambiguated wl-thing\">Tama\u00f1o del lote<\/span> 1, el proceso de licitaci\u00f3n y las finanzas modernas son s\u00f3lo ejemplares para la evaluaci\u00f3n de la <span id=\"urn:local-text-annotation-3ez86c3cnl7cetu8peaieaa7eumrayt8\" class=\"textannotation disambiguated wl-thing\">Proceso<\/span>-estructura y calidad de los datos en el sistema actual. Las siguientes opciones est\u00e1n disponibles para mapear los requisitos futuros:<\/p>\n<ol>\n<li><strong>Ilustraci\u00f3n en el <span id=\"urn:local-text-annotation-gaf3rq4y64aer4l7yp0y48408uv8d29f\" class=\"textannotation disambiguated wl-thing\">ERP SAP<\/span> y posterior cambio de versi\u00f3n a <span id=\"urn:local-text-annotation-y32azrzbw9juwhkucc95gpwhl66ikfra\" class=\"textannotation disambiguated wl-thing\">S\/4<\/span> Hana<\/strong><\/li>\n<li><strong> Asignaci\u00f3n basada en las nuevas funciones de <span id=\"urn:local-text-annotation-yt33w1najugvy6zgkvc4v2n50oybu4e4\" class=\"textannotation disambiguated wl-thing\">S\/4<\/span> Hana <\/strong><\/li>\n<li><strong>Asignaci\u00f3n con el complemento SAP<\/strong><\/li>\n<\/ol>\n<h3>Cambio de versi\u00f3n a S\/4<\/h3>\n<p>En muchas empresas, la situaci\u00f3n es tal que ya es posible optimizar considerablemente el sistema existente. Me gustar\u00eda ilustrarlo con el ejemplo de \"<span id=\"urn:local-text-annotation-o0in6ljpkgilv2ijb11c9b8yqrpkuhe0\" class=\"textannotation disambiguated wl-thing\">Tama\u00f1o del lote<\/span> 1\". Muchas funciones muy buenas ya est\u00e1n disponibles hoy aqu\u00ed en <span id=\"urn:local-text-annotation-mcft139bq882rc0i7j994gp7hlk0zvge\" class=\"textannotation disambiguated wl-thing\">ERP SAP<\/span> disponibles para modular los productos y apoyar de forma \u00f3ptima la asignaci\u00f3n de los deseos espec\u00edficos de los clientes a trav\u00e9s del proceso central de tramitaci\u00f3n de pedidos.<\/p>\n<p>A menudo, estos escenarios de proceso (configuraci\u00f3n de variantes, fabricaci\u00f3n contra pedido, fabricaci\u00f3n de proyectos) no se conocen o no se conocen lo suficiente. Otro potencial de optimizaci\u00f3n es la eliminaci\u00f3n de duplicados en los datos maestros de productos e interlocutores comerciales. Todos estos puntos pueden abordarse en actividades de housekeeping gestionables.<\/p>\n<p>El beneficio se despliega inmediatamente y el cambio posterior a <span id=\"urn:local-text-annotation-4at9b23asbtp3ivpeghco9n0w4ldr5s3\" class=\"textannotation disambiguated wl-thing\">S\/4<\/span> Hana se ve favorecido por ello, ya que un sistema optimizado y depurado constituye una buena base para el cambio de versi\u00f3n. Otro ejemplo es el redise\u00f1o de las estructuras organizativas en SAP. Por ejemplo, la fusi\u00f3n de \u00e1reas de contabilidad o controlling puede tener sentido. Una vez finalizada la limpieza, el cambio a <span id=\"urn:local-text-annotation-xseiw7059joewcskdp93lv6yk89w8bks\" class=\"textannotation disambiguated wl-thing\">S\/4<\/span> Hana en una fase relativamente tard\u00eda a trav\u00e9s de un cambio de versi\u00f3n t\u00e9cnica (enfoque brownfield).<\/p>\n<h3>Nuevo <span id=\"urn:local-text-annotation-updij0eockequgfc7a2bm1pextlcq9tr\" class=\"textannotation disambiguated wl-thing\">S\/4<\/span>-funcionalidades<\/h3>\n<p>Por supuesto, una nueva tecnolog\u00eda es siempre un motor de optimizaci\u00f3n en el \u00e1mbito empresarial. Esto tambi\u00e9n se aplica a <span id=\"urn:local-text-annotation-2v4u0hp881us8hu261hy7yv7x58vwhfa\" class=\"textannotation disambiguated wl-thing\">S\/4<\/span> Hana. Por un lado, importantes funciones del \u00e1rea de planificaci\u00f3n de la producci\u00f3n, que antes se implementaban en una herramienta independiente (SAP APO), se est\u00e1n integrando de nuevo en el sistema Hana. <span id=\"urn:local-text-annotation-adijtqumhsf3ayirph581xk1xo1chr4m\" class=\"textannotation disambiguated wl-thing\">ERP<\/span>-sistema est\u00e1 integrado. Tambi\u00e9n ofrece <span id=\"urn:local-text-annotation-69kargsda8vx67lmlctouez5blp5isr2\" class=\"textannotation disambiguated wl-thing\">S\/4<\/span> considerable potencial en la modernizaci\u00f3n del <span id=\"urn:local-text-annotation-ztszcpbr838b8dmvykquat4zq4oi8zc1\" class=\"textannotation disambiguated wl-thing\">Procesos<\/span> en finanzas y contabilidad. Esto se consigue principalmente normalizando la base de datos en la contabilidad interna y externa.<\/p>\n<p>En el futuro, s\u00f3lo habr\u00e1 una tabla de partidas con todos los detalles para controlling y finanzas.<\/p>\n<p>Esto no s\u00f3lo elimina los largos procesos de conciliaci\u00f3n entre FI y CO, sino que tambi\u00e9n facilita y acelera el cierre del per\u00edodo y abre nuevas posibilidades de elaboraci\u00f3n de informes. Adem\u00e1s, las nuevas estructuras de datos simplifican considerablemente la elaboraci\u00f3n de informes en tiempo real.<\/p>\n<p>Me gustar\u00eda poner s\u00f3lo un ejemplo: En el futuro, las caracter\u00edsticas CO-PA podr\u00e1n derivarse en tiempo real en el documento FI. As\u00ed, con s\u00f3lo pulsar un bot\u00f3n, se podr\u00e1 crear en cualquier momento una cuenta de resultados desde FI en funci\u00f3n de determinadas caracter\u00edsticas. El uso de CO-PA imputados para el c\u00e1lculo del margen de contribuci\u00f3n ya no es obligatorio. Ya no es necesaria una tediosa reconciliaci\u00f3n entre FI y CO-PA.<\/p>\n<p>Ya he se\u00f1alado m\u00e1s arriba que el camino hacia <span id=\"urn:local-text-annotation-tbzr3ghqkghk51hu8id14e09caka20hg\" class=\"textannotation disambiguated wl-thing\">S\/4<\/span> Hana puede adoptarse mediante una actualizaci\u00f3n de versi\u00f3n \"normal\". Sin embargo, si las estructuras entre lo \"viejo\" y lo \"nuevo\" est\u00e1n demasiado alejadas, tambi\u00e9n puede tener sentido una nueva introducci\u00f3n (enfoque greenfield).<\/p>\n<h3>Complementos SAP integrados<\/h3>\n<p>A pesar de todas las mejoras, seguir\u00e1 ocurriendo en el futuro que muchas empresas no podr\u00e1n satisfacer algunas de sus necesidades, o s\u00f3lo de forma limitada, mediante las funciones y procesos de <span id=\"urn:local-text-annotation-359kpnnr8jx7jpcu6ijakifclc2wjk7o\" class=\"textannotation disambiguated wl-thing\">S\/4<\/span> Hana. En los puntos cr\u00edticos para la competencia, la soluci\u00f3n puede ser proporcionada por un sistema de terceros o un complemento SAP de desarrollo propio. Lo importante aqu\u00ed es la integraci\u00f3n completa de datos y procesos en el est\u00e1ndar SAP y la <span id=\"urn:local-text-annotation-rbwg1iuyw74nrawv3n0aknc07510b8yj\" class=\"textannotation disambiguated wl-thing\">Calidad<\/span> de desarrollo.<\/p>\n<p>Con la tecnolog\u00eda Hana, muchas funciones se trasladan al nivel de la base de datos, pero las directrices b\u00e1sicas del desarrollo de software siguen siendo v\u00e1lidas. Una arquitectura orientada a objetos es de gran importancia si se quiere seguir desarrollando el software posteriormente de forma planificada y segura y adaptarlo a nuevas circunstancias.<\/p>\n<h3>Conclusi\u00f3n<\/h3>\n<p>Al prepararse para el futuro digital, las empresas deben tener en cuenta tanto los aspectos empresariales como los t\u00e9cnicos. <span id=\"urn:local-text-annotation-zu6milvrgp7y9havjdvksuvwqwam1w8p\" class=\"textannotation disambiguated wl-thing\">ERP<\/span>-son de suma importancia como columna vertebral digital. Sin embargo, sus beneficios no s\u00f3lo se derivan de sus funciones, sino tambi\u00e9n de la <span id=\"urn:local-text-annotation-sv1fhrecklng7yr4mo0r9c5lc3ip62fv\" class=\"textannotation disambiguated wl-thing\">Calidad<\/span> la cartograf\u00eda de estructuras, procesos y <span id=\"urn:local-text-annotation-7kl3l6dcwe715o94k5edhii21oy8h68c\" class=\"textannotation disambiguated wl-thing\">Datos<\/span> en el sistema ERP. \u00c9stos vienen determinados por el <span id=\"urn:local-text-annotation-2oh3a7nu1t3k8puittmt0fad2h93dnpk\" class=\"textannotation disambiguated wl-thing\">Calidad<\/span> del proceso de introducci\u00f3n y la <span id=\"urn:local-text-annotation-f9lbmy8crxoilk0xaeeq8sojpnr6opi1\" class=\"textannotation disambiguated wl-thing\">Calidad<\/span> el uso por parte de los usuarios.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/es\/socios\/pikon-international-consulting-group-pikon-deutschland-ag\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" title=\"S\/4 hana como columna vertebral digital\" class=\"aligncenter wp-image-11374 size-full\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/03\/CI-PIKON.jpg\" alt=\"https:\/\/e326.greatsolution.dev\/partners\/pikon-international-consulting-group-pikon-deutschland-ag\/\" width=\"1000\" height=\"112\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/03\/CI-PIKON.jpg 1000w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/03\/CI-PIKON-768x86.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/03\/CI-PIKON-100x11.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/03\/CI-PIKON-480x54.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/03\/CI-PIKON-640x72.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/03\/CI-PIKON-720x81.jpg 720w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/03\/CI-PIKON-960x108.jpg 960w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>El tema de S\/4 Hana sigue siendo de actualidad. El debate no solo debe desarrollarse desde el punto de vista de las funciones y posibilidades del nuevo sistema inform\u00e1tico S\/4 Hana.<\/p>","protected":false},"author":88,"featured_media":4879,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[4,731],"tags":[614,606,601,73,618,517,608],"coauthors":[25454],"class_list":["post-4872","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-management","category-mag1611","tag-anwender","tag-daten","tag-digitalisierung","tag-erp","tag-kunde","tag-s4","tag-unternehmen","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/shutterstock_201045836.jpg",1000,504,false],"thumbnail":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/shutterstock_201045836-150x150.jpg",150,150,true],"medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/shutterstock_201045836.jpg",400,202,false],"medium_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/shutterstock_201045836-768x387.jpg",768,387,true],"large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/shutterstock_201045836.jpg",1000,504,false],"image-100":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/shutterstock_201045836-100x50.jpg",100,50,true],"image-480":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/shutterstock_201045836-480x242.jpg",480,242,true],"image-640":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/shutterstock_201045836-640x323.jpg",640,323,true],"image-720":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/shutterstock_201045836-720x363.jpg",720,363,true],"image-960":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/shutterstock_201045836-960x484.jpg",960,484,true],"image-1168":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/shutterstock_201045836.jpg",1000,504,false],"image-1440":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/shutterstock_201045836.jpg",1000,504,false],"image-1920":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/shutterstock_201045836.jpg",1000,504,false],"1536x1536":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/shutterstock_201045836.jpg",1000,504,false],"2048x2048":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/shutterstock_201045836.jpg",1000,504,false],"trp-custom-language-flag":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/shutterstock_201045836.jpg",18,9,false],"bricks_large_16x9":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/shutterstock_201045836.jpg",1000,504,false],"bricks_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/shutterstock_201045836.jpg",1000,504,false],"bricks_large_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/shutterstock_201045836.jpg",1000,504,false],"bricks_medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/shutterstock_201045836.jpg",600,302,false],"bricks_medium_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/shutterstock_201045836.jpg",600,302,false],"profile_24":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/shutterstock_201045836-24x24.jpg",24,24,true],"profile_48":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/shutterstock_201045836-48x48.jpg",48,48,true],"profile_96":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/shutterstock_201045836-96x96.jpg",96,96,true],"profile_150":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/shutterstock_201045836-150x150.jpg",150,150,true],"profile_300":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/shutterstock_201045836-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Das Thema S\/4 Hana bleibt aktuell. Die Diskussion sollte dabei nicht nur unter dem Gesichtspunkt der Funktionen und M\u00f6glichkeiten des neuen IT-Systems S\/4 Hana gef\u00fchrt werden.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e326.greatsolution.dev\/es\/categoria\/gestion\/\" rel=\"category tag\">Business-Management<\/a>, <a href=\"https:\/\/e326.greatsolution.dev\/es\/categoria\/le-gusta1611\/\" rel=\"category tag\">MAG 16-11<\/a>","author_info_v2":{"name":"Sarah Leichtweis, Pikon","url":"https:\/\/e326.greatsolution.dev\/es\/author\/sarah-leichtweis\/"},"comments_num_v2":"0 comentarios","_links":{"self":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/4872","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/users\/88"}],"replies":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/comments?post=4872"}],"version-history":[{"count":0,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/4872\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/media\/4879"}],"wp:attachment":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/media?parent=4872"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/categories?post=4872"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/tags?post=4872"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/coauthors?post=4872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}