{"id":54190,"date":"2018-10-11T08:00:05","date_gmt":"2018-10-11T06:00:05","guid":{"rendered":"https:\/\/e326.greatsolution.dev\/?p=54190"},"modified":"2025-07-14T15:36:49","modified_gmt":"2025-07-14T13:36:49","slug":"digitalizacion-de-las-compras-b2b-redes-en-la-nube","status":"publish","type":"post","link":"https:\/\/e326.greatsolution.dev\/es\/digitalizacion-de-las-compras-b2b-redes-en-la-nube\/","title":{"rendered":"Hace tiempo que se esperaba: la digitalizaci\u00f3n en las compras B2B significa trabajar en red a trav\u00e9s de la nube"},"content":{"rendered":"<p>Amazon, Google y Uber han mostrado el camino, la era de los SRM cl\u00e1sicos y las soluciones on-premise hace tiempo que pas\u00f3 su cenit. Las plataformas de red desde la nube son la tendencia.<\/p>\n<p>\u00bfHasta qu\u00e9 punto est\u00e1n digitalizados y conectados en red los procesos empresariales de las compras hoy en d\u00eda? En nuestro \u00faltimo estudio, hemos preguntado a 438 directores de compras -incluidos muchos que ya utilizan SAP como soluci\u00f3n ERP- sobre la relevancia de las redes digitales en las compras, en colaboraci\u00f3n con la Universidad de Ciencias Aplicadas de Niederrhein y la Asociaci\u00f3n Alemana de Gesti\u00f3n de Materiales, Compras y Log\u00edstica (BME). El resultado: una gran mayor\u00eda espera claras oportunidades de mercado y desea invertir m\u00e1s en este \u00e1mbito.<\/p>\n<p>Qu\u00e9 comprador no querr\u00eda una plataforma abierta, neutral y no comisariada que evolucione libremente, por s\u00ed sola, de forma din\u00e1mica y \u00e1gil. La era de las plataformas hace tiempo que ha comenzado.<\/p>\n<p>Y quien ignore esta evoluci\u00f3n, tarde o temprano saldr\u00e1 perdiendo en el mercado. El profesor Willi Muschinski, director del estudio y profesor de Gesti\u00f3n de Compras en la Universidad de Ciencias Aplicadas de Niederrhein, predice con acierto: \"El comercio multinivel ser\u00e1 cada vez menos importante en un futuro pr\u00f3ximo. La automatizaci\u00f3n de los procesos de compra y la interconexi\u00f3n de compradores y proveedores son factores competitivos decisivos, especialmente para las medianas empresas. Las tradicionales relaciones cliente-proveedor 1:1 se convertir\u00e1n en relaciones de red n:n con un gran n\u00famero de proveedores, compradores y la m\u00e1xima experiencia para todas las partes implicadas como resultado de un creciente mercado de contrataci\u00f3n digital.\"<\/p>\n<p>En general, puede decirse que las empresas conceden gran importancia a las redes de contrataci\u00f3n digital dentro de su estrategia de digitalizaci\u00f3n: el 83 % de todos los participantes en la encuesta considera que las redes de contrataci\u00f3n son importantes. Para m\u00e1s de la mitad de los encuestados, las redes de contrataci\u00f3n son incluso muy importantes. Por lo tanto, no es de extra\u00f1ar que la disposici\u00f3n a invertir sea relativamente alta entre los participantes en la encuesta: el 83% tiene la intenci\u00f3n de invertir m\u00e1s en redes de contrataci\u00f3n digital en 2018.<\/p>\n<p>Lo satisfactorio aqu\u00ed es que los puestos no son meros marcadores de posici\u00f3n en la agenda digital; seg\u00fan nuestro estudio, casi la mitad ya han presupuestado estas inversiones. Estoy seguro de que las empresas bien conectadas seguir\u00e1n ampliando su ventaja en el futuro.<\/p>\n<h3>Las redes de contrataci\u00f3n allanan el camino del cambio<\/h3>\n<p>El B2C ha marcado el camino, y la tendencia en el B2B tambi\u00e9n se dirige cada vez m\u00e1s hacia la creaci\u00f3n de redes \u00e1giles y el trabajo colaborativo. El estudio de Onventis muestra que ya existen procesos de colaboraci\u00f3n entre compradores y proveedores, pero a menudo falta un soporte digital integral a lo largo de toda la cadena de suministro.<\/p>\n<p>El objetivo debe ser la automatizaci\u00f3n total de la contrataci\u00f3n. Esto se debe a que la interconexi\u00f3n y la comunicaci\u00f3n electr\u00f3nicas acortan considerablemente los procesos de coordinaci\u00f3n y optimizan notablemente los costes del proceso. La funci\u00f3n principal de las plataformas de contrataci\u00f3n es, por tanto, simplificar los procesos de coordinaci\u00f3n para lograr un mejor rendimiento del mercado para todos los socios de la red.<\/p>\n<p>Las ventajas de las redes en las compras est\u00e1n en ambos lados: Por ejemplo, para los compradores, la intensa investigaci\u00f3n de mercado previa a las licitaciones es cosa del pasado, ya que se muestran directamente los proveedores adecuados para los art\u00edculos que buscan.<\/p>\n<p>La transparencia resultante tambi\u00e9n aumenta el poder de decisi\u00f3n en las compras. Para los proveedores, a su vez, se abren nuevas oportunidades de mercado. Se presentan con contenidos de alta calidad en la red y ofrecen as\u00ed a los compradores una selecci\u00f3n superior.<\/p>\n<p>\u00a1Todos se benefician de todos! Esto es exactamente lo que pretenden las redes de contrataci\u00f3n, como la Onventis Cloud Procurement Network: digitalizar los procesos de compra operativos y estrat\u00e9gicos y conectar al m\u00e1ximo a todos los participantes.<\/p>","protected":false},"excerpt":{"rendered":"<p>En tiempos de digitalizaci\u00f3n, una cosa est\u00e1 clara: las redes globales determinar\u00e1n el futuro, especialmente en la contrataci\u00f3n. Sin redes no hay futuro, sin plataformas de colaboraci\u00f3n no hay redes. <\/p>","protected":false},"author":1577,"featured_media":2445,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[19,7,24724],"tags":[623,39,647,6798],"coauthors":[24946],"class_list":["post-54190","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-b2b2c-kolumne","category-meinung","category-mag-1809","tag-amazon","tag-cloud","tag-google","tag-uber","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/B2B2C.jpg",1000,432,false],"thumbnail":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/B2B2C-150x150.jpg",150,150,true],"medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/B2B2C.jpg",400,173,false],"medium_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/B2B2C-768x332.jpg",768,332,true],"large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/B2B2C.jpg",1000,432,false],"image-100":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/B2B2C-100x43.jpg",100,43,true],"image-480":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/B2B2C-480x207.jpg",480,207,true],"image-640":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/B2B2C-640x276.jpg",640,276,true],"image-720":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/B2B2C-720x311.jpg",720,311,true],"image-960":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/B2B2C-960x415.jpg",960,415,true],"image-1168":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/B2B2C.jpg",1000,432,false],"image-1440":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/B2B2C.jpg",1000,432,false],"image-1920":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/B2B2C.jpg",1000,432,false],"1536x1536":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/B2B2C.jpg",1000,432,false],"2048x2048":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/B2B2C.jpg",1000,432,false],"trp-custom-language-flag":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/B2B2C.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/B2B2C.jpg",1000,432,false],"bricks_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/B2B2C.jpg",1000,432,false],"bricks_large_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/B2B2C.jpg",1000,432,false],"bricks_medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/B2B2C.jpg",600,259,false],"bricks_medium_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/B2B2C.jpg",600,259,false],"profile_24":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/B2B2C-24x24.jpg",24,24,true],"profile_48":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/B2B2C-48x48.jpg",48,48,true],"profile_96":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/B2B2C-96x96.jpg",96,96,true],"profile_150":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/B2B2C-150x150.jpg",150,150,true],"profile_300":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/B2B2C-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>In Zeiten der Digitalisierung zeichnet sich eines deutlich ab: Globale Netzwerke werden die Zukunft bestimmen \u2013 vor allem in der Beschaffung. Ohne Vernetzung keine Zukunft, ohne Kollaborationsplattformen keine Vernetzung. <\/p>\n","category_list_v2":"<a href=\"https:\/\/e326.greatsolution.dev\/es\/categoria\/opinion\/columna-b2b2c\/\" rel=\"category tag\">B2B2C-Kolumne<\/a>, <a href=\"https:\/\/e326.greatsolution.dev\/es\/categoria\/opinion\/\" rel=\"category tag\">Die Meinung der SAP-Community<\/a>, <a href=\"https:\/\/e326.greatsolution.dev\/es\/categoria\/mag-1809\/\" rel=\"category tag\">MAG 18-09<\/a>","author_info_v2":{"name":"Frank Schmidt, Onventis","url":"https:\/\/e326.greatsolution.dev\/es\/author\/frank-schmidt\/"},"comments_num_v2":"0 comentarios","_links":{"self":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/54190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/users\/1577"}],"replies":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/comments?post=54190"}],"version-history":[{"count":1,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/54190\/revisions"}],"predecessor-version":[{"id":152477,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/54190\/revisions\/152477"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/media\/2445"}],"wp:attachment":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/media?parent=54190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/categories?post=54190"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/tags?post=54190"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/coauthors?post=54190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}