{"id":55212,"date":"2018-11-29T08:00:54","date_gmt":"2018-11-29T07:00:54","guid":{"rendered":"https:\/\/e326.greatsolution.dev\/?p=55212"},"modified":"2025-07-31T15:36:49","modified_gmt":"2025-07-31T13:36:49","slug":"devops-riesgo-ser-subestimado","status":"publish","type":"post","link":"https:\/\/e326.greatsolution.dev\/es\/devops-riesgo-ser-subestimado\/","title":{"rendered":"DevOps: se subestiman los riesgos"},"content":{"rendered":"<p>La transformaci\u00f3n digital requiere un alto nivel de agilidad y est\u00e1 impulsando el uso de entornos DevOps porque DevOps ofrece innovaci\u00f3n acelerada, mayor flexibilidad y menor complejidad en el desarrollo y despliegue de aplicaciones. Por lo tanto, las empresas desean principalmente obtener beneficios empresariales con las implantaciones de DevOps. Sin embargo, con demasiada frecuencia descuidan la seguridad en el proceso, un grave error, ya que DevOps en particular ampl\u00eda significativamente la superficie de ataque de los ciberataques.<\/p>\n<p>Cuando las empresas utilizan modelos DevOps, se generan y comparten autom\u00e1ticamente m\u00e1s cuentas privilegiadas y datos de acceso a trav\u00e9s de ecosistemas empresariales en red. Estos datos de acceso -que a menudo no se han tenido suficientemente en cuenta ni se han protegido hasta la fecha- incluyen cuentas de servicio, cifrado, claves API y SSH, secretos de contenedor o contrase\u00f1as incrustadas en el c\u00f3digo de los programas, que a menudo tambi\u00e9n se almacenan en repositorios centrales.<\/p>\n<p>Las credenciales privilegiadas de uso adicional asociadas a personas, servicios o aplicaciones representan inevitablemente un objetivo lucrativo para un atacante externo o un insider malintencionado. Al fin y al cabo, permiten un control total de toda la infraestructura inform\u00e1tica de una empresa.<\/p>\n<p>El riesgo de seguridad para las empresas aumenta a\u00fan m\u00e1s por el uso de numerosas herramientas de orquestaci\u00f3n y automatizaci\u00f3n, como las herramientas de CI (integraci\u00f3n continua) y CD (entrega continua) o repositorios de c\u00f3digo fuente como GitHub en proyectos DevOps. El reto aqu\u00ed es que las herramientas utilizadas en la cadena de herramientas DevOps, como Ansible, Chef, Puppet o Jenkins, no ofrecen ning\u00fan est\u00e1ndar com\u00fan y, por lo tanto, las empresas tienen que tomar medidas de seguridad individuales y espec\u00edficas para cada herramienta.<\/p>\n<p>Sobre todo, los flujos de trabajo para el control de acceso a credenciales privilegiadas difieren significativamente. Como resultado, muchas empresas siguen estrategias de control de acceso inexistentes, incoherentes o manuales, por lo que las brechas de seguridad est\u00e1n preprogramadas y los atacantes las buscan de forma tan autom\u00e1tica como se genera el c\u00f3digo en el proceso DevOps.<\/p>\n<h2>\u00bfC\u00f3mo combatir esta evoluci\u00f3n?<\/h2>\n<p>Las contramedidas exitosas solo pueden tomarse con una pila de seguridad DevOps dedicada, y aqu\u00ed es donde entra en juego la seguridad de TI. Debe adoptar un enfoque sistem\u00e1tico para ayudar a los equipos de DevOps a alcanzar un alto nivel de seguridad. Las herramientas y pr\u00e1cticas de DevOps y de seguridad deben integrarse entre s\u00ed para establecer una protecci\u00f3n eficaz de los datos privilegiados. Por lo tanto, la estrecha colaboraci\u00f3n entre los equipos de DevOps y de seguridad es el primer paso para construir con \u00e9xito una plataforma de seguridad escalable y aplicar una estrategia DevSecOps que pueda seguir el ritmo del entorno din\u00e1mico y la r\u00e1pida evoluci\u00f3n de la tecnolog\u00eda.<\/p>\n<p>La administraci\u00f3n de todas las herramientas DevOps y los datos de acceso debe tener lugar bajo el paraguas de una plataforma de seguridad de este tipo. La administraci\u00f3n central y autom\u00e1tica y la protecci\u00f3n de todos los datos de acceso confidenciales utilizados en un canal de DevOps, como claves de cifrado y API, contrase\u00f1as de bases de datos o certificados de seguridad de la capa de transporte (TLS), son de vital importancia.<\/p>\n<p>Ni que decir tiene que los secretos personalizados tambi\u00e9n se gestionan aqu\u00ed de forma autom\u00e1tica y din\u00e1mica para asegurar el acceso en la producci\u00f3n DevOps. Todos los datos de acceso utilizados por m\u00e1quinas, sistemas y personas deben protegerse en un sistema de almacenamiento seguro y de alta disponibilidad (b\u00f3veda), un servidor especialmente \"endurecido\" que ofrezca una protecci\u00f3n fiable contra el acceso no autorizado con varias capas de seguridad diferentes.<\/p>","protected":false},"excerpt":{"rendered":"<p>Las empresas utilizan cada vez m\u00e1s DevOps para el despliegue eficiente de aplicaciones. DevOps promete plazos de comercializaci\u00f3n m\u00e1s cortos, una mejor calidad del producto y una mayor satisfacci\u00f3n del cliente, pero tambi\u00e9n conlleva nuevos riesgos de seguridad.<\/p>","protected":false},"author":1249,"featured_media":50414,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[24421,7,26129],"tags":[1013,451],"coauthors":[23133],"class_list":["post-55212","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-devops-kolumne","category-meinung","category-mag-1811","tag-agilitaet","tag-devops","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/07\/DevOps.jpg",1000,450,false],"thumbnail":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/07\/DevOps-150x150.jpg",150,150,true],"medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/07\/DevOps.jpg",400,180,false],"medium_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/07\/DevOps-768x346.jpg",768,346,true],"large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/07\/DevOps.jpg",1000,450,false],"image-100":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/07\/DevOps-100x45.jpg",100,45,true],"image-480":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/07\/DevOps-480x216.jpg",480,216,true],"image-640":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/07\/DevOps-640x288.jpg",640,288,true],"image-720":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/07\/DevOps-720x324.jpg",720,324,true],"image-960":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/07\/DevOps-960x432.jpg",960,432,true],"image-1168":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/07\/DevOps.jpg",1000,450,false],"image-1440":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/07\/DevOps.jpg",1000,450,false],"image-1920":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/07\/DevOps.jpg",1000,450,false],"1536x1536":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/07\/DevOps.jpg",1000,450,false],"2048x2048":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/07\/DevOps.jpg",1000,450,false],"trp-custom-language-flag":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/07\/DevOps.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/07\/DevOps.jpg",1000,450,false],"bricks_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/07\/DevOps.jpg",1000,450,false],"bricks_large_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/07\/DevOps.jpg",1000,450,false],"bricks_medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/07\/DevOps.jpg",600,270,false],"bricks_medium_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/07\/DevOps.jpg",600,270,false],"profile_24":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/07\/DevOps-24x24.jpg",24,24,true],"profile_48":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/07\/DevOps-48x48.jpg",48,48,true],"profile_96":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/07\/DevOps-96x96.jpg",96,96,true],"profile_150":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/07\/DevOps-150x150.jpg",150,150,true],"profile_300":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/07\/DevOps-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Unternehmen nutzen verst\u00e4rkt DevOps zur effizienten Applikationsbereitstellung. DevOps verspricht eine k\u00fcrzere Time-to-Market, verbesserte Produktqualit\u00e4t und h\u00f6here Kundenzufriedenheit, bringt aber auch neue Sicherheitsrisiken mit sich.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e326.greatsolution.dev\/es\/categoria\/opinion\/columna-devops\/\" rel=\"category tag\">DevOps Kolumne<\/a>, <a href=\"https:\/\/e326.greatsolution.dev\/es\/categoria\/opinion\/\" rel=\"category tag\">Die Meinung der SAP-Community<\/a>, <a href=\"https:\/\/e326.greatsolution.dev\/es\/categoria\/mag-1811\/\" rel=\"category tag\">MAG 18-11<\/a>","author_info_v2":{"name":"Michael Kleist, CyberArk","url":"https:\/\/e326.greatsolution.dev\/es\/author\/michael-kleist\/"},"comments_num_v2":"0 comentarios","_links":{"self":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/55212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/users\/1249"}],"replies":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/comments?post=55212"}],"version-history":[{"count":1,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/55212\/revisions"}],"predecessor-version":[{"id":153128,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/55212\/revisions\/153128"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/media\/50414"}],"wp:attachment":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/media?parent=55212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/categories?post=55212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/tags?post=55212"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/coauthors?post=55212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}