{"id":60867,"date":"2016-05-02T09:16:31","date_gmt":"2016-05-02T07:16:31","guid":{"rendered":"https:\/\/e326.greatsolution.dev\/?p=60867"},"modified":"2019-07-11T09:31:27","modified_gmt":"2019-07-11T07:31:27","slug":"flujos-de-trabajo-documentos-digitales-kpis-estandarizados","status":"publish","type":"post","link":"https:\/\/e326.greatsolution.dev\/es\/flujos-de-trabajo-documentos-digitales-kpis-estandarizados\/","title":{"rendered":"Flujos de trabajo, documentos digitales, KPI normalizados"},"content":{"rendered":"<p>Muchas empresas alemanas combinan los principales procesos de RRHH -gesti\u00f3n de datos de personal, c\u00e1lculo de n\u00f3minas o gesti\u00f3n del tiempo- con las funciones integradas de SAP Human Capital Management (SAP HCM).<\/p>\n<p>Para las empresas descentralizadas, esto significa que el responsable in situ, es decir, el director de sucursal o de planta, se enfrenta a los procesos de recursos humanos, especialmente a los procesos de contrataci\u00f3n laboral:<\/p>\n<p>Elabora y comprueba el contrato de trabajo cuando se contrata, se prorroga un contrato de duraci\u00f3n determinada, se aplaza un contrato de duraci\u00f3n determinada, se transfiere o se rescinde un contrato. Sin embargo, adem\u00e1s de \u00e9l, suelen participar en estos procesos la organizaci\u00f3n central de RRHH y, posiblemente, un gestor empresarial de RRHH del departamento regional de RRHH.<\/p>\n<h3>Los procesos manuales ralentizan el trabajo de RRHH<\/h3>\n<p>En la mayor\u00eda de los casos, la coordinaci\u00f3n entre estas partes es manual y en papel, lo que la hace bastante compleja. Los documentos de acompa\u00f1amiento -contrato, hoja de personal, formularios, documentos de solicitud- se imprimen y a menudo se env\u00edan varias veces por correo.<\/p>\n<p>En un proceso de contrataci\u00f3n, por ejemplo, no existe entonces una visi\u00f3n clara de todo el proceso del contrato de trabajo. En consecuencia, las partes implicadas tienen que informarse sobre el estado actual de tramitaci\u00f3n del procedimiento por tel\u00e9fono o correo electr\u00f3nico si es necesario.<\/p>\n<p>En general, las numerosas discontinuidades de los medios tambi\u00e9n alargan los tiempos de procesamiento. Imaginemos los tiempos de ejecuci\u00f3n en una empresa que tiene m\u00e1s de 100 tiendas en toda Alemania y lleva a cabo procesos de contrataci\u00f3n laboral como los descritos.<\/p>\n<p>Por lo tanto, el director de la sucursal o de la planta debe prever un plazo considerable para el proceso de contrataci\u00f3n, y hay una sobrecarga burocr\u00e1tica que genera costes elevados.<\/p>\n<p>Es mucho m\u00e1s f\u00e1cil y eficaz si el proceso de contrataci\u00f3n, pero tambi\u00e9n otros procesos de RRHH como la tramitaci\u00f3n de las solicitudes de horas extraordinarias, se apoyan en flujos de trabajo y, por tanto, est\u00e1n normalizados y son continuos y automatizados.<\/p>\n<p>Para ello es necesario utilizar una soluci\u00f3n inform\u00e1tica f\u00e1cil de usar y que se integre perfectamente con SAP HCM, como Location Suite de Treorbis. Tiene una estructura modular y se basa en Web Dynpro para Abap.<\/p>\n<h3>Marco de flujo de trabajo<\/h3>\n<p>El n\u00facleo central de Location Suite es su potente marco de flujo de trabajo gen\u00e9rico y, por tanto, flexible, el gestor de procesos HCM. En \u00e9l, todos los datos de personal se registran y gestionan de forma centralizada y, en caso necesario, se remiten autom\u00e1ticamente y de forma directa a los lugares adecuados con todos los documentos necesarios para su posterior procesamiento.<\/p>\n<p>Se acabaron los tiempos del tedioso papeleo, los registros manuales ilegibles o la espera de informaci\u00f3n. Incluso el director de la sucursal o de la planta est\u00e1 siempre bien informado.<\/p>\n<p>Una cabina con funciones de sem\u00e1foro le muestra fechas importantes, como la expiraci\u00f3n de un plazo, para que pueda iniciar a tiempo las medidas correspondientes con un clic del rat\u00f3n.<\/p>\n<h3>Contrato de trabajo en horas<\/h3>\n<p>Gracias al flujo continuo de datos y documentos, los procesos relacionados con los contratos se agilizan y los plazos de tramitaci\u00f3n se reducen considerablemente.<\/p>\n<p>Con Treorbis Location Suite, un proceso de contrataci\u00f3n dura s\u00f3lo unas horas, desde la recogida de datos del personal hasta la presentaci\u00f3n del contrato listo para su firma.<\/p>\n<p>Una respuesta tan r\u00e1pida aumenta el atractivo de una empresa como empleador entre los solicitantes y supone una ganancia de imagen que no debe subestimarse.<\/p>\n<p>La calidad de los datos tambi\u00e9n se ve beneficiada, ya que toda la informaci\u00f3n s\u00f3lo tiene que introducirse una vez. Tanto si se trata de un proceso de contrataci\u00f3n como de un cambio de contrato, un flujo de trabajo env\u00eda los datos necesarios directamente a las oficinas correspondientes de la organizaci\u00f3n regional o central de RRHH.<\/p>\n<p>La secuencia de los distintos pasos de trabajo est\u00e1 definida con precisi\u00f3n, al igual que los datos que debe introducir el responsable de recursos humanos in situ y poner a disposici\u00f3n de las oficinas respectivas.<\/p>\n<h3>Transmisi\u00f3n de datos con s\u00f3lo pulsar un bot\u00f3n<\/h3>\n<p>Una vez comprobados y aprobados todos los datos por los departamentos de personal pertinentes, el responsable genera el contrato de trabajo listo para su firma y todos los dem\u00e1s documentos necesarios con s\u00f3lo pulsar un bot\u00f3n.<\/p>\n<p>El contrato se imprime y se firma, se escanea junto con los dem\u00e1s documentos y se le asigna autom\u00e1ticamente un c\u00f3digo de barras QR. Esto garantiza que los documentos se procesen sin problemas, se asignen claramente al proceso correcto en forma de \"carpeta de circulaci\u00f3n electr\u00f3nica\" y se archiven a prueba de auditor\u00edas.<\/p>\n<p>Los documentos relacionados con los procesos, como contratos, cuestionarios o formularios, pueden crearse r\u00e1pida y f\u00e1cilmente como PDF utilizando m\u00f3dulos de texto predefinidos almacenados en el Gestor de procesos HCM, incluso con el dise\u00f1o corporativo de la empresa correspondiente.<\/p>\n<p>Para garantizar la fiabilidad del proceso, la tramitaci\u00f3n posterior s\u00f3lo es posible cuando se dispone de todos los documentos necesarios. Un sistema de seguimiento del estado informa autom\u00e1ticamente a los empleados implicados de las tareas pendientes seg\u00fan su funci\u00f3n y autorizaci\u00f3n.<\/p>\n<p>Una vez finalizado el proceso, toda la informaci\u00f3n y los documentos correspondientes se transfieren a SAP HCM con s\u00f3lo pulsar un bot\u00f3n, donde se asignan a los infotipos SAP correctos o se almacenan en el expediente electr\u00f3nico de personal.<\/p>\n<h3>KPI uniformes<\/h3>\n<p>Una vez armonizados en toda la empresa los procesos de RR.HH. relacionados con los contratos, tambi\u00e9n pueden crearse ratios de RR.HH. uniformes que sirvan para realizar an\u00e1lisis. Con la ayuda del m\u00f3dulo de software HCM Analytics, que forma parte integral de Location Suite, el director de la sucursal puede, por ejemplo, consultar los KPI actuales sobre fluctuaci\u00f3n de empleados, salario o estructura de edad.<\/p>\n<p>Ahora tambi\u00e9n es posible comparar el rendimiento de los empleados de la propia sede con el de otras sucursales o con el de toda la empresa, lo que proporciona informaci\u00f3n importante para mejorar el trabajo de RRHH. Un cuadro de mandos central presenta las cifras clave de RR.HH. de una forma gr\u00e1ficamente clara, y pueden refinarse hasta el nivel de detalle deseado mediante el desglose.<\/p>\n<p>HCM Analytics se basa en la soluci\u00f3n SAP BusinessObjects Dashboards, y los datos se almacenan en un SAP Business Warehouse (SAP BW). La Location Suite tambi\u00e9n se sigue desarrollando y mejorando constantemente - y al hacerlo, tambi\u00e9n se tiene en cuenta la tendencia hacia la consumerizaci\u00f3n de las TI: como alternativa a la visualizaci\u00f3n \"cl\u00e1sica\" en pantalla web, determinados procesos de RRHH se visualizar\u00e1n en el futuro en la moderna e intuitiva interfaz SAPUI5 (Fiori).<\/p>\n<h3>En el banco de pruebas<\/h3>\n<p>A la hora de planificar e implantar procesos de RR.HH. basados en flujos de trabajo, hay que superar muchos retos muy diferentes. Por ello, a la hora de implantar un proyecto de este tipo, se debe confiar en un proveedor de servicios de gesti\u00f3n de recursos humanos con experiencia, como Treorbis, que cuenta con amplios conocimientos t\u00e9cnicos, un m\u00e9todo de implantaci\u00f3n estructurado y un cierto instinto para aportar innovaciones a los usuarios.<\/p>\n<p>En el marco de un an\u00e1lisis del estado actual, primero se examinan cr\u00edticamente los procesos de la empresa y luego se elaboran mejoras para cada paso individual. Entre otras cosas, se combinan procesos y se reduce el n\u00famero de documentos que los acompa\u00f1an.<\/p>\n<p>Tambi\u00e9n se pone a prueba el panorama inform\u00e1tico existente. Para ello resulta \u00fatil un enfoque gradual. Utilizando el m\u00e9todo BPMN (Business Process Model and Notation), primero se modela un prototipo de los procesos de extremo a extremo, que se adapta sucesivamente a los requisitos del cliente y se perfecciona hasta que est\u00e1 listo para su implantaci\u00f3n.<\/p>\n<p>El esfuerzo y los costes para establecer flujos de trabajo con soporte inform\u00e1tico siguen siendo manejables. Los componentes del flujo de trabajo -disposici\u00f3n de la pantalla, transici\u00f3n entre pasos del proceso, transferencia de datos o control de documentos- se mapean en Location Suite en forma de componentes reutilizables.<\/p>","protected":false},"excerpt":{"rendered":"<p>Los procesos de RR.HH. manuales y basados en papel son costosos y requieren mucho tiempo, especialmente en las empresas descentralizadas. Con una soluci\u00f3n inform\u00e1tica integrada en SAP-HCM se pueden dise\u00f1ar flujos de trabajo estandarizados y acortar los tiempos de procesamiento.<\/p>","protected":false},"author":1206,"featured_media":60767,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[13318,1607],"tags":[839,1104,13640],"coauthors":[19955],"class_list":["post-60867","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coverstory-1605","category-mag1605","tag-hcm","tag-hr","tag-sap-human-capital-management","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016.jpg",1000,387,false],"thumbnail":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016-150x150.jpg",150,150,true],"medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016.jpg",400,155,false],"medium_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016-768x297.jpg",768,297,true],"large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016.jpg",1000,387,false],"image-100":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016-100x39.jpg",100,39,true],"image-480":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016-480x186.jpg",480,186,true],"image-640":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016-640x248.jpg",640,248,true],"image-720":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016-720x279.jpg",720,279,true],"image-960":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016-960x372.jpg",960,372,true],"image-1168":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016.jpg",1000,387,false],"image-1440":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016.jpg",1000,387,false],"image-1920":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016.jpg",1000,387,false],"1536x1536":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016.jpg",1000,387,false],"2048x2048":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016.jpg",1000,387,false],"trp-custom-language-flag":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016.jpg",18,7,false],"bricks_large_16x9":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016.jpg",1000,387,false],"bricks_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016.jpg",1000,387,false],"bricks_large_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016.jpg",1000,387,false],"bricks_medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016.jpg",600,232,false],"bricks_medium_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016.jpg",600,232,false],"profile_24":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016-24x24.jpg",24,24,true],"profile_48":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016-48x48.jpg",48,48,true],"profile_96":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016-96x96.jpg",96,96,true],"profile_150":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016-150x150.jpg",150,150,true],"profile_300":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Manuelle, papiergebundene HR-Prozesse sind gerade bei dezentral aufgestellten Unternehmen aufw\u00e4ndig und zeitintensiv. Mit einer SAP-HCM-integrierten IT-L\u00f6sung lassen sich standardisierte Workflows gestalten und Durchlaufzeiten verk\u00fcrzen.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e326.greatsolution.dev\/es\/categoria\/portadas\/portada-1605\/\" rel=\"category tag\">Coverstory 16-05<\/a>, <a href=\"https:\/\/e326.greatsolution.dev\/es\/categoria\/mag1605\/\" rel=\"category tag\">MAG 16-05<\/a>","author_info_v2":{"name":"Andr\u00e9 Schulte, MSG Treorbis","url":"https:\/\/e326.greatsolution.dev\/es\/author\/andre-schulte\/"},"comments_num_v2":"0 comentarios","_links":{"self":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/60867","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/users\/1206"}],"replies":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/comments?post=60867"}],"version-history":[{"count":0,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/60867\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/media\/60767"}],"wp:attachment":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/media?parent=60867"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/categories?post=60867"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/tags?post=60867"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/coauthors?post=60867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}