{"id":63425,"date":"2019-11-21T09:02:15","date_gmt":"2019-11-21T08:02:15","guid":{"rendered":"https:\/\/e326.greatsolution.dev\/?p=63425"},"modified":"2020-02-07T22:53:00","modified_gmt":"2020-02-07T21:53:00","slug":"servicios-arquitectura-informatica","status":"publish","type":"post","link":"https:\/\/e326.greatsolution.dev\/es\/servicios-arquitectura-informatica\/","title":{"rendered":"Servicios, arquitectura inform\u00e1tica, puntos de contacto, tiendas web, back-end y front office"},"content":{"rendered":"<p><strong><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63445\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger.jpg\" alt=\"Faerbinger\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>\u00bfQu\u00e9 pasa con el tema del comercio electr\u00f3nico? \u00bfQu\u00e9 pasa con el recorrido del cliente? \u00bfCu\u00e1l es el estado de \u00e1nimo en el mercado?<\/strong><\/p>\n<p><strong><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63435\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher.jpg\" alt=\"Hendrick Van Laaten Orador\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a><\/strong>\u00bfQu\u00e9 h\u00e1bitos observamos en el comportamiento B2C? \u00bfQu\u00e9 servicios reciben los clientes? La historia de Amazon es bien conocida.<\/p>\n<p>Al principio, Amazon pr\u00e1cticamente no hac\u00eda publicidad; todo el presupuesto se invert\u00eda en servicios, en cadenas de procesos, en gestionar entregas m\u00e1s r\u00e1pidas. Y eso cre\u00f3 una expectativa.<\/p>\n<p>Los compradores B2B, o buyer personas como se les llama, ahora tambi\u00e9n son exigentes: tiene que ser f\u00e1cil, tiene que tramitarse r\u00e1pidamente, tenemos que obtener informaci\u00f3n, mis t\u00e9cnicos de servicio tienen que responder r\u00e1pidamente una vez que he comprado el producto. Si eso no ocurre, es un reto.<\/p>\n<p>En SAP Commerce (antes SAP Hybris), la atenci\u00f3n se centra en el comercio minorista en l\u00ednea. El ADN de SAP no es la orientaci\u00f3n al cliente de la que todos hablamos. Esto est\u00e1 surgiendo lentamente con C\/4.<\/p>\n<p>A m\u00ed mismo me parece emocionante sentarme aqu\u00ed con colegas de la comunidad SAP. Y analizar los procesos desde la perspectiva del cliente y no de la empresa.<\/p>\n<p>Hay que gestionar, suministrar y orquestar otros canales, otros puntos de contacto.<\/p>\n<p>Se trata de un reto importante para las PYME e incluso para las grandes empresas. A menudo percibido como un temor, es en realidad una enorme oportunidad.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63436\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS.jpg\" alt=\"Carnicero KPS\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>En KPS, tenemos una divisi\u00f3n SAP muy grande y compramos una agencia digital hace seis a\u00f1os. Entonces tuvimos que aprender lo que significa armonizar las dos culturas.<\/p>\n<p>Porque son culturas diferentes, la del consultor cl\u00e1sico de SAP y la del consultor cl\u00e1sico de comercio electr\u00f3nico. Vemos fuertes departamentos de TI centrados por naturaleza en SAP y que a\u00fan no han entendido lo que significa adoptar un enfoque centrado en el cliente.<\/p>\n<p>Por otro lado, tenemos departamentos especializados que tambi\u00e9n est\u00e1n cada vez m\u00e1s sobrecargados de TI y no comprenden los procesos de back-end.<\/p>\n<p>Unir estos mundos era un reto para nosotros. Y esa fue una de las razones por las que SAP compr\u00f3 Hybris.<\/p>\n<figure id=\"attachment_63427\" aria-describedby=\"caption-attachment-63427\" style=\"width: 1000px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/DSC_6591_cmyk.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-63427\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/DSC_6591_cmyk.jpg\" alt=\"DSC 6591 Cmyk\" width=\"1000\" height=\"450\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/DSC_6591_cmyk.jpg 1000w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/DSC_6591_cmyk-768x346.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/DSC_6591_cmyk-100x45.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/DSC_6591_cmyk-480x216.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/DSC_6591_cmyk-640x288.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/DSC_6591_cmyk-720x324.jpg 720w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/DSC_6591_cmyk-960x432.jpg 960w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><figcaption id=\"caption-attachment-63427\" class=\"wp-caption-text\">De izquierda a derecha: Hendrik van Laaten (Medienwerft\/FIS), Johannes H\u00e4usele (OpenText), Michael Kramer (E-3 Magazin, como oyente), Stefan Metzger (KPS), Stefan Oltmanns (RealCore) y el analista Frank Niemann (Teknowlogy\/PAC). Por detr\u00e1s: Patrick Pierron (CAS AG) y Peter F\u00e4rbinger como moderador.<\/figcaption><\/figure>\n<p>Porque nos dimos cuenta de que no basta con dominar solo el back end, tambi\u00e9n necesito el front end. Creo que nos cost\u00f3 mucho conseguir esta integraci\u00f3n con las distintas tecnolog\u00edas.<\/p>\n<p>Y creo que es hora de empezar a adoptar un enfoque centrado en el cliente, es decir, en el recorrido del cliente.<\/p>\n<p>Por otro lado, los procesos est\u00e1ndar tienen que integrarse porque los sistemas de gesti\u00f3n de mercanc\u00edas tambi\u00e9n tienen que hacer mucho m\u00e1s que antes.<\/p>\n<p>Tambi\u00e9n est\u00e1 el aspecto de volver a la norma. Sin embargo, este requisito no termina en la parte de atr\u00e1s, sino que debe ser coherente hasta llegar al cliente.<\/p>\n<p>Sin embargo, la visi\u00f3n y la perspectiva deben partir del cliente. Yo parto del punto de vista del cliente final, pero no s\u00f3lo con un enfoque de comercio electr\u00f3nico; el marketing, la personalizaci\u00f3n y la segmentaci\u00f3n tambi\u00e9n influyen hasta el back end. Hay que reunir los datos de las transacciones con los datos de los clientes.<\/p>\n<p><strong><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63445\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger.jpg\" alt=\"Faerbinger\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>\u00bfQui\u00e9n es el responsable, el propietario de estos procesos?<\/strong><\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63436\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS.jpg\" alt=\"Carnicero KPS\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>No creo que el mismo propietario tenga que estar presente en todos los procesos. Y creo que el entendimiento entre el departamento de TI y los departamentos especializados tiene que ser mucho m\u00e1s intenso.<\/p>\n<p>Los departamentos de TI se actualizan con los conocimientos especializados de cada departamento. Los departamentos especializados tienen cada vez m\u00e1s conocimientos inform\u00e1ticos, y esto crece conjuntamente. \u00bfQui\u00e9n es el responsable de cada proceso? Los departamentos de TI y de empresa deben coordinarse entre s\u00ed.<\/p>\n<p>Y, por supuesto, hay un comit\u00e9 de direcci\u00f3n. No creo que en este mundo complejo una sola persona sea la due\u00f1a de todos los procesos.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Patrick-Pirron-CAS.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63437\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Patrick-Pirron-CAS.jpg\" alt=\"Patrick Pirron CAS\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Patrick-Pirron-CAS.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Patrick-Pirron-CAS-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Patrick-Pirron-CAS-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Patrick-Pirron-CAS-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Patrick-Pirron-CAS-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Patrick-Pirron-CAS-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>Este es un punto crucial. Conozco a un cliente que construye equipos de procesos de extremo a extremo, quieren alejarse de este enfoque, yo soy la persona responsable del ERP, yo soy la persona responsable del CRM, de la tienda web, etc., y yo soy la persona responsable del ERP.<\/p>\n<p>Est\u00e1n reestructurando su organizaci\u00f3n de tal forma que fusionan la inform\u00e1tica y el \u00e1rea especializada. Un planteamiento muy interesante. Las TI y la empresa est\u00e1n cada vez m\u00e1s unidas y creo que eso es crucial.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Pirron-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63430\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Pirron-1.jpg\" alt=\"Pirron\" width=\"1000\" height=\"554\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Pirron-1.jpg 1000w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Pirron-1-768x425.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Pirron-1-100x55.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Pirron-1-480x266.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Pirron-1-640x355.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Pirron-1-720x399.jpg 720w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Pirron-1-960x532.jpg 960w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63438\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text.jpg\" alt=\"Texto abierto Haeusele\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>Para los clientes actuales de SAP, todo gira en torno al tiempo de comercializaci\u00f3n o a la mejor forma de implantar las cosas.<\/p>\n<p>\u00bfLa persona con la responsabilidad general debe proceder del \u00e1rea especializada? \u00bfO sigue marcando la pauta el cl\u00e1sico back end SAP de la capa ERP? Yo dir\u00eda espont\u00e1neamente que el departamento de negocio deber\u00eda llevar la voz cantante.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63435\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher.jpg\" alt=\"Hendrick Van Laaten Orador\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>En los equipos \u00e1giles hay, por supuesto, un propietario del producto que coordina los requisitos de los departamentos especializados. Sin embargo, a menudo existe una mentalidad de silo en los departamentos especializados que hay que romper.<\/p>\n<p>El reto consiste en aunar los distintos objetivos para lograr el mejor resultado posible.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63439\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore.jpg\" alt=\"Oltmanns RealCore\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>\u00bfCu\u00e1ndo empiezo con equipos \u00e1giles y multifuncionales si ya me he decidido por un producto?<\/p>\n<p>Creo que los equipos interfuncionales son la clave de la nueva arquitectura SAP. Hay tantos componentes SAP, pero casi nadie sabe lo que pueden hacer. Pero yo me decido por un componente y solo entonces empiezo el proyecto.<\/p>\n<p>Ser \u00e1giles y reunir a todos: eso es. Aqu\u00ed es donde se necesita de nuevo la experiencia b\u00e1sica del Grupo SAP. Hay que integrar a los equipos internos de SAP.<\/p>\n<p>Para m\u00ed, es una cuesti\u00f3n de integraci\u00f3n, porque hasta ahora muchas cosas se han creado en silos: en el lado del comercio electr\u00f3nico y en el lado del back-end del ERP.<\/p>\n<p>Las empresas ya trabajan juntas. Sin embargo, a\u00fan no hemos crecido juntos en el aspecto inform\u00e1tico. SAP dispone ahora de un conjunto de herramientas que puede funcionar, pero tenemos que ser capaces de explicarlo como socios.<\/p>\n<p>No creo que sea f\u00e1cil ponerse en marcha. Todo el mundo dice que queremos ir por este camino, pero claro, es una gran inversi\u00f3n.<\/p>\n<p>En el sector del comercio electr\u00f3nico, hay un equipo joven que avanza muy deprisa y de forma \u00e1gil utilizando Scrum. Y, por supuesto, el petrolero de SAP no puede seguirle el ritmo.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63435\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher.jpg\" alt=\"Hendrick Van Laaten Orador\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>No solo nos centramos en la tecnolog\u00eda. En el pasado tambi\u00e9n utilizamos otras tecnolog\u00edas y no est\u00e1bamos especializados principalmente en SAP Hybris.<\/p>\n<p>No quiero alejarme completamente de los temas tecnol\u00f3gicos, pero la pregunta es: \u00bfD\u00f3nde quiere estar la empresa dentro de cinco a\u00f1os? \u00bfQu\u00e9 est\u00e1 pasando fuera, en el mercado, en la competencia? El enfoque centrado en el cliente es crucial.<\/p>\n<p><strong><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Stefan-Oltmanns.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63431\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Stefan-Oltmanns.jpg\" alt=\"Stefan Oltmanns\" width=\"1000\" height=\"554\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Stefan-Oltmanns.jpg 1000w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Stefan-Oltmanns-768x425.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Stefan-Oltmanns-100x55.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Stefan-Oltmanns-480x266.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Stefan-Oltmanns-640x355.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Stefan-Oltmanns-720x399.jpg 720w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Stefan-Oltmanns-960x532.jpg 960w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/strong><\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63439\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore.jpg\" alt=\"Oltmanns RealCore\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>Intentamos explicar c\u00f3mo es el mundo del proceso integrador hasta llegar a la tienda online. Y luego vienen precisamente estos retos y preguntas:<\/p>\n<p>\u00bfAd\u00f3nde quiere ir ahora? Estamos hablando de su futuro y lo que traemos con nosotros es su futuro. El cliente actual de SAP y nosotros a menudo ni siquiera sabemos todav\u00eda ad\u00f3nde queremos ir. Tenemos que pensar en ello juntos.<\/p>\n<p>El \u00e1rea especializada suele decidir cuando se trata del front end. Sin embargo, como consultores SAP, a menudo somos incapaces de demostrar el valor a\u00f1adido.<\/p>\n<p>Pero el valor a\u00f1adido suele ser la integraci\u00f3n. Toda la interacci\u00f3n es crucial. Tengo que explicar todo el proceso al usuario de SAP.<\/p>\n<p>Y el departamento de TI y nosotros, como consultores, debemos ser capaces de explicar el valor empresarial. Por supuesto, yo soy mucho m\u00e1s r\u00e1pido en comercio electr\u00f3nico y despliegue de front-end que en desarrollo inform\u00e1tico de back-end durante la integraci\u00f3n.<\/p>\n<p>Ese es tambi\u00e9n el gran problema de SAP: las ventas no pueden explicar el \"comercio electr\u00f3nico\" porque el tema del \"comercio\" tambi\u00e9n se ha vuelto muy complejo.<\/p>\n<p>Creo que tambi\u00e9n tenemos que pensar en dos velocidades. Por detr\u00e1s tengo un enorme back end, por delante soy muy r\u00e1pido con herramientas inform\u00e1ticas modernas, pero ya no estoy integrado en muchos sitios.<\/p>\n<p><strong><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63440\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann.jpg\" alt=\"Frank Niemann\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a><\/strong> \u00bfC\u00f3mo empieza? B\u00e1sicamente, hay tres capas: Cultura empresarial, procesos empresariales y tecnolog\u00eda.<\/p>\n<p>Hay que moverse en estas dimensiones. Muchos clientes actuales de SAP siguen dedicando demasiado tiempo a la tecnolog\u00eda. No se trata de un problema espec\u00edfico de SAP.<\/p>\n<p>Se dar\u00e1 cuenta de lo mismo cuando trate con Salesforce u Oracle. Cultura significa: \u00bfA d\u00f3nde quiero llegar realmente? \u00bfQuiero mejorar mi servicio de atenci\u00f3n al cliente o la experiencia del cliente, ahorrar dinero o quiz\u00e1s quiero apoyar nuevos procesos empresariales?<\/p>\n<p>Los empleados de los departamentos especializados lo saben. Los empleados saben lo que quieren los clientes. Pero no siempre se les pregunta.<\/p>\n<p>La gesti\u00f3n, en cambio, tiene que cambiar algo y llevarse a todo el mundo por delante; es sobre todo la gesti\u00f3n del cambio de lo que estamos hablando aqu\u00ed.<\/p>\n<p>No se trata tanto de introducir o integrar la pr\u00f3xima tecnolog\u00eda. La gente tiende a hacer eso: Necesitamos una aplicaci\u00f3n r\u00e1pidamente, necesitamos un front-end r\u00e1pidamente ahora, un omnichannel.<\/p>\n<p>Todo eso es cierto. Pero no hay que olvidar el back end, porque el cumplimiento tambi\u00e9n forma parte de la experiencia del cliente.<\/p>\n<p>Estas funciones son los procesos empresariales importantes y s\u00f3lo despu\u00e9s viene la tecnolog\u00eda; despu\u00e9s viene el plan de desarrollo y ah\u00ed SAP tiene ahora a\u00fan m\u00e1s tecnolog\u00eda con Qualtrics.<\/p>\n<p>La tecnolog\u00eda est\u00e1 ah\u00ed. Se puede integrar. Se pueden unir los distintos productos. Pero no puedes comprar el proyecto, la arquitectura de SAP.<\/p>\n<p>Cada uno tiene que desarrollar la arquitectura por s\u00ed mismo. Puedes comprobar los bloques de construcci\u00f3n y luego decir, voy a tomar eso de SAP. Hybris a\u00fan no est\u00e1 integrado, sigue siendo un trabajo en curso, pero es un buen producto.<\/p>\n<p>Sin embargo, puede haber otros temas en los que otros proveedores de TI est\u00e9n mejor posicionados, en cuyo caso podr\u00eda utilizar un servicio en la nube de Azure en lugar de SAP para los an\u00e1lisis.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63438\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text.jpg\" alt=\"Texto abierto Haeusele\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>Si tuviera una nube global, no tendr\u00eda estos problemas de integraci\u00f3n, \u00bfverdad?<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63440\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann.jpg\" alt=\"Frank Niemann\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>Estamos avanzando en esta direcci\u00f3n. Los grandes hiperescaladores no solo han construido infraestructuras en los \u00faltimos a\u00f1os, sino que tambi\u00e9n han invertido mucho en la capacidad de desarrollar aplicaciones y gestionar las API de estas aplicaciones. Los hiperescaladores pueden ofrecer cierto grado de integraci\u00f3n previa.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63439\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore.jpg\" alt=\"Oltmanns RealCore\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>Tenemos un problema cuando hablamos de cosas que son posibles, pero a\u00fan no hemos hecho los deberes... y ni siquiera hacemos llegar la mercanc\u00eda al cliente\". Me ha gustado la introducci\u00f3n.<\/p>\n<p>Amazon ha crecido de forma diferente. Ahora observamos que el front end se est\u00e1 configurando en sentido contrario al original. Pero para muchos clientes SAP existentes, todav\u00eda no ha pasado nada en el back end.<\/p>\n<p>Eso es un gran problema. En realidad deber\u00edas poner en orden el front-end y las aplicaciones para poder aumentar la velocidad.<\/p>\n<p>Ah\u00ed es donde tenemos una gran discrepancia. Hay muchos productos estupendos, pero primero hay que hacer los deberes en la parte de atr\u00e1s.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63438\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text.jpg\" alt=\"Texto abierto Haeusele\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>S\u00ed, o tal vez empezar de nuevo con S\/4 en el extremo posterior.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63440\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann.jpg\" alt=\"Frank Niemann\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>Pero as\u00ed es Greenfield.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63438\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text.jpg\" alt=\"Texto abierto Haeusele\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>Amazon ha crecido de forma diferente. Primero hicieron el back-end y luego programaron el front-end.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63440\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann.jpg\" alt=\"Frank Niemann\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>Pero Amazon tampoco ten\u00eda un legado, empezaron en un prado.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Johannes-Haeusele.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63432\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Johannes-Haeusele.jpg\" alt=\"Johannes Haeusele\" width=\"1000\" height=\"554\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Johannes-Haeusele.jpg 1000w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Johannes-Haeusele-768x425.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Johannes-Haeusele-100x55.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Johannes-Haeusele-480x266.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Johannes-Haeusele-640x355.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Johannes-Haeusele-720x399.jpg 720w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Johannes-Haeusele-960x532.jpg 960w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63438\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text.jpg\" alt=\"Texto abierto Haeusele\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>Y Amazon no ten\u00eda empleados que llevaran cincuenta o sesenta a\u00f1os trabajando en los procesos. Era una start-up, por eso empezaron de cero, y no todo el mundo es un Amazon. El enfoque greenfield me parece m\u00e1s interesante para deshacerse de todos estos problemas heredados.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63435\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher.jpg\" alt=\"Hendrick Van Laaten Orador\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>\u00bfCu\u00e1nto dinero habr\u00eda que invertir para que hubiera un retorno de la inversi\u00f3n centrado en el cliente? La respuesta podr\u00eda ser: poco en el front office, pero mucho en los procesos.<\/p>\n<p>No es f\u00e1cil tener esta visi\u00f3n y saber en qu\u00e9 se quiere invertir. Pero si solo nos centramos en la tecnolog\u00eda y perdemos de vista al cliente final, se hace dif\u00edcil.<\/p>\n<p>No habr\u00e1 tecnolog\u00eda sin clientes, porque entonces la tienda estar\u00e1 fuera del negocio. Es importante centrarse en ambos aspectos: en el cliente y en la tecnolog\u00eda.<\/p>\n<p>Creo que todo crece conjuntamente. No basta con hacer una tienda web bonita e intentar estar presente en todos los canales, que es lo que hacen muchos proveedores de servicios. Nuestros retos son mayores: servicios digitales, venta multinivel o gesti\u00f3n documental integral.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63439\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore.jpg\" alt=\"Oltmanns RealCore\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>Pero tambi\u00e9n estamos diciendo: tengo que trabajar con nuevas tecnolog\u00edas. Este enfoque es una gran oportunidad.<\/p>\n<p>Hay muchos problemas y tambi\u00e9n es un gran proceso de cambio en la empresa. Y puedo ser mucho m\u00e1s r\u00e1pido con las nuevas opciones en la nube, con SAP Cloud Platform puedo sacarlo adelante.<\/p>\n<p>Aporto velocidad a mi desarrollo front-end, pero esto tiene un enorme impacto en el back-end y supone un gran cambio no solo en TI, sino tambi\u00e9n en la empresa.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63436\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS.jpg\" alt=\"Carnicero KPS\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>El debate sobre la tecnolog\u00eda nace de una incertidumbre extrema, porque casi nadie sabe realmente lo que nos espera.<\/p>\n<p>A algunas empresas les vendr\u00eda bien una evaluaci\u00f3n conjunta con profesionales de la estrategia: \u00bfHacia d\u00f3nde se dirige mi empresa y el sector? No creo que muchas empresas lo hagan.<\/p>\n<p>\u00bfY qu\u00e9 ocurre en su lugar? Hay un departamento de ventas de SAP que est\u00e1 orientado al producto, y se precipita en todas las empresas y el departamento de ventas tiene sus especificaciones y vende productos.<\/p>\n<p>Sin embargo, este planteamiento no tiene ning\u00fan beneficio para las empresas en s\u00ed. Ser\u00eda importante preguntarse: \u00bfA d\u00f3nde me lleva el viaje? No creo que mucha gente piense en esto, sino que cae en el accionismo: ahora yo tambi\u00e9n tengo que centrarme en el cliente.<\/p>\n<p>Tenemos muchos interlocutores que nos inundan con historias de clientes, pero este enfoque no es coherente. Hay lagunas en los procesos y en el back end, de las que los implicados a menudo no se dan cuenta en el momento.<\/p>\n<p>Hay mucho accionismo y a menudo se descuida el back end. Los usuarios B2B son extremadamente prudentes y se centran en el back end; se lo piensan mucho antes de cambiar nada en el front office.<\/p>\n<p>Si esto no se integra correctamente, no tiene ninguna posibilidad. La plataforma en la nube de SAP se descuida porque no hay expertos internos en este \u00e1mbito.<\/p>\n<p>En contraste con el B2C, donde las aplicaciones est\u00e1n dispersas por toda la empresa pero no son escalables porque no est\u00e1n orquestadas con el back-end.<\/p>\n<p>Nuestro trabajo es discutir al m\u00e1s alto nivel: \u00bfDe qu\u00e9 estamos hablando? No estamos hablando de tecnolog\u00eda, no estamos hablando solo de centrarnos en el cliente, estamos hablando de tu empresa y de hacia d\u00f3nde vas.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63445\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger.jpg\" alt=\"Faerbinger\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a><strong>Entonces, \u00bfla demanda o la cuesti\u00f3n de un modelo de arquitectura de comercio electr\u00f3nico?<\/strong><\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Patrick-Pirron-CAS.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63437\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Patrick-Pirron-CAS.jpg\" alt=\"Patrick Pirron CAS\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Patrick-Pirron-CAS.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Patrick-Pirron-CAS-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Patrick-Pirron-CAS-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Patrick-Pirron-CAS-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Patrick-Pirron-CAS-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Patrick-Pirron-CAS-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>Exactamente. Ese es el resultado. Si hablo de forma centrada en el cliente, entonces har\u00eda bien en contar con alguien que tambi\u00e9n conozca la infraestructura existente y que tambi\u00e9n comprenda la arquitectura inform\u00e1tica de SAP.<\/p>\n<p>Tambi\u00e9n es importante tener al cliente final en el centro. Pero tambi\u00e9n necesito contar con la experiencia de mis equipos \u00e1giles: \u00bfQu\u00e9 es completamente irrealista y qu\u00e9 es factible? Pero es dif\u00edcil formar estos grupos y moderarlos de esta manera.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63435\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher.jpg\" alt=\"Hendrick Van Laaten Orador\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>Hay que tener el valor de reunir a estas personas. Los responsables de marketing y comercio electr\u00f3nico nos encuentran interesantes, y los responsables de SAP encuentran interesante a FIS.<\/p>\n<p>Cuando s\u00f3lo se habla de los procesos existentes, siempre resulta sorprendente el potencial que yace latente en la empresa.<\/p>\n<p>A menudo, basta con adaptar un poco los procesos para obtener enormes beneficios para el cliente. Estos procesos simplemente no se utilizan porque el departamento de TI no ha preguntado a nadie y los departamentos de marketing o ventas no eran conscientes de las posibilidades.<\/p>\n<p>Hay que reunir a la gente y preguntarle: \u00bfQu\u00e9 podemos sacar de esta optimizaci\u00f3n de procesos, optimizaci\u00f3n de tiendas y optimizaci\u00f3n multicanal?<\/p>\n<p>S\u00e9 que todos tienen miedo, nadie puede ver el futuro. Me oriento en lo que puedo hacer y en lo que puedo aprovechar.<\/p>\n<p>Hay mucha experiencia en el servicio. Que sea digital no significa que ya no se necesiten personas. \u00bfPor qu\u00e9 no utilizar esto como diferenciador, como ventaja competitiva?<\/p>\n<p>Se trata de una gran oportunidad para que muchas empresas, incluso con presupuestos reducidos, aprovechen poco a poco este potencial latente.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63439\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore.jpg\" alt=\"Oltmanns RealCore\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>No lo veo desde el punto de vista del cliente, sino un poco desde el punto de vista tecnol\u00f3gico, y eso tambi\u00e9n es un problema para m\u00ed. Cuando hablamos hoy con los clientes, surge la pregunta: \u00bfPor qu\u00e9 necesito ma\u00f1ana un nuevo sistema de procesamiento de campa\u00f1as?<\/p>\n<p>\u00bfNo puedo pasarme a S\/4 y entonces todo seguir\u00e1 funcionando? Hoy o ma\u00f1ana, los procesos saldr\u00e1n del ERP y pasar\u00e1n a la capa superior.<\/p>\n<p>Si los procesos se desplazan, naturalmente tengo que reconstruir algo en el backend. Sigue siendo dif\u00edcil discutir hoy qu\u00e9 funcionalidad dejar\u00e1 de existir ma\u00f1ana, pero ya no necesito instalar en el backend lo que se traslada a otro lugar.<\/p>\n<p>Es una discusi\u00f3n muy dif\u00edcil. Tengo que reunir a todo el mundo y ser muy abierto al respecto, lo que, por supuesto, es dif\u00edcil. Todo el mundo quiere proteger sus propias acciones y afrontar el futuro con seguridad.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63436\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS.jpg\" alt=\"Carnicero KPS\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>Ese es tambi\u00e9n el reto al que se enfrentan las empresas. Y en el que nosotros, como consultores, s\u00f3lo podemos ejercer una influencia limitada. Es una moderaci\u00f3n entre los mundos.<\/p>\n<p>Antes, los contactos eran los departamentos de inform\u00e1tica, comercio electr\u00f3nico, etc. Hab\u00eda casos aislados. Hoy, todo crece conjuntamente.<\/p>\n<p>Tengo que elevar a las personas implicadas al mismo nivel para que luego puedan encontrar la soluci\u00f3n adecuada dentro de la empresa. Esto ha cambiado por completo nuestro perfil como consultores.<\/p>\n<p>Antes te centrabas mucho m\u00e1s en los aspectos t\u00e9cnicos y eras mejor o peor que la otra persona. Hoy est\u00e1s mucho m\u00e1s implicado en el entorno pol\u00edtico de la empresa. \u00bfC\u00f3mo me desenvuelvo all\u00ed? \u00bfC\u00f3mo convenzo a la gente?<\/p>\n<p><strong><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63433\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten.jpg\" alt=\"Hendrick Van Laaten\" width=\"1000\" height=\"554\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten.jpg 1000w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-768x425.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-100x55.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-480x266.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-640x355.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-720x399.jpg 720w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-960x532.jpg 960w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/strong><\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63435\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher.jpg\" alt=\"Hendrick Van Laaten Orador\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>Ya sean datos maestros, campa\u00f1as publicitarias, material publicitario, datos de clientes, etc. Si estos par\u00e1metros se enriquecen de forma centralizada y todos los departamentos viven de ellos, se pueden tender puentes bastante bien en la realidad.<\/p>\n<p><strong><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63445\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger.jpg\" alt=\"Faerbinger\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>As\u00ed que emocionalmente, estoy contigo. Pero si no pongo en orden mi gesti\u00f3n de datos maestros, todas las experiencias de los clientes ser\u00e1n dif\u00edciles, \u00bfverdad?<\/strong><\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Patrick-Pirron-CAS.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63437\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Patrick-Pirron-CAS.jpg\" alt=\"Patrick Pirron CAS\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Patrick-Pirron-CAS.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Patrick-Pirron-CAS-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Patrick-Pirron-CAS-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Patrick-Pirron-CAS-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Patrick-Pirron-CAS-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Patrick-Pirron-CAS-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>Pero no los veo como problemas del futuro. Son problemas que siempre han existido y creo que seguir\u00e1n existiendo dentro de diez a\u00f1os. No creo que se vayan a resolver todos.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63440\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann.jpg\" alt=\"Frank Niemann\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>La calidad de los datos seguir\u00e1 siendo un reto dentro de diez a\u00f1os.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63439\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore.jpg\" alt=\"Oltmanns RealCore\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>El mensaje muy claro sobre una \u00fanica fuente de verdad en el futuro es que puede parecer un poco mejor, pero no resolver\u00e1 todos los problemas.<\/p>\n<p>Cuando analizamos SAP desde el punto de vista de los productos, \u00bftenemos una \u00fanica fuente de verdad? Est\u00e1 claro que no.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63435\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher.jpg\" alt=\"Hendrick Van Laaten Orador\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>La idea b\u00e1sica ya ha sido reconocida en SAP. Los problemas surgen cuando las empresas tienen datos en lugares diferentes. Y creo que SAP ya tiene un enfoque \u00fatil en cuanto a la idea b\u00e1sica.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63439\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore.jpg\" alt=\"Oltmanns RealCore\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>SAP ha reconocido la idea b\u00e1sica y avanza en la direcci\u00f3n correcta. Pero en los \u00faltimos a\u00f1os SAP se ha interpuesto en su propio camino.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63440\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann.jpg\" alt=\"Frank Niemann\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>Y no s\u00f3lo por los problemas heredados, SAP tambi\u00e9n ha creado nuevas cargas al adquirir productos que tienen cada uno su propio modelo de datos.<\/p>\n<p>Todos los dem\u00e1s fabricantes tambi\u00e9n lo tienen. Salesforce y otros est\u00e1n luchando con los mismos problemas. Esta es una direcci\u00f3n de desarrollo, por ejemplo, tener una \u00fanica fuente de verdad para el perfil del cliente.<\/p>\n<p>A\u00fan no hemos llegado a ese punto. Y no creo que este reto se resuelva creando un modelo de datos basado en S\/4, sino introduciendo un sistema de gesti\u00f3n de datos subyacente que re\u00fana estos diferentes cacharros en una especie de middleware, como est\u00e1n intentando hacer actualmente otros fabricantes.<\/p>\n<p>Ese es su componente t\u00e9cnico. Entonces ser\u00e1 posible integrar estos productos no solo a trav\u00e9s de interfaces, sino tambi\u00e9n a nivel de datos.<\/p>\n<p>Pero a\u00fan no hemos llegado a ese punto. Esto puede instalarse individualmente para cada cliente: es mucho trabajo. Pero creo que empresas como SAP y otras tienen que evolucionar en esta direcci\u00f3n.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63439\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore.jpg\" alt=\"Oltmanns RealCore\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>Lo que ha dicho sobre los modelos de datos es que los clientes deben unificar sus \u00e1reas. Los distintos modelos de datos del front office y el back office deben reunirse en una \u00fanica soluci\u00f3n.<\/p>\n<p>Esta complejidad debe reducirse, tambi\u00e9n en el lado SAP. Entonces, el back-end podr\u00e1 por fin aceptar las solicitudes del front-end.<\/p>\n<p>Por el momento, no se trata de un rechazo del back end, sino de una demanda excesiva. No hay recursos, no hay una definici\u00f3n clara por parte del departamento, eso es lo que lleva a los problemas. Simplemente porque los dos grupos no pueden hablar entre s\u00ed.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63440\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann.jpg\" alt=\"Frank Niemann\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>Si SAP promete que tenemos una cartera que puede gestionar todo lo que una empresa necesita de extremo a extremo, entonces el cliente, especialmente el cliente PYME, puede esperar que las cosas est\u00e9n armonizadas, tanto a nivel de interfaz como a nivel de proceso.<\/p>\n<p>El punto \u00fanico de verdad va a\u00fan m\u00e1s lejos. Tambi\u00e9n significa, por ejemplo, una orientaci\u00f3n coherente del usuario. Gesti\u00f3n de identidades, un concepto de seguridad, un concepto de aprovisionamiento, un concepto de licencia y uso. Y el siguiente paso es un ciclo de vida armonizado.<\/p>\n<p>Si utilizo los productos juntos, tengo que asegurarme de que alguna actualizaci\u00f3n no signifique que determinados procesos dejen de funcionar con la misma fluidez y que tenga que \"pensar\" en ellos de otra manera.<\/p>\n<p>En otras palabras, es necesaria esta integraci\u00f3n previa en los productos, pero tambi\u00e9n una integraci\u00f3n completa en las cadenas de procesos. Cuando se introduce S\/4 o C\/4 en determinados sectores, considero que los socios son especialmente competentes, ya que naturalmente tienen conocimientos m\u00e1s detallados que SAP, que a su vez se concentra en el desarrollo de otros productos.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63435\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher.jpg\" alt=\"Hendrick Van Laaten Orador\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>Tenemos una soluci\u00f3n especial para la venta t\u00e9cnica al por mayor. Todos los componentes espec\u00edficos del sector est\u00e1n predefinidos como est\u00e1ndares.<\/p>\n<p>Creo que, como proveedor de servicios, tenemos que estar contentos si SAP no lo hace todo. Las funcionalidades b\u00e1sicas de SAP deben estar disponibles. Y luego la experiencia en el sector tiene que venir de los proveedores de servicios.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Patrick-Pirron-CAS.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63437\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Patrick-Pirron-CAS.jpg\" alt=\"Patrick Pirron CAS\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Patrick-Pirron-CAS.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Patrick-Pirron-CAS-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Patrick-Pirron-CAS-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Patrick-Pirron-CAS-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Patrick-Pirron-CAS-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Patrick-Pirron-CAS-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>Somos empresas de consultor\u00eda. Siempre digo que el mundo no es unidimensional. Digo que tampoco nada es unidimensional desde el punto de vista de SAP.<\/p>\n<p>Incluso en el futuro, no habr\u00e1 clientes que s\u00f3lo utilicen productos SAP. Tambi\u00e9n debemos centrarnos en reunir a esta orquesta.<\/p>\n<p>Pero est\u00e1 claro que con la exigencia a SAP: si utilizo componentes est\u00e1ndar, tanto en la parte de procesos como en la t\u00e9cnica, tiene que ser m\u00e1s compatible.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63440\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann.jpg\" alt=\"Frank Niemann\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>No solo en lo que respecta a la experiencia del cliente, sino tambi\u00e9n a la gesti\u00f3n del capital humano. Tambi\u00e9n tengo que integrar Salesforce y C\/4 Hana, y tengo que integrar SuccessFactors y Workday.<\/p>\n<p>Y a veces la habilidad del equipo de ventas decide que ser\u00e1 una soluci\u00f3n de Workday y no de SuccessFactors. Sin embargo, tal y como est\u00e1n las cosas hoy en d\u00eda, SAP todav\u00eda no est\u00e1 jugando con las ventajas que podr\u00eda aportar de tal manera que la ventaja de las funciones sea grande.<\/p>\n<p>Otros pueden ser un poco mejores en cuanto a funciones y m\u00e1s modernos en cuanto a interfaz de usuario, pero la integraci\u00f3n es tan importante para m\u00ed que el mandato es para SAP.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63438\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text.jpg\" alt=\"Texto abierto Haeusele\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>S\u00ed, desde la perspectiva de un cliente de SAP, ser\u00eda deseable se\u00f1alar las opciones de integraci\u00f3n con mucha m\u00e1s frecuencia, se\u00f1alar lo que ya existe, si entonces utilizo SuccessFactors en lugar de Workday.<\/p>\n<p>Y tambi\u00e9n ser\u00eda deseable que los consultores y proveedores de servicios se\u00f1alaran lo que ya est\u00e1 disponible de serie: \u00bfes f\u00e1cil reunirlo todo?<\/p>\n<p>Veo muchos proyectos con el argumento de que el cliente es tan dif\u00edcil porque no lo ha entendido y realmente lo quiere as\u00ed, etc.<\/p>\n<p>Y como eso es lo que el cliente dice y quiere, eso es lo que uno hace como proveedor de servicios: siempre ser\u00e1 as\u00ed. Pero estar\u00eda bien que hubiera m\u00e1s casos en los que se pudiera recurrir a estas funciones est\u00e1ndar, a lo que ya existe.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63440\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann.jpg\" alt=\"Frank Niemann\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>Una peque\u00f1a cr\u00edtica a los proveedores de servicios: en los \u00faltimos a\u00f1os, por supuesto, tambi\u00e9n han ganado bastante con el hecho de que hay deseos individuales que luego se pueden poner en pr\u00e1ctica en forma de personalizaciones y otros servicios - esto, por supuesto, depende del cliente. Pero tambi\u00e9n porque el proveedor de servicios dec\u00eda: Lo hacemos todo.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63439\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore.jpg\" alt=\"Oltmanns RealCore\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>Y todo lo que la norma SAP no proporcionaba, lo atornill\u00e1bamos, tarde o temprano, porque en alg\u00fan momento la presi\u00f3n era muy alta o no ten\u00edamos ganas de seguir discutiendo. En alg\u00fan momento, lo atornillamos.<\/p>\n<p>Creo que el mundo ha cambiado. Las ofertas y los servicios de asesoramiento tendr\u00e1n que cambiar. Tenemos que volver a ofrecer asesoramiento, y creo que eso es realmente emocionante y exactamente el camino correcto a seguir. Pero, \u00bfqu\u00e9 son las normas?<\/p>\n<p>No hablo solo de S\/4, tambi\u00e9n hablamos de integraci\u00f3n. Y tenemos que explicar la integraci\u00f3n, tenemos que ser capaces de explicar la funcionalidad de SAP al cliente.<\/p>\n<p>Tengo que ser capaz de explicar los marcos API, etc. No es f\u00e1cil. Pero tengo que explicar este escenario a un cliente para que entienda el panorama.<\/p>\n<p>Una organizaci\u00f3n de ventas SAP no podr\u00e1 hacerlo. Creo que eso est\u00e1 de nuestra parte. Por eso tenemos normas para los procesos y el back-end.<\/p>\n<p>Integrar un sistema entero es m\u00e1s f\u00e1cil que integrar muchas partes peque\u00f1as. Esto llega hasta los datos de Google: hay muchos est\u00e1ndares, incluso en nuestra arquitectura SAP.<\/p>\n<p>Y muchos clientes est\u00e1n jodiendo, jodiendo, jodiendo. Pero todav\u00eda hay muchas cosas que no sabemos. Hay que ser honestos al respecto. Nuestras tropas tienen que entender la tecnolog\u00eda y convencer al cliente:<\/p>\n<p>Ten cuidado, si vas all\u00ed, tendr\u00e1 estas y aquellas consecuencias. Este enfoque de asesoramiento es especialmente importante.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63438\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text.jpg\" alt=\"Texto abierto Haeusele\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>En el mundo ideal, el proveedor de servicios cuenta con un responsable de preventa o un arquitecto de soluciones que est\u00e1 siempre al d\u00eda de la cartera de SAP.<\/p>\n<p>Y s\u00f3lo entonces, una vez informado y asesorado el cliente, se pone en marcha el proyecto. As\u00ed deber\u00eda ser un mundo ideal. Pero no funciona. No se puede vender, tambi\u00e9n porque los presupuestos suelen venir de otro lado.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63439\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore.jpg\" alt=\"Oltmanns RealCore\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>A veces me pregunto: \u00bfqu\u00e9 hago con todos estos datos? Cuando analizo -\u00bfcu\u00e1ntos minoristas tienen cient\u00edficos de datos?<\/p>\n<p>Si no tengo un experto, no necesito la mayor\u00eda de los datos. Esta es otra reorientaci\u00f3n que no siempre funciona en la empresa.<\/p>\n<p>En primer lugar, lo quieren todo: los mejores y m\u00e1s grandes productos, pero al final se hace muy poco con los datos.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63435\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher.jpg\" alt=\"Hendrick Van Laaten Orador\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>La idea b\u00e1sica de conocer al cliente, segmentar y automatizar alberga un gran potencial para los clientes que suelen tener menos recursos pero procesos muy complejos.<\/p>\n<p>\u00bfPorque qu\u00e9 hace la automatizaci\u00f3n? A\u00f1ade impulsos de marketing a procesos complejos. Ese es nuestro trabajo. Datos de Facebook y Google, ahora hay una estrategia muy clara en el marketing.<\/p>\n<p>Muchos clientes piensan que compro una suite de marketing y puedo utilizarla para organizar estos canales. No. Ni siquiera pueden replicar las nuevas oportunidades de marketing que Facebook presenta cada mes.<\/p>\n<p>Tenemos nuestro propio equipo para controlar esto. Y luego hay que conectarlo. Por ejemplo, est\u00e1 el \"Facebook Business Manager\", que se conecta a SAP Marketing a trav\u00e9s de determinadas interfaces y luego solo proporciona datos y KPI relevantes.<\/p>\n<p>SAP ha reconocido con raz\u00f3n que no puede encajar todo en una sola suite. Hay mundos que necesitan estar conectados.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63439\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore.jpg\" alt=\"Oltmanns RealCore\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>Puedo cargar muchas cosas desde fuera y trabajar con ellas. As\u00ed es como est\u00e1 integrado. Pero en muchos casos tambi\u00e9n se desconoce la funcionalidad disponible.<\/p>\n<p>Ahora existe el procesamiento de cupones, algo que tradicionalmente nunca ha formado parte de la cartera de SAP. Donde los proveedores de TPV siempre se han dado palmaditas en la espalda porque eran los \u00fanicos que pod\u00edan hacerlo: cupones.<\/p>\n<p>Sin embargo, tengo la herramienta en combinaci\u00f3n con SAP Hybris. Pero nadie lo sabe. En algunos casos, SAP Sales tampoco lo sabe. \u00bfQui\u00e9n sabe lo que se est\u00e1 construyendo en todas partes? No es f\u00e1cil porque SAP tambi\u00e9n se est\u00e1 superando a s\u00ed misma. Nuestro trabajo es mostrar lo que es posible.<\/p>\n<p><strong><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63445\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger.jpg\" alt=\"Faerbinger\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>SAP tiene oportunidades. Pero, \u00bfseguir\u00e1 siendo SAP el sistema l\u00edder en comercio electr\u00f3nico?<\/strong><\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63439\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore.jpg\" alt=\"Oltmanns RealCore\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>Si SAP pierde esta batalla, SAP Sales tendr\u00e1 un gran problema.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63435\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher.jpg\" alt=\"Hendrick Van Laaten Orador\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>SAP es un est\u00e1ndar. Y todo el conocimiento que hay en torno a la mesa, los 20 a\u00f1os de experiencia en SAP que aporta FIS, es un potencial enorme.<\/p>\n<p>Las PYME quieren ser atendidas a la altura de los ojos. Naturalmente, las PYME quieren un mediador, un socio. Ese ser\u00e1 siempre nuestro trabajo.<\/p>\n<p>Los requisitos para los socios de SAP existen: Crear un sistema de bonificaciones, crear un programa de fidelizaci\u00f3n para la tienda, conectar con el sistema de caja desde el comercio electr\u00f3nico, hacer marketing local a trav\u00e9s de Facebook.<\/p>\n<p>Puedes resolverlo utilizando los bloques de construcci\u00f3n b\u00e1sicos. Y creo que eso es bueno. Si SAP pisa el acelerador, se puede hacer. Creo que SAP no se ha esforzado lo suficiente en los \u00faltimos dos o tres a\u00f1os, en comparaci\u00f3n con Adobe.<\/p>\n<p>SAP se centra en el negocio B2B o en el gran negocio B2C. Por supuesto, ah\u00ed siguen bien posicionados. Pero tienen que mantener el ritmo.<\/p>\n<p>SAP necesita ampliar la perspectiva y la aceptaci\u00f3n del marketing en sus departamentos de marketing y ventas. Muchos usuarios piensan en Salesforce, otros pueden pensar en Adobe o Magento: es m\u00e1s barato y m\u00e1s r\u00e1pido.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63439\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore.jpg\" alt=\"Oltmanns RealCore\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>En mi opini\u00f3n, la pelota est\u00e1 en el tejado de la consultora y ya no en el de SAP. Es mi opini\u00f3n personal.<\/p>\n<p>Porque no s\u00e9 si SAP tiene un equipo en el mercado alem\u00e1n. Puede que haya un equipo, pero no hay mano de obra detr\u00e1s que pueda explicar el gran n\u00famero de clientes.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Patrick-Pirron-CAS.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63437\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Patrick-Pirron-CAS.jpg\" alt=\"Patrick Pirron CAS\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Patrick-Pirron-CAS.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Patrick-Pirron-CAS-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Patrick-Pirron-CAS-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Patrick-Pirron-CAS-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Patrick-Pirron-CAS-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Patrick-Pirron-CAS-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>SAP est\u00e1 orientado al producto. Para nosotros, como empresa de consultor\u00eda, esto significa que la integraci\u00f3n de procesos sigue siendo importante.<\/p>\n<p>Tanto si realizo la integraci\u00f3n de procesos teniendo en cuenta qu\u00e9 soluci\u00f3n tiene el cliente y c\u00f3mo la a\u00fano, como si utilizo nuevos m\u00f3dulos de SAP, para nosotros, como empresa de consultor\u00eda, en realidad es exactamente lo que hemos estado haciendo durante los \u00faltimos 20 a\u00f1os.<\/p>\n<p><strong><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Stefan-Metzger.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63434\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Stefan-Metzger.jpg\" alt=\"Stefan Metzger\" width=\"1000\" height=\"554\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Stefan-Metzger.jpg 1000w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Stefan-Metzger-768x425.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Stefan-Metzger-100x55.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Stefan-Metzger-480x266.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Stefan-Metzger-640x355.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Stefan-Metzger-720x399.jpg 720w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Stefan-Metzger-960x532.jpg 960w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/strong><\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63436\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS.jpg\" alt=\"Carnicero KPS\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>SAP tiene ventaja porque ocupa toda el \u00e1rea de back-end. Y ahora estamos hablando mucho de integraci\u00f3n, que tiene que encajar, y Salesforce o Adobe no tienen este back-end. Y ahora tienen que utilizarlo.<\/p>\n<p>Hay muchos deberes por delante. El \u00e1rea SAP CRM con Sales Cloud, Service Cloud, Callidus y los sistemas centrales es todo un reto.<\/p>\n<p>No tenemos ning\u00fan proyecto en el que se utilicen todos estos productos. Ahora el cliente tambi\u00e9n quiere Qualtrics. Crees que todo viene de SAP y SAP ya ha comprado los temas adecuados, pero no es posible presentarlo de forma coherente e integrada.<\/p>\n<p>Aqu\u00ed SAP sigue atrapada en sus silos. \u00bfAlguien sabe de alg\u00fan t\u00edtulo que SAP haya ganado por su cuenta en el \u00e1rea de C\/4 Hana? Yo creo que no.<\/p>\n<p>El socio siempre est\u00e1 implicado. Y si no hay un socio fuerte que se lo explique al cliente, SAP no ganar\u00e1.<\/p>\n<p>SAP tiene ventaja porque ocupa toda el \u00e1rea de back-end. Y ahora estamos hablando mucho de integraci\u00f3n, que tiene que encajar, y Salesforce o Adobe no tienen este back-end. Y ahora tienen que utilizarlo.<\/p>\n<p>Hay muchos deberes por delante. El \u00e1rea SAP CRM con Sales Cloud, Service Cloud, Callidus y los sistemas centrales es todo un reto.<\/p>\n<p>No tenemos ning\u00fan proyecto en el que se utilicen todos estos productos. Ahora el cliente tambi\u00e9n quiere Qualtrics. Crees que todo viene de SAP y SAP ya ha comprado los temas adecuados, pero no es posible presentarlo de forma coherente e integrada.<\/p>\n<p>Aqu\u00ed SAP sigue atrapada en sus silos. \u00bfAlguien sabe de alg\u00fan t\u00edtulo que SAP haya ganado s\u00f3lo en el \u00e1rea de C\/4 Hana? Yo creo que no.<\/p>\n<p>El socio siempre est\u00e1 implicado. Y si no hay un socio fuerte que se lo explique al cliente, SAP no ganar\u00e1.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63438\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text.jpg\" alt=\"Texto abierto Haeusele\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>Creo que a menudo falta informaci\u00f3n sobre la integraci\u00f3n. Y, por supuesto, con los nuevos productos no se puede esperar que la gente compre algo nuevo y seis meses despu\u00e9s sea igual que los antiguos productos est\u00e1ndar de SAP.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63435\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher.jpg\" alt=\"Hendrick Van Laaten Orador\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>SAP no capta al grupo objetivo. Lo siento, pero hablan de customer journeys y no recogen a la gente de marketing. El comercio electr\u00f3nico con Hybris es realmente un golpe directo.<\/p>\n<p>La mejor compra que SAP ha hecho nunca. Sin embargo, otros proveedores consiguen preparar y comercializar de forma pr\u00e1ctica las funciones que se demandan. SAP debe centrarse en los retos diarios a los que se enfrentan los equipos operativos para ganarse a los responsables de marketing.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63436\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS.jpg\" alt=\"Carnicero KPS\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>Creo que SAP todav\u00eda tiene que trabajar un poco en el lado de las licencias. SAP sigue queriendo vender Hybris como un gran monolito. Eso ya no funciona.<\/p>\n<p>Especialmente en \u00e1reas en las que simplemente necesita piezas m\u00e1s peque\u00f1as.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63439\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore.jpg\" alt=\"Oltmanns RealCore\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>Este es el siguiente debate: SAP's Go to Market. \u00bfVendo orientado a procesos, vendo todo en microservicios o como plataforma? Debe ser la plataforma lo que se venda.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63435\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher.jpg\" alt=\"Hendrick Van Laaten Orador\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>Sigo viendo Commerce como una herramienta muy flexible. Cuando pienso en los procesos empresariales que hemos creado, lo hago como complementos y a precios asequibles.<\/p>\n<p>Simplemente hemos creado valor a\u00f1adido y servicios con procesos de compra. Porque el modelo de datos est\u00e1 ah\u00ed. Creo que un cierto grado de flexibilidad ayuda al cliente si existe un est\u00e1ndar. Por supuesto, si solo fueran microservicios que funcionaran todos a la perfecci\u00f3n, ser\u00eda una situaci\u00f3n estupenda.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63440\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann.jpg\" alt=\"Frank Niemann\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>De hecho, veo una brecha en SAP. SAP est\u00e1 tratando de servir a las peque\u00f1as y medianas empresas en el \u00e1rea de ERP: con SAP Business One y Business by Design - que, por cierto, todav\u00eda existe, aunque SAP no hable de ello.<\/p>\n<p>Sin embargo, actualmente no existe Magento de SAP - Hybris es s\u00f3lo un tama\u00f1o m\u00e1s peque\u00f1o. Puede que veamos una reencarnaci\u00f3n de esto en SAP Cloud Platform.<\/p>\n<p>Existe Magento y no digo que sea la respuesta a tu pregunta, pero Magento es r\u00e1pido y f\u00e1cil. Si no funciona, no hay mucho roto.<\/p>\n<p>Tambi\u00e9n puedo empezar con la edici\u00f3n comunitaria. SAP a\u00fan no tiene nada parecido. En mi opini\u00f3n, falta. Por otra parte:<\/p>\n<p>Una gran ventaja de Hybris, de la que no todos los clientes son conscientes y puede que SAP tampoco, es que Hybris es uno de los pocos sistemas que pueden utilizarse tanto para B2B como para B2C en una misma plataforma t\u00e9cnica.<\/p>\n<p>La mayor\u00eda de los competidores, incluido Salesforce, tienen dos sistemas diferentes para esto.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63435\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher.jpg\" alt=\"Hendrick Van Laaten Orador\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>Por eso SAP no tiene problemas con Commerce en este momento. Creo que la direcci\u00f3n es buena y el producto es bueno por ahora.<\/p>\n<p>Sin duda podemos venderlo. Por supuesto, no siempre tiene un precio competitivo. Ser\u00eda estupendo que hubiera un mejor punto de entrada. Pero Hybris en s\u00ed no nos ha decepcionado todav\u00eda.<\/p>\n<p>Tambi\u00e9n sol\u00edamos implementar Magento. Tuvimos situaciones en las que el rendimiento simplemente no era lo suficientemente bueno.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63436\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS.jpg\" alt=\"Carnicero KPS\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>El producto en s\u00ed est\u00e1 perfectamente bien. Tenemos dos casos en los que alojamos la versi\u00f3n local en Azure. Eso funciona muy bien, as\u00ed que es realmente perfecto.<\/p>\n<p>Pero convencer de ello a un nuevo cliente -dada la situaci\u00f3n de la competencia- es cada vez m\u00e1s dif\u00edcil.<\/p>\n<h3><\/h3>\n<p><strong><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63445\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger.jpg\" alt=\"Faerbinger\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>S\u00ed, necesito el recorrido del cliente. Hay que poner orden en el back end. Para terminar, me gustar\u00eda decir el cl\u00e1sico prototipo de cliente SAP existente: \u00bfCu\u00e1l podr\u00eda ser el siguiente paso concreto?<\/strong><\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63436\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS.jpg\" alt=\"Carnicero KPS\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Metzger-KPS-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>Creo que SAP es la elecci\u00f3n correcta para el futuro porque lo tiene todo, desde el back end hasta el front end, y por tanto est\u00e1 muy, muy bien posicionada.<\/p>\n<p>Pero hay que empezar a pensar en ello dentro de la empresa: \u00bfCon qu\u00e9 \u00e1reas y personas de mi empresa puedo iniciar el viaje?<\/p>\n<p>Se necesita un socio que tambi\u00e9n conozca la experiencia de SAP y otros productos y sepa hacia d\u00f3nde va el viaje, hacia d\u00f3nde quiere ir mi empresa, qu\u00e9 quieren mis clientes y d\u00f3nde estar\u00e1 el valor a\u00f1adido al final.<\/p>\n<p>Una vez que he hecho estos deberes, puedo profundizar y pensar detenidamente: \u00bfC\u00f3mo es mi arquitectura, mi recorrido del cliente, c\u00f3mo lo unifico todo?<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63435\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher.jpg\" alt=\"Hendrick Van Laaten Orador\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Hendrick-van-Laaten-Sprecher-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>S\u00f3lo puedo estar de acuerdo con eso. Hay que adoptar una visi\u00f3n estrat\u00e9gica. Especialmente si se est\u00e1 en el sector de las PYME, desarrollar ideas y luego empezar operativamente con las primeras medidas, con los primeros bloques de construcci\u00f3n.<\/p>\n<p>Desde un punto de vista estrat\u00e9gico, la suite es una buena elecci\u00f3n porque te da flexibilidad para el futuro. No son decisiones equivocadas si vienes del mundo SAP.<\/p>\n<p>Sin embargo, el valor empresarial debe buscarse despu\u00e9s de forma operativa y paso a paso. \u00bfD\u00f3nde obtengo el mayor valor empresarial? Recomendamos empezar por los talleres. Empezamos con esto operativamente y formamos equipos.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63438\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text.jpg\" alt=\"Texto abierto Haeusele\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Haeusele-Open-Text-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>Yo recomendar\u00eda al cliente: Primero defina los objetivos con su direcci\u00f3n. Si no los tiene, forme un equipo de proyecto y defina los objetivos.<\/p>\n<p>Y, a continuaci\u00f3n, abra la caja de herramientas de TI. \u00bfQu\u00e9 tengo ya hoy en la caja de herramientas SAP? Utiliza lo que hay. Y si luego haces algo nuevo, c\u00ed\u00f1ete al est\u00e1ndar y compra este est\u00e1ndar de SAP.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Patrick-Pirron-CAS.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63437\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Patrick-Pirron-CAS.jpg\" alt=\"Patrick Pirron CAS\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Patrick-Pirron-CAS.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Patrick-Pirron-CAS-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Patrick-Pirron-CAS-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Patrick-Pirron-CAS-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Patrick-Pirron-CAS-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Patrick-Pirron-CAS-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>Empezar\u00eda por reunir a mi organizaci\u00f3n interna, tanto en el plano profesional como en el inform\u00e1tico. Los equipos de procesos integrales son importantes.<\/p>\n<p>\u00bfDe qu\u00e9 me sirven los grandes objetivos que tal vez pueda contar a mi asesor, que de alguna manera los realizar\u00e1 por m\u00ed? Pero tengo que llevar conmigo a mi departamento interno de inform\u00e1tica, porque es un activo importante.<\/p>\n<p>Tienen que cuidarlo despu\u00e9s. Y luego mirar r\u00e1pido: \u00bfC\u00f3mo puedo crear valor a\u00f1adido? \u00bfD\u00f3nde puedo optimizar r\u00e1pidamente los procesos existentes con nuevos componentes si es necesario?<\/p>\n<p>El punto clave: tengo que llevar conmigo mi organizaci\u00f3n interna. Porque, al final, no es el producto lo que nos hace avanzar, sino las personas que hay detr\u00e1s.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63439\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore.jpg\" alt=\"Oltmanns RealCore\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Oltmanns-RealCore-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>Yo no vendr\u00eda de tan arriba, pero para m\u00ed el factor decisivo en este momento es: \u00bfC\u00f3mo avanzo hacia el futuro con mi sistema actual?<\/p>\n<p>Hasta SAP Cloud Platform y C\/4. No creo que nadie pueda decir y definir d\u00f3nde quiere estar la empresa dentro de tres a\u00f1os. S\u00ed creo que se deber\u00eda organizar un taller de arquitectura y procesos en las empresas.<\/p>\n<p>Es un verdadero \u00e9xito sentarse juntos. Empiezo por el final y termino por el principio y digo: \u00bfQu\u00e9 pasa hoy? \u00bfHacia d\u00f3nde vas? \u00bfAd\u00f3nde puedes ir?<\/p>\n<p>Siempre con el trasfondo de: \u00bfde qu\u00e9 disponemos como sistema modular hol\u00edstico? Y hablo de procesos, procesos est\u00e1ndar y tecnolog\u00edas est\u00e1ndar.<\/p>\n<p>Y al final, hay un modelo de proceso que se pone sobre la mesa y se dice: Deber\u00edais analizar esto. Para m\u00ed, siempre se desv\u00eda demasiado si solo analizo desde el punto de vista del cliente y me centro siempre en la tienda web.<\/p>\n<p>Y luego tengo discusiones de marketing. Lo entiendo y hay que hacer estos proyectos. No deber\u00edan retrasarse y cancelarse porque la conclusi\u00f3n equivocada ser\u00eda: ahora viene el grupo SAP y entonces habr\u00e1 un par\u00f3n aqu\u00ed durante dos a\u00f1os.<\/p>\n<p>No tiene por qu\u00e9 ser as\u00ed. Puedo continuar, pero tengo que trabajar en la parte de atr\u00e1s al mismo tiempo. Y tengo que hacer que la parte de atr\u00e1s est\u00e9 preparada para el futuro. Es un camino dif\u00edcil.<\/p>\n<p>Porque no se trata s\u00f3lo de los nuevos componentes como C\/4 Hana. Tambi\u00e9n hay un S\/4 cl\u00e1sico, que yo considero cl\u00e1sico porque es un producto que lleva tiempo en el mercado. Pero nadie lo ha introducido realmente todav\u00eda.<\/p>\n<p>El sector minorista tiene que avanzar incre\u00edblemente r\u00e1pido y no debe provocar un estancamiento en otros \u00e1mbitos, porque de lo contrario volveremos a tener un mundo paralelo.<\/p>\n<p>Por supuesto, tambi\u00e9n veo este plan de acci\u00f3n por nuestra parte. Y creo que tambi\u00e9n tenemos que acelerarlo. No podemos dejarlo en manos de SAP.<\/p>\n<h3><\/h3>\n<p><strong><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63445\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger.jpg\" alt=\"Faerbinger\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>\u00bfExiste la posibilidad de que SAP cumpla a tiempo todos estos requisitos, deseos y perspectivas? El tiempo apremia. Esto se ha subrayado una y otra vez en todos los discursos. No se trata s\u00f3lo de conceptos, arquitectura y productos. Tambi\u00e9n se trata del tiempo que se escapa entre los dedos.<\/strong><\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63440\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann.jpg\" alt=\"Frank Niemann\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Frank-Niemann-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a>Doy una oportunidad a SAP porque SAP ha demostrado a lo largo de los a\u00f1os que puede ofrecer innovaciones fiables para el cliente.<\/p>\n<p>El tiempo es un reto, pero no creo que SAP est\u00e9 sola en esto. Porque SAP tambi\u00e9n forma parte de un ecosistema. Uno son los clientes con sus deseos y requisitos, pero tambi\u00e9n con su capacidad para desarrollar soluciones mutuas junto con SAP.<\/p>\n<p>Un ejemplo: Porsche y SAP trabajan juntos. Porsche es un cliente, pero ahora la empresa es un socio. Y luego est\u00e1n los socios, representados aqu\u00ed en la mesa.<\/p>\n<p>Los socios desempe\u00f1an un papel muy decisivo, no s\u00f3lo para vender el producto, sino para mejorarlo. Los socios muestran al cliente lo que ya est\u00e1 disponible de serie.<\/p>\n<p>S\u00f3lo hay que utilizarla all\u00ed. Por supuesto, tambi\u00e9n se aplica el tema de la gesti\u00f3n del cambio, as\u00ed como la voluntad de aceptar o reintroducir la norma.<\/p>\n<p>Al final, podemos darnos cuenta de lo que nos diferencia a trav\u00e9s de una aplicaci\u00f3n, pero muchas funciones y servicios son est\u00e1ndar en SAP. Creo que este punto de vista tiene mucho que ver con la comunicaci\u00f3n y la educaci\u00f3n.<\/p>\n<p>La cooperaci\u00f3n con los socios es importante, tanto con los especialistas como con los socios grandes y universales de SAP. SAP tiende a centrarse principalmente en los grandes socios, pero los socios m\u00e1s peque\u00f1os, los especialistas, son al menos igual de importantes.<\/p>\n<p>Y, en \u00faltima instancia, los clientes deben participar. Los clientes influyen en el desarrollo de los productos de SAP. Esto se olvida a menudo en la relaci\u00f3n cliente-proveedor.<\/p>\n<p>Los clientes existentes est\u00e1n en cierto modo a merced de SAP en un sentido positivo debido al back-end ERP. Es un reto importante. No se cuestiona a SAP en el back-end ERP.<\/p>\n<p>No ser\u00e1n muchos los clientes que digan: no voy a seguir el camino de S\/4 Hana. A\u00fan no est\u00e1 claro si SAP ganar\u00e1 la competici\u00f3n en experiencia del cliente o en plataformas en la nube.<\/p>\n<p>Esto vendr\u00e1 determinado por muchos factores de los que hemos hablado hoy. El factor decisivo ser\u00e1 la integraci\u00f3n, la transferencia de competencias y habilidades que tienen estos productos.<\/p>\n<p>En \u00faltima instancia, tambi\u00e9n ser\u00e1 decisiva la capacidad de SAP para ganar los proyectos pendientes a trav\u00e9s de sus socios y con ellos.<\/p>\n<p>Ahora le toca a SAP demostrar que puede existir m\u00e1s all\u00e1 del ERP frente a competidores de diversos or\u00edgenes. Y que puede convencer a los clientes del mismo modo que lo hizo con R\/3. Ha sido un largo comentario final.<\/p>\n<p><strong><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63445\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger.jpg\" alt=\"Faerbinger\" width=\"859\" height=\"78\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger.jpg 859w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger-768x70.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger-100x9.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger-480x44.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger-640x58.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/Faerbinger-720x65.jpg 720w\" sizes=\"auto, (max-width: 859px) 100vw, 859px\" \/><\/a><\/strong><\/p>\n<p><strong>Gracias por la entrevista.<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>La variedad de temas en el campo del comercio electr\u00f3nico es asombrosa. Junto con los socios de SAP y un reconocido analista de SAP de Teknowlogy\/PAC, fue posible desarrollar una estrategia para los clientes existentes de SAP, es decir, orientaci\u00f3n para futuros proyectos de comercio electr\u00f3nico.<\/p>","protected":false},"author":38,"featured_media":63426,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[37021,37003],"tags":[23816,21121,229,4253,13864],"coauthors":[19920],"class_list":["post-63425","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-e-3-special-1912","category-mag-1912","tag-c-4-hana","tag-callidus","tag-e-commerce","tag-successfactors","tag-workday","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/DSC_6839_cmyk.jpg",1000,450,false],"thumbnail":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/DSC_6839_cmyk-150x150.jpg",150,150,true],"medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/DSC_6839_cmyk.jpg",400,180,false],"medium_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/DSC_6839_cmyk-768x346.jpg",768,346,true],"large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/DSC_6839_cmyk.jpg",1000,450,false],"image-100":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/DSC_6839_cmyk-100x45.jpg",100,45,true],"image-480":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/DSC_6839_cmyk-480x216.jpg",480,216,true],"image-640":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/DSC_6839_cmyk-640x288.jpg",640,288,true],"image-720":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/DSC_6839_cmyk-720x324.jpg",720,324,true],"image-960":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/DSC_6839_cmyk-960x432.jpg",960,432,true],"image-1168":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/DSC_6839_cmyk.jpg",1000,450,false],"image-1440":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/DSC_6839_cmyk.jpg",1000,450,false],"image-1920":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/DSC_6839_cmyk.jpg",1000,450,false],"1536x1536":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/DSC_6839_cmyk.jpg",1000,450,false],"2048x2048":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/DSC_6839_cmyk.jpg",1000,450,false],"trp-custom-language-flag":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/DSC_6839_cmyk.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/DSC_6839_cmyk.jpg",1000,450,false],"bricks_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/DSC_6839_cmyk.jpg",1000,450,false],"bricks_large_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/DSC_6839_cmyk.jpg",1000,450,false],"bricks_medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/DSC_6839_cmyk.jpg",600,270,false],"bricks_medium_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/DSC_6839_cmyk.jpg",600,270,false],"profile_24":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/DSC_6839_cmyk-24x24.jpg",24,24,true],"profile_48":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/DSC_6839_cmyk-48x48.jpg",48,48,true],"profile_96":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/DSC_6839_cmyk-96x96.jpg",96,96,true],"profile_150":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/DSC_6839_cmyk-150x150.jpg",150,150,true],"profile_300":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/11\/DSC_6839_cmyk-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Die Themenvielfalt im Bereich E-Commerce ist erschreckend hoch. Gemeinsam mit SAP-Partnern und einem anerkannten SAP-Analysten von Teknowlogy\/PAC gelang es, eine Strategie f\u00fcr SAP-Bestandskunden zu entwickeln \u2013 also Orientierung f\u00fcr zuk\u00fcnftige E-Commerce-Projekte.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e326.greatsolution.dev\/es\/categoria\/e-3-especial-1912\/\" rel=\"category tag\">E-3 Special 1912<\/a>, <a href=\"https:\/\/e326.greatsolution.dev\/es\/categoria\/mag-1912\/\" rel=\"category tag\">MAG 19-12<\/a>","author_info_v2":{"name":"Revista E-3","url":"https:\/\/e326.greatsolution.dev\/es\/author\/e-3-magazin\/"},"comments_num_v2":"0 comentarios","_links":{"self":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/63425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/comments?post=63425"}],"version-history":[{"count":0,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/63425\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/media\/63426"}],"wp:attachment":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/media?parent=63425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/categories?post=63425"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/tags?post=63425"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/coauthors?post=63425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}