{"id":66583,"date":"2020-06-04T12:00:00","date_gmt":"2020-06-04T10:00:00","guid":{"rendered":"https:\/\/e326.greatsolution.dev\/?p=66583"},"modified":"2020-05-26T14:01:42","modified_gmt":"2020-05-26T12:01:42","slug":"despues-del-crecimiento-es-antes-del-crecimiento","status":"publish","type":"post","link":"https:\/\/e326.greatsolution.dev\/es\/despues-del-crecimiento-es-antes-del-crecimiento\/","title":{"rendered":"Despu\u00e9s del crecimiento es antes del crecimiento"},"content":{"rendered":"<p>Nos encontramos en una situaci\u00f3n que parece irreal. Muchos libros y pel\u00edculas sobre el brote de \"virus asesinos\" muestran la lucha heroica y su contenci\u00f3n por unos pocos protagonistas. <\/p>\n\n\n\n<p>No necesit\u00e1bamos la transformaci\u00f3n de estos temas cinematogr\u00e1ficos en realidad. Lo que resulta evidente es que no son los h\u00e9roes de las pel\u00edculas los que se revelan como h\u00e9roes en la crisis, sino la gente corriente que trabaja en \u00e1mbitos que -cuando est\u00e1n enfermos- nos mantienen con vida o, de forma a\u00fan m\u00e1s mundana, mantienen en funcionamiento las infraestructuras, proporcionan seguridad...<\/p>\n\n\n\n<p>Lo que tambi\u00e9n es evidente es que aquellas empresas son m\u00e1s fuertes en sus respectivos sectores que est\u00e1n m\u00e1s adelantadas en automatizaci\u00f3n y transformaci\u00f3n digital que otras.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Preparar y planificar<\/h3>\n\n\n\n<p>Esto ya es evidente cuando se trabaja con empresas que ya no pueden mantener sus propias operaciones en funcionamiento porque no han creado los requisitos t\u00e9cnicos previos con antelaci\u00f3n. Los principales problemas que veo son la falta de l\u00edneas VPN, la escasez de dispositivos m\u00f3viles, la falta de ancho de banda y, por supuesto, la falta de licencias.<\/p>\n\n\n\n<p>Adem\u00e1s, la falta de una estructura de seguridad para poder procesar los datos de los clientes y de la empresa desde la oficina en casa. Tambi\u00e9n se menciona en algunos casos el bloqueo del uso compartido de archivos (incluido el uso de almacenamiento compartido en la nube). En algunos casos, tambi\u00e9n hay una falta de opciones de videoconferencia, o la gente tiene que trabajar con soluciones gratuitas y no seguras.<\/p>\n\n\n\n<p>En la mayor\u00eda de las empresas de TI, el \"trabajo m\u00f3vil\" es la norma desde hace tiempo. No me refiero a los \"n\u00f3madas digitales\", que pueden trabajar desde cualquier lugar del mundo siempre que dispongan de un acceso (razonablemente r\u00e1pido) a Internet y un adaptador de corriente adecuado para su port\u00e1til.<\/p>\n\n\n\n<p>Para muchos empleados que trabajan en una oficina dom\u00e9stica, esto tambi\u00e9n incluye partes de la infraestructura con la que est\u00e1n familiarizados desde la oficina, es decir, la posibilidad m\u00e1s bien mundana de imprimir y escanear o una segunda pantalla y acceso remoto a importantes recursos internos. <\/p>\n\n\n\n<p>Soy optimista y creo que, al menos en este caso, se encontrar\u00e1n soluciones a posteriori para la mayor\u00eda de las empresas, aunque haya que realizar inversiones -previstas para m\u00e1s adelante- para ello.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Comunicaci\u00f3n y digitalizaci\u00f3n<\/h3>\n\n\n\n<p>Tambi\u00e9n se digitalizar\u00e1 la comunicaci\u00f3n con clientes y proveedores. Esto permitir\u00e1 que los procesos se activen autom\u00e1ticamente o que los documentos y decisiones (como los pedidos) se intercambien digitalmente y a prueba de auditor\u00edas. <\/p>\n\n\n\n<p>Tambi\u00e9n aqu\u00ed hemos visto en las \u00faltimas semanas lo dif\u00edcil que es para algunas empresas pasar con \u00e9xito las cadenas de aprobaci\u00f3n o apoyar a sus socios comerciales para que lo hagan.<\/p>\n\n\n\n<p>Otro paso muy importante es la optimizaci\u00f3n de los recursos disponibles. Esto comienza con la visibilidad de los propios niveles de existencias, que pueden llegar r\u00e1pidamente a cientos de ubicaciones de almacenamiento para un minorista. <\/p>\n\n\n\n<p>Pero incluso en la producci\u00f3n, los mismos materiales y medios de producci\u00f3n se distribuyen a menudo en distintos lugares. Una mayor visibilidad sirve para abastecerse r\u00e1pidamente por cuenta propia sin tener que acudir al tercer mercado. <\/p>\n\n\n\n<p>Una vez implantado, ahora se puede comprobar la disponibilidad en la propia zona de influencia, adem\u00e1s de la situaci\u00f3n del suministro en los proveedores.<\/p>\n\n\n\n<p>Mis consejos cinematogr\u00e1ficos si te apetecen pel\u00edculas sobre pandemias: \"El s\u00e9ptimo sello\" (1957), una pel\u00edcula hist\u00f3rica atmosf\u00e9ricamente muy densa sobre la \u00e9poca de la peste, y \"Contagio\" (2011), una pel\u00edcula de Hollywood sobre el brote de un virus mortal.<\/p>\n\n\n\n<p>Por favor, \u00a1mant\u00e9ngase sano!<\/p>","protected":false},"excerpt":{"rendered":"<p>La pandemia de Covid 19 y su contenci\u00f3n son el mayor reto de este siglo hasta la fecha. Cu\u00e1nto se contraer\u00e1 la econom\u00eda s\u00f3lo se ver\u00e1 m\u00e1s adelante. Pero veamos tambi\u00e9n esta situaci\u00f3n como una oportunidad.<\/p>","protected":false},"author":25,"featured_media":62243,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[7,36188,37619],"tags":[601,37611],"coauthors":[21819],"class_list":["post-66583","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-meinung","category-digitale-transformation","category-mag-2005","tag-digitalisierung","tag-homeoffice-4","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/08\/Digital-Transformation.jpg",1000,450,false],"thumbnail":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/08\/Digital-Transformation-150x150.jpg",150,150,true],"medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/08\/Digital-Transformation.jpg",400,180,false],"medium_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/08\/Digital-Transformation-768x346.jpg",768,346,true],"large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/08\/Digital-Transformation.jpg",1000,450,false],"image-100":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/08\/Digital-Transformation-100x45.jpg",100,45,true],"image-480":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/08\/Digital-Transformation-480x216.jpg",480,216,true],"image-640":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/08\/Digital-Transformation-640x288.jpg",640,288,true],"image-720":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/08\/Digital-Transformation-720x324.jpg",720,324,true],"image-960":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/08\/Digital-Transformation-960x432.jpg",960,432,true],"image-1168":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/08\/Digital-Transformation.jpg",1000,450,false],"image-1440":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/08\/Digital-Transformation.jpg",1000,450,false],"image-1920":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/08\/Digital-Transformation.jpg",1000,450,false],"1536x1536":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/08\/Digital-Transformation.jpg",1000,450,false],"2048x2048":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/08\/Digital-Transformation.jpg",1000,450,false],"trp-custom-language-flag":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/08\/Digital-Transformation.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/08\/Digital-Transformation.jpg",1000,450,false],"bricks_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/08\/Digital-Transformation.jpg",1000,450,false],"bricks_large_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/08\/Digital-Transformation.jpg",1000,450,false],"bricks_medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/08\/Digital-Transformation.jpg",600,270,false],"bricks_medium_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/08\/Digital-Transformation.jpg",600,270,false],"profile_24":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/08\/Digital-Transformation-24x24.jpg",24,24,true],"profile_48":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/08\/Digital-Transformation-48x48.jpg",48,48,true],"profile_96":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/08\/Digital-Transformation-96x96.jpg",96,96,true],"profile_150":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/08\/Digital-Transformation-150x150.jpg",150,150,true],"profile_300":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/08\/Digital-Transformation-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Die Covid-19-Pandemie und ihre Eind\u00e4mmung sind die bisher gr\u00f6\u00dfte Herausforde\u00ad-rung dieses Jahrhunderts. Wie stark die Wirtschaft schrumpfen wird, wird erst sp\u00e4ter zu sehen sein. Lassen Sie uns diese Situation auch als Chance sehen.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e326.greatsolution.dev\/es\/categoria\/opinion\/\" rel=\"category tag\">Die Meinung der SAP-Community<\/a>, <a href=\"https:\/\/e326.greatsolution.dev\/es\/categoria\/opinion\/transformacion-digital-2\/\" rel=\"category tag\">Digitale Transformation<\/a>, <a href=\"https:\/\/e326.greatsolution.dev\/es\/categoria\/mag-2005\/\" rel=\"category tag\">MAG 20-05<\/a>","author_info_v2":{"name":"Michael Kramer","url":"https:\/\/e326.greatsolution.dev\/es\/author\/michael-kramer\/"},"comments_num_v2":"0 comentarios","_links":{"self":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/66583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/comments?post=66583"}],"version-history":[{"count":0,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/66583\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/media\/62243"}],"wp:attachment":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/media?parent=66583"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/categories?post=66583"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/tags?post=66583"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/coauthors?post=66583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}