{"id":73730,"date":"2021-06-17T08:00:00","date_gmt":"2021-06-17T06:00:00","guid":{"rendered":"https:\/\/e326.greatsolution.dev\/?p=73730"},"modified":"2025-08-23T12:11:51","modified_gmt":"2025-08-23T10:11:51","slug":"digitalizacion-una-solucion-transitoria","status":"publish","type":"post","link":"https:\/\/e326.greatsolution.dev\/es\/digitalizacion-una-solucion-transitoria\/","title":{"rendered":"\u00bfDigitalizaci\u00f3n? S\u00f3lo una soluci\u00f3n temporal"},"content":{"rendered":"<p>Cuando hoy se escanean recibos en papel en las oficinas alemanas, muchas empresas ya se muestran muy orgullosas: \"\u00a1Aqu\u00ed la digitalizaci\u00f3n est\u00e1 en pleno apogeo!\". Por supuesto, las facturas entrantes pueden procesarse mejor en formato digital. Sin embargo, los colegas empresarios estadounidenses no har\u00e1n m\u00e1s que enarcar las cejas ante esta visi\u00f3n m\u00e1s bien limitada de la digitalizaci\u00f3n. Porque, \u00bfqu\u00e9 ha ocurrido? El remitente crea su documento en un sistema digital, lo imprime y lo env\u00eda, s\u00f3lo para que el destinatario vuelva a digitalizarlo. Muchos pa\u00edses del mundo ya han ido mucho m\u00e1s lejos en este sentido. <\/p>\n\n\n\n<p>Ya no es necesario escanear las facturas, porque ya llegan en formato digital, por ejemplo como correo electr\u00f3nico, PDF o XML. Tambi\u00e9n en Alemania hay que pensar por fin en el futuro. En \u00faltima instancia, se trata de trabajar digitalmente, es decir, de forma electr\u00f3nica y autom\u00e1tica. <\/p>\n\n\n\n<p>La digitalizaci\u00f3n como medio de convertir el papel en bits deber\u00eda perder importancia a medida que operemos cada vez m\u00e1s con documentos digitales por defecto. La digitalizaci\u00f3n es una soluci\u00f3n transitoria y ahora deber\u00eda convertirse en un modelo descatalogado.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Aumenta el trabajo digital<\/h3>\n\n\n\n<p>La situaci\u00f3n actual de la oficina en casa, en particular, nos ha demostrado claramente que los procesos basados en papel sencillamente no funcionan desde casa. La escasez de mano de obra cualificada tambi\u00e9n est\u00e1 impulsando la cuesti\u00f3n del \"trabajo digital\". Si no se pueden cubrir las vacantes en compras y contabilidad, la carga de trabajo se reparte entre menos hombros. Esto s\u00f3lo puede funcionar si se automatizan las actividades rutinarias manuales que consumen mucho tiempo. S\u00f3lo se puede automatizar lo que es digital. Si para ello hay que digitalizar el papel, perfecto. Si no se crea papel, \u00a1mejor que mejor!<\/p>\n\n\n\n<p>Los j\u00f3venes profesionales de hoy son nativos digitales y no quieren estar delante del esc\u00e1ner o teclear facturas a mano en SAP. No tienen reparos en trabajar digitalmente e incluso lo esperan de su empleador. No s\u00f3lo ahorran esfuerzo, tiempo y dinero, sino que tambi\u00e9n pueden evaluar los datos digitales mucho mejor que los anal\u00f3gicos, lo que a su vez proporciona informaci\u00f3n importante y descubre por primera vez el potencial de optimizaci\u00f3n. A pesar de la resistencia y la incertidumbre, la facturaci\u00f3n electr\u00f3nica ya se ha introducido en la administraci\u00f3n p\u00fablica alemana, una cuesti\u00f3n clave en lo que respecta a los procesos empresariales basados en documentos y el trabajo digital de extremo a extremo. Puede haber muchas razones por las que esto ha sido bastante lento. En los Pa\u00edses Bajos, Italia y Espa\u00f1a, por ejemplo, es posible enviar facturas electr\u00f3nicas a las autoridades desde hace varios a\u00f1os. Lo \u00fanico importante es que las cosas se est\u00e1n moviendo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Pensar en el futuro<\/h2>\n\n\n\n<p>En su \u00faltima encuesta a clientes, el Grupo xSuite descubri\u00f3 que las empresas alemanas tambi\u00e9n reciben cada vez m\u00e1s facturas digitalmente. La tendencia a abandonar el papel con respecto a encuestas anteriores es, por tanto, inequ\u00edvoca. Quien piense que esto es el final de la historia est\u00e1 muy equivocado. Ahora es el momento de anticiparse y replantearse las cosas, atreverse a probar cosas nuevas y experimentar. La digitalizaci\u00f3n est\u00e1 muy bien, pero los procesos pueden hacer mucho m\u00e1s. \u00bfPor qu\u00e9 no ir a\u00fan m\u00e1s lejos y digitalizar toda la comunicaci\u00f3n con los proveedores, por ejemplo con un portal de proveedores basado en la nube? Esto tambi\u00e9n permitir\u00eda que todos los pasos previos a la factura se realizaran digitalmente. Los pedidos podr\u00edan enviarse digitalmente, el proveedor podr\u00eda crear la confirmaci\u00f3n del pedido y m\u00e1s tarde la factura directamente en el mismo sistema y tambi\u00e9n enviarlas digitalmente de nuevo. Por tanto, todo el intercambio de documentos en el curso de los procesos procure-to-pay tendr\u00eda lugar digitalmente. Las interrupciones de los medios no s\u00f3lo se superan, sino que se eliminan. Y ya no es necesaria la digitalizaci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/e326.greatsolution.dev\/es\/socios\/xsuite-group-gmbh\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"112\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2021\/04\/xSuite-CI-Banner.jpg\" alt=\"xSuite-CI-Banner.jpg\" class=\"wp-image-73324\" title=\"\u00bfDigitalizaci\u00f3n? s\u00f3lo una soluci\u00f3n temporal\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2021\/04\/xSuite-CI-Banner.jpg 1000w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2021\/04\/xSuite-CI-Banner-768x86.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2021\/04\/xSuite-CI-Banner-100x11.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2021\/04\/xSuite-CI-Banner-480x54.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2021\/04\/xSuite-CI-Banner-640x72.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2021\/04\/xSuite-CI-Banner-720x81.jpg 720w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2021\/04\/xSuite-CI-Banner-960x108.jpg 960w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure>","protected":false},"excerpt":{"rendered":"<p>\"Superar las discontinuidades de los medios\" es una palabra m\u00e1gica para conectar mejor entre s\u00ed los pasos del proceso. Pero no va lo suficientemente lejos: si queremos conseguir un trabajo verdaderamente digital, tenemos que acabar con las discontinuidades de los medios.<\/p>","protected":false},"author":2345,"featured_media":36685,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[39280,20393],"tags":[1114,601,38924],"coauthors":[39309],"class_list":["post-73730","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mag-21-05","category-cfo-kolumne","tag-cfo","tag-digitalisierung","tag-xsuite-group","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU.jpg",1200,540,false],"thumbnail":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU-80x80.jpg",80,80,true],"medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU.jpg",400,180,false],"medium_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU-768x346.jpg",768,346,true],"large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU-1030x464.jpg",1030,464,true],"image-100":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU-100x45.jpg",100,45,true],"image-480":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU-480x216.jpg",480,216,true],"image-640":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU-640x288.jpg",640,288,true],"image-720":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU-720x324.jpg",720,324,true],"image-960":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU-960x432.jpg",960,432,true],"image-1168":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU-1168x526.jpg",1168,526,true],"image-1440":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU.jpg",1200,540,false],"image-1920":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU.jpg",1200,540,false],"1536x1536":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU.jpg",1200,540,false],"2048x2048":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU.jpg",1200,540,false],"trp-custom-language-flag":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU.jpg",1200,540,false],"bricks_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU.jpg",1200,540,false],"bricks_large_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU.jpg",1200,540,false],"bricks_medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU.jpg",600,270,false],"bricks_medium_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU.jpg",600,270,false],"profile_24":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU-24x24.jpg",24,24,true],"profile_48":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU-48x48.jpg",48,48,true],"profile_96":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU-96x96.jpg",96,96,true],"profile_150":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU-150x150.jpg",150,150,true],"profile_300":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/header_cfo_kolumne_NEU-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>\u201eMedienbr\u00fcche \u00fcberwinden\u201c, hei\u00dft ein Zauberwort, um Prozessschritte besser miteinander zu verbinden. Es geht aber nicht weit genug: Wollen wir zu einem wirklich digitalen Arbeiten kommen, m\u00fcssen wir Medienbr\u00fcche abschaffen.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e326.greatsolution.dev\/es\/categoria\/mag-21-05\/\" rel=\"category tag\">MAG 21-05<\/a>, <a href=\"https:\/\/e326.greatsolution.dev\/es\/categoria\/opinion\/columna-cfo\/\" rel=\"category tag\">CFO - Kolumne<\/a>","author_info_v2":{"name":"Matthias Lehmenk\u00fchler","url":"https:\/\/e326.greatsolution.dev\/es\/author\/matthias-lehmenkuehler-xsuite\/"},"comments_num_v2":"0 comentarios","_links":{"self":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/73730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/users\/2345"}],"replies":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/comments?post=73730"}],"version-history":[{"count":3,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/73730\/revisions"}],"predecessor-version":[{"id":154294,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/73730\/revisions\/154294"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/media\/36685"}],"wp:attachment":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/media?parent=73730"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/categories?post=73730"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/tags?post=73730"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/coauthors?post=73730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}