{"id":92804,"date":"2021-08-19T08:00:00","date_gmt":"2021-08-19T06:00:00","guid":{"rendered":"https:\/\/e326.greatsolution.dev\/?p=92804"},"modified":"2022-08-21T19:42:25","modified_gmt":"2022-08-21T17:42:25","slug":"que-considerar-con-la-mudanza-hxm","status":"publish","type":"post","link":"https:\/\/e326.greatsolution.dev\/es\/que-considerar-con-la-mudanza-hxm\/","title":{"rendered":"Qu\u00e9 hay que tener en cuenta con HXM Move"},"content":{"rendered":"<p>Si hay algo que se le da bien a SAP, adem\u00e1s del desarrollo de software, es crear un lenguaje de marketing pegadizo. Fue a principios de este a\u00f1o cuando Christian Klein present\u00f3 la oferta Business Transformation as a Service Rise with SAP. <\/p>\n\n\n\n<p>As\u00ed que, en el futuro, se supone que los usuarios se elevar\u00e1n a s\u00ed mismos con la ayuda del proveedor tecnol\u00f3gico: una redacci\u00f3n que recuerda al autodescubrimiento y al desarrollo personal. Namaste. En realidad, sin embargo, el objetivo es facilitar el camino hacia S\/4 Hana en la nube. Para ello, SAP ha elaborado un paquete con licencias, herramientas y servicios.<\/p>\n\n\n\n<p>Siguiendo la estela de la iniciativa Rise, el programa HXM Move, sucesor de Upgrade2Success, tambi\u00e9n ha cobrado velocidad. En nuestra opini\u00f3n, SAP no s\u00f3lo ha inventado otro nombre extravagante, sino algo que muchos usuarios de la regi\u00f3n DACH estaban esperando. As\u00ed, HXM Move ofrece una respuesta concreta a una pregunta que lleva tiempo preocupando a muchas empresas: \u00bfQu\u00e9 es lo pr\u00f3ximo para los procesos de RRHH?<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfCu\u00e1les son las innovaciones<\/h3>\n\n\n\n<p>La atenci\u00f3n sigue centrada en SAP SuccessFactors, que desde hace alg\u00fan tiempo SAP denomina suite HXM (un nuevo acr\u00f3nimo del fabricante de software para la gesti\u00f3n de la experiencia humana). Las innovaciones s\u00f3lo se producir\u00e1n aqu\u00ed. Los usuarios se alegrar\u00e1n de saber que la suite SuccessFactors HXM tambi\u00e9n ofrecer\u00e1 funciones que hasta ahora faltaban o eran s\u00f3lo rudimentarias. <\/p>\n\n\n\n<p>En concreto, HXM Move contempla cuatro puntos: Core HR, Hybrid, Gesti\u00f3n de Tiempos y N\u00f3mina. Los dos primeros puntos se refieren a la ampliaci\u00f3n de Employee Central, por ejemplo en el \u00e1mbito de los convenios colectivos o el procesamiento masivo, as\u00ed como a la estandarizaci\u00f3n de la experiencia de usuario entre los productos SAP HR.<\/p>\n\n\n\n<p>Hasta aqu\u00ed todo bien, aunque sin concretar. Los puntos m\u00e1s importantes para la mayor\u00eda de los clientes son los otros dos. Cabe mencionar aqu\u00ed en particular el anuncio de querer alcanzar la \"paridad de caracter\u00edsticas\" entre el mundo antiguo y SuccessFactors Time en la gesti\u00f3n del tiempo. Ya hab\u00eda habido otras voces al respecto en el pasado. <\/p>\n\n\n\n<p>Adem\u00e1s, la \"N\u00f3mina de nueva generaci\u00f3n\" se lanzar\u00e1 con las primeras versiones por pa\u00edses a partir de finales de la d\u00e9cada de 2020. Menos agradable: probablemente pasar\u00e1n algunos a\u00f1os m\u00e1s hasta que el nuevo sistema de c\u00e1lculo de n\u00f3minas est\u00e9 disponible para Alemania; en cualquier caso, a\u00fan no hay plazos. As\u00ed que los usuarios tendr\u00e1n que pens\u00e1rselo hasta entonces.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">C\u00f3mo llegar<\/h3>\n\n\n\n<p>Con la iniciativa HXM Move, la propia SAP propone varios escenarios de migraci\u00f3n. Las llamadas soluciones de transici\u00f3n representan una conexi\u00f3n entre el antiguo mundo on-premises (SAP ERP HCM y H4S4) y el nuevo mundo cloud. Qu\u00e9 cambio tiene sentido en cada momento depende de muchos factores. Sobre todo, depende de qu\u00e9 funciones centrales de RRHH necesite una empresa. <\/p>\n\n\n\n<p>El camino puede ser a trav\u00e9s de las Soluciones de Transici\u00f3n - en particular Employee Central Payroll - con un posterior cambio sucesivo de funcionalidades a la Suite HXM, dependiendo de la disponibilidad. Consideramos que esta opci\u00f3n es especialmente atractiva si SuccessFactors ya est\u00e1 en uso y SAP HCM solo se necesita esencialmente para el c\u00e1lculo de la n\u00f3mina, quiz\u00e1 con funcionalidades muy sencillas de gesti\u00f3n del tiempo.<\/p>\n\n\n\n<p>Por otro lado, aquellos que todav\u00eda est\u00e9n utilizando una instalaci\u00f3n m\u00e1s extensa de SAP ERP HCM probablemente no podr\u00e1n evitar H4S4 (HR para S\/4 Hana). Se supone que el cambio a esta es comparativamente sencillo como migraci\u00f3n t\u00e9cnica y la promesa de mantenimiento es v\u00e1lida al menos hasta 2040. <\/p>\n\n\n\n<p>Por tanto, hay tiempo suficiente para observar con tranquilidad la evoluci\u00f3n del paquete HXM. Consideramos que la permanencia en el actual sistema SAP ERP HCM tiene un sentido limitado. Cuando finalice el mantenimiento en 2027, la suite HXM a\u00fan no cubrir\u00e1 todas las funcionalidades necesarias. Y confiar en un mantenimiento ampliado hasta 2030 s\u00f3lo ser\u00e1 m\u00e1s caro sin cambiar realmente la situaci\u00f3n.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Lo que ya se puede decir<\/h3>\n\n\n\n<p>Independientemente de todo esto: Todas las funcionalidades que ofrece SAP SuccessFactors para la gesti\u00f3n del talento, la contrataci\u00f3n y el aprendizaje son ya la primera opci\u00f3n en la mayor\u00eda de los casos. La soluci\u00f3n en la nube es simplemente m\u00e1s innovadora, m\u00e1s centrada en el empleado y m\u00e1s moderna en t\u00e9rminos de experiencia general del usuario.<\/p>\n\n\n\n<p>Para los usuarios, HXM Move ofrece definitivamente m\u00e1s claridad y un abanico de opciones. En Empleox, ayudamos a los usuarios a encontrar la mejor manera para su propia situaci\u00f3n con nuestros conocimientos tecnol\u00f3gicos y experiencia en RRHH.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/e326.greatsolution.dev\/es\/socios\/empleox-gmbh\/\"><img decoding=\"async\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2021\/07\/empleox_CI-Banner.jpg\" alt=\"\" class=\"wp-image-92807\"\/><\/a><\/figure>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Si hay algo que se le da bien a SAP, adem\u00e1s del desarrollo de software, es crear un lenguaje de marketing memorable. Fue a principios de este a\u00f1o cuando Christian Klein present\u00f3 la oferta de transformaci\u00f3n empresarial como servicio Rise with SAP. En el futuro, los usuarios podr\u00e1n elevarse con la ayuda del proveedor tecnol\u00f3gico, una frase que recuerda al autodescubrimiento y la realizaci\u00f3n personal. Namaste. Pero en realidad, se trata de [...]<\/p>","protected":false},"author":2388,"featured_media":4163,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[10,39637],"tags":[40204,839,5654],"coauthors":[39643],"class_list":["post-92804","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-das-aktuelle-stichwort","category-mag-21-07","tag-das-aktuelle-stichwort","tag-hcm","tag-human-capital-management","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",1000,431,false],"thumbnail":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort-150x150.jpg",150,150,true],"medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",400,172,false],"medium_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort-768x331.jpg",768,331,true],"large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",1000,431,false],"image-100":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort-100x43.jpg",100,43,true],"image-480":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort-480x207.jpg",480,207,true],"image-640":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort-640x276.jpg",640,276,true],"image-720":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort-720x310.jpg",720,310,true],"image-960":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort-960x414.jpg",960,414,true],"image-1168":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",1000,431,false],"image-1440":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",1000,431,false],"image-1920":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",1000,431,false],"1536x1536":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",1000,431,false],"2048x2048":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",1000,431,false],"trp-custom-language-flag":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",1000,431,false],"bricks_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",1000,431,false],"bricks_large_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",1000,431,false],"bricks_medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",600,259,false],"bricks_medium_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",600,259,false],"profile_24":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort-24x24.jpg",24,24,true],"profile_48":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort-48x48.jpg",48,48,true],"profile_96":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort-96x96.jpg",96,96,true],"profile_150":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort-150x150.jpg",150,150,true],"profile_300":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Wenn SAP neben Softwareentwicklung eine Sache gut kann, dann ist das die Kreation von einpr\u00e4gsamer Marketingsprache. Erst Anfang dieses Jahres stellte Christian Klein das Business-Transformation-as-a-Service- Angebot Rise with SAP vor. Die Anwender sollen sich also k\u00fcnftig mithilfe des Technologieanbieters erheben \u2013 ein Wording, das an Selbstfindung und pers\u00f6nliche Entfaltung erinnert. Namaste. Tats\u00e4chlich aber geht es darum, den Weg zu S\/4 Hana in der Cloud zu erleichtern. Daf\u00fcr hat SAP ein Paket mit Lizenzen, Tools und Services geschn\u00fcrt. Im Windschatten der Rise-Initiative hat nun auch das Programm HXM Move \u2013 als Nachfolger von Upgrade2Success \u2013 Fahrt aufgenommen. Nach unserer Einsch\u00e4tzung ist&hellip;<\/p>\n","category_list_v2":"<a href=\"https:\/\/e326.greatsolution.dev\/es\/categoria\/opinion\/la-palabra-clave-actual\/\" rel=\"category tag\">Das aktuelle Stichwort<\/a>, <a href=\"https:\/\/e326.greatsolution.dev\/es\/categoria\/mag-21-07\/\" rel=\"category tag\">MAG 21-07<\/a>","author_info_v2":{"name":"Andre Schulte Empleox","url":"https:\/\/e326.greatsolution.dev\/es\/author\/andre-schulte-empleox\/"},"comments_num_v2":"0 comentarios","_links":{"self":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/92804","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/users\/2388"}],"replies":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/comments?post=92804"}],"version-history":[{"count":0,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/92804\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/media\/4163"}],"wp:attachment":[{"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/media?parent=92804"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/categories?post=92804"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/tags?post=92804"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/es\/wp-json\/wp\/v2\/coauthors?post=92804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}