{"id":128126,"date":"2023-06-07T08:00:00","date_gmt":"2023-06-07T06:00:00","guid":{"rendered":"https:\/\/e326.greatsolution.dev\/?p=128126"},"modified":"2023-06-05T12:34:52","modified_gmt":"2023-06-05T10:34:52","slug":"faire-courir-les-hackers-contre-les-murs","status":"publish","type":"post","link":"https:\/\/e326.greatsolution.dev\/fr\/faire-courir-les-hackers-contre-les-murs\/","title":{"rendered":"Laisser les hackers se heurter \u00e0 un mur"},"content":{"rendered":"<h2 class=\"wp-block-heading\">Lorsque les cybercriminels attaquent les syst\u00e8mes SAP ou la technologie op\u00e9rationnelle (OT)<\/h2>\n\n\n\n<p>En tant que backbone omnipr\u00e9sent, SAP est souvent n\u00e9cessaire au bon d\u00e9roulement des affaires. Il en va de m\u00eame pour la technologie d'exploitation. Il est donc dans l'int\u00e9r\u00eat des entreprises de prot\u00e9ger au mieux leur environnement SAP et OT. Mais dans la pratique, des failles apparaissent g\u00e9n\u00e9ralement. En mai 2021, des pirates informatiques ont attaqu\u00e9 des pipelines Colonial en tant qu'infrastructure critique aux \u00c9tats-Unis. Suite \u00e0 cette attaque par ransomware, l'approvisionnement en essence a \u00e9t\u00e9 limit\u00e9 dans certains \u00c9tats. A peu pr\u00e8s au m\u00eame moment, une autre attaque avait \u00e9t\u00e9 signal\u00e9e en Floride. Les pirates ont utilis\u00e9 une faille RDP (Remote Desktop Protocol) sur un appareil Windows pour s'introduire dans les syst\u00e8mes d'une station d'\u00e9puration afin de les manipuler. Les attaques prennent rapidement une nouvelle dimension, en particulier dans le domaine des services publics : Les ransomwares OT ne se contentent pas d'exfiltrer et de crypter les donn\u00e9es, ils peuvent prendre le contr\u00f4le de syst\u00e8mes critiques. Bien entendu, les entreprises sont conscientes du danger permanent. C'est pourquoi elles s'occupent de cybers\u00e9curit\u00e9 et font g\u00e9n\u00e9ralement appel aux groupes d'experts suivants.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Managers et nerds<\/h3>\n\n\n\n<p>Les responsables de la conformit\u00e9 veillent \u00e0 ce que les entreprises respectent les directives en mati\u00e8re de s\u00e9curit\u00e9, telles que celles de l'Office f\u00e9d\u00e9ral allemand de la s\u00e9curit\u00e9 des technologies de l'information (BSI), et les normes internationales telles que la norme ISO\/IEC 27001 ; les experts en s\u00e9curit\u00e9 sont charg\u00e9s de s\u00e9curiser efficacement les solutions informatiques bas\u00e9es sur le cloud \u00e0 l'\u00e8re du big data et de l'intelligence artificielle ; et les hackers nerds connaissent les derni\u00e8res techniques d'attaque et pensent donc un peu plus loin en mati\u00e8re de s\u00e9curit\u00e9.<\/p>\n\n\n\n<p>Mais cette triple approche est souvent insuffisante. En effet, il ne suffit pas que des groupes d'experts se penchent sur le th\u00e8me de la cybers\u00e9curit\u00e9 \u00e0 un niveau plut\u00f4t th\u00e9orique, ind\u00e9pendamment de tous les autres processus et \u00e9quipes de l'entreprise. Il s'agit plut\u00f4t de savoir comment s\u00e9curiser efficacement ses propres activit\u00e9s. Pour atteindre cet objectif, les entreprises doivent consid\u00e9rer la s\u00e9curit\u00e9 SAP et OT comme un processus commercial impliquant tous les groupes de personnes concern\u00e9s au sein de l'entreprise. Ce n'est qu'ainsi que des mesures pratiques appropri\u00e9es - telles que l'utilisation de la technologie de s\u00e9curit\u00e9 ad\u00e9quate - peuvent \u00eatre d\u00e9duites de la vision th\u00e9orique (ou strat\u00e9gique).&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">S\u00e9curit\u00e9 SAP et OT<\/h3>\n\n\n\n<p>Si la cybers\u00e9curit\u00e9 est consid\u00e9r\u00e9e comme un processus commercial critique, ce processus doit \u00eatre mod\u00e9lis\u00e9 avec soin, g\u00e9r\u00e9 \u00e0 l'aide de m\u00e9triques, surveill\u00e9 \u00e0 l'aide d'outils et optimis\u00e9 en permanence. De m\u00eame, il faut une gestion des risques d\u00e9finie dans laquelle le lien avec la pratique est au premier plan. Si, par exemple, le succ\u00e8s commercial d'une entreprise de construction m\u00e9canique d\u00e9pend en grande partie du bon fonctionnement de ses chariots \u00e9l\u00e9vateurs, elle veille \u00e0 ce qu'il y ait toujours suffisamment de lubrifiant, elle respecte toutes les dates de maintenance et met \u00e0 disposition suffisamment de v\u00e9hicules de remplacement. De m\u00eame, les entreprises doivent toujours \u00eatre pr\u00eates \u00e0 faire face \u00e0 toute \u00e9ventualit\u00e9 en mati\u00e8re de s\u00e9curit\u00e9 informatique.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">S\u00e9curit\u00e9 interdisciplinaire<\/h3>\n\n\n\n<p>Pour garantir la s\u00e9curit\u00e9 OT et SAP \u00e0 long terme, il faut d\u00e9passer les fronti\u00e8res entre les services dans le sens d'une pens\u00e9e et d'une organisation orient\u00e9es vers les processus. Le management, l'informatique et la production doivent notamment parvenir \u00e0 un \u00e9change interdisciplinaire. En effet, il arrive que le management n'ait pas une id\u00e9e pr\u00e9cise de l'importance de la s\u00e9curit\u00e9 SAP et OT pour le bon fonctionnement de l'entreprise. Le service informatique peut aider \u00e0 transmettre cette compr\u00e9hension. Le point de vue des Blue Collar Worker, les collaborateurs de la production, est particuli\u00e8rement important. En effet, ces derniers connaissent parfaitement les cons\u00e9quences d'un \u00e9ventuel arr\u00eat de la machine A sur la ligne de production B. Ils savent que la machine A ne peut pas \u00eatre utilis\u00e9e.<\/p>\n\n\n\n<p>Outre une compr\u00e9hension strat\u00e9gique de la pertinence de la s\u00e9curit\u00e9 OT et SAP et un dialogue entre les diff\u00e9rents services, il faut des solutions de s\u00e9curit\u00e9 performantes. Ces derni\u00e8res ann\u00e9es, la technologie a consid\u00e9rablement \u00e9volu\u00e9 : de l'analyse de r\u00e9seau \u00e0 la s\u00e9curit\u00e9 des plateformes en passant par la d\u00e9tection inter-syst\u00e8mes.<\/p>\n\n\n\n<p>Il y a quelque temps encore, il \u00e9tait courant d'analyser le r\u00e9seau et de corr\u00e9ler les fichiers journaux avec un syst\u00e8me SIEM (Security Information and Event Management) afin d'obtenir des indications sur les menaces potentielles - une simple mesure de d\u00e9tection. Il est certes possible de d\u00e9duire une r\u00e9ponse cibl\u00e9e \u00e0 partir des r\u00e9sultats de la corr\u00e9lation, mais pas de la mettre en \u0153uvre directement. Comme la transmission des donn\u00e9es est aujourd'hui le plus souvent crypt\u00e9e, les seules analyses de r\u00e9seau ne sont plus \u00e0 la pointe de la technologie.<\/p>\n\n\n\n<p>Pour traiter les donn\u00e9es sensorielles provenant de diff\u00e9rentes sources, deux nouvelles m\u00e9thodes se sont impos\u00e9es : Endpoint Detection and Response (EDR) et Extended Detection and Response (XDR). Un outil EDR permet d'enregistrer des \u00e9v\u00e9nements tels que l'ouverture de session d'un utilisateur, l'ouverture d'un fichier et les connexions r\u00e9seau \u00e9tablies sur des terminaux tels que des PC, des ordinateurs portables, des tablettes et des smartphones. En outre, XDR permet de collecter et de relier automatiquement des donn\u00e9es sur plusieurs vecteurs d'attaque, tels que les e-mails, les identit\u00e9s, les appareils, les serveurs, les charges de travail en nuage et les r\u00e9seaux.<\/p>\n\n\n\n<p>Si de plus en plus de donn\u00e9es et de syst\u00e8mes se trouvent dans le cloud, il est logique d'y mettre en \u0153uvre des mesures de s\u00e9curit\u00e9 efficaces. Les solutions de plateforme des hyperscaleurs \u00e9tablis ont fait leurs preuves. Microsoft, en particulier, propose une gamme compl\u00e8te de produits de s\u00e9curit\u00e9 avec une multitude de composants pr\u00eats \u00e0 l'emploi qui peuvent \u00eatre facilement mis en service et configur\u00e9s en fonction des besoins individuels de l'entreprise : de la protection des utilisateurs (PC, identit\u00e9s et e-mails) \u00e0 la s\u00e9curisation de diff\u00e9rents sc\u00e9narios d'exploitation (propres serveurs, sur site dans le centre de calcul ainsi que cloud Azure, Google ou AWS) jusqu'aux cas d'application sp\u00e9ciaux comme la s\u00e9curit\u00e9 OT et SAP. De plus, l'int\u00e9gration de telles plateformes est beaucoup plus efficace que les solutions individuelles.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">S\u00e9curit\u00e9 de la plate-forme<\/h3>\n\n\n\n<p>Compte tenu de la complexit\u00e9 de certains environnements SAP et de la d\u00e9pendance des entreprises de production et d'approvisionnement vis-\u00e0-vis de leur technologie d'exploitation, la s\u00e9curit\u00e9 de la plate-forme est une approche efficace. Aujourd'hui, le mouvement lat\u00e9ral est une tactique cl\u00e9 des menaces avanc\u00e9es persistantes (APT) : Les pirates p\u00e9n\u00e8trent par exemple dans une infrastructure informatique critique via une attaque de phishing et obtiennent de plus en plus de droits \u00e0 l'aide des donn\u00e9es r\u00e9cup\u00e9r\u00e9es, en compromettant ou en infectant les syst\u00e8mes les uns apr\u00e8s les autres. Les pirates pourraient par exemple acc\u00e9der au syst\u00e8me informatique de l'entreprise via un modem dans l'atelier de production et crypter les disques durs, ce qui toucherait particuli\u00e8rement les entreprises, \u00e0 savoir leurs processus cl\u00e9s rentables.<\/p>\n\n\n\n<p>Les entreprises n'ont donc pas d'autre choix que de relier les capteurs \u00e0 l'\u00e9chelle du syst\u00e8me et de surveiller les alertes 24 heures sur 24. Elles peuvent \u00e9galement faire appel aux services de d\u00e9tection et de r\u00e9ponse g\u00e9r\u00e9s d'un centre de cybers\u00e9curit\u00e9 sp\u00e9cialis\u00e9 (CSDC). Au centre se trouve Microsoft Threat Monitoring for SAP. Un capteur permet de consolider des donn\u00e9es provenant d'environnements SAP complexes, de sorte qu'elles soient disponibles pour un traitement ult\u00e9rieur dans le syst\u00e8me SIEM cloud-natif Microsoft Sentinel. Une fois connect\u00e9 \u00e0 diff\u00e9rentes sources de logs SAP, le capteur collecte toutes les donn\u00e9es qui sont ensuite transmises \u00e0 Sentinel via une API pour \u00eatre corr\u00e9l\u00e9es et analys\u00e9es. Si l'outil d\u00e9tecte une menace, il g\u00e9n\u00e8re des alertes correspondantes. Des r\u00e8gles standardis\u00e9es forment la base des processus SOAR (Security Orchestration, Automation and Response) (partiellement) automatis\u00e9s : Lorsqu'une alerte est re\u00e7ue, une analyse bas\u00e9e sur l'IA est effectu\u00e9e sur les donn\u00e9es d'\u00e9v\u00e9nements saisies. Selon le type d'attaque, des mesures de r\u00e9ponse pr\u00e9d\u00e9finies se mettent alors en place.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Prot\u00e9ger SAP et OT de mani\u00e8re fiable<\/h3>\n\n\n\n<p>La cybercriminalit\u00e9 est un business lucratif pour les criminels, dont les cons\u00e9quences peuvent aller bien au-del\u00e0 des aspects \u00e9conomiques pour les entreprises concern\u00e9es. C'est pr\u00e9cis\u00e9ment dans le domaine des infrastructures critiques que les attaques peuvent se transformer en une menace s\u00e9rieuse. Et les entreprises doivent \u00eatre mieux pr\u00e9par\u00e9es \u00e0 cette menace r\u00e9elle. Pour cela, il faut d'une part que la culture d'entreprise change : Il ne doit pas y avoir de foss\u00e9s entre les d\u00e9partements, une collaboration interdisciplinaire est n\u00e9cessaire. D'autre part, les KRITIS tels que les entreprises de distribution d'eau et d'\u00e9lectricit\u00e9 sont notamment appel\u00e9s \u00e0 int\u00e9rioriser le rapport pratique de leur IT et de leur OT avec l'entreprise et \u00e0 ne pas seulement en d\u00e9duire les objectifs de protection n\u00e9cessaires, mais aussi \u00e0 les mettre en \u0153uvre. Pour les syst\u00e8mes et infrastructures li\u00e9s \u00e0 l'approvisionnement, il est possible de bien les prot\u00e9ger. Mais pour cela, il est n\u00e9cessaire de comprendre la cybers\u00e9curit\u00e9 comme un processus commercial et de la mettre en \u0153uvre de mani\u00e8re cons\u00e9quente.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Les 3 niveaux de la s\u00e9curit\u00e9 OT<\/h3>\n\n\n\n<p><strong>L'informatique de terrain :<\/strong> Dans une usine \u00e9quip\u00e9e de vieilles machines, l'analyse de r\u00e9seau est g\u00e9n\u00e9ralement la seule chose \u00e0 faire.<br>des moyens probants.<\/p>\n\n\n\n<p><strong>Greenfield-IT :<\/strong> Les entreprises qui lancent de nouveaux syst\u00e8mes informatiques peuvent int\u00e9grer directement les fonctions de s\u00e9curit\u00e9 n\u00e9cessaires.<\/p>\n\n\n\n<p><strong>Informatique d'entreprise :<\/strong> \u00c0 l'heure de l'Internet des objets (IoT), avec des appareils intelligents tels que les \u00e9crans de conf\u00e9rence, les ascenseurs et les machines \u00e0 caf\u00e9, toutes les donn\u00e9es, tous les syst\u00e8mes et tous les appareils doivent \u00eatre s\u00e9curis\u00e9s efficacement.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/e326.greatsolution.dev\/fr\/partenaires\/arvato-systems-gmbh\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"112\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/03\/CI-ARVATO.jpg\" alt=\"https:\/\/e326.greatsolution.dev\/partners\/arvato-systems-gmbh\/\" class=\"wp-image-11355\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/03\/CI-ARVATO.jpg 1000w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/03\/CI-ARVATO-768x86.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/03\/CI-ARVATO-100x11.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/03\/CI-ARVATO-480x54.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/03\/CI-ARVATO-640x72.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/03\/CI-ARVATO-720x81.jpg 720w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/03\/CI-ARVATO-960x108.jpg 960w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure>","protected":false},"excerpt":{"rendered":"<p>Les lignes de production sont des \u00e9l\u00e9ments indispensables des cha\u00eenes d'approvisionnement complexes. Si elles sont perturb\u00e9es, l'existence des entreprises concern\u00e9es peut \u00eatre mise en p\u00e9ril. Que peuvent faire les entreprises pour que les pirates informatiques \"se heurtent au mur\" chez OT ? <\/p>","protected":false},"author":2612,"featured_media":128128,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[5,42541],"tags":[4354,31057,637,42543,1516],"coauthors":[41786],"class_list":["post-128126","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-it-management","category-mag-23-05","tag-arvato-systems","tag-cybercrime","tag-hacker","tag-mag-23-05","tag-security","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/05\/shutterstock_87499840_Ollyy.jpg",1200,540,false],"thumbnail":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/05\/shutterstock_87499840_Ollyy-150x150.jpg",150,150,true],"medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/05\/shutterstock_87499840_Ollyy-400x180.jpg",400,180,true],"medium_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/05\/shutterstock_87499840_Ollyy-768x346.jpg",768,346,true],"large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/05\/shutterstock_87499840_Ollyy.jpg",1200,540,false],"image-100":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/05\/shutterstock_87499840_Ollyy-100x45.jpg",100,45,true],"image-480":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/05\/shutterstock_87499840_Ollyy-480x216.jpg",480,216,true],"image-640":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/05\/shutterstock_87499840_Ollyy-640x288.jpg",640,288,true],"image-720":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/05\/shutterstock_87499840_Ollyy-720x324.jpg",720,324,true],"image-960":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/05\/shutterstock_87499840_Ollyy-960x432.jpg",960,432,true],"image-1168":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/05\/shutterstock_87499840_Ollyy-1168x526.jpg",1168,526,true],"image-1440":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/05\/shutterstock_87499840_Ollyy.jpg",1200,540,false],"image-1920":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/05\/shutterstock_87499840_Ollyy.jpg",1200,540,false],"1536x1536":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/05\/shutterstock_87499840_Ollyy.jpg",1200,540,false],"2048x2048":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/05\/shutterstock_87499840_Ollyy.jpg",1200,540,false],"trp-custom-language-flag":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/05\/shutterstock_87499840_Ollyy.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/05\/shutterstock_87499840_Ollyy.jpg",1200,540,false],"bricks_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/05\/shutterstock_87499840_Ollyy.jpg",1200,540,false],"bricks_large_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/05\/shutterstock_87499840_Ollyy.jpg",1200,540,false],"bricks_medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/05\/shutterstock_87499840_Ollyy-600x270.jpg",600,270,true],"bricks_medium_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/05\/shutterstock_87499840_Ollyy-600x540.jpg",600,540,true],"profile_24":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/05\/shutterstock_87499840_Ollyy-24x24.jpg",24,24,true],"profile_48":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/05\/shutterstock_87499840_Ollyy-48x48.jpg",48,48,true],"profile_96":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/05\/shutterstock_87499840_Ollyy-96x96.jpg",96,96,true],"profile_150":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/05\/shutterstock_87499840_Ollyy-150x150.jpg",150,150,true],"profile_300":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/05\/shutterstock_87499840_Ollyy-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Fertigungslinien sind unverzichtbare Bestandteile komplexer Lieferketten. Sind diese gest\u00f6rt, kann das die Existenz der betroffenen Firmen gef\u00e4hrden. Was k\u00f6nnen Unternehmen tun, damit Hacker bei OT \u201egegen die Wand laufen\u201c? <\/p>\n","category_list_v2":"<a href=\"https:\/\/e326.greatsolution.dev\/fr\/categorie\/gestion-de-linformatique\/\" rel=\"category tag\">IT-Management<\/a>, <a href=\"https:\/\/e326.greatsolution.dev\/fr\/categorie\/mag-23-05\/\" rel=\"category tag\">Mag 23-05<\/a>","author_info_v2":{"name":"Andreas Nolte, Arvato Systems GmbH","url":"https:\/\/e326.greatsolution.dev\/fr\/author\/andreas-nolte\/"},"comments_num_v2":"0 commentaire","_links":{"self":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/posts\/128126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/users\/2612"}],"replies":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/comments?post=128126"}],"version-history":[{"count":0,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/posts\/128126\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/media\/128128"}],"wp:attachment":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/media?parent=128126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/categories?post=128126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/tags?post=128126"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/coauthors?post=128126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}