{"id":129412,"date":"2023-07-06T08:30:00","date_gmt":"2023-07-06T06:30:00","guid":{"rendered":"https:\/\/e326.greatsolution.dev\/?p=129412"},"modified":"2023-06-13T11:43:39","modified_gmt":"2023-06-13T09:43:39","slug":"composable-erp","status":"publish","type":"post","link":"https:\/\/e326.greatsolution.dev\/fr\/composable-erp\/","title":{"rendered":"ERP composable"},"content":{"rendered":"<p>Pendant de nombreuses ann\u00e9es, nous avons discut\u00e9 au sein de la communaut\u00e9 SAP de la position monopolistique de SAP. M\u00eame l'autorit\u00e9 de la concurrence \u00e0 Bonn s'est pench\u00e9e sur cette histoire. Si l'\u00e9volution de l'informatique avait \u00e9t\u00e9 lin\u00e9aire, il y aurait certainement eu une condamnation de SAP. Mais comme l'informatique poss\u00e8de un facteur de disruption \u00e9lev\u00e9, le R\/3 monolithique a \u00e9volu\u00e9 vers un S\/4 h\u00e9t\u00e9rog\u00e8ne et ouvert. La prochaine \u00e9tape sera un ERP composable, qui finira par arracher \u00e0 SAP la souverainet\u00e9 sur l'architecture ERP.<\/p>\n\n\n\n<p>La conception du syst\u00e8me d'un futur ERP peut \u00eatre bas\u00e9e sur des composants SAP, mais son essence sera constitu\u00e9e de solutions informatiques composites. La composabilit\u00e9 d\u00e9finira les futures architectures ERP. Les plateformes deviendront encore plus importantes, car elles repr\u00e9sentent l'homog\u00e9n\u00e9it\u00e9. En tant que client SAP existant, nous nous sommes int\u00e9ress\u00e9s de pr\u00e8s \u00e0 la Business Technology Platform au cours des derniers mois. Il n'est pas encore possible de dire \u00e0 l'heure actuelle si c'est cette plateforme ou celle d'un hyperscaler qui sera d\u00e9terminante pour les architectures ERP \u00e0 l'avenir.<\/p>\n\n\n\n<p>Des constructions telles que SAP Business Suite 7 et S\/4 ont toutefois fait leur temps, leur pr\u00e9tention monopolistique au leadership n'est plus d'actualit\u00e9. En tant que client SAP existant, nous observons donc avec impatience une \u00e9volution qui est pouss\u00e9e par SAP et qui menace en m\u00eame temps l'existence de SAP. L'orientation de SAP vers l'open source, les plateformes, les mod\u00e8les de programmation d\u00e9mocratiques, l'IA et le Machine Learning nous permettra, \u00e0 nous clients existants, de progresser rapidement dans la transformation num\u00e9rique, tout en r\u00e9duisant rapidement notre d\u00e9pendance vis-\u00e0-vis de SAP.<\/p>\n\n\n\n<p>Deux \u00e2mes semblent d\u00e9sormais habiter la poitrine de Christian Klein, CEO de SAP : Avec la Business Technology Platform, Steampunk en tant qu'Embedded Abap, les coop\u00e9rations en mati\u00e8re d'IA avec IBM, Microsoft et bien d'autres, SAP atteint un niveau d'agilit\u00e9, de transparence et d'ouverture inconnu jusqu'\u00e0 pr\u00e9sent ; avec les r\u00e9centes modifications de la liste des prix SAP, le leader mondial de l'ERP tente de rattraper les esprits et de tenir une nouvelle fois les clients existants par la bride. (Le forfait S\/4 de 9000 euros a \u00e9t\u00e9 supprim\u00e9, sans lequel il n'y aura \u00e0 l'avenir pas de conversion de produit lors du passage \u00e0 S\/4).<\/p>\n\n\n\n<p>Composable ERP porte aussi en lui un peu de cybern\u00e9tique. La perte de contr\u00f4le de SAP r\u00e9sulte de l'interaction autonome des diff\u00e9rents composants informatiques sur une plate-forme ad\u00e9quate. Il s'agit d'interactions entre les composants. Un syst\u00e8me hautement combinable nous offre, \u00e0 nous clients existants, les composants ERP qui peuvent \u00eatre assembl\u00e9s dans diff\u00e9rentes combinaisons afin de r\u00e9pondre \u00e0 nos besoins d'utilisateurs. Avec des outils informatiques tels que BTP, SAP Build et Steampunk, le paysage des partenaires SAP va \u00e9galement se transformer de mani\u00e8re r\u00e9volutionnaire, car toute forme de d\u00e9pendance et de monopole dispara\u00eet.<\/p>\n\n\n\n<p>La combinaison des r\u00e9centes annonces de SAP telles que Datasphere, Build, BTP, Steampunk et les coop\u00e9rations en mati\u00e8re d'IA donne au total des degr\u00e9s de libert\u00e9 \u00e9lev\u00e9s pour les clients existants. Nous ne d\u00e9pendrons plus des d\u00e9veloppements et des feuilles de route des fournisseurs informatiques et des partenaires SAP, mais pourrons suivre nos propres voies sur la base de l'open source, de l'IA g\u00e9n\u00e9rative, des plateformes et du low-code\/no-code. Mais cette fois-ci, nos feuilles de route seront agiles, ouvertes et transparentes et ne finiront pas dans le chaos d'un espace de noms en Z avec des modifications Abap singuli\u00e8res. Le steampunk en tant qu'Abap embarqu\u00e9 sur le BTP est un nouveau concept de libert\u00e9.<\/p>\n\n\n\n<p>Composable ERP ne signifie donc pas que chaque client SAP existant fait ce qu'il veut, mais qu'il y aura une compr\u00e9hension commune du contexte au sein de la communaut\u00e9 SAP. Cette composabilit\u00e9 sera un principe de la conception du syst\u00e8me ERP et sera la propri\u00e9t\u00e9 de la communaut\u00e9. SAP et de nombreux autres fournisseurs informatiques deviendront des fournisseurs d'outils. Ils perdent toutefois toute position dominante de type monopolistique. Cela semble ouvrir la voie \u00e0 une \u00e8re post-S\/4. Le d\u00e9bat sur un ERP post-S\/4 n'est pas men\u00e9 chez SAP, mais par nous, les clients existants, au sein de la communaut\u00e9.<\/p>","protected":false},"excerpt":{"rendered":"<p>Une nouvelle architecture ERP est en train de na\u00eetre, pouss\u00e9e par la technologie SAP, mais qui plaira moins \u00e0 SAP lui-m\u00eame. Le CEO Christian Klein a d\u00e9j\u00e0 pris acte des premiers revers et a revu \u00e0 la baisse les pr\u00e9visions de chiffre d'affaires pour le cloud computing.<\/p>","protected":false},"author":9,"featured_media":2461,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[43065,12],"tags":[42055,73,43067,38454,517,236],"coauthors":[21816],"class_list":["post-129412","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mag-23-06","category-noname","tag-composable-erp","tag-erp","tag-mag-23-06","tag-noname-2","tag-s4","tag-sap","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/NoName.jpg",1000,431,false],"thumbnail":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/NoName-150x150.jpg",150,150,true],"medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/NoName.jpg",400,172,false],"medium_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/NoName-768x331.jpg",768,331,true],"large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/NoName.jpg",1000,431,false],"image-100":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/NoName-100x43.jpg",100,43,true],"image-480":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/NoName-480x207.jpg",480,207,true],"image-640":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/NoName-640x276.jpg",640,276,true],"image-720":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/NoName-720x310.jpg",720,310,true],"image-960":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/NoName-960x414.jpg",960,414,true],"image-1168":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/NoName.jpg",1000,431,false],"image-1440":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/NoName.jpg",1000,431,false],"image-1920":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/NoName.jpg",1000,431,false],"1536x1536":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/NoName.jpg",1000,431,false],"2048x2048":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/NoName.jpg",1000,431,false],"trp-custom-language-flag":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/NoName.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/NoName.jpg",1000,431,false],"bricks_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/NoName.jpg",1000,431,false],"bricks_large_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/NoName.jpg",1000,431,false],"bricks_medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/NoName.jpg",600,259,false],"bricks_medium_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/NoName.jpg",600,259,false],"profile_24":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/NoName-24x24.jpg",24,24,true],"profile_48":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/NoName-48x48.jpg",48,48,true],"profile_96":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/NoName-96x96.jpg",96,96,true],"profile_150":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/NoName-150x150.jpg",150,150,true],"profile_300":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/NoName-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Es erw\u00e4chst eine neue ERP-Architektur, die durch SAP-Technik getrieben wird, aber SAP selbst weniger gefallen wird. CEO Christian Klein hat die ersten R\u00fcckschl\u00e4ge bereits zur Kenntnis genommen und die Umsatzerwartung f\u00fcr Cloud Computing gesenkt.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e326.greatsolution.dev\/fr\/categorie\/mag-23-06\/\" rel=\"category tag\">Mag 23-06<\/a>, <a href=\"https:\/\/e326.greatsolution.dev\/fr\/categorie\/avis\/noname\/\" rel=\"category tag\">No\/Name-Kolumne<\/a>","author_info_v2":{"name":"no-name","url":"https:\/\/e326.greatsolution.dev\/fr\/author\/no-name\/"},"comments_num_v2":"0 commentaire","_links":{"self":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/posts\/129412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/comments?post=129412"}],"version-history":[{"count":0,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/posts\/129412\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/media\/2461"}],"wp:attachment":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/media?parent=129412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/categories?post=129412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/tags?post=129412"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/coauthors?post=129412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}