{"id":135919,"date":"2023-12-12T15:50:40","date_gmt":"2023-12-12T14:50:40","guid":{"rendered":"https:\/\/e326.greatsolution.dev\/?p=135919"},"modified":"2024-01-19T14:44:58","modified_gmt":"2024-01-19T13:44:58","slug":"lhotellerie-sert-avec-oracle-netsuite","status":"publish","type":"post","link":"https:\/\/e326.greatsolution.dev\/fr\/lhotellerie-sert-avec-oracle-netsuite\/","title":{"rendered":"L'h\u00f4tellerie et la restauration servies avec Oracle NetSuite"},"content":{"rendered":"<p>Les entreprises de restauration et d'h\u00f4tellerie se tournent vers Oracle NetSuite pour augmenter la productivit\u00e9, am\u00e9liorer la visibilit\u00e9 et la prise de d\u00e9cision. Hofman Hospitality Group, Lettuce Entertain You, Union Square Hospitality Group et bien d'autres ont choisi NetSuite pour rationaliser leurs processus commerciaux et cr\u00e9er une base \u00e9volutive pour leur croissance future.<\/p>\n\n\n\n<p>NetSuite aide les restaurants et les entreprises de restauration avec des fonctions de gestion des ressources d'entreprise pour les finances, la comptabilit\u00e9, l'approvisionnement, la gestion des actifs et la gestion des franchises. NetSuite aide les restaurants et les entreprises de restauration \u00e0 int\u00e9grer et \u00e0 automatiser les processus, \u00e0 introduire de nouveaux mod\u00e8les d'exploitation, \u00e0 diversifier les sources de revenus et \u00e0 am\u00e9liorer l'exp\u00e9rience client.<\/p>\n\n\n\n<p>\"Le secteur de la restauration et de l'h\u00f4tellerie est de plus en plus concurrentiel et les entreprises sont confront\u00e9es au d\u00e9fi de suivre l'\u00e9volution des pr\u00e9f\u00e9rences des consommateurs ainsi que l'augmentation des co\u00fbts de l'alimentation et de la main-d'\u0153uvre\", d\u00e9clare David Rodman, vice-pr\u00e9sident senior de Customer Success, Oracle NetSuite. \"Avec NetSuite, les entreprises de restauration et d'h\u00f4tellerie peuvent rationaliser les processus financiers et autres processus op\u00e9rationnels afin d'augmenter la productivit\u00e9, de saisir les opportunit\u00e9s de croissance et d'\u00e9voluer avec succ\u00e8s\".<\/p>\n\n\n\n<p><a href=\"https:\/\/www.oracle.com\/de\/\" target=\"_blank\" rel=\"noopener\">oracle.com<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>NetSuite aide les restaurants et les entreprises d'h\u00f4tellerie \u00e0 rationaliser leurs processus et \u00e0 stimuler leur croissance<\/p>","protected":false},"author":2368,"featured_media":136016,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[2,43385],"tags":[43754,198],"coauthors":[39720],"class_list":["post-135919","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sap-nachrichten","category-pressemeldung","tag-netsuite","tag-oracle","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/12\/kellnerin-gastronomie.jpg",998,449,false],"thumbnail":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/12\/kellnerin-gastronomie-150x150.jpg",150,150,true],"medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/12\/kellnerin-gastronomie-400x180.jpg",400,180,true],"medium_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/12\/kellnerin-gastronomie-768x346.jpg",768,346,true],"large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/12\/kellnerin-gastronomie.jpg",998,449,false],"image-100":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/12\/kellnerin-gastronomie-100x45.jpg",100,45,true],"image-480":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/12\/kellnerin-gastronomie-480x216.jpg",480,216,true],"image-640":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/12\/kellnerin-gastronomie-640x288.jpg",640,288,true],"image-720":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/12\/kellnerin-gastronomie-720x324.jpg",720,324,true],"image-960":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/12\/kellnerin-gastronomie-960x432.jpg",960,432,true],"image-1168":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/12\/kellnerin-gastronomie.jpg",998,449,false],"image-1440":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/12\/kellnerin-gastronomie.jpg",998,449,false],"image-1920":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/12\/kellnerin-gastronomie.jpg",998,449,false],"1536x1536":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/12\/kellnerin-gastronomie.jpg",998,449,false],"2048x2048":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/12\/kellnerin-gastronomie.jpg",998,449,false],"trp-custom-language-flag":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/12\/kellnerin-gastronomie-18x8.jpg",18,8,true],"bricks_large_16x9":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/12\/kellnerin-gastronomie.jpg",998,449,false],"bricks_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/12\/kellnerin-gastronomie.jpg",998,449,false],"bricks_large_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/12\/kellnerin-gastronomie.jpg",998,449,false],"bricks_medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/12\/kellnerin-gastronomie-600x270.jpg",600,270,true],"bricks_medium_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/12\/kellnerin-gastronomie-600x449.jpg",600,449,true],"profile_24":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/12\/kellnerin-gastronomie-24x24.jpg",24,24,true],"profile_48":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/12\/kellnerin-gastronomie-48x48.jpg",48,48,true],"profile_96":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/12\/kellnerin-gastronomie-96x96.jpg",96,96,true],"profile_150":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/12\/kellnerin-gastronomie-150x150.jpg",150,150,true],"profile_300":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/12\/kellnerin-gastronomie-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>NetSuite hilft Restaurants und Gastgewerbe-Unternehmen, Prozesse zu rationalisieren und das Wachstum voranzutreiben<\/p>\n","category_list_v2":"<a href=\"https:\/\/e326.greatsolution.dev\/fr\/categorie\/sap-nouvelles\/\" rel=\"category tag\">Community Nachrichten<\/a>, <a href=\"https:\/\/e326.greatsolution.dev\/fr\/categorie\/sap-nouvelles\/communique-de-presse\/\" rel=\"category tag\">Pressemeldung<\/a>","author_info_v2":{"name":"Magazine E3","url":"https:\/\/e326.greatsolution.dev\/fr\/author\/e3_magazin\/"},"comments_num_v2":"0 commentaire","_links":{"self":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/posts\/135919","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/users\/2368"}],"replies":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/comments?post=135919"}],"version-history":[{"count":6,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/posts\/135919\/revisions"}],"predecessor-version":[{"id":136039,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/posts\/135919\/revisions\/136039"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/media\/136016"}],"wp:attachment":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/media?parent=135919"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/categories?post=135919"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/tags?post=135919"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/coauthors?post=135919"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}