{"id":150766,"date":"2025-04-28T11:34:23","date_gmt":"2025-04-28T09:34:23","guid":{"rendered":"https:\/\/e326.greatsolution.dev\/?p=150766"},"modified":"2025-04-28T13:48:51","modified_gmt":"2025-04-28T11:48:51","slug":"minsait-implemente-des-assistants-ki-chez-helvetia","status":"publish","type":"post","link":"https:\/\/e326.greatsolution.dev\/fr\/minsait-implemente-des-assistants-ki-chez-helvetia\/","title":{"rendered":"Minsait impl\u00e9mente des assistants IA chez Helvetia"},"content":{"rendered":"<p>Minsait, une entreprise sp\u00e9cialis\u00e9e dans le conseil SAP, soutient Helvetia Seguros avec un assistant virtuel intelligent qui accompagne les interm\u00e9diaires d'assurance en Espagne pendant leurs processus de vente. L'assistant, bas\u00e9 sur l'intelligence artificielle, offre aux experts de la compagnie d'assurance un soutien technique et op\u00e9rationnel cibl\u00e9, en leur fournissant des informations pr\u00e9cises, compr\u00e9hensibles et actualis\u00e9es sur les produits avec lesquels ils travaillent au quotidien. Les premiers rapports d'exp\u00e9rience des utilisateurs sont tr\u00e8s positifs, c'est pourquoi le syst\u00e8me doit d\u00e9sormais \u00eatre mis \u00e0 la disposition de tous les collaborateurs dans les meilleurs d\u00e9lais.<\/p>\n\n\n\n<p>Ana Ariztegui, responsable des solutions num\u00e9riques et de l'analyse des donn\u00e9es dans le domaine de la technologie et des donn\u00e9es chez Helvetia Seguros, explique : \"Chez Helvetia, le client est au centre de nos activit\u00e9s et les connaissances approfondies sont notre plus grande valeur ajout\u00e9e. Nous avons cr\u00e9\u00e9 une communaut\u00e9 de donn\u00e9es gr\u00e2ce \u00e0 laquelle nous pouvons partager efficacement les connaissances et les informations et utiliser au mieux les donn\u00e9es que nous avons collect\u00e9es depuis des ann\u00e9es. Gr\u00e2ce \u00e0 cette base technologique, nous pouvons int\u00e9grer des ressources innovantes telles que l'IA afin de r\u00e9duire les temps de traitement et de rendre les t\u00e2ches r\u00e9p\u00e9titives plus efficaces\".<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1177\" height=\"784\" data-id=\"150776\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/Ana-Ariztegui-edited-1.jpg\" alt=\"\" class=\"wp-image-150776\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/Ana-Ariztegui-edited-1.jpg 1177w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/Ana-Ariztegui-edited-1-400x266.jpg 400w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/Ana-Ariztegui-edited-1-768x512.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/Ana-Ariztegui-edited-1-100x67.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/Ana-Ariztegui-edited-1-480x320.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/Ana-Ariztegui-edited-1-640x426.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/Ana-Ariztegui-edited-1-720x480.jpg 720w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/Ana-Ariztegui-edited-1-960x639.jpg 960w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/Ana-Ariztegui-edited-1-1168x778.jpg 1168w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/Ana-Ariztegui-edited-1-18x12.jpg 18w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/Ana-Ariztegui-edited-1-600x400.jpg 600w\" sizes=\"auto, (max-width: 1177px) 100vw, 1177px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"has-text-align-center\"><em>Ana Ar\u00edztegui, responsable des solutions num\u00e9riques et de l'analyse des donn\u00e9es dans le domaine de la technologie et des donn\u00e9es, Helvetia Seguros<\/em><\/p>\n\n\n\n<p>La num\u00e9risation chez Helvetia a \u00e9t\u00e9 r\u00e9alis\u00e9e par Minsait en utilisant la technologie Agentforce de Salesforce. Gr\u00e2ce \u00e0 l'utilisation g\u00e9n\u00e9ralis\u00e9e de l'assistant IA, les collaborateurs de la vente auront \u00e0 l'avenir nettement moins de temps \u00e0 consacrer aux t\u00e2ches de routine et pourront au contraire se concentrer davantage sur des activit\u00e9s strat\u00e9giques et de qualit\u00e9.<\/p>\n\n\n\n<p><strong>Comp\u00e9tences de l'assistant<\/strong><\/p>\n\n\n\n<p>L'agent d\u00e9ploy\u00e9 peut rechercher, interpr\u00e9ter et extraire des informations de documents relatifs \u00e0 des produits d'assurance, y compris des questions sur les couvertures, les risques ou les exclusions. De m\u00eame, il identifie clairement le produit d'assurance sur lequel une question est pos\u00e9e, fournit des informations sp\u00e9cifiques sur chaque produit et \u00e9vite toute confusion entre les couvertures, les exclusions, les tarifs et les risques associ\u00e9s \u00e0 diff\u00e9rents produits.<\/p>\n\n\n\n<p>Il peut \u00e9galement r\u00e9pondre \u00e0 des questions sur les prestations de base et compl\u00e9mentaires, les exclusions g\u00e9n\u00e9rales et les risques exceptionnels, les modalit\u00e9s contractuelles ou les aspects g\u00e9n\u00e9raux des polices. Les r\u00e9ponses sont claires, compl\u00e8tes et adapt\u00e9es au contexte de la demande, en \u00e9vitant les termes trop techniques.<\/p>\n\n\n\n<p>La solution de Minsait analyse chaque demande afin de comprendre l'intention de l'interm\u00e9diaire et de fournir les infos les plus pertinentes. Ce faisant, elle adapte la profondeur des r\u00e9ponses \u00e0 la complexit\u00e9 de la question et fournit tout ce qui est n\u00e9cessaire, des r\u00e9sum\u00e9s aux explications d\u00e9taill\u00e9es.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.minsait.com\/es\" target=\"_blank\" rel=\"noopener\">minsait.com<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/www.helvetia.es\" target=\"_blank\" rel=\"noopener\">helvetia.es<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>L'assistant v\u00e9rifie chaque demande afin de fournir des informations pertinentes et utiles, adapte la profondeur des r\u00e9ponses \u00e0 la complexit\u00e9 de la question et offre des assistants IA clairs, complets et Minsait impl\u00e9ment\u00e9s chez Helvetia.<\/p>","protected":false},"author":2368,"featured_media":150771,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[2],"tags":[],"coauthors":[39720],"class_list":["post-150766","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sap-nachrichten","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/AI-assistant.jpg",1000,456,false],"thumbnail":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/AI-assistant-150x150.jpg",150,150,true],"medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/AI-assistant-400x182.jpg",400,182,true],"medium_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/AI-assistant-768x350.jpg",768,350,true],"large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/AI-assistant.jpg",1000,456,false],"image-100":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/AI-assistant-100x46.jpg",100,46,true],"image-480":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/AI-assistant-480x219.jpg",480,219,true],"image-640":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/AI-assistant-640x292.jpg",640,292,true],"image-720":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/AI-assistant-720x328.jpg",720,328,true],"image-960":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/AI-assistant-960x438.jpg",960,438,true],"image-1168":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/AI-assistant.jpg",1000,456,false],"image-1440":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/AI-assistant.jpg",1000,456,false],"image-1920":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/AI-assistant.jpg",1000,456,false],"1536x1536":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/AI-assistant.jpg",1000,456,false],"2048x2048":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/AI-assistant.jpg",1000,456,false],"trp-custom-language-flag":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/AI-assistant-18x8.jpg",18,8,true],"bricks_large_16x9":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/AI-assistant.jpg",1000,456,false],"bricks_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/AI-assistant.jpg",1000,456,false],"bricks_large_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/AI-assistant.jpg",1000,456,false],"bricks_medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/AI-assistant-600x274.jpg",600,274,true],"bricks_medium_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/AI-assistant-600x456.jpg",600,456,true],"profile_24":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/AI-assistant-24x24.jpg",24,24,true],"profile_48":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/AI-assistant-48x48.jpg",48,48,true],"profile_96":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/AI-assistant-96x96.jpg",96,96,true],"profile_150":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/AI-assistant-150x150.jpg",150,150,true],"profile_300":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/04\/AI-assistant-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Der Assistent checkt jede Anfrage, um relevante und hilfreiche Infos zu liefern, passt die Tiefe der Antworten an die Komplexit\u00e4t der Frage an und bietet klare, umfassende und Minsait implementiert KI-Assistenten bei Helvetia.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e326.greatsolution.dev\/fr\/categorie\/sap-nouvelles\/\" rel=\"category tag\">Community Nachrichten<\/a>","author_info_v2":{"name":"Magazine E3","url":"https:\/\/e326.greatsolution.dev\/fr\/author\/e3_magazin\/"},"comments_num_v2":"0 commentaire","_links":{"self":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/posts\/150766","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/users\/2368"}],"replies":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/comments?post=150766"}],"version-history":[{"count":6,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/posts\/150766\/revisions"}],"predecessor-version":[{"id":150831,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/posts\/150766\/revisions\/150831"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/media\/150771"}],"wp:attachment":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/media?parent=150766"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/categories?post=150766"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/tags?post=150766"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/coauthors?post=150766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}