{"id":1838,"date":"2016-11-25T03:00:42","date_gmt":"2016-11-25T02:00:42","guid":{"rendered":"https:\/\/e326.greatsolution.dev\/?p=1838"},"modified":"2022-02-05T23:54:55","modified_gmt":"2022-02-05T22:54:55","slug":"hueterdesgoldenrecords","status":"publish","type":"post","link":"https:\/\/e326.greatsolution.dev\/fr\/hueterdesgoldenrecords\/","title":{"rendered":"Gardien du Golden Record"},"content":{"rendered":"<p>Lorsqu'il s'agit d'am\u00e9liorer l'efficacit\u00e9 et de r\u00e9duire les co\u00fbts, les entreprises <span id=\"urn:local-text-annotation-wqzeq332g8no9qk34a60nyxl1evde9rp\" class=\"textannotation disambiguated wl-thing\">Entreprise<\/span> rapidement des oreilles attentives.<\/p>\n<p>\"Et c'est exactement ce dont il s'agit avec la gestion des donn\u00e9es de base\"<\/p>\n<p>d\u00e9finit la CEO Monika P\u00fcrsing, fixant ainsi la direction \u00e0 suivre d\u00e8s le d\u00e9but de l'entretien E-3.<\/p>\n<p>Moderne <span id=\"urn:local-text-annotation-ndr9zktnr1cprr1e7cldnwixx1bjgv0i\" class=\"textannotation disambiguated wl-thing\">Gestion des donn\u00e9es<\/span> n'est pas une discipline technique, mais un d\u00e9fi entrepreneurial pour l'ensemble de l'entreprise. <span id=\"urn:local-text-annotation-1r0pw94gswxtrhzdc239tknx99tzd9rs\" class=\"textannotation disambiguated wl-thing\">Entreprise<\/span>. Le site <span id=\"urn:local-text-annotation-h2ydzmwuq9tcmhz2zfylo9lixdie7s0u\" class=\"textannotation disambiguated wl-organization\">SAP<\/span>-La base de donn\u00e9es doit \u00eatre embarqu\u00e9e au m\u00eame titre que les d\u00e9partements sp\u00e9cialis\u00e9s.<\/p>\n<h2>Cause et effet<\/h2>\n<p>Selon les estimations g\u00e9n\u00e9rales, l'effet n\u00e9gatif des mauvaises <span id=\"urn:local-text-annotation-nwp9ixx089zouj5yshy2evsml8ohzs4x\" class=\"textannotation disambiguated wl-thing\">Qualit\u00e9 des donn\u00e9es<\/span> entre huit et douze pour cent du b\u00e9n\u00e9fice d'exploitation.<\/p>\n<p>\"Mauvaise <span id=\"urn:local-text-annotation-qrg2fgw6ktz1i1rvsekd8lyvmeyx373g\" class=\"textannotation disambiguated wl-thing\">Qualit\u00e9 des donn\u00e9es<\/span> co\u00fbte donc vraiment de l'argent\",<\/p>\n<p>Monika P\u00fcrsing le sait aussi et elle en cite les causes :<\/p>\n<p>\"La raison en est un syst\u00e8me souvent totalement inefficace ,<span id=\"urn:local-text-annotation-n9ppze8msqph33i5tukkidl1h52qhuyp\" class=\"textannotation disambiguated wl-thing\">Gestion des donn\u00e9es<\/span>Si tant est que l'on puisse en parler. Des formes historiquement sauvages <span id=\"urn:local-text-annotation-jjna4c28htln1zgikkwotzupzatp2bus\" class=\"textannotation disambiguated wl-thing\">Donn\u00e9es<\/span>Les donn\u00e9es sont souvent incompl\u00e8tes, les silos de donn\u00e9es sont isol\u00e9s les uns des autres, les comp\u00e9tences sont enchev\u00eatr\u00e9es, la gestion des donn\u00e9es est manuelle et co\u00fbteuse, les processus sont complexes et compliqu\u00e9s, les probl\u00e8mes de donn\u00e9es font l'objet de \"fire fighting\" r\u00e9guliers, il n'y a pas de directives internes \u00e0 l'entreprise concernant l'utilisation des donn\u00e9es. <span id=\"urn:local-text-annotation-u3sxk8pgwievx1pg5qvvefm85klcwfox\" class=\"textannotation disambiguated wl-thing\">Donn\u00e9es<\/span>Pas de \"Golden Record\", pour ne citer que quelques-uns des aspects essentiels\".<\/p>\n<p>Une gestion professionnelle des donn\u00e9es de base devient en outre plus importante en raison de d\u00e9veloppements tels que le Big Data, l'Internet des objets et l'industrie 4.0, l'analyse pr\u00e9dictive, etc.<\/p>\n<p>\"L'Internet des objets, l'industrie 4.0, la num\u00e9risation des cha\u00eenes de valeur sont d'importants moteurs actuels pour le sujet <span id=\"urn:local-text-annotation-fhtmsfgz5450ye2lmsmjtyl9b14p424w\" class=\"textannotation disambiguated wl-thing\">Qualit\u00e9 des donn\u00e9es<\/span>\"<\/p>\n<p>\"\u00c0 cela s'ajoutent la Business Intelligence et le Big Data Analytics. Pour une \u00e9valuation et une utilisation efficaces des <span id=\"urn:local-text-annotation-ysvsn9cclno78llf63cpilkquu3k8rnr\" class=\"textannotation disambiguated wl-thing\">Donn\u00e9es<\/span> doit \u00eatre <span id=\"urn:local-text-annotation-wlr9ohq08j1as7shjboxzx6rdom6gd1u\" class=\"textannotation disambiguated wl-thing\">Qualit\u00e9 des donn\u00e9es<\/span> sont d'accord. L'utilisation de m\u00e9thodes de traitement et d'analyse ne peut g\u00e9n\u00e9rer une valeur mon\u00e9taire \u00e0 partir des Big Data que si les <span id=\"urn:local-text-annotation-lkdoe3jp4pm6ukubf6qt7nx6307rgojm\" class=\"textannotation disambiguated wl-thing\">Donn\u00e9es<\/span> voter\", c'est-\u00e0-dire \"voter\". De \"mauvais <span id=\"urn:local-text-annotation-cj63lsvspeqn7ww78h7mfppy0z83g78l\" class=\"textannotation disambiguated wl-thing\">Donn\u00e9es<\/span> il ne peut pas y avoir de \"bonnes\" informations. Les \u00e9valuations ou les planifications sont sujettes \u00e0 des erreurs si elles ne reposent pas sur des informations compl\u00e8tes, claires et \"correctes\". <span id=\"urn:local-text-annotation-duderuonbchc0ilkfssjeldvfqxbuz42\" class=\"textannotation disambiguated wl-thing\">Donn\u00e9es<\/span> sont bas\u00e9es sur\".<\/p>\n<figure id=\"attachment_1936\" aria-describedby=\"caption-attachment-1936\" style=\"width: 219px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/ZetVisions.jpg\"><img loading=\"lazy\" decoding=\"async\" title=\"Gardien du golden record\" class=\"wp-image-1936\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/ZetVisions-e1479896159851.jpg\" alt=\"ZetVisions\" width=\"219\" height=\"594\" \/><\/a><figcaption id=\"caption-attachment-1936\" class=\"wp-caption-text\">La CEO de ZetVisions, Monika P\u00fcrsing, a r\u00e9pondu \u00e0 toutes les questions concernant la gestion des donn\u00e9es de r\u00e9f\u00e9rence, le big data, la gouvernance, la qualit\u00e9 des donn\u00e9es, les structures de donn\u00e9es et les algorithmes en compagnie de Border Collie Spot, le \"gardien du Golden Records\".<\/figcaption><\/figure>\n<p>L'impact : l'hypoth\u00e8se selon laquelle les pr\u00e9visions ne peuvent \u00eatre bonnes que si les <span id=\"urn:local-text-annotation-txhoxcpr3tjx3g7lc4qsoepwd6ankl7c\" class=\"textannotation disambiguated wl-thing\">Donn\u00e9es<\/span>L'hypoth\u00e8se d'un lien entre les deux, sur laquelle ils se basent, semble plausible.<\/p>\n<p>Dans le cadre d'un travail de bachelor \u00e0 la Hochschule der Medien (HdM) de Stuttgart, cette relation a \u00e9t\u00e9 \u00e9tudi\u00e9e pour la premi\u00e8re fois de mani\u00e8re empirique et confirm\u00e9e \u00e0 l'aide d'une s\u00e9rie de tests concrets.<\/p>\n<p>L'auteur du travail, Paul Titze, \u00e9tudiant au d\u00e9partement Information et communication de la fili\u00e8re <span id=\"urn:local-text-annotation-wqx95jaodlc4po1hd2no7vdwxghel0lu\" class=\"textannotation disambiguated wl-thing\">Informatique de gestion<\/span> et des m\u00e9dias num\u00e9riques \u00e0 la HdM, a v\u00e9rifi\u00e9 \u00e0 l'aide de diff\u00e9rents sc\u00e9narios de test, dans lesquels des analyses de donn\u00e9es sont effectu\u00e9es \u00e0 l'aide de <span id=\"urn:local-text-annotation-4bzfsj9q3a4sfkgti6x2aq2hakvl4jtd\" class=\"textannotation disambiguated wl-thing\">Donn\u00e9es de base<\/span> de qualit\u00e9 diff\u00e9rente, ont mis en \u00e9vidence le lien entre la qualit\u00e9 de l'enseignement et la qualit\u00e9 de la formation. <span id=\"urn:local-text-annotation-im0irz1j0mq1k163sh5cnij4rna3rgpq\" class=\"textannotation disambiguated wl-thing\">Donn\u00e9es de base<\/span> et les r\u00e9sultats de la <span id=\"urn:local-text-annotation-gvqn8ie8byelps2difz5thpce449kykr\" class=\"textannotation disambiguated wl-thing\">Analyse<\/span> entre autres au moyen de <span id=\"urn:local-text-annotation-s7mb3ssfyldo2c5sbyxhbvl5e9y9vzm8\" class=\"textannotation disambiguated wl-thing\">Apprentissage automatique<\/span>.<\/p>\n<p>R\u00e9sultat : surtout pour le <span id=\"urn:local-text-annotation-1ao7z2qac1rt4yjg3tifj0642vbysyaz\" class=\"textannotation disambiguated wl-thing\">Apprentissage automatique<\/span>o\u00f9 les <span id=\"urn:local-text-annotation-iov4vvuzu696ch7hwkueisvf2trdzs45\" class=\"textannotation disambiguated wl-thing\">Donn\u00e9es de base<\/span> qui constituent la base de l'apprentissage de l'algorithme, une base de donn\u00e9es pr\u00e9par\u00e9e de mani\u00e8re qualitative par la gestion des donn\u00e9es de base a permis d'obtenir des pr\u00e9dictions nettement meilleures que lors de la <span id=\"urn:local-text-annotation-b9q5zob53djnq6tg1khy9vxu31j87med\" class=\"textannotation disambiguated wl-thing\">Apprentissage automatique<\/span> avec un ensemble de donn\u00e9es non trait\u00e9es.<\/p>\n<p>\"\u00c0 propos de <span id=\"urn:local-text-annotation-rqsqep691mbevpnvsp97svkhpkozyo5z\" class=\"textannotation disambiguated wl-thing\">Qualit\u00e9 des donn\u00e9es<\/span> on en parle en effet depuis longtemps\" \"Mais la pression sur les <span id=\"urn:local-text-annotation-q9fzf1m13i7rsd87eqspwoqfhbxazwef\" class=\"textannotation disambiguated wl-thing\">Entreprise<\/span> grandit de plus en plus pour prendre le sujet vraiment au s\u00e9rieux et faire quelque chose\".<\/p>\n<p>Les volumes de donn\u00e9es augmentent rapidement. Seuls de nombreux <span id=\"urn:local-text-annotation-kmhw4uef96cruw26iygbm3ncjoe7e5dv\" class=\"textannotation disambiguated wl-thing\">Donn\u00e9es<\/span> apportent le <span id=\"urn:local-text-annotation-yoq173ikd8id9e0ar63fzwi7voti54db\" class=\"textannotation disambiguated wl-thing\">Entreprise<\/span> mais peu de choses. Sans la reconnaissance de contextes, de significations et de mod\u00e8les, ils sont en grande partie sans valeur.<\/p>\n<p>Selon une \u00e9tude de PwC datant de 2014, 90% des entreprises de tous les secteurs d'activit\u00e9 pr\u00e9voient une augmentation de leur chiffre d'affaires \u00e0 l'avenir. <span id=\"urn:local-text-annotation-oeo0mpnlt5o1iprnqdfe329yzsr40p5h\" class=\"textannotation disambiguated wl-thing\">Entreprise<\/span> convaincus que la capacit\u00e9 d'analyser et d'utiliser efficacement de grandes quantit\u00e9s de donn\u00e9es sera d\u00e9terminante pour le succ\u00e8s de leur mod\u00e8le d'entreprise.<\/p>\n<p>\"Pour d\u00e9velopper cette capacit\u00e9 et \u00eatre en <span id=\"urn:local-text-annotation-do4jzo8fudvxs54llyi8urckqh8uw2lo\" class=\"textannotation disambiguated wl-thing\">Entreprise<\/span> il faut une gouvernance des donn\u00e9es efficace, c'est-\u00e0-dire des processus et des responsabilit\u00e9s uniformes pour la saisie, la validation et la mise \u00e0 jour des donn\u00e9es\".<\/p>\n<h2><span id=\"urn:local-text-annotation-f0wdef10hr48d3qhtfajdshti243y73v\" class=\"textannotation disambiguated wl-thing\">Algorithmes<\/span> et structures de donn\u00e9es<\/h2>\n<p>\"Sans gouvernance des donn\u00e9es, c'est-\u00e0-dire des processus contr\u00f4l\u00e9s et des responsabilit\u00e9s claires, rien n'est possible. Ils constituent la base sur laquelle nous nous appuyons avec notre solution de donn\u00e9es de r\u00e9f\u00e9rence ZetVisions SPoT\" \"Il ne s'agit pas d'un outil de qualit\u00e9 des donn\u00e9es pour le nettoyage des donn\u00e9es \u00e0 court terme, mais d'une solution MDM multi-domaines durablement efficace, avec laquelle <span id=\"urn:local-text-annotation-cnpht9emxpyx25owbk7e3878alhsnb9s\" class=\"textannotation disambiguated wl-thing\">Entreprise<\/span> un \"Golden Record\" pour, par exemple <span id=\"urn:local-text-annotation-vu46hrlv5sxzump4wt4akaist07fy1jo\" class=\"textannotation disambiguated wl-thing\">Clients<\/span>Les participants doivent \u00eatre capables d'identifier les interactions entre ces domaines. Vous obtiendrez une vue d'ensemble de la <span id=\"urn:local-text-annotation-18o4nu2en8sa433aomvztzhkq2efrs9e\" class=\"textannotation disambiguated wl-thing\">Donn\u00e9es de base<\/span> \u00e0 travers tous les domaines\".<\/p>\n<p>On observe actuellement une interaction passionnante entre le Big Data et l'Algorithmic Business. L'un ne peut sans doute pas exister sans l'autre - dans les deux cas, c'est toujours la qualit\u00e9 qui compte.<\/p>\n<p>D\u00e9j\u00e0 ex-<span id=\"urn:local-text-annotation-7t6xmhlgkfh858pjrmx4nj230ptr064x\" class=\"textannotation disambiguated wl-organization\">SAP<\/span>-Vishal Sikka, directeur technique de l'entreprise, a reconnu qu'une base de donn\u00e9es rapide ne suffisait pas pour le Big Data, il faut aussi des math\u00e9matiques et de l'informatique. <span id=\"urn:local-text-annotation-ez84z25g8wv6i8jbv38wh5n2gp0by2zh\" class=\"textannotation disambiguated wl-thing\">Algorithmes<\/span>. <span id=\"urn:local-text-annotation-p8d3j33k0mnb80s9lrnwfvd8fqp42gz6\" class=\"textannotation disambiguated wl-organization\">SAP<\/span> pense que <span id=\"urn:local-text-annotation-ljnc5fpocfnm4ppomcnpvu0rvn81crso\" class=\"textannotation disambiguated wl-thing\">Master<\/span> Data l'\"ADN\" d'un <span id=\"urn:local-text-annotation-qognambkklryu4s0kjw4pryl7cpmocpe\" class=\"textannotation disambiguated wl-thing\">Entreprise<\/span> c'est. Est-ce vrai ?<\/p>\n<p>&nbsp;<\/p>\n<p>\"Je suis d'accord : <span id=\"urn:local-text-annotation-86qbl5d93z51ri1ywun4lvlvcwr8a5pu\" class=\"textannotation disambiguated wl-thing\">Donn\u00e9es de base<\/span> forment la moelle \u00e9pini\u00e8re des <span id=\"urn:local-text-annotation-augnsqszy4nrkgnwvmek3npqe2vht0c8\" class=\"textannotation disambiguated wl-thing\">Processus d'affaires<\/span>\" \" C'est sur leur base que les d\u00e9cisions sont prises, qu'elles r\u00e8glent le <span id=\"urn:local-text-annotation-y1wf0kq85hideooq01f454lx8pr1tjry\" class=\"textannotation disambiguated wl-thing\">Processus d'affaires<\/span>. <span id=\"urn:local-text-annotation-uc7v9d4jit8sqggh6qo2f874ij6wml74\" class=\"textannotation disambiguated wl-thing\">Donn\u00e9es de base<\/span> sont une composante transversale importante, impliqu\u00e9e dans les processus op\u00e9rationnels et les d\u00e9cisions de l'entreprise, tout comme dans l'\u00e9valuation et l'analyse des donn\u00e9es ou des produits et services\".<\/p>\n<p>Disruptif num\u00e9rique <span id=\"urn:local-text-annotation-cwip5jwk98cc94rixnwctwrzl3xj5g1p\" class=\"textannotation disambiguated wl-thing\">Technologies<\/span> comme <span id=\"urn:local-text-annotation-uzpk5gqhvf9i35j2p088y92kb1g4gq6t\" class=\"textannotation disambiguated wl-thing\">Algorithmes<\/span>L'intelligence artificielle, les bots et les chatbots transforment d\u00e9j\u00e0 le monde des affaires.<\/p>\n<p>Le site <span id=\"urn:local-text-annotation-vzzrmffhfpsxbxlk7c3run539969glft\" class=\"textannotation disambiguated wl-thing\">IT<\/span>-Le cabinet de recherche et de conseil Gartner estime que le \"business algorithmique\" va g\u00e9n\u00e9rer un nombre encore plus important de d\u00e9veloppements disruptifs et cr\u00e9er ainsi de nouvelles industries.<\/p>\n<p>Pour utiliser les nouvelles technologies num\u00e9riques et <span id=\"urn:local-text-annotation-9inyaq6ki3ancqrl1l0ufgc0jljcy7ly\" class=\"textannotation disambiguated wl-thing\">Algorithmes<\/span> Les DSI doivent d\u00e9velopper et d\u00e9ployer une plateforme technologique pour le commerce num\u00e9rique.<\/p>\n<p>\"<span id=\"urn:local-text-annotation-x6ixscmtnn97sv7270rm89qnd2xjz5sa\" class=\"textannotation disambiguated wl-thing\">Donn\u00e9es<\/span>L'algorithmique, l'analyse et l'intelligence artificielle sont les moteurs de la croissance et de l'expansion de l'activit\u00e9 algorithmique. <span id=\"urn:local-text-annotation-y1bph35i07h6r1ufuazn06ulqjtct52b\" class=\"textannotation disambiguated wl-thing\">Entreprise<\/span> Cette croissance se poursuit sans rel\u00e2che, car l'\u00e9conomie mondiale est en train de changer. <span id=\"urn:local-text-annotation-tyg739v3cz8uu3b93qzzbejxw16f3e3g\" class=\"textannotation disambiguated wl-thing\">Algorithmes<\/span> s'enrichir de la quantit\u00e9 inexorablement croissante de donn\u00e9es\".<\/p>\n<p>Plus de 500.000 nouveaux appareils se connectent \u00e0 Internet chaque heure et chacun d'entre eux contribue \u00e0 l'in\u00e9vitable croissance des donn\u00e9es.<\/p>\n<p>\"Processus commerciaux cl\u00e9s et <span id=\"urn:local-text-annotation-owjuf7evjgsox9ce38fb1fhrlang5hfu\" class=\"textannotation disambiguated wl-thing\">Donn\u00e9es de base<\/span> Ils sont \u00e9troitement imbriqu\u00e9s les uns dans les autres\"\"S'ils sont coordonn\u00e9s de mani\u00e8re optimale, ils n'entra\u00eenent pas de co\u00fbts suppl\u00e9mentaires dans l'ensemble du syst\u00e8me. <span id=\"urn:local-text-annotation-7mpa7a1j7a38r9xd9ooz8rcap9eghhid\" class=\"textannotation disambiguated wl-thing\">Entreprise<\/span>. Au c\u0153ur de chaque <span id=\"urn:local-text-annotation-mzlfh26ig93dsa7p05a27rhbpd9p6enq\" class=\"textannotation disambiguated wl-thing\">Entreprise<\/span> et en tant que base des d\u00e9cisions de l'entreprise, des informations fiables ont un effet positif sur l'image de l'entreprise. <span id=\"urn:local-text-annotation-5ehbnrccpzncfc4u9ry7c9uendpit9dm\" class=\"textannotation disambiguated wl-thing\">Donn\u00e9es de base<\/span> ont un impact positif sur l'efficacit\u00e9 des processus et permettent de r\u00e9duire les co\u00fbts\".<\/p>\n<p>L'institut d'\u00e9tudes de march\u00e9 L\u00fcnendonk a interrog\u00e9 103 conseillers en management, dont pr\u00e8s des trois quarts ont d\u00e9clar\u00e9 avoir des comp\u00e9tences analytiques. <span id=\"urn:local-text-annotation-9wisrvfm8f5shk011bxluqtjus29upsh\" class=\"textannotation disambiguated wl-thing\">Logiciel<\/span> d'utiliser des outils informatiques. Il s'agit encore souvent d'outils classiques comme Excel ou d'outils standard de Microsoft ou SAP, ainsi que de d\u00e9veloppements personnels.<\/p>\n<p>Agile et interactif <span id=\"urn:local-text-annotation-qksh2b1gz4j0mvs7h4tu4btpihk8mzz3\" class=\"textannotation disambiguated wl-thing\">Logiciel<\/span>-outils, qui sont g\u00e9n\u00e9ralement plus profonds <span id=\"urn:local-text-annotation-nylhlxki3tyvef94sivbz9usl7komkn0\" class=\"textannotation disambiguated wl-thing\">Analyse<\/span> Les outils d'aide \u00e0 la d\u00e9cision, qui permettent d'utiliser les technologies de l'information et de la communication, ne sont utilis\u00e9s que par moins de la moiti\u00e9 des conseillers interrog\u00e9s.<\/p>\n<p>Il reste encore beaucoup \u00e0 faire dans ce domaine, car 77 % des consultants estiment, enti\u00e8rement ou en grande partie, qu'il est possible d'utiliser des logiciels d'analyse et des <span id=\"urn:local-text-annotation-065170wy0znus2ifoqrfo7lqn40114a4\" class=\"textannotation disambiguated wl-thing\">Algorithmes<\/span> de mieux identifier les liens de cause \u00e0 effet et donc de mieux mettre en \u0153uvre les projets de conseil.<\/p>\n<h2>Analyse pr\u00e9dictive<\/h2>\n<p>\"Si l'on veut que l'analyse pr\u00e9dictive fournisse des r\u00e9sultats valables, il faut une grande <span id=\"urn:local-text-annotation-uoz5l0mjy7a9gbb7ie8u7bbp9rv3e1lm\" class=\"textannotation disambiguated wl-thing\">Qualit\u00e9 des donn\u00e9es<\/span> condition obligatoire\"<\/p>\n<p>Voici un exemple de GE, d\u00e9crit par Sokwoo Rhee, directeur du programme Cyber-Physical Systems au National Institute of Standards and Technology aux \u00c9tats-Unis.<\/p>\n<p>GE vendait autrefois des moteurs d'avion \u00e0 un prix unique. Aujourd'hui, ils fournissent les moteurs gratuitement dans le cadre d'un mod\u00e8le de souscription et facturent des frais d'utilisation mensuels ou annuels, assortis d'une garantie.<\/p>\n<p><span id=\"urn:local-text-annotation-m7wotu38bmnnpjbxzwz1nn4qcbair3hu\" class=\"textannotation disambiguated wl-thing\">Clients<\/span> n'ont pas \u00e0 s'inqui\u00e9ter des r\u00e9parations ou autres. Vous pouvez \u00eatre s\u00fbr que les moteurs d\u00e9marreront et fonctionneront d\u00e8s que vous actionnerez l'interrupteur.<\/p>\n<p>Pour que ce mod\u00e8le fonctionne, GE doit savoir exactement quand les moteurs risquent de tomber en panne. S'ils sont remplac\u00e9s trop t\u00f4t, la soci\u00e9t\u00e9 perd de l'argent. <span id=\"urn:local-text-annotation-fl14w9e7vsl4nzr2lkgwqmu7n440j0i3\" class=\"textannotation disambiguated wl-thing\">Entreprise<\/span> De l'argent, car les moteurs auraient pu g\u00e9n\u00e9rer d'autres revenus.<\/p>\n<p>En revanche, s'ils attendent trop longtemps, les cons\u00e9quences peuvent \u00eatre d\u00e9sastreuses.<\/p>\n<p>Pour savoir exactement quand les moteurs risquent de tomber en panne, GE collecte les <span id=\"urn:local-text-annotation-9u8517nxxw27vbc0gnv0kj7sqj11jw6f\" class=\"textannotation disambiguated wl-thing\">Donn\u00e9es<\/span> de plusieurs centaines de capteurs et les exploite \u00e0 l'aide de Big Data Analytics.<\/p>\n<p>\"<span id=\"urn:local-text-annotation-noxpj56dcvmz921tthbrju6u4nshgj98\" class=\"textannotation disambiguated wl-thing\">Donn\u00e9es de base<\/span> sont un facteur de succ\u00e8s critique pour pouvoir obtenir ces connaissances analytiques et pr\u00e9visionnelles\" \"Bien s\u00fbr, le th\u00e8me devrait \u00eatre <span id=\"urn:local-text-annotation-yg2hmogl9j439q75t89nqzi1h4x46vd8\" class=\"textannotation disambiguated wl-thing\">Qualit\u00e9 des donn\u00e9es<\/span> tous dans le <span id=\"urn:local-text-annotation-9bowgdg9mvgbqcc7xncerbs1mg8jif03\" class=\"textannotation disambiguated wl-thing\">Entreprise<\/span> existant <span id=\"urn:local-text-annotation-sxm6w7zv7s80apfaoxo8n8uhzfhvd4rl\" class=\"textannotation disambiguated wl-thing\">Donn\u00e9es<\/span> comprennent\"<\/p>\n<p>De plus, il n'y a pas que le <span id=\"urn:local-text-annotation-z0tp3wmc43as8vyv1l4rwyfzhm3lrsal\" class=\"textannotation disambiguated wl-thing\">ERP<\/span> <span id=\"urn:local-text-annotation-fr6gte2l34bwc78vnykql87ijxz5bmbk\" class=\"textannotation disambiguated wl-thing\">Donn\u00e9es de base<\/span>mais aussi, par exemple, la cha\u00eene d'approvisionnement <span id=\"urn:local-text-annotation-89fyqezvar3invn8joyj69jjdyqaofxg\" class=\"textannotation disambiguated wl-thing\">Gestion<\/span>la gestion de la relation client, le marketing, les ventes, les RH, la comptabilit\u00e9 et le contr\u00f4le de gestion. Dans cette mesure, le th\u00e8me <span id=\"urn:local-text-annotation-fkg3yz4hcy7o19wpvfodtehm0niezbut\" class=\"textannotation disambiguated wl-thing\">Donn\u00e9es de base<\/span> le site <span id=\"urn:local-text-annotation-6f7n0lmfya2flztz1wihl0why8vpy644\" class=\"textannotation disambiguated wl-thing\">ERP<\/span>-L'analyse pr\u00e9dictive n'en est qu'une partie, m\u00eame si elle prend de plus en plus d'importance.<\/p>\n<p>\"Des solutions individuelles pour les diff\u00e9rents domaines de donn\u00e9es de base ne sont pas judicieuses, car il y a finalement \u00e0 nouveau divers silos de donn\u00e9es\" \"Dans un projet de donn\u00e9es de base, il est tout \u00e0 fait judicieux de commencer par un seul domaine - par exemple les donn\u00e9es de base des clients\".<\/p>\n<p><span id=\"urn:local-text-annotation-5iyk9dpslyb8a8tnpkrezxi3nbenjsxi\" class=\"textannotation disambiguated wl-thing\">Entreprise<\/span> devraient toutefois veiller \u00e0 mettre en \u0153uvre d\u00e8s le d\u00e9part une solution multi-domaines permettant de couvrir tous les domaines de donn\u00e9es de base pertinents. Une telle solution offre la possibilit\u00e9 de g\u00e9rer successivement l'ensemble du <span id=\"urn:local-text-annotation-qe1ypreyynacmoora53i27ns2c8okgxi\" class=\"textannotation disambiguated wl-thing\">Master<\/span> centraliser la gestion des donn\u00e9es en un seul endroit<\/p>\n<p>Et Monika P\u00fcrsing explique qu'il est possible d'associer ZetVisions SPoT \u00e0 du contenu pour <span id=\"urn:local-text-annotation-y825168c8qrbpdqm4uqrd3mkr9lbb5nr\" class=\"textannotation disambiguated wl-thing\">Clients<\/span>- et les donn\u00e9es de base fournisseurs, les donn\u00e9es de base produits et les donn\u00e9es de base financi\u00e8res. En outre, il est possible de <span id=\"urn:local-text-annotation-1qq5waodm8414uxnr6n8fbh06xso4cvt\" class=\"textannotation disambiguated wl-thing\">Entreprise<\/span> <span id=\"urn:local-text-annotation-a0ifxnjfqo6kimy8susmmj3ckp6u478u\" class=\"textannotation disambiguated wl-thing\">Donn\u00e9es de base<\/span> qui ne peuvent pas \u00eatre attribu\u00e9es \u00e0 un autre domaine de donn\u00e9es de base.<\/p>\n<p>Il peut s'agir par exemple de structures organisationnelles ou de donn\u00e9es de r\u00e9f\u00e9rence telles que les hi\u00e9rarchies de r\u00e9gions ou de pays.<\/p>\n<p>ZetVisions SPoT est un produit unique qui offre les m\u00eames fonctionnalit\u00e9s (cadre de validation, requ\u00eates, tableau de bord de qualit\u00e9 des donn\u00e9es, transfert de donn\u00e9es, rapports ad hoc, hi\u00e9rarchies) pour tous les domaines.<\/p>\n<p>Il n'y a pas de feuilles de route diff\u00e9rentes ; les am\u00e9liorations fonctionnelles sont disponibles pour tous les domaines, par exemple la gestion des donn\u00e9es de masse ou la cr\u00e9ation \u00e0 partir de mod\u00e8les.<\/p>\n<h2><span id=\"urn:local-text-annotation-b2x673eoh8nvc5vr9dxpsgvvkpeecvv0\" class=\"textannotation disambiguated wl-thing\">Qualit\u00e9 des donn\u00e9es<\/span> ou MDM<\/h2>\n<p>\"<span id=\"urn:local-text-annotation-puh11mqncph8y4312zw9vzil4yaxivfg\" class=\"textannotation disambiguated wl-thing\">Qualit\u00e9 des donn\u00e9es<\/span> et MDM ne sont pas la m\u00eame chose\".<\/p>\n<p>La gestion des donn\u00e9es de base est l'assemblage de toutes les donn\u00e9es <span id=\"urn:local-text-annotation-dgiarwtm60ld84pw9fxg0rqokqdgaju8\" class=\"textannotation disambiguated wl-thing\">Entreprise<\/span> Les informations et les donn\u00e9es qui s'y trouvent forment un tout coh\u00e9rent, le \"Golden Record\", qui peut \u00eatre utilis\u00e9 par exemple pour la recherche d'un emploi. <span id=\"urn:local-text-annotation-8dlfissaikf4eb6o63n80dk9s7gnq6kw\" class=\"textannotation disambiguated wl-thing\">Clients<\/span>, produits, fournisseurs.<\/p>\n<p>Ce n'est qu'ainsi qu'il est possible d'identifier les interactions entre ces domaines et d'obtenir une vue panoramique de la <span id=\"urn:local-text-annotation-9mvfdllo0wle6ut2zti1njg0jl44ehy7\" class=\"textannotation disambiguated wl-thing\">Donn\u00e9es de base<\/span> \u00e0 travers tous les domaines. Un <span id=\"urn:local-text-annotation-onhqw4yeiibx9l6jx5sk4sbmmcno82jx\" class=\"textannotation disambiguated wl-thing\">Master<\/span> La gestion des donn\u00e9es cr\u00e9e ainsi une \"v\u00e9rit\u00e9 unique\" pour diff\u00e9rents domaines de donn\u00e9es de base sur l'ensemble de l'entreprise. <span id=\"urn:local-text-annotation-8zqqink0va3ojtrnh9chdp3oy894yd52\" class=\"textannotation disambiguated wl-thing\">Processus d'affaires<\/span>.<\/p>\n<p>Un effet secondaire en est une coh\u00e9rence am\u00e9lior\u00e9e et durable des donn\u00e9es et <span id=\"urn:local-text-annotation-hekhcypm0cnpoz5sl9fa5sqap4bwf0gq\" class=\"textannotation disambiguated wl-thing\">Qualit\u00e9 des donn\u00e9es<\/span> sur l'ensemble <span id=\"urn:local-text-annotation-ewdzm6iueejeocvtmrj5naha07afolbb\" class=\"textannotation disambiguated wl-thing\">Processus d'affaires<\/span> de l'entreprise. Mais surtout, l'efficacit\u00e9 et la performance des processus sont am\u00e9lior\u00e9es gr\u00e2ce \u00e0 la collaboration intersectorielle.<\/p>\n<p><span id=\"urn:local-text-annotation-chxk9qk355o8gbb1xcr9ia36i8l2lbq7\" class=\"textannotation disambiguated wl-thing\">Qualit\u00e9 des donn\u00e9es<\/span> indique en revanche quelque chose sur la correction, la coh\u00e9rence, la fiabilit\u00e9, l'exhaustivit\u00e9, l'exactitude et l'actualit\u00e9 de <span id=\"urn:local-text-annotation-q1l9rkujcu91s1oshk67afvq1qmov7vg\" class=\"textannotation disambiguated wl-thing\">Donn\u00e9es<\/span> - pas seulement de <span id=\"urn:local-text-annotation-920vu2dx6kdkr786xtbpby6y7zhvupsd\" class=\"textannotation disambiguated wl-thing\">Donn\u00e9es de base<\/span>. <span id=\"urn:local-text-annotation-sxg3kyt2le0xccwxp4uhtst2rnr1szct\" class=\"textannotation disambiguated wl-thing\">Qualit\u00e9 des donn\u00e9es<\/span> est donc un aspect de la gestion des donn\u00e9es de base.<\/p>\n<p>\"MDM n'est pas un sujet uniquement <span id=\"urn:local-text-annotation-56q00cpx95de79d4sqk00gvqwj9goimd\" class=\"textannotation disambiguated wl-thing\">IT<\/span>. Il peut \u00eatre utilis\u00e9 par <span id=\"urn:local-text-annotation-fr9i145wl2c73fdhsjffs44c6i7v3wng\" class=\"textannotation disambiguated wl-thing\">IT<\/span> mais doit \u00eatre port\u00e9e par les domaines sp\u00e9cialis\u00e9s concern\u00e9s. La responsabilit\u00e9 des donn\u00e9es devrait \u00e9galement incomber aux domaines sp\u00e9cialis\u00e9s\".<\/p>\n<p>Il n'est jamais trop tard pour <span id=\"urn:local-text-annotation-06kvei0py4mr9jyag31am6cxnsasdov8\" class=\"textannotation disambiguated wl-thing\">Qualit\u00e9 des donn\u00e9es<\/span> Monika P\u00fcrsing est fermement convaincue qu'il est important de s'occuper des enfants :<\/p>\n<p>\"Si de mauvaises <span id=\"urn:local-text-annotation-hwqmbutddgtzojvrrpl8jf0zssg0x6vf\" class=\"textannotation disambiguated wl-thing\">Qualit\u00e9 des donn\u00e9es<\/span> conduit \u00e0 ce qu'un <span id=\"urn:local-text-annotation-ft5pbjwzl8ht01skeun6mks23vahdqln\" class=\"textannotation disambiguated wl-thing\">Entreprise<\/span> perd des affaires ou de l'argent, il est toutefois grand temps de se pencher sur la question. Pas dans un avenir lointain, mais tout de suite\".<\/p>\n<p>C'est ce que l'on appelle le Compelling Event, qui apporte une r\u00e9ponse claire \u00e0 la question \"Pourquoi maintenant\". Des d\u00e9veloppements tels que l'Internet des objets, l'industrie 4.0, etc. poussent le sujet <span id=\"urn:local-text-annotation-7zw4vlcxyrmdgs9gymz216m98js0bpfa\" class=\"textannotation disambiguated wl-thing\">Qualit\u00e9 des donn\u00e9es<\/span> continue.<\/p>\n<p>Il n'y a pas de place pour les atermoiements et les reports. Une autre chose est importante pour le CEO P\u00fcrsing :<\/p>\n<p>\"Que <span id=\"urn:local-text-annotation-0plgvmz1quyggol9zxf9t4b9hwct9e8e\" class=\"textannotation disambiguated wl-thing\">Donn\u00e9es<\/span> sont le nouveau p\u00e9trole, on philosophe volontiers \u00e0 ce sujet depuis une dizaine d'ann\u00e9es, depuis que ce dicton est apparu pour la premi\u00e8re fois. En fin de compte, il n'est pas d\u00e9cisif de savoir si le p\u00e9trole et les donn\u00e9es diff\u00e8rent plus qu'ils n'ont en commun. Ce qui compte, c'est de garder \u00e0 l'esprit que <span id=\"urn:local-text-annotation-a9m05u58zgi9prr7s8jkyi542lwl5xbu\" class=\"textannotation disambiguated wl-thing\">Donn\u00e9es<\/span> sont un lubrifiant pr\u00e9cieux pour les entreprises et l'\u00e9conomie dans l'\u00e9conomie num\u00e9rique. <span id=\"urn:local-text-annotation-l1rijiwn70ro8cuelw8tmck3xjwqp43y\" class=\"textannotation disambiguated wl-thing\">Donn\u00e9es<\/span> sont la mati\u00e8re premi\u00e8re centrale du changement num\u00e9rique. Cette constatation devrait \u00e0 elle seule suffire pour que l'on s'occupe de <span id=\"urn:local-text-annotation-lrssfn9n3rii8p69fkzva8dnbzszvs2u\" class=\"textannotation disambiguated wl-thing\">Qualit\u00e9 des donn\u00e9es<\/span> ne pas remettre \u00e0 plus tard\".<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/Screenshot-2016-11-23-um-09.40.52.png\"><img loading=\"lazy\" decoding=\"async\" title=\"Gardien du golden record\" class=\"alignleft wp-image-1863 size-full\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/Screenshot-2016-11-23-um-09.40.52.png\" alt=\"ZetVision, data governance, Big Data, Il doit y avoir un point central pour la gestion, la qualit\u00e9 et la gouvernance du patrimoine de donn\u00e9es de chaque entreprise : SPoT.\" width=\"1402\" height=\"843\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/Screenshot-2016-11-23-um-09.40.52.png 1402w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/Screenshot-2016-11-23-um-09.40.52-1200x722.png 1200w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/Screenshot-2016-11-23-um-09.40.52-768x462.png 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/Screenshot-2016-11-23-um-09.40.52-100x60.png 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/Screenshot-2016-11-23-um-09.40.52-480x289.png 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/Screenshot-2016-11-23-um-09.40.52-640x385.png 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/Screenshot-2016-11-23-um-09.40.52-720x433.png 720w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/Screenshot-2016-11-23-um-09.40.52-960x577.png 960w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/Screenshot-2016-11-23-um-09.40.52-1168x702.png 1168w\" sizes=\"auto, (max-width: 1402px) 100vw, 1402px\" \/><\/a><\/p>\n<p>De plus, il faut d\u00e9finir les responsabilit\u00e9s, les r\u00f4les tels que <span id=\"urn:local-text-annotation-gva6su1uprtxw4k2880oye3dez9q6s8k\" class=\"textannotation disambiguated wl-thing\">Master<\/span> Data Expert et Data Steward - La gestion des donn\u00e9es de base va au-del\u00e0 de la simple gestion et distribution des donn\u00e9es.<\/p>\n<p>\"De notre point de vue, MDM et MDG vont de pair. La gouvernance des donn\u00e9es est essentielle pour une gestion efficace des donn\u00e9es de r\u00e9f\u00e9rence\".<\/p>\n<p>explique P\u00fcrsing.<\/p>\n<p>Une solution logicielle professionnelle fournit ensuite le soutien technique. Le MDM seul - sans gouvernance des donn\u00e9es - pourrait n'\u00eatre qu'un HUB ou la consolidation des donn\u00e9es. <span id=\"urn:local-text-annotation-ge9uzy6j15pjdj4hw698vxmtml7pex8t\" class=\"textannotation disambiguated wl-thing\">Donn\u00e9es de base<\/span> \u00eatre - sans la d\u00e9finition de r\u00e8gles de gestion des <span id=\"urn:local-text-annotation-a82z95i5blp1n0x4f1r8d1u2rnihu9o0\" class=\"textannotation disambiguated wl-thing\">Donn\u00e9es<\/span> et l'adaptation de l'organisation, des structures et des processus.<\/p>\n<p>\"<span id=\"urn:local-text-annotation-gnhre47337m79xwvm3uynyswmyew90p0\" class=\"textannotation disambiguated wl-thing\">Donn\u00e9es de base<\/span>-La gouvernance est avant tout une question d'organisation, <span id=\"urn:local-text-annotation-1pzipsuk5ws1wruarpjwzqlcj7if9x56\" class=\"textannotation disambiguated wl-thing\">Technologie<\/span> n'est qu'un soutien\",<\/p>\n<p>sait le CEO P\u00fcrsing.<\/p>\n<p>Et du point de vue de la gestion d'entreprise, le sujet est pertinent dans la mesure o\u00f9 <span id=\"urn:local-text-annotation-dx2hsq5bwdbxeylpfnxijdxgmjfnf0yv\" class=\"textannotation disambiguated wl-thing\">Entreprise<\/span> sans directives internes sur le traitement des <span id=\"urn:local-text-annotation-z5q4xeimwr18uobyn8t3z808628w6bro\" class=\"textannotation disambiguated wl-thing\">Donn\u00e9es<\/span>Les entreprises qui ne disposent pas de processus et de responsabilit\u00e9s uniformes pour la saisie, la validation et la mise \u00e0 jour des donn\u00e9es risquent de se heurter \u00e0 long terme \u00e0 un probl\u00e8me de qualit\u00e9 des donn\u00e9es. <span id=\"urn:local-text-annotation-12pbicm8ieb1zmdf2g0lb77hcxmcg4yz\" class=\"textannotation disambiguated wl-thing\">Qualit\u00e9 des donn\u00e9es<\/span> ont.<\/p>\n<p>\"Et de mauvaises <span id=\"urn:local-text-annotation-1d40ag8hnp3j8geyxlns1a6nisl2y7gp\" class=\"textannotation disambiguated wl-thing\">Qualit\u00e9 des donn\u00e9es<\/span> co\u00fbte de l'argent\"<\/p>\n<p>sait la PDG de ZetVisions.<\/p>\n<p>La gouvernance des donn\u00e9es cr\u00e9e le cadre d'ordre et de contr\u00f4le n\u00e9cessaire comme base organisationnelle pour assurer une gestion des donn\u00e9es de base au sein de l'entreprise. <span id=\"urn:local-text-annotation-7b6vu6oo78t1iady4l8n957sav7cp9np\" class=\"textannotation disambiguated wl-thing\">Entreprise<\/span> de l'introduire.<\/p>\n<p>Les r\u00f4les, les responsabilit\u00e9s et les processus pertinents doivent \u00eatre d\u00e9finis \u00e0 cet \u00e9gard. Par exemple, il convient de d\u00e9finir, dans les politiques correspondantes, qui est responsable de certains aspects de la s\u00e9curit\u00e9. <span id=\"urn:local-text-annotation-4uo43nbvjqehzk8a6uk24vgb4ypbxc82\" class=\"textannotation disambiguated wl-thing\">Donn\u00e9es<\/span> et le respect des normes de qualit\u00e9 ; quels sont les r\u00f4les des collaborateurs qui travaillent avec des <span id=\"urn:local-text-annotation-kp6wx6t6nhyzipj0nkmwmdyk2jjw6gdj\" class=\"textannotation disambiguated wl-thing\">Donn\u00e9es<\/span> et comment ils utilisent les <span id=\"urn:local-text-annotation-wdqxrjpcoskgo468k909v3jmxq2i9fzl\" class=\"textannotation disambiguated wl-thing\">Donn\u00e9es<\/span> les normes auxquelles ils doivent se conformer <span id=\"urn:local-text-annotation-rn6w9eobebk3otv4vtb9utie3wrmtxxw\" class=\"textannotation disambiguated wl-thing\">Donn\u00e9es<\/span> (il conviendrait de d\u00e9finir ici les exigences minimales en mati\u00e8re de <span id=\"urn:local-text-annotation-rlz8it6w59ytjn482f76e5jv0w7nktpb\" class=\"textannotation disambiguated wl-thing\">Donn\u00e9es<\/span> ) ; et enfin, les r\u00e8gles de s\u00e9curit\u00e9 \u00e0 respecter.<\/p>\n<p>Pour mettre en \u0153uvre la gouvernance des donn\u00e9es de mani\u00e8re efficace, un bureau de gouvernance des donn\u00e9es peut servir de structure institutionnalis\u00e9e. <span id=\"urn:local-text-annotation-21vuw3ktr6xj5lpyua7jyuun7pfmst10\" class=\"textannotation disambiguated wl-thing\">Donn\u00e9es<\/span>-Il s'agit de mettre en place une autorit\u00e9 qui autorise l'utilisation de l'Internet. <span id=\"urn:local-text-annotation-vf0dq2o7wvgkuxjqucv3zwhh870y595y\" class=\"textannotation disambiguated wl-thing\">Donn\u00e9es<\/span> au sein du <span id=\"urn:local-text-annotation-qghefw7qy8kqhaepqzgowv61ae42sbko\" class=\"textannotation disambiguated wl-thing\">Entreprise<\/span> de l'entreprise.<\/p>\n<p>L'office se compose de repr\u00e9sentants des secteurs d'activit\u00e9 concern\u00e9s ; il est possible d'opter pour une sp\u00e9cialisation (fonctions de vente centrales\/d\u00e9centralis\u00e9es, Finance, HR, <span id=\"urn:local-text-annotation-gor3tmrjrz5zjcnxglv6jr79oyw3wfxp\" class=\"textannotation disambiguated wl-thing\">IT<\/span>) ou g\u00e9ographique (toutes les fonctions d'une repr\u00e9sentation nationale).<\/p>\n<p>Et pour finir, quels sont, du point de vue de ZetVisions, les plus grands d\u00e9fis \u00e0 relever dans la qu\u00eate d'un haut niveau de <span id=\"urn:local-text-annotation-jh2ibcwx5cfq62hz06866b9jn3a84hub\" class=\"textannotation disambiguated wl-thing\">Donn\u00e9es<\/span>qualit\u00e9 ?<\/p>\n<p>\"Il faut avoir la volont\u00e9 de changer, \u00eatre pr\u00eat \u00e0 remettre en question les acquis. Celui qui <span id=\"urn:local-text-annotation-2dm1owt6fo4ieeli9y6sdp1pa82cmhtf\" class=\"textannotation disambiguated wl-thing\">Gestion<\/span> de <span id=\"urn:local-text-annotation-wh7ftlr4pipu6frqp8ycgotoaolpzexb\" class=\"textannotation disambiguated wl-thing\">Donn\u00e9es de base<\/span> Si l'on veut aborder le sujet de mani\u00e8re professionnelle, on ne pourra pas \u00e9viter de briser d'anciens processus et d'empi\u00e9ter sur les \"territoires\" existants. Il y a des \"sensibilit\u00e9s\" qui doivent \u00eatre abord\u00e9es. Il faut d\u00e9finir de nouveaux processus uniformes et d\u00e9signer des responsables des donn\u00e9es\".<\/p>","protected":false},"excerpt":{"rendered":"<p>ZetVisions, partenaire SAP, a publi\u00e9 une analogie tr\u00e8s int\u00e9ressante : Le tr\u00e9sor de donn\u00e9es d'une entreprise ne doit pas seulement \u00eatre relev\u00e9, mais aussi entretenu et surveill\u00e9 - tout comme un troupeau est non seulement prot\u00e9g\u00e9 par un chien de garde, mais aussi dirig\u00e9 et organis\u00e9. Les \"moutons noirs\" n'ont alors aucune chance s'il y a un gardien. Le r\u00e9dacteur en chef d'E-3 Peter F\u00e4rbinger s'est entretenu avec Monika P\u00fcrsing, CEO de ZetVisions, sur la qualit\u00e9 des donn\u00e9es et la gestion des donn\u00e9es de base en g\u00e9n\u00e9ral et sur le Golden Record en particulier.<\/p>","protected":false},"author":2,"featured_media":1968,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[741,740],"tags":[259,210,606,73,367,143,236,400,610,608],"coauthors":[27825],"class_list":["post-1838","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coverstory1612","category-mag1612","tag-analyse","tag-big-data","tag-daten","tag-erp","tag-industrie-4-0","tag-management","tag-sap","tag-software","tag-stammdaten","tag-unternehmen","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/ShutterstockTitelbild.jpg",1000,667,false],"thumbnail":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/ShutterstockTitelbild-150x150.jpg",150,150,true],"medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/ShutterstockTitelbild.jpg",400,267,false],"medium_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/ShutterstockTitelbild-768x512.jpg",768,512,true],"large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/ShutterstockTitelbild.jpg",1000,667,false],"image-100":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/ShutterstockTitelbild-100x67.jpg",100,67,true],"image-480":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/ShutterstockTitelbild-480x320.jpg",480,320,true],"image-640":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/ShutterstockTitelbild-640x427.jpg",640,427,true],"image-720":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/ShutterstockTitelbild-720x480.jpg",720,480,true],"image-960":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/ShutterstockTitelbild-960x640.jpg",960,640,true],"image-1168":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/ShutterstockTitelbild.jpg",1000,667,false],"image-1440":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/ShutterstockTitelbild.jpg",1000,667,false],"image-1920":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/ShutterstockTitelbild.jpg",1000,667,false],"1536x1536":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/ShutterstockTitelbild.jpg",1000,667,false],"2048x2048":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/ShutterstockTitelbild.jpg",1000,667,false],"trp-custom-language-flag":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/ShutterstockTitelbild.jpg",18,12,false],"bricks_large_16x9":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/ShutterstockTitelbild.jpg",1000,667,false],"bricks_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/ShutterstockTitelbild.jpg",1000,667,false],"bricks_large_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/ShutterstockTitelbild.jpg",1000,667,false],"bricks_medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/ShutterstockTitelbild.jpg",600,400,false],"bricks_medium_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/ShutterstockTitelbild.jpg",600,400,false],"profile_24":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/ShutterstockTitelbild-24x24.jpg",24,24,true],"profile_48":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/ShutterstockTitelbild-48x48.jpg",48,48,true],"profile_96":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/ShutterstockTitelbild-96x96.jpg",96,96,true],"profile_150":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/ShutterstockTitelbild-150x150.jpg",150,150,true],"profile_300":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/11\/ShutterstockTitelbild-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>SAP-Partner ZetVisions hat eine sehr interessante Analogie publiziert: Der Datenschatz eines Unternehmens geh\u00f6rt nicht nur gehoben, sondern auch gepflegt und bewacht \u2013 \u00e4hnlich wie eine Herde von einem Wachhund nicht nur besch\u00fctzt, sondern auch geleitet und organisiert wird. \u201eSchwarze Schafe\u201c haben dann keine Chance, wenn es einen H\u00fcter gibt. Mit ZetVisions CEO Monika P\u00fcrsing sprach E-3 Chefredakteur Peter F\u00e4rbinger \u00fcber Datenqualit\u00e4t und Stammdatenmanagement im Allgemeinen und den Golden Record im Speziellen.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e326.greatsolution.dev\/fr\/categorie\/coverstories\/coverstory1612\/\" rel=\"category tag\">Coverstory 16-12<\/a>, <a href=\"https:\/\/e326.greatsolution.dev\/fr\/categorie\/mag1612\/\" rel=\"category tag\">MAG 16-12<\/a>","author_info_v2":{"name":"Peter M. F\u00e4rbinger, E3 Magazine","url":"https:\/\/e326.greatsolution.dev\/fr\/author\/peter-m-faerbinger-e-3-magazin\/"},"comments_num_v2":"0 commentaire","_links":{"self":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/posts\/1838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/comments?post=1838"}],"version-history":[{"count":0,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/posts\/1838\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/media\/1968"}],"wp:attachment":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/media?parent=1838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/categories?post=1838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/tags?post=1838"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/coauthors?post=1838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}