{"id":43011,"date":"2018-06-13T08:00:12","date_gmt":"2018-06-13T06:00:12","guid":{"rendered":"https:\/\/e326.greatsolution.dev\/?p=43011"},"modified":"2022-05-01T10:02:50","modified_gmt":"2022-05-01T08:02:50","slug":"employer-brand-experience-la-marque-employeur-cree-des-experiences","status":"publish","type":"post","link":"https:\/\/e326.greatsolution.dev\/fr\/employer-brand-experience-la-marque-employeur-cree-des-experiences\/","title":{"rendered":"Employer Brand Experience - La marque employeur cr\u00e9e des exp\u00e9riences"},"content":{"rendered":"<p>Trouver le personnel ad\u00e9quat et le garder \u00e0 long terme repr\u00e9sente un d\u00e9fi de plus en plus important pour de nombreuses entreprises. Dans la \"guerre des talents\", les responsables doivent faire preuve d'imagination - il ne suffit pas de r\u00e9diger de jolies offres d'emploi.<\/p>\n<p>Il s'agit plut\u00f4t de construire une marque employeur authentique et de la faire vivre tant en interne qu'en externe. La conf\u00e9rence Employer Brand Experience met l'accent sur les exp\u00e9riences et les enseignements des experts en marque employeur qui travaillent d\u00e9j\u00e0 avec succ\u00e8s \u00e0 la construction d'une marque employeur.<\/p>\n<p>Salvador Viera, par exemple, donne un aper\u00e7u passionnant de la mani\u00e8re dont Volkswagen g\u00e8re le changement de culture d'entreprise avec plus de 600.000 collaborateurs.<\/p>\n<p>Kristian Gr\u00fcndling pr\u00e9sentera une perspective qui d\u00e9passe le cadre de l'entreprise : le r\u00e9alisateur du film prim\u00e9 \"Die stille Revolution\" parlera des changements radicaux et de la recherche de sens dans le monde du travail. Ces cas et plus de 30 autres sessions inspirantes sont au programme de l'Employer Brand Experience qui se tiendra les 15 et 16 mai \u00e0 Hambourg, dans les Schanzenh\u00f6fen (Altes M\u00e4dchen).<\/p>\n<p>La conf\u00e9rence se d\u00e9roule en parall\u00e8le du salon Zukunft Personal Nord - l'\u00e9v\u00e9nement phare de la gestion des ressources humaines dans le nord de l'Allemagne.<\/p>","protected":false},"excerpt":{"rendered":"<p>La conf\u00e9rence Employer Brand Experience, qui se tiendra les 15 et 16 mai \u00e0 Hambourg, montrera comment r\u00e9ussir \u00e0 se positionner comme employeur attractif.  <\/p>","protected":false},"author":38,"featured_media":43062,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[2,22044],"tags":[],"coauthors":[19920],"class_list":["post-43011","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sap-nachrichten","category-mag-1805","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_608860169.jpg",1000,450,false],"thumbnail":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_608860169-150x150.jpg",150,150,true],"medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_608860169.jpg",400,180,false],"medium_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_608860169-768x346.jpg",768,346,true],"large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_608860169.jpg",1000,450,false],"image-100":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_608860169-100x45.jpg",100,45,true],"image-480":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_608860169-480x216.jpg",480,216,true],"image-640":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_608860169-640x288.jpg",640,288,true],"image-720":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_608860169-720x324.jpg",720,324,true],"image-960":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_608860169-960x432.jpg",960,432,true],"image-1168":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_608860169.jpg",1000,450,false],"image-1440":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_608860169.jpg",1000,450,false],"image-1920":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_608860169.jpg",1000,450,false],"1536x1536":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_608860169.jpg",1000,450,false],"2048x2048":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_608860169.jpg",1000,450,false],"trp-custom-language-flag":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_608860169.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_608860169.jpg",1000,450,false],"bricks_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_608860169.jpg",1000,450,false],"bricks_large_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_608860169.jpg",1000,450,false],"bricks_medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_608860169.jpg",600,270,false],"bricks_medium_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_608860169.jpg",600,270,false],"profile_24":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_608860169-24x24.jpg",24,24,true],"profile_48":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_608860169-48x48.jpg",48,48,true],"profile_96":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_608860169-96x96.jpg",96,96,true],"profile_150":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_608860169-150x150.jpg",150,150,true],"profile_300":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_608860169-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Wie die Positionierung als attraktiver Arbeitgeber gelingen kann, zeigt die Konferenz Employer Brand Experience am 15. und 16. Mai in Hamburg.  <\/p>\n","category_list_v2":"<a href=\"https:\/\/e326.greatsolution.dev\/fr\/categorie\/sap-nouvelles\/\" rel=\"category tag\">Community Nachrichten<\/a>, <a href=\"https:\/\/e326.greatsolution.dev\/fr\/categorie\/mag-1805\/\" rel=\"category tag\">MAG 18-05<\/a>","author_info_v2":{"name":"Magazine E-3","url":"https:\/\/e326.greatsolution.dev\/fr\/author\/e-3-magazin\/"},"comments_num_v2":"0 commentaire","_links":{"self":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/posts\/43011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/comments?post=43011"}],"version-history":[{"count":0,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/posts\/43011\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/media\/43062"}],"wp:attachment":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/media?parent=43011"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/categories?post=43011"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/tags?post=43011"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/coauthors?post=43011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}