{"id":43112,"date":"2018-05-30T10:00:02","date_gmt":"2018-05-30T08:00:02","guid":{"rendered":"https:\/\/e326.greatsolution.dev\/?p=43112"},"modified":"2020-02-09T21:19:10","modified_gmt":"2020-02-09T20:19:10","slug":"le-temps-est-venu-pour-lintelligence-artificielle-vous-letes-aussi","status":"publish","type":"post","link":"https:\/\/e326.greatsolution.dev\/fr\/le-temps-est-venu-pour-lintelligence-artificielle-vous-letes-aussi\/","title":{"rendered":"Le temps est venu pour l'intelligence artificielle - l'\u00eates-vous aussi ?"},"content":{"rendered":"<p>L'intelligence artificielle (IA) est pass\u00e9e du statut de simple sujet de recherche \u00e0 celui de technologie d'application et est devenue un \u00e9l\u00e9ment central de l'innovation num\u00e9rique dans chaque secteur.<\/p>\n<p>Les cabinets d'analyse s'accordent sur le grand avenir de cette technologie - m\u00eame si leurs estimations diff\u00e8rent quelque peu en chiffres absolus. Le cabinet d'\u00e9tudes de march\u00e9 Tractica pr\u00e9voit par exemple que le chiffre d'affaires des logiciels d'IA atteindra environ 60 milliards de dollars US d'ici 2025.<\/p>\n<p>Les attentes \u00e9lev\u00e9es \u00e0 l'\u00e9gard de l'IA ne sont pas nouvelles : selon le cabinet d'analyse Gartner, qui mesure les technologies en fonction de leur perception sur le march\u00e9 et du temps n\u00e9cessaire \u00e0 leur perc\u00e9e, l'IA traverse d\u00e9j\u00e0 son troisi\u00e8me cycle dit de \"hype\".<\/p>\n<p>Le coup d'envoi a \u00e9t\u00e9 donn\u00e9 dans les ann\u00e9es 50, lorsque des scientifiques du Dartmouth College ont d\u00e9velopp\u00e9 des programmes de strat\u00e9gies d'\u00e9checs. Les projets de cette phase initiale \u00e9taient toutefois encore loin des cas d'application dans l'\u00e9conomie.<\/p>\n<p>Au d\u00e9but des ann\u00e9es 80, l'IA a donn\u00e9 naissance aux syst\u00e8mes experts (XPS). Ces programmes aidaient \u00e0 r\u00e9soudre des probl\u00e8mes complexes et \u00e9taient par exemple utilis\u00e9s comme Computer Trader dans le secteur financier.<\/p>\n<p>Les deux cycles d'engouement ont \u00e9t\u00e9 suivis de d\u00e9ceptions, car l'IA n'a pas pu r\u00e9pondre aux attentes fix\u00e9es. Les analystes sont convaincus que, pour la premi\u00e8re fois, l'enthousiasme actuel ne sera pas suivi d'un \"hiver de l'IA\" et que la grande perc\u00e9e est imminente.<\/p>\n<p>La raison du regain d'int\u00e9r\u00eat pour l'IA depuis la fin des ann\u00e9es 90 repose sur le succ\u00e8s av\u00e9r\u00e9 des algorithmes et des mod\u00e8les d'apprentissage automatique, qui constituent la base de \"l'intelligence\" dans l'IA.<\/p>\n<p>Ils aident les machines \u00e0 apprendre des t\u00e2ches puis \u00e0 les ex\u00e9cuter de mani\u00e8re autonome - en d'autres termes, ils permettent aux machines de se comporter de mani\u00e8re adaptative ou autonome.<\/p>\n<p>Il est vrai que certaines choses que les humains font naturellement repr\u00e9sentent un grand d\u00e9fi pour les syst\u00e8mes d'IA - par exemple, r\u00e9soudre des probl\u00e8mes en faisant preuve de cr\u00e9ativit\u00e9 et de bon sens. Mais il existe une multitude de processus difficiles \u00e0 apprendre pour les humains, mais relativement faciles \u00e0 ma\u00eetriser par l'IA.<\/p>\n<p>Rien que dans l'industrie, il existe de nombreux domaines d'application et un grand potentiel d'augmentation de la productivit\u00e9. Jusqu'\u00e0 pr\u00e9sent, des robots relativement simples, mais programm\u00e9s avec pr\u00e9cision, g\u00e9raient de mani\u00e8re fiable une grande partie des manipulations sur les cha\u00eenes de production allemandes.<\/p>\n<p>L'apprentissage automatique nous ouvre la voie vers des sc\u00e9narios dans lesquels les robots effectuent des t\u00e2ches beaucoup plus complexes - et ce sans intervention humaine et sans processus pr\u00e9d\u00e9finis avec pr\u00e9cision.<\/p>\n<p>Les machines peuvent apprendre des relations complexes \u00e0 l'aide de donn\u00e9es historiques, par exemple pour pr\u00e9dire avec pr\u00e9cision, \u00e0 partir de donn\u00e9es de capteurs, si, quand et quels probl\u00e8mes pourraient survenir sur une machine. Un autre exemple est le contr\u00f4le de la qualit\u00e9 qui, par le pass\u00e9, faisait toujours appel au jugement d'un \u00eatre humain.<\/p>\n<p>Les entreprises ont aujourd'hui le choix entre des plateformes informatiques sp\u00e9cialis\u00e9es qui offrent une puissance de calcul suffisante pour traiter les algorithmes d'IA. Celles-ci utilisent les donn\u00e9es n\u00e9cessaires de mani\u00e8re beaucoup plus rentable qu'auparavant.<\/p>\n<p>Les plateformes de cloud computing et les outils de stockage et de traitement des donn\u00e9es, ainsi que les processeurs puissants, sont aujourd'hui largement r\u00e9pandus et constituent une base capable de r\u00e9pondre aux exigences techniques de l'IA - dans tous les sens du terme.<\/p>\n<p>Gr\u00e2ce \u00e0 l'engouement r\u00e9cent pour le \"big data\" et aux investissements qui en d\u00e9coulent dans les data lakes et les solutions analytiques, les entreprises ont acc\u00e8s \u00e0 de nombreuses informations sur tous les aspects des processus d'entreprise.<\/p>\n<p>Pour la premi\u00e8re fois depuis le d\u00e9but de la recherche sur l'IA, toutes les conditions sont r\u00e9unies pour une large mise en \u0153uvre de cas d'application dans la pratique.<\/p>\n<p>Les entreprises doivent d\u00e9sormais investir et transformer les technologies et applications intelligentes en valeur ajout\u00e9e \u00e9conomique afin de s'assurer un avantage concurrentiel d\u00e9cisif et de rester viables.<\/p>","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s des d\u00e9cennies de recherche, la perc\u00e9e de l'IA est imminente. Elle offre aux entreprises qui misent sur les technologies ax\u00e9es sur les donn\u00e9es et l'IA \u00e0 la fois d'\u00e9normes opportunit\u00e9s de revenus et des avantages concurrentiels d\u00e9cisifs. <\/p>","protected":false},"author":1527,"featured_media":21247,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[12999,7,22044],"tags":[624,626],"coauthors":[23138],"class_list":["post-43112","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kuenstliche-intelligenz","category-meinung","category-mag-1805","tag-ki","tag-kuenstliche-intelligenz","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/05\/KI-Kolumne-OS.jpg",1000,431,false],"thumbnail":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/05\/KI-Kolumne-OS-150x150.jpg",150,150,true],"medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/05\/KI-Kolumne-OS.jpg",400,172,false],"medium_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/05\/KI-Kolumne-OS-768x331.jpg",768,331,true],"large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/05\/KI-Kolumne-OS.jpg",1000,431,false],"image-100":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/05\/KI-Kolumne-OS-100x43.jpg",100,43,true],"image-480":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/05\/KI-Kolumne-OS-480x207.jpg",480,207,true],"image-640":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/05\/KI-Kolumne-OS-640x276.jpg",640,276,true],"image-720":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/05\/KI-Kolumne-OS-720x310.jpg",720,310,true],"image-960":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/05\/KI-Kolumne-OS-960x414.jpg",960,414,true],"image-1168":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/05\/KI-Kolumne-OS.jpg",1000,431,false],"image-1440":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/05\/KI-Kolumne-OS.jpg",1000,431,false],"image-1920":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/05\/KI-Kolumne-OS.jpg",1000,431,false],"1536x1536":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/05\/KI-Kolumne-OS.jpg",1000,431,false],"2048x2048":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/05\/KI-Kolumne-OS.jpg",1000,431,false],"trp-custom-language-flag":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/05\/KI-Kolumne-OS.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/05\/KI-Kolumne-OS.jpg",1000,431,false],"bricks_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/05\/KI-Kolumne-OS.jpg",1000,431,false],"bricks_large_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/05\/KI-Kolumne-OS.jpg",1000,431,false],"bricks_medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/05\/KI-Kolumne-OS.jpg",600,259,false],"bricks_medium_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/05\/KI-Kolumne-OS.jpg",600,259,false],"profile_24":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/05\/KI-Kolumne-OS-24x24.jpg",24,24,true],"profile_48":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/05\/KI-Kolumne-OS-48x48.jpg",48,48,true],"profile_96":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/05\/KI-Kolumne-OS-96x96.jpg",96,96,true],"profile_150":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/05\/KI-Kolumne-OS-150x150.jpg",150,150,true],"profile_300":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2017\/05\/KI-Kolumne-OS-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Nach jahrzehntelanger Forschung steht der Durchbruch von KI unmittelbar bevor. Sie bietet Unternehmen, die auf Daten- und KI-getriebene Technologien setzen, sowohl enorme Umsatzchancen als auch entscheidende Wettbewerbsvorteile. <\/p>\n","category_list_v2":"<a href=\"https:\/\/e326.greatsolution.dev\/fr\/categorie\/avis\/intelligence-artificielle\/\" rel=\"category tag\">K\u00fcnstliche Intelligenz<\/a>, <a href=\"https:\/\/e326.greatsolution.dev\/fr\/categorie\/avis\/\" rel=\"category tag\">Die Meinung der SAP-Community<\/a>, <a href=\"https:\/\/e326.greatsolution.dev\/fr\/categorie\/mag-1805\/\" rel=\"category tag\">MAG 18-05<\/a>","author_info_v2":{"name":"Michael Zeller, Software AG","url":"https:\/\/e326.greatsolution.dev\/fr\/author\/michael-zeller\/"},"comments_num_v2":"0 commentaire","_links":{"self":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/posts\/43112","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/users\/1527"}],"replies":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/comments?post=43112"}],"version-history":[{"count":0,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/posts\/43112\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/media\/21247"}],"wp:attachment":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/media?parent=43112"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/categories?post=43112"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/tags?post=43112"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/coauthors?post=43112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}