{"id":54360,"date":"2018-08-30T11:00:28","date_gmt":"2018-08-30T09:00:28","guid":{"rendered":"https:\/\/e326.greatsolution.dev\/?p=54360"},"modified":"2025-07-14T11:46:11","modified_gmt":"2025-07-14T09:46:11","slug":"la-chasse-au-tresor-numerique-une-question-de-survie","status":"publish","type":"post","link":"https:\/\/e326.greatsolution.dev\/fr\/la-chasse-au-tresor-numerique-une-question-de-survie\/","title":{"rendered":"La chasse au tr\u00e9sor num\u00e9rique, une question de survie"},"content":{"rendered":"<p>De nombreuses entreprises se comportent actuellement de la m\u00eame mani\u00e8re : Elles cherchent au loin des impulsions pour leurs strat\u00e9gies de num\u00e9risation et d'industrie 4.0. Mais elles ne tiennent pas compte de leurs donn\u00e9es - le tr\u00e9sor en or sur lequel elles sont assises.<\/p>\n<h3>L'IA : entre engouement et incertitude<\/h3>\n<p>Pourtant, un engouement traverse actuellement le pays : intelligence artificielle, big data ... ces th\u00e8mes font la une de la presse sp\u00e9cialis\u00e9e et \u00e9conomique. Mais dans les entreprises elles-m\u00eames, l'incertitude est grande.<\/p>\n<p>C'est ce qu'a montr\u00e9 ma petite enqu\u00eate men\u00e9e l'autre jour lors du hackathon de la VDMA sur la maintenance pr\u00e9dictive : les entreprises participantes s'int\u00e9ressent toutes au sujet, mais seules 5 \u00e0 10 pour cent sont d\u00e9j\u00e0 en mesure de fournir des services concrets. Toutes veulent faire quelque chose, mais seules quelques-unes avancent de mani\u00e8re cibl\u00e9e. Quelle en est la raison ? Un facteur de r\u00e9ussite essentiel est un mandat clair de la direction pour s'en occuper de mani\u00e8re strat\u00e9gique et visionnaire - par exemple dans le r\u00f4le d'un CDO.<\/p>\n<p>En outre, une strat\u00e9gie de donn\u00e9es est n\u00e9cessaire et doit faire partie de la strat\u00e9gie de l'entreprise. En effet, en mati\u00e8re de num\u00e9risation et de donn\u00e9es, il s'agit souvent d'une question existentielle : avec quoi l'entreprise gagnera-t-elle de l'argent dans dix ans ? En plus du mandat du conseil d'administration, il faut une organisation de direction qui englobe toutes les activit\u00e9s, les pilotes et les projets relatifs \u00e0 ces th\u00e8mes. Avec un tel \"hub num\u00e9rique\" comme mod\u00e8le de gouvernance, on s'assure que le sujet est promu \u00e0 l'\u00e9chelle de l'entreprise.<\/p>\n<p>Parall\u00e8lement \u00e0 cette approche descendante, une approche ascendante est \u00e9galement d\u00e9cisive pour le succ\u00e8s. En effet, il est n\u00e9cessaire d'avoir un acc\u00e8s direct aux processus op\u00e9rationnels dans lesquels se trouvent les donn\u00e9es.<\/p>\n<h2>Trois plus un<\/h2>\n<p>La r\u00e9ussite d'un projet concret de num\u00e9risation d\u00e9pend en fait toujours de quatre facteurs, d\u00e9crits dans la r\u00e8gle des 3+1 (Michael Herbst, Unity) : Les trois \u00e9l\u00e9ments technologie + service\/application + b\u00e9n\u00e9fice forment ensemble un cas d'utilisation. Celui-ci ne sera toujours couronn\u00e9 de succ\u00e8s que s'il y a \u00e9galement un client (+1) qui en tire un avantage concret. Dans l'esprit de la d\u00e9marche bottom-up, il s'agit donc, pour chaque projet de donn\u00e9es ou de num\u00e9risation, de r\u00e9unir pr\u00e9cis\u00e9ment les personnes qui, ensemble, remplissent la r\u00e8gle des 3+1.<\/p>\n<p>Il ne suffit pas d'ajouter quelques analystes de donn\u00e9es au service informatique. Si les m\u00e9tiers ne sont pas impliqu\u00e9s, cela ne r\u00e9ussira pas. Et inversement, si les m\u00e9tiers veulent utiliser leurs donn\u00e9es mais qu'il leur manque les bons outils, cela ne fonctionnera pas non plus.<\/p>\n<p>Un autre aspect qui fait \u00e9chouer de nombreux projets de donn\u00e9es est le suivant : la taille rend lent. Ce ne sont pas les grands projets pr\u00e9vus pour de nombreuses ann\u00e9es qui sont n\u00e9cessaires ici. Il vaut mieux apprendre de mani\u00e8re it\u00e9rative au d\u00e9but, essayer rapidement des cas d'utilisation tr\u00e8s concrets et prouver, par le biais de Minimum Viable Products (MVP) ou d'une preuve de concept, que l'avantage concret pour le client est pr\u00e9sent et que l'application fonctionne dans un processus r\u00e9el.<\/p>\n<p>Ce n'est qu'une fois cet objectif atteint que le service de donn\u00e9es peut \u00eatre \"industrialis\u00e9\". On d\u00e9veloppe alors une proc\u00e9dure applicable \u00e0 tous les cas d'utilisation similaires de l'entreprise. Ce n'est qu'\u00e0 ce stade que l'on d\u00e9pense beaucoup d'argent - pour l'int\u00e9gration technique, pour la s\u00e9curit\u00e9 informatique et des donn\u00e9es, etc. - mais avec la certitude que l'ensemble apporte une valeur ajout\u00e9e et fonctionne.<\/p>\n<h2>Essentiel \u00e0 la survie<\/h2>\n<p>Chaque entreprise est assise sur un tr\u00e9sor de donn\u00e9es - tout simplement parce qu'elle a des processus op\u00e9rationnels. Celles qui utilisent ces donn\u00e9es pourront faire la diff\u00e9rence dans leur secteur. J'irai m\u00eame jusqu'\u00e0 dire que seules ces entreprises survivront. De nombreux outils n\u00e9cessaires \u00e0 l'intelligence artificielle ou \u00e0 l'analyse des donn\u00e9es sont aujourd'hui disponibles gratuitement et de grande qualit\u00e9 dans le domaine de l'open source. Les entreprises ne devraient pas \u00eatre d\u00e9pendantes d'experts externes, mais plut\u00f4t s'en servir comme partenaires d'innovation afin de d\u00e9velopper des comp\u00e9tences importantes. Creusez de mani\u00e8re cibl\u00e9e pour trouver votre tr\u00e9sor !<\/p>","protected":false},"excerpt":{"rendered":"<p>Ces derniers temps, une image me vient souvent \u00e0 l'esprit lorsque je parle de donn\u00e9es : celle d'une personne assise sur une plage, regardant avec nostalgie par-dessus la mer vers l'\u00eele suivante et ne remarquant pas le tr\u00e9sor d'or enfoui sous elle dans le sable. <\/p>","protected":false},"author":1557,"featured_media":4163,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[10,7,23656],"tags":[210,367,624,626,3812],"coauthors":[24196],"class_list":["post-54360","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-das-aktuelle-stichwort","category-meinung","category-mag-1807","tag-big-data","tag-industrie-4-0","tag-ki","tag-kuenstliche-intelligenz","tag-predictive-maintenance","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",1000,431,false],"thumbnail":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort-150x150.jpg",150,150,true],"medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",400,172,false],"medium_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort-768x331.jpg",768,331,true],"large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",1000,431,false],"image-100":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort-100x43.jpg",100,43,true],"image-480":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort-480x207.jpg",480,207,true],"image-640":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort-640x276.jpg",640,276,true],"image-720":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort-720x310.jpg",720,310,true],"image-960":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort-960x414.jpg",960,414,true],"image-1168":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",1000,431,false],"image-1440":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",1000,431,false],"image-1920":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",1000,431,false],"1536x1536":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",1000,431,false],"2048x2048":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",1000,431,false],"trp-custom-language-flag":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",1000,431,false],"bricks_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",1000,431,false],"bricks_large_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",1000,431,false],"bricks_medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",600,259,false],"bricks_medium_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",600,259,false],"profile_24":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort-24x24.jpg",24,24,true],"profile_48":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort-48x48.jpg",48,48,true],"profile_96":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort-96x96.jpg",96,96,true],"profile_150":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort-150x150.jpg",150,150,true],"profile_300":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Beim Thema Daten kommt mir in letzter Zeit h\u00e4ufig ein Bild in den Kopf: ein Bild von einem Menschen, der am Strand sitzt, voller Sehnsucht \u00fcber das Meer auf die n\u00e4chste Insel schaut und von dem Goldschatz unter sich im Sand nichts bemerkt. <\/p>\n","category_list_v2":"<a href=\"https:\/\/e326.greatsolution.dev\/fr\/categorie\/avis\/le-mot-cle-actuel\/\" rel=\"category tag\">Das aktuelle Stichwort<\/a>, <a href=\"https:\/\/e326.greatsolution.dev\/fr\/categorie\/avis\/\" rel=\"category tag\">Die Meinung der SAP-Community<\/a>, <a href=\"https:\/\/e326.greatsolution.dev\/fr\/categorie\/mag-1807\/\" rel=\"category tag\">MAG 18-07<\/a>","author_info_v2":{"name":"Marcus Goerke, Next Data Service","url":"https:\/\/e326.greatsolution.dev\/fr\/author\/marcus-goerke\/"},"comments_num_v2":"0 commentaire","_links":{"self":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/posts\/54360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/users\/1557"}],"replies":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/comments?post=54360"}],"version-history":[{"count":2,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/posts\/54360\/revisions"}],"predecessor-version":[{"id":152448,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/posts\/54360\/revisions\/152448"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/media\/4163"}],"wp:attachment":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/media?parent=54360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/categories?post=54360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/tags?post=54360"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/coauthors?post=54360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}