{"id":55792,"date":"2019-02-18T08:00:13","date_gmt":"2019-02-18T07:00:13","guid":{"rendered":"https:\/\/e326.greatsolution.dev\/?p=55792"},"modified":"2020-02-09T15:07:13","modified_gmt":"2020-02-09T14:07:13","slug":"le-jour-apres-que-hana-soit-partie-vivre","status":"publish","type":"post","link":"https:\/\/e326.greatsolution.dev\/fr\/le-jour-apres-que-hana-soit-partie-vivre\/","title":{"rendered":"The Day after Hana Going Live"},"content":{"rendered":"<p>Pour beaucoup, le passage \u00e0 Hana et S\/4 est un \u00e9norme changement, car ce n'est pas seulement la base de donn\u00e9es qui change, mais aussi le syst\u00e8me d'exploitation sous-jacent. L'exploitation actuelle et donc le manuel d'exploitation doivent \u00eatre revus en profondeur.<\/p>\n<p>C'est \u00e0 partir de l\u00e0 que commence une th\u00e9matique que beaucoup n\u00e9gligent souvent dans leurs projets, car le lien pratique avec le nouvel environnement fait \u00e9galement d\u00e9faut pour de nombreux administrateurs, ce qui fait que certains pi\u00e8ges ne sont d\u00e9couverts que lors de la mise en \u0153uvre.<\/p>\n<p>La plupart du temps, il n'existe pas encore de concepts pour les paquets de travail que sont le provisionnement du syst\u00e8me sous Linux, les copies du syst\u00e8me avec Hana, la surveillance, le transport des objets Hana, les autorisations, les maintenances cycliques ou pour la v\u00e9rification et la validation des nouvelles r\u00e9visions Hana.<\/p>\n<p>Il ne faut pas sous-estimer les efforts \u00e0 fournir en mati\u00e8re de maintenance, car de nombreux composants ont des interd\u00e9pendances qui n'ont pas d\u00fb \u00eatre prises en compte auparavant.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-55793 size-full\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/Jens-Gleichmann-1812.jpg\" alt=\"Jens-Gleichmann-1812\" width=\"800\" height=\"800\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/Jens-Gleichmann-1812.jpg 800w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/Jens-Gleichmann-1812-150x150.jpg 150w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/Jens-Gleichmann-1812-768x768.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/Jens-Gleichmann-1812-100x100.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/Jens-Gleichmann-1812-480x480.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/Jens-Gleichmann-1812-640x640.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/Jens-Gleichmann-1812-720x720.jpg 720w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/Jens-Gleichmann-1812-24x24.jpg 24w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/Jens-Gleichmann-1812-48x48.jpg 48w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/Jens-Gleichmann-1812-96x96.jpg 96w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/Jens-Gleichmann-1812-300x300.jpg 300w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Outre les restrictions connues de tous en mati\u00e8re de stockage, de serveurs et de syst\u00e8mes d'exploitation, il existe d'autres limitations. Cela a pour cons\u00e9quence que de nombreuses \u00e9quipes (serveurs, syst\u00e8me d'exploitation, bases de donn\u00e9es, base SAP) doivent se concerter encore plus qu'avant.<\/p>\n<p>Pour produire le moins de temps d'arr\u00eat possible, il est recommand\u00e9 de synchroniser les cycles de maintenance des composants. Dans le \"Suse Linux Enterprise Server for SAP Applications\" avec le support \u00e9tendu pour le produit, Suse a d\u00e9j\u00e0 int\u00e9gr\u00e9 cela avec beaucoup de succ\u00e8s.<\/p>\n<p>Ici, par exemple, la fin de la maintenance de Hana 2 SPS01 a \u00e9t\u00e9 coupl\u00e9e \u00e0 SLES for SAP 12 SP1. Les prochaines \u00e9ch\u00e9ances seront SLES for SAP 12 SP2 en avril 2019 et Hana 2 SPS02 en fin de maintenance.<\/p>\n<p>Lors d'une telle maintenance, la question de la v\u00e9rification technique et de la validation fonctionnelle se pose toujours. La plupart des utilisateurs cl\u00e9s n'ont gu\u00e8re de capacit\u00e9s pour les tests en plus du travail de projet et de l'exploitation normale. C'est l\u00e0 que la fonctionnalit\u00e9 \"Capture &amp; Replay\", qui est gratuite - c'est-\u00e0-dire d\u00e9j\u00e0 incluse dans la licence Hana - entre en jeu.<\/p>\n<p>Cela permet de reproduire 1:1 sur un autre syst\u00e8me la charge de travail g\u00e9n\u00e9r\u00e9e par les instructions SQL. Ainsi, si votre syst\u00e8me ERP de production compte 2000 utilisateurs, vous pouvez ex\u00e9cuter \u00e0 nouveau toutes les transactions dans un d\u00e9lai d\u00e9fini. Les seules conditions sont une sauvegarde du syst\u00e8me de production ainsi qu'un enregistrement d'une telle p\u00e9riode.<\/p>\n<figure id=\"attachment_55794\" aria-describedby=\"caption-attachment-55794\" style=\"width: 1000px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-55794\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/Abbildung3_Vorgang_cmyk.jpg\" alt=\"Figure3_Processus_cmyk\" width=\"1000\" height=\"306\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/Abbildung3_Vorgang_cmyk.jpg 1000w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/Abbildung3_Vorgang_cmyk-768x235.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/Abbildung3_Vorgang_cmyk-100x31.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/Abbildung3_Vorgang_cmyk-480x147.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/Abbildung3_Vorgang_cmyk-640x196.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/Abbildung3_Vorgang_cmyk-720x220.jpg 720w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/Abbildung3_Vorgang_cmyk-960x294.jpg 960w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption id=\"caption-attachment-55794\" class=\"wp-caption-text\">Vue d'ensemble du processus : 1. d\u00e9finition de la \"Golden Image\" dans l'environnement Linux avec les param\u00e8tres correspondants ; 2. \"Capture &amp; Replay\" avec diff\u00e9rentes versions\/configuration des composants ; 3. reprise de la copie du syst\u00e8me pour rafra\u00eechir les donn\u00e9es.<\/figcaption><\/figure>\n<p>Cette sauvegarde est transf\u00e9r\u00e9e sur un autre syst\u00e8me, par exemple le syst\u00e8me d'assurance qualit\u00e9 (QAS). Vous pouvez y reproduire plusieurs it\u00e9rations de modifications (patch Hana\/Linux, modifications de param\u00e8tres) et comparer les r\u00e9sultats \u00e0 chaque passage, par exemple si les requ\u00eates \u00e9taient plus rapides ou plus lentes, ou m\u00eame si une erreur s'est produite.<\/p>\n<p>Cette proc\u00e9dure permet de d\u00e9charger les utilisateurs cl\u00e9s et m\u00eame d'effectuer un test de charge avec des donn\u00e9es productives, y compris 2000 utilisateurs ou plus. A la fin, le syst\u00e8me ne doit pas \u00eatre \"\u00e9limin\u00e9\", mais peut \u00eatre r\u00e9introduit dans le paysage en tant que QAS avec les travaux ult\u00e9rieurs de la copie du syst\u00e8me. Il est donc tr\u00e8s judicieux de coupler de tels travaux de maintenance \u00e0 la planification existante des copies du syst\u00e8me.<\/p>\n<p>Que ne peut pas faire \"Capture &amp; Replay\" ? Il n'est pas possible de tester un remplacement de noyau SAP ou un changement de version.<\/p>\n<h3>Conclusion<\/h3>\n<p>En raison de la complexit\u00e9 et des interd\u00e9pendances des composants du syst\u00e8me Hana, une automatisation partielle des tests s'impose. En raison des exigences croissantes, de la diminution du nombre de fen\u00eatres de maintenance et des cycles de mise \u00e0 jour serr\u00e9s, une optimisation du processus de maintenance est plus que souhait\u00e9e.<\/p>\n<p>Si l'on combine encore cela avec la proc\u00e9dure \"Near Zero Downtime Maintenance\" (Hana System Replication + DBSL Suspend) et un Rolling Kernel Switch (RKS), il serait possible d'effectuer des maintenances en semaine pratiquement sans impact sur l'utilisateur final.<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/fr\/partenaires\/q-partners-gmbh\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-55702 size-full\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/QPCM-CI-Banner.jpg\" alt=\"https:\/\/e326.greatsolution.dev\/partners\/q-partners-gmbh\/\" width=\"1000\" height=\"112\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/QPCM-CI-Banner.jpg 1000w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/QPCM-CI-Banner-768x86.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/QPCM-CI-Banner-100x11.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/QPCM-CI-Banner-480x54.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/QPCM-CI-Banner-640x72.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/QPCM-CI-Banner-720x81.jpg 720w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/QPCM-CI-Banner-960x108.jpg 960w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Certains clients existants de SAP ont d\u00e9j\u00e0 pu passer \u00e0 Hana, sont en pleine conversion ou en cours de conversion \u00e0 S\/4. Maintenant que les phases du projet sont termin\u00e9es et que les syst\u00e8mes ont \u00e9t\u00e9 mis en service, c'est \u00e0 l'\u00e9quipe SAP Basis de les faire fonctionner.<\/p>","protected":false},"author":107,"featured_media":55795,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[5,27178],"tags":[65,67,12211,21219,189],"coauthors":[22259],"class_list":["post-55792","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-it-management","category-mag-1812","tag-hana","tag-linux","tag-monitoring","tag-s-4","tag-sles","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/shutterstock_750212500.jpg",1000,450,false],"thumbnail":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/shutterstock_750212500-150x150.jpg",150,150,true],"medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/shutterstock_750212500.jpg",400,180,false],"medium_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/shutterstock_750212500-768x346.jpg",768,346,true],"large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/shutterstock_750212500.jpg",1000,450,false],"image-100":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/shutterstock_750212500-100x45.jpg",100,45,true],"image-480":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/shutterstock_750212500-480x216.jpg",480,216,true],"image-640":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/shutterstock_750212500-640x288.jpg",640,288,true],"image-720":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/shutterstock_750212500-720x324.jpg",720,324,true],"image-960":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/shutterstock_750212500-960x432.jpg",960,432,true],"image-1168":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/shutterstock_750212500.jpg",1000,450,false],"image-1440":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/shutterstock_750212500.jpg",1000,450,false],"image-1920":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/shutterstock_750212500.jpg",1000,450,false],"1536x1536":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/shutterstock_750212500.jpg",1000,450,false],"2048x2048":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/shutterstock_750212500.jpg",1000,450,false],"trp-custom-language-flag":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/shutterstock_750212500.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/shutterstock_750212500.jpg",1000,450,false],"bricks_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/shutterstock_750212500.jpg",1000,450,false],"bricks_large_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/shutterstock_750212500.jpg",1000,450,false],"bricks_medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/shutterstock_750212500.jpg",600,270,false],"bricks_medium_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/shutterstock_750212500.jpg",600,270,false],"profile_24":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/shutterstock_750212500-24x24.jpg",24,24,true],"profile_48":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/shutterstock_750212500-48x48.jpg",48,48,true],"profile_96":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/shutterstock_750212500-96x96.jpg",96,96,true],"profile_150":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/shutterstock_750212500-150x150.jpg",150,150,true],"profile_300":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/11\/shutterstock_750212500-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Einige SAP-Bestandskunden konnten schon auf Hana umstellen, sind mitten in der Umstellung oder Konvertierung zu S\/4. Nachdem die Projektphasen abgeschlossen sind und die Systeme in Betrieb genommen wurden, liegt es nun an dem SAP-Basis-Team, diese auch zu betreiben.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e326.greatsolution.dev\/fr\/categorie\/gestion-de-linformatique\/\" rel=\"category tag\">IT-Management<\/a>, <a href=\"https:\/\/e326.greatsolution.dev\/fr\/categorie\/mag-1812\/\" rel=\"category tag\">MAG 18-12<\/a>","author_info_v2":{"name":"Jens Gleichmann, Q-Partners","url":"https:\/\/e326.greatsolution.dev\/fr\/author\/jens-gleichmann\/"},"comments_num_v2":"0 commentaire","_links":{"self":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/posts\/55792","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/users\/107"}],"replies":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/comments?post=55792"}],"version-history":[{"count":0,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/posts\/55792\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/media\/55795"}],"wp:attachment":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/media?parent=55792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/categories?post=55792"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/tags?post=55792"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/coauthors?post=55792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}