{"id":59755,"date":"2019-05-23T13:02:30","date_gmt":"2019-05-23T11:02:30","guid":{"rendered":"https:\/\/e326.greatsolution.dev\/?p=59755"},"modified":"2022-05-01T09:56:30","modified_gmt":"2022-05-01T07:56:30","slug":"pouvoir-a-la-communaute","status":"publish","type":"post","link":"https:\/\/e326.greatsolution.dev\/fr\/pouvoir-a-la-communaute\/","title":{"rendered":"Le pouvoir \u00e0 la communaut\u00e9"},"content":{"rendered":"<p>Le professeur Hasso Plattner s'est choisi de mauvais amis en ce qui concerne la base de donn\u00e9es de calcul en m\u00e9moire Hana : En collaboration avec Intel, un concept de base de donn\u00e9es en m\u00e9moire a \u00e9t\u00e9 d\u00e9velopp\u00e9 \u00e0 l'Institut Hasso Plattner (HPI) de Potsdam.<\/p>\n<p>Huit ans plus tard, il s'av\u00e8re que presque tous les concepts \u00e9taient corrects - sauf la base mat\u00e9rielle et le concept des appliances.<\/p>\n<p>Pour les experts, il \u00e9tait d\u00e9j\u00e0 clair peu de temps apr\u00e8s les premi\u00e8res installations de Hana sur l'architecture Intel que les performances, la mise \u00e0 l'\u00e9chelle et la virtualisation ne pouvaient pas \u00eatre mises en \u0153uvre de mani\u00e8re satisfaisante ici.<\/p>\n<p>Mais Intel n'a pas voulu ou n'a pas pu am\u00e9liorer la situation. Intel a peut-\u00eatre aussi succomb\u00e9 \u00e0 l'illusion que le lien avec SAP \u00e9tait au-dessus de tout soup\u00e7on. Et en effet : le professeur Hasso Plattner et le directeur technique de SAP de l'\u00e9poque, Vishal Sikka, se sont longtemps oppos\u00e9s \u00e0 un portage de la base de donn\u00e9es Hana sur l'architecture Power d'IBM. Bien que dans le milieu, tout le monde savait d\u00e9j\u00e0 que HoP, Hana on Power, \u00e9tait une bien meilleure r\u00e9ponse, SAP a longtemps refus\u00e9 \u00e0 IBM la certification Hana.<\/p>\n<p>M\u00eame une filiale exotique de HP comme SGI a obtenu une certification Hana presque du jour au lendemain, tandis qu'IBM a d\u00fb attendre \u00e0 la porte avec l'architecture Power. Sur la plate-forme Intel, en revanche, les probl\u00e8mes li\u00e9s \u00e0 Hana s'aggravaient de jour en jour.<\/p>\n<p>Les tailles des appliances ne correspondaient pas aux attentes des clients SAP existants et la virtualisation avec VMware n'a longtemps pas \u00e9t\u00e9 adapt\u00e9e \u00e0 une exploitation productive.<\/p>\n<p>En revanche, l'ensemble de la communaut\u00e9 SAP savait que le syst\u00e8me d'exploitation Hana Suse Linux \u00e9tait \u00e9galement disponible pour l'architecture Power d'IBM et qu'un changement ne poserait donc aucun probl\u00e8me. SAP a finalement c\u00e9d\u00e9 et IBM a pu prouver officiellement que l'architecture informatique de Power est bien sup\u00e9rieure \u00e0 un processeur Intel en ce qui concerne Hana.<\/p>\n<p>Bien entendu, IBM a \u00e9galement renonc\u00e9 au mod\u00e8le d'appliance avec des tailles de T-shirt, mais a imm\u00e9diatement mis \u00e0 disposition des serveurs Hana selon les attentes des clients SAP existants.<\/p>\n<p>L'attitude de SAP et de l'HPI vis-\u00e0-vis d'IBM Power a finalement \u00e9volu\u00e9 : Un cours en ligne sur l'avenir de l'informatique a \u00e9t\u00e9 lanc\u00e9 par l'Institut Hasso Plattner le 1er mai de cette ann\u00e9e. Il a dur\u00e9 quatre semaines et a \u00e9t\u00e9 propos\u00e9 gratuitement sur la plate-forme d'apprentissage informatique openHPI : \"Future of Computing - IBM Power 9 and beyond\".<\/p>\n<figure id=\"attachment_59761\" aria-describedby=\"caption-attachment-59761\" style=\"width: 1000px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" title=\"Le pouvoir \u00e0 la communaut\u00e9\" class=\"size-full wp-image-59761\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/Missbach-Spahn.jpg\" alt=\"Missbach &amp; Spahn\" width=\"1000\" height=\"657\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/Missbach-Spahn.jpg 1000w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/Missbach-Spahn-768x505.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/Missbach-Spahn-100x66.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/Missbach-Spahn-480x315.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/Missbach-Spahn-640x420.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/Missbach-Spahn-720x473.jpg 720w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/Missbach-Spahn-960x631.jpg 960w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption id=\"caption-attachment-59761\" class=\"wp-caption-text\">Andreas Klaus Span, IBM, et Michael Missbach, Syntax, racontent dans les pages suivantes, en termes tr\u00e8s personnels, leur exp\u00e9rience avec Hana on Power.<\/figcaption><\/figure>\n<h3>IBM Power \u00e0 l'HPI<\/h3>\n<p>Le professeur HPI Andreas Polze, directeur du d\u00e9partement Syst\u00e8mes d'exploitation et middleware, a organis\u00e9 le cours en collaboration avec Hildegard Gerhardy de l'IBM Academic Initiative Europe et Wolfgang Maier, directeur du d\u00e9veloppement mat\u00e9riel d'IBM \u00e0 B\u00f6blingen.<\/p>\n<p><em>\"Nous pr\u00e9sentons aux participants diff\u00e9rentes approches permettant de relever les d\u00e9fis de la num\u00e9risation, notamment la croissance exponentielle des donn\u00e9es\".<\/em><\/p>\n<p>a expliqu\u00e9 le professeur d'informatique Polze.<\/p>\n<p>Il a rappel\u00e9 que la capacit\u00e9 de stockage d'informations par habitant dans le monde avait presque doubl\u00e9 tous les 40 mois depuis les ann\u00e9es 80.<\/p>\n<p><em>\"Et d'ici cinq ans environ, certains chercheurs pr\u00e9voient d\u00e9j\u00e0 plus de 160 zettaoctets de volume de donn\u00e9es global\".<\/em><\/p>\n<p>a ajout\u00e9 Gerhardy.<\/p>\n<p><em>\"Comme il y a de plus en plus de donn\u00e9es non structur\u00e9es, par exemple dans l'Internet des objets, qui doivent \u00eatre analys\u00e9es, il est n\u00e9cessaire d'adopter de nouvelles approches dans le d\u00e9veloppement de logiciels\".<\/em><\/p>\n<p>a d\u00e9clar\u00e9 Wolfgang Maier.<\/p>\n<p>Il s'agit \u00e9galement de mettre \u00e0 disposition des microservices, des solutions de conteneurs et des applications bas\u00e9es sur le cloud. En outre, les d\u00e9partements informatiques ont besoin de nouvelles technologies de base telles que les acc\u00e9l\u00e9rateurs mat\u00e9riels, l'intelligence artificielle et les technologies blockchain pour traiter d'\u00e9normes quantit\u00e9s de donn\u00e9es.<\/p>\n<p>Polze et les deux autres directeurs de cours ont confront\u00e9 cette tendance de l'analyse de donn\u00e9es d'un nouveau genre dans ce que l'on appelle les \"Systems of Engagement\" aux technologies essentielles des \"Systems of Record\" traditionnels.<\/p>\n<p><em>\"La fiabilit\u00e9, la haute disponibilit\u00e9 et la facilit\u00e9 d'entretien des syst\u00e8mes exigent du mat\u00e9riel sophistiqu\u00e9, des syst\u00e8mes d'exploitation et des programmes neutres par rapport aux applications, afin de pouvoir traiter des transactions \u00e0 grande \u00e9chelle\".<\/em><\/p>\n<p>explique le professeur Polze de l'HPI.<\/p>\n<p>Le cours sur l'avenir de l'informatique a mis l'accent sur les technologies li\u00e9es \u00e0 IBM Power Systems. Dans le cadre de son initiative Open Power, IBM coop\u00e8re avec plus de 300 entreprises membres, dont Google, Samsung et Nvidia, afin de cr\u00e9er de multiples innovations, du logiciel au mat\u00e9riel.<\/p>\n<h3><img loading=\"lazy\" decoding=\"async\" title=\"Le pouvoir \u00e0 la communaut\u00e9\" class=\"aligncenter size-full wp-image-59758\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/0108_IBM_POWER_ZEPPELIN_cmyk.jpg\" alt=\"IBM POWER ZEPPELIN\" width=\"1000\" height=\"450\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/0108_IBM_POWER_ZEPPELIN_cmyk.jpg 1000w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/0108_IBM_POWER_ZEPPELIN_cmyk-768x346.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/0108_IBM_POWER_ZEPPELIN_cmyk-100x45.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/0108_IBM_POWER_ZEPPELIN_cmyk-480x216.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/0108_IBM_POWER_ZEPPELIN_cmyk-640x288.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/0108_IBM_POWER_ZEPPELIN_cmyk-720x324.jpg 720w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/0108_IBM_POWER_ZEPPELIN_cmyk-960x432.jpg 960w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/h3>\n<h3>Big Data &amp; Architecture DB<\/h3>\n<p>Lors de sa keynote Sapphire de cette ann\u00e9e \u00e0 Orlando, le professeur Plattner a lui aussi soulign\u00e9 l'\u00e9norme croissance des donn\u00e9es et la n\u00e9cessit\u00e9 de trouver rapidement des r\u00e9ponses avec des architectures informatiques et des bases de donn\u00e9es appropri\u00e9es.<\/p>\n<p>Selon sa pr\u00e9sentation, le passage \u00e0 Hana au sein de la communaut\u00e9 SAP aurait d\u00fb avoir lieu dans environ trois ans. Maintenant, le \"changement de version de la base de donn\u00e9es\" dure d\u00e9j\u00e0 un peu plus longtemps, ce qui est probablement d\u00fb \u00e0 l'insuffisance de la plateforme Intel au cours des premi\u00e8res ann\u00e9es de Hana.<\/p>\n<p>Le d\u00e9veloppement de Hana \u00e0 l'Institut Hasso Plattner de l'Universit\u00e9 de Potsdam \u00e9tait coordonn\u00e9 avec Intel et se concentrait sur l'architecture x86 des processeurs Xeon. Mais l'architecture Power d'IBM s'est av\u00e9r\u00e9e \u00eatre la meilleure base. Ce n'est qu'en 2014 que SAP a renonc\u00e9 \u00e0 sa r\u00e9sistance et a autoris\u00e9 HoP - Hana on Power.<\/p>\n<p>La base de donn\u00e9es de calcul en m\u00e9moire Hana pr\u00e9sente de nombreux avantages formidables par rapport aux bases de donn\u00e9es SQL classiques - non pas parce que SAP est meilleur, mais parce que le professeur Hasso Plattner a eu le courage de faire table rase du pass\u00e9 : Hana a pu voir le jour sur les planches \u00e0 dessin de Potsdam \u00e0 l'Institut Hasso Plattner et de Walldorf au si\u00e8ge de SAP, sans charges h\u00e9rit\u00e9es du pass\u00e9 ni contraintes de compatibilit\u00e9.<\/p>\n<p>\u00c0 Potsdam, les \u00e9tudiants du professeur Plattner ont effectu\u00e9 des recherches et programm\u00e9 avec Alexander Zeier. C'est Vishal Sikka, math\u00e9maticien et ex-directeur technique de SAP, qui a men\u00e9 Hana \u00e0 sa maturit\u00e9 op\u00e9rationnelle \u00e0 Palo Alto, en Californie.<\/p>\n<p>On peut supposer que tous les trois - Plattner, Zeier et Sikka - n'\u00e9taient pas seulement des connaisseurs de premier ordre de l'architecture des processeurs Intel, mais qu'ils croyaient fermement que seul ce processeur \u00e0 usage g\u00e9n\u00e9ral \u00e9tait le mieux adapt\u00e9 \u00e0 leur base de donn\u00e9es Hana - une erreur, comme il a \u00e9t\u00e9 officiellement d\u00e9montr\u00e9 en 2014.<\/p>\n<h3>IBM Power pour le Big Data<\/h3>\n<p>\"Power 8 et Power 9 ont tous deux \u00e9t\u00e9 con\u00e7us pour traiter de grandes quantit\u00e9s de donn\u00e9es, avec une grande largeur de bande m\u00e9moire - quatre fois plus grande que celle d'Intel x86, plus de m\u00e9moire cache - cinq fois plus de m\u00e9moire cache que celle de x86, ainsi que des performances \u00e9lev\u00e9es - deux fois par c\u0153ur dans le benchmark, jusqu'\u00e0 quatre fois dans les charges de travail r\u00e9elles des clients, une plus grande flexibilit\u00e9 avec PowerVM, une grande fiabilit\u00e9 gr\u00e2ce \u00e0 la redondance, en particulier pour les serveurs Power Entreprise\".<\/p>\n<p>confirme dans l'entretien E-3 Andreas Klaus Span, directeur et Business Unit Executive pour SAP Hana on Power.<\/p>\n<p>D'une mani\u00e8re g\u00e9n\u00e9rale, Andreas Span estime que l'argument selon lequel Intel x86 vient du secteur commercial avec l'approche \"good enough\" et que Power a toujours d\u00fb r\u00e9pondre aux exigences du monde de l'entreprise et a donc d\u00e9velopp\u00e9 une toute autre architecture est pertinent.<\/p>\n<figure id=\"attachment_59759\" aria-describedby=\"caption-attachment-59759\" style=\"width: 900px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" title=\"Le pouvoir \u00e0 la communaut\u00e9\" class=\"size-full wp-image-59759\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/Two-Memory-Architecture-for-Power-9.jpg\" alt=\"Architecture \u00e0 deux m\u00e9moires pour Power 9\" width=\"900\" height=\"449\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/Two-Memory-Architecture-for-Power-9.jpg 900w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/Two-Memory-Architecture-for-Power-9-768x383.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/Two-Memory-Architecture-for-Power-9-100x50.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/Two-Memory-Architecture-for-Power-9-480x239.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/Two-Memory-Architecture-for-Power-9-640x319.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/Two-Memory-Architecture-for-Power-9-720x359.jpg 720w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><figcaption id=\"caption-attachment-59759\" class=\"wp-caption-text\">Avec Power 9, IBM offre aux utilisateurs de Hana deux architectures : il en r\u00e9sulte ainsi une flexibilit\u00e9 maximale pour l'approche TDI (Tailored Datacenter Integration). De plus en plus d'outsourceurs et de fournisseurs de cloud passent \u00e9galement d'une plateforme Intel \u00e0 une plateforme Power en raison des options disponibles.<\/figcaption><\/figure>\n<h3>Facteur de diff\u00e9renciation \"Power<\/h3>\n<p>Depuis fin 2015, Hana est disponible sur IBM Power Systems avec l'architecture et les processeurs innovants Power 8 d'IBM - \u00e9tat actuel : Power 9. Les analystes de march\u00e9 d'IDC sont convaincus que les syst\u00e8mes Power repr\u00e9sentent un facteur de diff\u00e9renciation convaincant pour Hana et S\/4.<\/p>\n<p>Power a \u00e9t\u00e9 con\u00e7u pour les charges de travail tr\u00e8s intensives en donn\u00e9es, comme Hana, et comprend une virtualisation int\u00e9gr\u00e9e puissante certifi\u00e9e SAP, ainsi que de nombreuses caract\u00e9ristiques destin\u00e9es \u00e0 am\u00e9liorer la fiabilit\u00e9.<\/p>\n<p>Andreas Span sait tr\u00e8s bien qu'en raison de la faiblesse de la virtualisation, de l'augmentation des erreurs de s\u00e9curit\u00e9, de la limitation et de la faible capacit\u00e9 de charge des DIMM de m\u00e9moire x86, l'approche du co\u00fbt total de possession est de moins en moins rentable \u00e0 l'achat.<\/p>\n<p>Span : \"<em>A cela s'ajoute la croissance exponentielle des bases de donn\u00e9es Hana et des donn\u00e9es en g\u00e9n\u00e9ral, qui r\u00e9clament une approche flexible et adaptable du co\u00fbt total de possession. Dans ce contexte, Power n'est pas seulement la plate-forme la plus stable et de meilleure qualit\u00e9, mais aussi la moins ch\u00e8re\".<\/em><\/p>\n<p>La flexibilit\u00e9 des syst\u00e8mes IBM Power permet d'ex\u00e9cuter plusieurs environnements en m\u00eame temps. Il est par exemple possible d'utiliser la capacit\u00e9 inutilis\u00e9e de l'environnement de production pour le d\u00e9veloppement ou pour les tests d'acceptation des utilisateurs.<\/p>\n<p>Par rapport \u00e0 la plupart des autres architectures, IBM Power permet donc d'obtenir une plus grande efficacit\u00e9 \u00e0 partir de ressources partag\u00e9es. IBM Power offre la r\u00e9silience que les clients Hana exigent pour les charges de travail critiques.<\/p>\n<p>Gr\u00e2ce aux caract\u00e9ristiques et aux fonctions de fiabilit\u00e9, de disponibilit\u00e9 et de facilit\u00e9 de maintenance de l'architecture Power, ces syst\u00e8mes conviennent parfaitement aux d\u00e9ploiements Hana.<\/p>\n<p>Cette solution combin\u00e9e prend \u00e9galement en charge un grand nombre de m\u00e9canismes, d'outils et de proc\u00e9dures diff\u00e9rents, notamment une prise en charge de premier ordre de la redondance et de la r\u00e9plication.<\/p>\n<h3>Int\u00e9gration de centres de donn\u00e9es sur mesure<\/h3>\n<p>Comme toujours, cela d\u00e9pend de la taille :<\/p>\n<p><em>\"Il peut toutefois y avoir des domaines, caract\u00e9ris\u00e9s par de petites bases de donn\u00e9es et un nombre d'applications raisonnable, o\u00f9 Intel est rentable. Mais la plupart du temps, ce n'est que dans l'approche TDI (Tailored Datacenter Integration) r\u00e9cemment recommand\u00e9e par SAP - pas en tant qu'appliance !\"<\/em><\/p>\n<p>Toute la plateforme Power est certifi\u00e9e pour Hana.<\/p>\n<p>\"Une fois pour toutes\"<\/p>\n<p>explique Andreas Span.<\/p>\n<p><em>\"Cela signifie que nous ne devons pas autoriser chaque serveur individuellement et le faire approuver \u00e0 nouveau au moindre changement, comme c'est le cas avec les appliances. <\/em><\/p>\n<p><em>Lorsque de nouvelles versions arrivent sur le march\u00e9 - comme Power 9 -, elles sont test\u00e9es ensemble d\u00e8s la phase de d\u00e9veloppement et, si tout se passe bien, le niveau de documentation de SAP est \u00e9lev\u00e9 en temps voulu\".<\/em><\/p>\n<p>SAP s'est fix\u00e9 comme objectif d'avoir converti tout et n'importe qui d'ici 2025 gr\u00e2ce \u00e0 la base de donn\u00e9es Hana, mais surtout en tant que plateforme.<\/p>\n<p><em>\"Pour cela, ils ont aussi besoin d'un partenaire qui leur offre des perspectives d'avenir comparables\".<\/em><\/p>\n<p>estime Span, directeur d'IBM, dans un entretien avec E-3.<\/p>\n<p><em>Ils ont ce partenaire avec nous\". En dehors de cela, le code pour Hana on Power et Intel a toujours \u00e9t\u00e9 presque identique - plus de 97 pour cent. Entre-temps, il n'y a qu'une seule ligne de d\u00e9veloppement pour les deux plates-formes, le code est identique et les dates de sortie sont simultan\u00e9es\".<\/em><\/p>\n<p>Une \u00e9tude du cabinet d'\u00e9tudes de march\u00e9 IDC le souligne \u00e0 juste titre :<\/p>\n<p><em>\"Le passage \u00e0 une plateforme in-memory SAP Hana est devenu moins compliqu\u00e9 qu'il y a quelques ann\u00e9es. <\/em><\/p>\n<p><em>De nombreuses entreprises ont d\u00e9j\u00e0 fait le premier pas en migrant vers SAP Business Warehouse sur Hana. BW est un bon point de d\u00e9part pour une \"base de donn\u00e9es en m\u00e9moire\" SAP Hana :<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" title=\"Le pouvoir \u00e0 la communaut\u00e9\" class=\"aligncenter size-full wp-image-59760\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/Hasso-Plattner-Sapphire.jpg\" alt=\"Hasso Plattner Sapphire\" width=\"1000\" height=\"509\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/Hasso-Plattner-Sapphire.jpg 1000w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/Hasso-Plattner-Sapphire-768x391.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/Hasso-Plattner-Sapphire-100x51.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/Hasso-Plattner-Sapphire-480x244.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/Hasso-Plattner-Sapphire-640x326.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/Hasso-Plattner-Sapphire-720x366.jpg 720w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/Hasso-Plattner-Sapphire-960x489.jpg 960w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p>IDC voit la situation du march\u00e9 de la m\u00eame mani\u00e8re :<\/p>\n<p><em>\"IBM est en train de se positionner en tant qu'expert Hana et S\/4, capable d'offrir un package complet - de la d\u00e9finition de la strat\u00e9gie et des sp\u00e9cifications fonctionnelles, en passant par IBM Global Business Services, jusqu'\u00e0 la mise en \u0153uvre et le d\u00e9ploiement de mat\u00e9riel bas\u00e9 sur Power, sur site et en tant que cloud hybride. <\/em><\/p>\n<p><em>En avril 2016 d\u00e9j\u00e0, IBM et SAP ont annonc\u00e9 un partenariat pour la transformation num\u00e9rique afin de cr\u00e9er ensemble des solutions innovantes autour des extensions cognitives, des exp\u00e9riences utilisateur et des fonctionnalit\u00e9s sp\u00e9cifiques \u00e0 l'industrie avec Hana et S\/4. <\/em><\/p>\n<p><em>Il y a plusieurs raisons qui font des syst\u00e8mes IBM Power une excellente plateforme pour Hana, avec en point de mire une flexibilit\u00e9, une r\u00e9silience et des performances de plateforme exceptionnelles\".<\/em><\/p>\n<p>Pour conclure, il convient de mentionner que les aspects commerciaux vont bien au-del\u00e0 de l'approche TCO purement arithm\u00e9tique. Un positionnement et une impl\u00e9mentation Hana pr\u00e9coces fournissent souvent un avantage concurrentiel et aident une entreprise \u00e0 se positionner strat\u00e9giquement pour l'avenir.<\/p>\n<p>IBM agit ici non seulement comme fournisseur d'infrastructure, mais aussi comme conseiller et accompagnateur d'un voyage qui ne fait que commencer. Car Hana n'est pas seulement une base de donn\u00e9es, mais une plate-forme ERP\/CRM en constante \u00e9volution pour S\/4, BW\/4 et C\/4.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/E-3-Magazin-Coverstory-1906.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" title=\"Le pouvoir \u00e0 la communaut\u00e9\" class=\"aligncenter wp-image-37442 size-full\" src=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/Download-Coverstory.jpg\" alt=\"T\u00e9l\u00e9charger l&#039;article de couverture\" width=\"1000\" height=\"125\" srcset=\"https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/Download-Coverstory.jpg 1000w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/Download-Coverstory-768x96.jpg 768w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/Download-Coverstory-100x13.jpg 100w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/Download-Coverstory-480x60.jpg 480w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/Download-Coverstory-640x80.jpg 640w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/Download-Coverstory-720x90.jpg 720w, https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2018\/04\/Download-Coverstory-960x120.jpg 960w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Dans un livre blanc publi\u00e9 au d\u00e9but de cette ann\u00e9e, les analystes de march\u00e9 d'IDC ont pos\u00e9 la question suivante : qui peut profiter de SAP Hana et S\/4 sur la base du syst\u00e8me de puissance d'IBM ? Entre-temps, de nombreuses exp\u00e9riences ont \u00e9t\u00e9 faites par des clients SAP existants et des partenaires, de sorte que la r\u00e9ponse est claire : tout le monde !<\/p>","protected":false},"author":2,"featured_media":59756,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[30554,30555],"tags":[647,65,10602,381,396,13893,7040,306],"coauthors":[27825],"class_list":["post-59755","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coverstory-1906","category-mag-1906","tag-google","tag-hana","tag-hpi","tag-in-memory","tag-intel","tag-nvidia","tag-virtualisierung","tag-vmware","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/shutterstock_316204241.jpg",1000,450,false],"thumbnail":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/shutterstock_316204241-150x150.jpg",150,150,true],"medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/shutterstock_316204241.jpg",400,180,false],"medium_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/shutterstock_316204241-768x346.jpg",768,346,true],"large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/shutterstock_316204241.jpg",1000,450,false],"image-100":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/shutterstock_316204241-100x45.jpg",100,45,true],"image-480":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/shutterstock_316204241-480x216.jpg",480,216,true],"image-640":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/shutterstock_316204241-640x288.jpg",640,288,true],"image-720":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/shutterstock_316204241-720x324.jpg",720,324,true],"image-960":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/shutterstock_316204241-960x432.jpg",960,432,true],"image-1168":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/shutterstock_316204241.jpg",1000,450,false],"image-1440":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/shutterstock_316204241.jpg",1000,450,false],"image-1920":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/shutterstock_316204241.jpg",1000,450,false],"1536x1536":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/shutterstock_316204241.jpg",1000,450,false],"2048x2048":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/shutterstock_316204241.jpg",1000,450,false],"trp-custom-language-flag":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/shutterstock_316204241.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/shutterstock_316204241.jpg",1000,450,false],"bricks_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/shutterstock_316204241.jpg",1000,450,false],"bricks_large_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/shutterstock_316204241.jpg",1000,450,false],"bricks_medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/shutterstock_316204241.jpg",600,270,false],"bricks_medium_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/shutterstock_316204241.jpg",600,270,false],"profile_24":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/shutterstock_316204241-24x24.jpg",24,24,true],"profile_48":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/shutterstock_316204241-48x48.jpg",48,48,true],"profile_96":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/shutterstock_316204241-96x96.jpg",96,96,true],"profile_150":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/shutterstock_316204241-150x150.jpg",150,150,true],"profile_300":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/05\/shutterstock_316204241-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>In einem White Paper von Anfang dieses Jahres stellten die Marktforscher von IDC die Frage: Wer kann von SAP Hana und S\/4 auf Basis des IBM-Power-Systems profitieren? Mittlerweile liegen zahlreiche Erfahrungen von SAP-Bestandskunden und Partnern vor, sodass die eindeutige Antwort lautet: Jeder!<\/p>\n","category_list_v2":"<a href=\"https:\/\/e326.greatsolution.dev\/fr\/categorie\/coverstories\/coverstory-1906\/\" rel=\"category tag\">Coverstory 19-06<\/a>, <a href=\"https:\/\/e326.greatsolution.dev\/fr\/categorie\/mag-1906\/\" rel=\"category tag\">MAG 19-06<\/a>","author_info_v2":{"name":"Peter M. F\u00e4rbinger, E3 Magazine","url":"https:\/\/e326.greatsolution.dev\/fr\/author\/peter-m-faerbinger-e-3-magazin\/"},"comments_num_v2":"0 commentaire","_links":{"self":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/posts\/59755","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/comments?post=59755"}],"version-history":[{"count":0,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/posts\/59755\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/media\/59756"}],"wp:attachment":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/media?parent=59755"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/categories?post=59755"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/tags?post=59755"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/coauthors?post=59755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}