{"id":60997,"date":"2016-03-03T11:40:52","date_gmt":"2016-03-03T10:40:52","guid":{"rendered":"https:\/\/e326.greatsolution.dev\/?p=60997"},"modified":"2019-07-12T12:24:40","modified_gmt":"2019-07-12T10:24:40","slug":"gerer-les-systemes-sap-dans-le-cloud-hybride","status":"publish","type":"post","link":"https:\/\/e326.greatsolution.dev\/fr\/gerer-les-systemes-sap-dans-le-cloud-hybride\/","title":{"rendered":"G\u00e9rer les syst\u00e8mes SAP dans le cloud hybride"},"content":{"rendered":"<p>De nombreuses entreprises sont actuellement confront\u00e9es \u00e0 la tendance du cloud computing. Dans l'environnement SAP en particulier, la pression est de plus en plus forte pour r\u00e9duire les co\u00fbts gr\u00e2ce \u00e0 l'utilisation de services en nuage.<\/p>\n<p>La premi\u00e8re r\u00e9action est souvent de mettre en place un cloud priv\u00e9 pour SAP. Les clouds priv\u00e9s pour SAP ne se distinguent pas seulement par une mise \u00e0 disposition \u00e9conomique des syst\u00e8mes SAP, mais souvent aussi par d'autres caract\u00e9ristiques pour la mise \u00e0 disposition et l'exploitation des syst\u00e8mes SAP.<\/p>\n<p>Souvent, les business units veulent avoir un acc\u00e8s rapide aux derniers syst\u00e8mes de test ou de formation. Dans l'exploitation traditionnelle des syst\u00e8mes SAP, la mise \u00e0 disposition de nouveaux syst\u00e8mes de test ou de formation fait partie des op\u00e9rations qui prennent beaucoup de temps.<\/p>\n<p>Dans un cloud priv\u00e9, cela doit \u00eatre \u00e9vit\u00e9 en permettant aux unit\u00e9s commerciales de commander de nouveaux syst\u00e8mes SAP via un portail central. Gr\u00e2ce \u00e0 une offre standardis\u00e9e, on ne r\u00e9pond pas forc\u00e9ment \u00e0 toutes les exigences, mais les syst\u00e8mes SAP sont livr\u00e9s rapidement gr\u00e2ce \u00e0 un processus de d\u00e9ploiement automatis\u00e9.<\/p>\n<p>Alors que dans l'environnement traditionnel, les syst\u00e8mes SAP sont souvent cr\u00e9\u00e9s et livr\u00e9s manuellement par diff\u00e9rentes \u00e9quipes, dans l'environnement Private Cloud, cela doit se faire de mani\u00e8re automatis\u00e9e. Ici, un haut degr\u00e9 d'automatisation est une n\u00e9cessit\u00e9 absolue. Cela ne concerne pas seulement la mise \u00e0 disposition, mais aussi des activit\u00e9s telles que les copies automatiques du syst\u00e8me ou les rafra\u00eechissements du syst\u00e8me.<\/p>\n<p>SAP Landscape Virtualization Management est une solution qui permet au client d'offrir exactement ces fonctionnalit\u00e9s. SAP LVM n'est pas une nouvelle solution, mais se base sur le contr\u00f4leur informatique adaptatif SAP et est d\u00e9j\u00e0 disponible depuis quelques ann\u00e9es pour les clients SAP.<\/p>\n<p>SAP LVM est licenci\u00e9 en deux \u00e9ditions, qui d\u00e9terminent l'\u00e9tendue des fonctions. L'\u00e9dition Standard propose toutes les fonctionnalit\u00e9s essentielles pour l'exploitation d'un propre cloud priv\u00e9, tandis que l'\u00e9dition Enterprise offre des cas d'utilisation \u00e9tendus.<\/p>\n<p>SAP LVM s'int\u00e8gre via les agents h\u00f4tes SAP et peut ainsi contr\u00f4ler les syst\u00e8mes SAP. Les t\u00e2ches \u00e9l\u00e9mentaires de SAP LVM sont les suivantes.<\/p>\n<h3>Marche\/Arr\u00eat\/Relocaliser<\/h3>\n<p>Gr\u00e2ce \u00e0 SAP LVM, les clients peuvent d\u00e9marrer, arr\u00eater et d\u00e9placer des syst\u00e8mes SAP. Le d\u00e9m\u00e9nagement de syst\u00e8mes SAP est possible d'un serveur \u00e0 un autre. Cela peut se faire aussi bien d'une machine virtuelle \u00e0 une autre VM que d'un serveur physique \u00e0 un autre serveur physique.<\/p>\n<p>Les syst\u00e8mes SAP peuvent ainsi \u00eatre d\u00e9plac\u00e9s facilement. SAP LVM propose \u00e9galement l'ex\u00e9cution en masse de ces op\u00e9rations.<\/p>\n<p>D\u00e9marrage\/provisionnement dynamique des instances : Si n\u00e9cessaire, les instances de dialogue peuvent \u00eatre sorties de l'\u00e9tat de repos et d\u00e9marr\u00e9es. Habituellement, cela se fait avant un changement de mois afin de mettre \u00e0 disposition des capacit\u00e9s suppl\u00e9mentaires qui ne sont pas utilis\u00e9es en fonctionnement normal.<\/p>\n<p>Des serveurs d'applications suppl\u00e9mentaires peuvent \u00eatre provisionn\u00e9s de mani\u00e8re dynamique via SAP LVM. Les fonctionnalit\u00e9s de l'\u00e9dition Enterprise \u00e9largissent toutefois consid\u00e9rablement la liste des cas d'utilisation. Il s'agit notamment des cas d'utilisation relatifs \u00e0 l'int\u00e9gration avec les fabricants de solutions de stockage et de virtualisation.<\/p>\n<p>Les clients peuvent ainsi tr\u00e8s facilement mettre en place des clonages ou des rafra\u00eechissements de syst\u00e8mes et simplifier ainsi consid\u00e9rablement le d\u00e9ploiement de nouveaux syst\u00e8mes SAP, par exemple pour des syst\u00e8mes de formation ou de test.<\/p>\n<p>SAP LVM peut \u00e9galement recourir aux fonctionnalit\u00e9s des fabricants de stockage ou de virtualisation. Ainsi, de nouveaux syst\u00e8mes peuvent \u00eatre cr\u00e9\u00e9s en quelques minutes par clonage sur la base de snapshots de stockage.<\/p>\n<p>C'est le degr\u00e9 d'automatisation dont les clients ont besoin dans un cloud priv\u00e9 pour SAP. L'objectif est de mettre \u00e0 disposition des business units de nouveaux syst\u00e8mes SAP de mani\u00e8re rapide et confortable. Cela est tout \u00e0 fait possible avec SAP LVM. Un tr\u00e8s bon aper\u00e7u de tous les cas d'utilisation des deux \u00e9ditions peut \u00eatre trouv\u00e9 sous le lien suivant :<\/p>\n<p><a href=\"https:\/\/help.sap.com\/nwlvm\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/help.sap.com\/nwlvm<\/a> - outre les fonctionnalit\u00e9s visant \u00e0 simplifier l'exploitation de son propre cloud priv\u00e9, SAP LVM permet \u00e9galement de connecter des ressources provenant du cloud Amazon. La configuration est tr\u00e8s simple. Il suffit d'ouvrir un compte Amazon.<\/p>\n<p>D\u00e8s que le compte est configur\u00e9, de nouvelles ressources peuvent \u00eatre ajout\u00e9es et utilis\u00e9es de mani\u00e8re dynamique dans un paysage SAP. Dans ce cas, le SAP LVM peut prendre en charge et coordonner le contr\u00f4le des ressources du cloud Amazon. Tous les syst\u00e8mes SAP cr\u00e9\u00e9s dans le cloud Amazon sont int\u00e9gr\u00e9s dans le paysage comme des ressources sur site.<\/p>\n<p>En utilisant les ressources bas\u00e9es sur Amazon, le paysage peut ainsi passer d'un cloud priv\u00e9 \u00e0 un cloud hybride. SAP LVM fait office de pont.<\/p>\n<p>Cela pr\u00e9sente un avantage d\u00e9cisif pour les clients SAP : le lien entre l'environnement sur site et l'environnement en nuage est un morceau de logiciel de SAP, et donc le support et l'assistance de SAP existent pour ce sc\u00e9nario.<\/p>\n<p>Les clients qui utilisent SAP LVM peuvent ainsi effectuer une simple transition vers le cloud public et passer au sc\u00e9nario du cloud hybride.<\/p>","protected":false},"excerpt":{"rendered":"<p>Avoir son propre cloud priv\u00e9 peut grandement simplifier l'h\u00e9bergement des syst\u00e8mes SAP et ouvrir la voie au cloud hybride. La gestion de la virtualisation de SAP Landscape aide \u00e0 connecter les ressources du cloud public et simplifie la gestion dans le cloud priv\u00e9. <\/p>","protected":false},"author":1789,"featured_media":60767,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[5,1603],"tags":[145,621,5009,5010,236,7040],"coauthors":[32373],"class_list":["post-60997","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-it-management","category-mag1603","tag-automatisierung","tag-cloud-computing","tag-private-cloud","tag-public-cloud","tag-sap","tag-virtualisierung","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016.jpg",1000,387,false],"thumbnail":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016-150x150.jpg",150,150,true],"medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016.jpg",400,155,false],"medium_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016-768x297.jpg",768,297,true],"large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016.jpg",1000,387,false],"image-100":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016-100x39.jpg",100,39,true],"image-480":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016-480x186.jpg",480,186,true],"image-640":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016-640x248.jpg",640,248,true],"image-720":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016-720x279.jpg",720,279,true],"image-960":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016-960x372.jpg",960,372,true],"image-1168":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016.jpg",1000,387,false],"image-1440":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016.jpg",1000,387,false],"image-1920":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016.jpg",1000,387,false],"1536x1536":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016.jpg",1000,387,false],"2048x2048":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016.jpg",1000,387,false],"trp-custom-language-flag":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016.jpg",18,7,false],"bricks_large_16x9":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016.jpg",1000,387,false],"bricks_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016.jpg",1000,387,false],"bricks_large_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016.jpg",1000,387,false],"bricks_medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016.jpg",600,232,false],"bricks_medium_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016.jpg",600,232,false],"profile_24":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016-24x24.jpg",24,24,true],"profile_48":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016-48x48.jpg",48,48,true],"profile_96":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016-96x96.jpg",96,96,true],"profile_150":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016-150x150.jpg",150,150,true],"profile_300":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2016-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Eine eigene Private Cloud kann das Hosting von SAP-Systemen stark vereinfachen und den Weg in die Hybrid Cloud ebnen. Das SAP Landscape Virtualization Management hilft bei der Anbindung von Ressourcen aus der Public Cloud und vereinfacht das Management in der Private Cloud. <\/p>\n","category_list_v2":"<a href=\"https:\/\/e326.greatsolution.dev\/fr\/categorie\/gestion-de-linformatique\/\" rel=\"category tag\">IT-Management<\/a>, <a href=\"https:\/\/e326.greatsolution.dev\/fr\/categorie\/mag1603\/\" rel=\"category tag\">MAG 16-03<\/a>","author_info_v2":{"name":"Andr\u00e9 B\u00f6gelsack, Accenture","url":"https:\/\/e326.greatsolution.dev\/fr\/author\/andre-boegelsack\/"},"comments_num_v2":"0 commentaire","_links":{"self":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/posts\/60997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/users\/1789"}],"replies":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/comments?post=60997"}],"version-history":[{"count":0,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/posts\/60997\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/media\/60767"}],"wp:attachment":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/media?parent=60997"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/categories?post=60997"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/tags?post=60997"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/coauthors?post=60997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}