{"id":70066,"date":"2020-12-07T08:00:00","date_gmt":"2020-12-07T07:00:00","guid":{"rendered":"https:\/\/e326.greatsolution.dev\/?p=70066"},"modified":"2020-12-03T09:34:21","modified_gmt":"2020-12-03T08:34:21","slug":"manque-de-confiance-et-de-conscience-du-probleme","status":"publish","type":"post","link":"https:\/\/e326.greatsolution.dev\/fr\/manque-de-confiance-et-de-conscience-du-probleme\/","title":{"rendered":"Manque de confiance et de conscience du probl\u00e8me"},"content":{"rendered":"<p>L'une des raisons est que seulement 53 % des organisations disposent d'un cadre sup\u00e9rieur responsable de l'\u00e9thique et de la fiabilit\u00e9 des syst\u00e8mes d'IA. Parall\u00e8lement, les consommateurs sont moins nombreux que l'ann\u00e9e derni\u00e8re (62 % au lieu de 76 %) \u00e0 penser que les entreprises font preuve d'une transparence totale quant \u00e0 la mani\u00e8re dont les donn\u00e9es personnelles sont utilis\u00e9es. <\/p>\n\n\n\n<p>L'\u00e9tude \"AI and the Ethical Conundrum : How organizations can build ethically robust AI systems and gain trust\" de Capgemini parvient \u00e0 ces conclusions et \u00e0 d'autres. Elle souligne \u00e9galement qu'il est essentiel de se concentrer sur les aspects \u00e9thiques pour exploiter le potentiel de transformation de l'IA pour l'environnement, l'\u00e9conomie et la soci\u00e9t\u00e9. <\/p>\n\n\n\n<p>Les organisations sont de plus en plus conscientes de la n\u00e9cessit\u00e9 d'agir en ce qui concerne les syst\u00e8mes d'IA \u00e9thiques : 45 % ont d\u00e9fini une charte d'IA en 2020 (5 % en 2019) et deux tiers (65 %) des dirigeants sont conscients que les syst\u00e8mes d'IA peuvent potentiellement conduire \u00e0 des d\u00e9cisions discriminatoires. De nombreuses institutions publiques et priv\u00e9es ont introduit des technologies d'IA suppl\u00e9mentaires pour faire face aux cons\u00e9quences de la pand\u00e9mie de coronavirus. <\/p>\n\n\n\n<p>La confiance des consommateurs dans les interactions de l'IA sera donc d'autant plus importante \u00e0 l'avenir. Au cours des trois derni\u00e8res ann\u00e9es, 22 % des entreprises ont \u00e9t\u00e9 confront\u00e9es \u00e0 des clients qui remettent en question les d\u00e9cisions bas\u00e9es sur l'IA ou qui souhaitent comprendre le processus d\u00e9cisionnel. <\/p>\n\n\n\n<p>Il s'agit l\u00e0 d'un risque de r\u00e9ussite, car 45 % des clients partagent des exp\u00e9riences n\u00e9gatives avec leur entourage et les incitent \u00e0 ne pas interagir avec les entreprises concern\u00e9es.<\/p>","protected":false},"excerpt":{"rendered":"<p>Les entreprises et les administrations sont de plus en plus conscientes des questions \u00e9thiques li\u00e9es \u00e0 l'utilisation de l'intelligence artificielle (IA). Le bilan des actions men\u00e9es cette ann\u00e9e est mitig\u00e9. <\/p>","protected":false},"author":38,"featured_media":70067,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[2,38353],"tags":[625,650,624,626],"coauthors":[19920],"class_list":["post-70066","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sap-nachrichten","category-mag-20-11","tag-ai","tag-artificial-intelligence","tag-ki","tag-kuenstliche-intelligenz","pmpro-has-access"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2020\/11\/shutterstock_1273562923.jpg",1000,450,false],"thumbnail":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2020\/11\/shutterstock_1273562923-150x150.jpg",150,150,true],"medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2020\/11\/shutterstock_1273562923.jpg",400,180,false],"medium_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2020\/11\/shutterstock_1273562923-768x346.jpg",768,346,true],"large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2020\/11\/shutterstock_1273562923.jpg",1000,450,false],"image-100":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2020\/11\/shutterstock_1273562923-100x45.jpg",100,45,true],"image-480":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2020\/11\/shutterstock_1273562923-480x216.jpg",480,216,true],"image-640":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2020\/11\/shutterstock_1273562923-640x288.jpg",640,288,true],"image-720":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2020\/11\/shutterstock_1273562923-720x324.jpg",720,324,true],"image-960":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2020\/11\/shutterstock_1273562923-960x432.jpg",960,432,true],"image-1168":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2020\/11\/shutterstock_1273562923.jpg",1000,450,false],"image-1440":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2020\/11\/shutterstock_1273562923.jpg",1000,450,false],"image-1920":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2020\/11\/shutterstock_1273562923.jpg",1000,450,false],"1536x1536":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2020\/11\/shutterstock_1273562923.jpg",1000,450,false],"2048x2048":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2020\/11\/shutterstock_1273562923.jpg",1000,450,false],"trp-custom-language-flag":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2020\/11\/shutterstock_1273562923.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2020\/11\/shutterstock_1273562923.jpg",1000,450,false],"bricks_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2020\/11\/shutterstock_1273562923.jpg",1000,450,false],"bricks_large_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2020\/11\/shutterstock_1273562923.jpg",1000,450,false],"bricks_medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2020\/11\/shutterstock_1273562923.jpg",600,270,false],"bricks_medium_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2020\/11\/shutterstock_1273562923.jpg",600,270,false],"profile_24":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2020\/11\/shutterstock_1273562923-24x24.jpg",24,24,true],"profile_48":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2020\/11\/shutterstock_1273562923-48x48.jpg",48,48,true],"profile_96":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2020\/11\/shutterstock_1273562923-96x96.jpg",96,96,true],"profile_150":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2020\/11\/shutterstock_1273562923-150x150.jpg",150,150,true],"profile_300":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2020\/11\/shutterstock_1273562923-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Das Bewusstsein f\u00fcr ethische Fragestellungen beim Einsatz von k\u00fcnstlicher Intelligenz (KI) ist in Unternehmen und Verwaltungen gestiegen. Die diesj\u00e4hrige Handlungsbilanz f\u00e4llt gemischt aus. <\/p>\n","category_list_v2":"<a href=\"https:\/\/e326.greatsolution.dev\/fr\/categorie\/sap-nouvelles\/\" rel=\"category tag\">Community Nachrichten<\/a>, <a href=\"https:\/\/e326.greatsolution.dev\/fr\/categorie\/mag-20-11\/\" rel=\"category tag\">MAG 20-11<\/a>","author_info_v2":{"name":"Magazine E-3","url":"https:\/\/e326.greatsolution.dev\/fr\/author\/e-3-magazin\/"},"comments_num_v2":"0 commentaire","_links":{"self":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/posts\/70066","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/comments?post=70066"}],"version-history":[{"count":0,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/posts\/70066\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/media\/70067"}],"wp:attachment":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/media?parent=70066"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/categories?post=70066"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/tags?post=70066"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/coauthors?post=70066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}