{"id":117012,"date":"2022-08-17T15:47:12","date_gmt":"2022-08-17T13:47:12","guid":{"rendered":"https:\/\/e326.greatsolution.dev\/?post_type=tribe_events&#038;p=117012"},"modified":"2022-08-25T20:25:43","modified_gmt":"2022-08-25T18:25:43","slug":"xsuite-public-sector-event","status":"publish","type":"tribe_events","link":"https:\/\/e326.greatsolution.dev\/fr\/evenement\/xsuite-public-sector-event\/","title":{"rendered":"xSuite Public Sector Event"},"content":{"rendered":"<p>Num\u00e9risation, moins de papier, plus d'intelligence artificielle et de cloud - autant d'\u00e9l\u00e9ments qui permettent aux pouvoirs publics d'introduire la standardisation dans leurs processus comptables et de les optimiser consid\u00e9rablement. Ce qui est techniquement possible et ce qui est d\u00e9j\u00e0 pratiqu\u00e9 avec succ\u00e8s au quotidien, c'est ce que la xSuite explique sur son site web.\u00a0<strong><a href=\"https:\/\/news.xsuite.com\/public-sector-event-2022\" target=\"_blank\" rel=\"noopener\">\u00c9v\u00e9nement du secteur public<\/a><\/strong>\u00a0sur le site <strong>22 septembre 2022 \u00e0 Hambourg<\/strong>. L'accent est mis sur le traitement des factures entrantes comme sc\u00e9nario d'entr\u00e9e pour la num\u00e9risation et l'automatisation.<\/p>\n<p>Des clients et des experts de xSuite parleront de la num\u00e9risation et de l'automatisation des processus commerciaux chez les donneurs d'ordre publics, les communes et les administrations. Les participants auront un aper\u00e7u de la feuille de route strat\u00e9gique des produits de xSuite et un aper\u00e7u des technologies telles que S\/4HANA, le cloud et l'intelligence artificielle.<\/p>\n<p>Les pouvoirs adjudicateurs apprennent en outre \u00e0 quoi ils doivent accorder une attention particuli\u00e8re lors de la num\u00e9risation de remplacement, de la documentation des proc\u00e9dures et d'un archivage conforme \u00e0 la GoBD des documents lisibles par machine.<br \/>\nLa journ\u00e9e se terminera par une soir\u00e9e commune au Quai 10 (\u00e0 partir de 18h00).<\/p>\n<p>Co\u00fbts :<br \/>\nPour les clients disposant d'un contrat de maintenance en cours de validit\u00e9, les frais de participation sont inclus dans les frais de maintenance pour un maximum de 3 personnes. Pour les autres employ\u00e9s des clients ainsi que pour les employ\u00e9s des entreprises int\u00e9ress\u00e9es, des frais de 49,90 \u20ac par personne s'appliquent.<\/p>\n<p><strong>Action Early Bird :<\/strong>\u00a0Les frais de participation d'un montant de 49,90 \u20ac par personne sont supprim\u00e9s pour les inscriptions fermes effectu\u00e9es avant le 15.09.2022.<\/p>\n<p><strong><a href=\"https:\/\/news.xsuite.com\/public-sector-event-2022\" target=\"_blank\" rel=\"noopener\">Vers l'inscription<\/a><\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Num\u00e9risation, moins de papier, plus d'intelligence artificielle et de cloud - autant d'\u00e9l\u00e9ments qui permettent aux donneurs d'ordre publics d'introduire la standardisation dans leurs processus comptables et de les optimiser ainsi consid\u00e9rablement. Ce qui est techniquement possible et qui est d\u00e9j\u00e0 pratiqu\u00e9 avec succ\u00e8s au quotidien, c'est ce que xSuite informera lors de son Public-Sector-Event le 22 septembre 2022 \u00e0 Hambourg. L'accent sera mis sur le traitement des factures entrantes comme sc\u00e9nario d'entr\u00e9e pour la num\u00e9risation et [...].<\/p>","protected":false},"author":38,"featured_media":117013,"template":"","meta":{"_acf_changed":false,"pmpro_default_level":"","_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[41690],"coauthors":[19920],"class_list":["post-117012","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-fachtagung","pmpro-has-access","cat_fachtagung"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2022\/08\/2022-09_xSuite_titelbild.jpeg",747,289,false],"thumbnail":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2022\/08\/2022-09_xSuite_titelbild-80x80.jpeg",80,80,true],"medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2022\/08\/2022-09_xSuite_titelbild.jpeg",400,155,false],"medium_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2022\/08\/2022-09_xSuite_titelbild.jpeg",747,289,false],"large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2022\/08\/2022-09_xSuite_titelbild.jpeg",747,289,false],"image-100":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2022\/08\/2022-09_xSuite_titelbild-100x39.jpeg",100,39,true],"image-480":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2022\/08\/2022-09_xSuite_titelbild-480x186.jpeg",480,186,true],"image-640":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2022\/08\/2022-09_xSuite_titelbild-640x248.jpeg",640,248,true],"image-720":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2022\/08\/2022-09_xSuite_titelbild-720x279.jpeg",720,279,true],"image-960":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2022\/08\/2022-09_xSuite_titelbild.jpeg",747,289,false],"image-1168":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2022\/08\/2022-09_xSuite_titelbild.jpeg",747,289,false],"image-1440":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2022\/08\/2022-09_xSuite_titelbild.jpeg",747,289,false],"image-1920":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2022\/08\/2022-09_xSuite_titelbild.jpeg",747,289,false],"1536x1536":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2022\/08\/2022-09_xSuite_titelbild.jpeg",747,289,false],"2048x2048":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2022\/08\/2022-09_xSuite_titelbild.jpeg",747,289,false],"trp-custom-language-flag":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2022\/08\/2022-09_xSuite_titelbild.jpeg",18,7,false],"bricks_large_16x9":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2022\/08\/2022-09_xSuite_titelbild.jpeg",747,289,false],"bricks_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2022\/08\/2022-09_xSuite_titelbild.jpeg",747,289,false],"bricks_large_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2022\/08\/2022-09_xSuite_titelbild.jpeg",747,289,false],"bricks_medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2022\/08\/2022-09_xSuite_titelbild.jpeg",600,232,false],"bricks_medium_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2022\/08\/2022-09_xSuite_titelbild.jpeg",600,232,false],"profile_24":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2022\/08\/2022-09_xSuite_titelbild-24x24.jpeg",24,24,true],"profile_48":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2022\/08\/2022-09_xSuite_titelbild-48x48.jpeg",48,48,true],"profile_96":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2022\/08\/2022-09_xSuite_titelbild-96x96.jpeg",96,96,true],"profile_150":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2022\/08\/2022-09_xSuite_titelbild-150x150.jpeg",150,150,true],"profile_300":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2022\/08\/2022-09_xSuite_titelbild-300x289.jpeg",300,289,true]},"post_excerpt_stackable_v2":"<p>Digitalisierung, weniger Papier, mehr K\u00fcnstliche Intelligenz und Cloud \u2013 damit k\u00f6nnen \u00f6ffentliche Auftraggeber Standardisierung in ihre Buchhaltungsprozesse bringen und sie dadurch deutlich optimieren. Was technisch m\u00f6glich ist und bereits erfolgreich im Alltag praktiziert wird, dar\u00fcber informiert die xSuite auf ihrem\u00a0Public-Sector-Event\u00a0am 22. September 2022 in Hamburg. Im Mittelpunkt steht die Eingangsrechnungsverarbeitung als Einstiegszenario f\u00fcr Digitalisierung und Automatisierung. \u00dcber die Digitalisierung und Automatisierung der kaufm\u00e4nnischen Prozesse bei \u00f6ffentlichen Auftraggebern, Kommunen und Verwaltungen berichten Kunden und Experten der xSuite. Die Teilnehmenden erhalten einen Einblick in die strategische Produkt-Roadmap von xSuite und einen Ausblick zu Technologien wie S\/4HANA, Cloud und K\u00fcnstliche Intelligenz. \u00d6ffentliche Auftraggeber\u2026<\/p>\n","category_list_v2":"","author_info_v2":{"name":"Magazine E-3","url":"https:\/\/e326.greatsolution.dev\/fr\/author\/e-3-magazin\/"},"comments_num_v2":"0 commentaire","_links":{"self":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/tribe_events\/117012","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/users\/38"}],"version-history":[{"count":0,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/tribe_events\/117012\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/media\/117013"}],"wp:attachment":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/media?parent=117012"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/tags?post=117012"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/tribe_events_cat?post=117012"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/coauthors?post=117012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}