{"id":131993,"date":"2023-08-30T12:53:40","date_gmt":"2023-08-30T10:53:40","guid":{"rendered":"https:\/\/e326.greatsolution.dev\/?post_type=tribe_events&#038;p=131993"},"modified":"2024-01-24T09:28:32","modified_gmt":"2024-01-24T08:28:32","slug":"world-class-workforce-transformation-2024","status":"publish","type":"tribe_events","link":"https:\/\/e326.greatsolution.dev\/fr\/evenement\/world-class-workforce-transformation-2024\/","title":{"rendered":"Transformation de la main-d'\u0153uvre de classe mondiale en 2024"},"content":{"rendered":"<p>Cette ann\u00e9e, la 7e \u00e9dition de la conf\u00e9rence World Class Workforce Transformation vous surprendra par la vari\u00e9t\u00e9 des sujets abord\u00e9s, qui vous donneront de nouvelles perspectives et id\u00e9es essentielles pour les RH et la gestion du changement, pour vous et votre entreprise. Les leaders europ\u00e9ens parleront des nouvelles m\u00e9thodes de formation, de l'agilit\u00e9, de l'engagement des employ\u00e9s et de bien d'autres choses encore.<br \/>\nEn r\u00e9unissant des d\u00e9cideurs de haut niveau issus de diff\u00e9rents secteurs, vous aurez l'occasion d'apprendre de leurs exp\u00e9riences et de leurs d\u00e9fis et de discuter de nouvelles possibilit\u00e9s pour l'avenir du travail.<br \/>\nVous ne pouvez pas le manquer.<\/p>\n<p><a href=\"https:\/\/www.worldclassbusinessleaders.com\/events\/WCCTCM24?utm_source=Listing&amp;utm_medium=WCCTCM24&amp;utm_campaign=E3Mag+\" target=\"_blank\" rel=\"noopener\">Cliquez ici pour vous inscrire.<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Cette ann\u00e9e, la 7e \u00e9dition de la conf\u00e9rence World Class Workforce Transformation vous surprendra par la vari\u00e9t\u00e9 des sujets abord\u00e9s, qui vous donneront de nouvelles perspectives et id\u00e9es essentielles pour les RH et la gestion du changement, pour vous et votre entreprise. Les leaders europ\u00e9ens parleront de nouvelles m\u00e9thodes de formation, d'agilit\u00e9, d'engagement des employ\u00e9s et de bien d'autres choses encore. [...]<\/p>","protected":false},"author":2713,"featured_media":131998,"template":"","meta":{"_acf_changed":false,"pmpro_default_level":"","_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[293],"tribe_events_cat":[42124],"coauthors":[43310],"class_list":["post-131993","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tag-business","tribe_events_cat-event","pmpro-has-access","cat_event"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/08\/World-Class-Workforce-Transformation-2024.jpg",747,289,false],"thumbnail":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/08\/World-Class-Workforce-Transformation-2024-150x150.jpg",150,150,true],"medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/08\/World-Class-Workforce-Transformation-2024-400x155.jpg",400,155,true],"medium_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/08\/World-Class-Workforce-Transformation-2024.jpg",747,289,false],"large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/08\/World-Class-Workforce-Transformation-2024.jpg",747,289,false],"image-100":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/08\/World-Class-Workforce-Transformation-2024-100x39.jpg",100,39,true],"image-480":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/08\/World-Class-Workforce-Transformation-2024-480x186.jpg",480,186,true],"image-640":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/08\/World-Class-Workforce-Transformation-2024-640x248.jpg",640,248,true],"image-720":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/08\/World-Class-Workforce-Transformation-2024-720x279.jpg",720,279,true],"image-960":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/08\/World-Class-Workforce-Transformation-2024.jpg",747,289,false],"image-1168":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/08\/World-Class-Workforce-Transformation-2024.jpg",747,289,false],"image-1440":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/08\/World-Class-Workforce-Transformation-2024.jpg",747,289,false],"image-1920":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/08\/World-Class-Workforce-Transformation-2024.jpg",747,289,false],"1536x1536":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/08\/World-Class-Workforce-Transformation-2024.jpg",747,289,false],"2048x2048":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/08\/World-Class-Workforce-Transformation-2024.jpg",747,289,false],"trp-custom-language-flag":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/08\/World-Class-Workforce-Transformation-2024-18x7.jpg",18,7,true],"bricks_large_16x9":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/08\/World-Class-Workforce-Transformation-2024.jpg",747,289,false],"bricks_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/08\/World-Class-Workforce-Transformation-2024.jpg",747,289,false],"bricks_large_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/08\/World-Class-Workforce-Transformation-2024.jpg",747,289,false],"bricks_medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/08\/World-Class-Workforce-Transformation-2024-600x232.jpg",600,232,true],"bricks_medium_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/08\/World-Class-Workforce-Transformation-2024-600x289.jpg",600,289,true],"profile_24":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/08\/World-Class-Workforce-Transformation-2024-24x24.jpg",24,24,true],"profile_48":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/08\/World-Class-Workforce-Transformation-2024-48x48.jpg",48,48,true],"profile_96":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/08\/World-Class-Workforce-Transformation-2024-96x96.jpg",96,96,true],"profile_150":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/08\/World-Class-Workforce-Transformation-2024-150x150.jpg",150,150,true],"profile_300":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2023\/08\/World-Class-Workforce-Transformation-2024-300x289.jpg",300,289,true]},"post_excerpt_stackable_v2":"<p>This year, the 7th edition of the World Class Workforce Transformation conference will surprise you with various topics that will give you new perspectives and ideas that are crucial for HR and Change management, for you, and your business. Europe\u2019s leaders will talk about cutting-edge new ways of training, agility, employee engagement, and much more. As we bring together senior decision-makers from various industries, you will have a chance to learn from their experiences and challenges and discuss new possibilities for the future of work. You can\u2019t miss it. Click here to sign up.<\/p>\n","category_list_v2":"","author_info_v2":{"name":"Laura Cepeda","url":"https:\/\/e326.greatsolution.dev\/fr\/author\/laura-cepeda\/"},"comments_num_v2":"0 commentaire","_links":{"self":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/tribe_events\/131993","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/users\/2713"}],"version-history":[{"count":5,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/tribe_events\/131993\/revisions"}],"predecessor-version":[{"id":132006,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/tribe_events\/131993\/revisions\/132006"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/media\/131998"}],"wp:attachment":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/media?parent=131993"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/tags?post=131993"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/tribe_events_cat?post=131993"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/coauthors?post=131993"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}