{"id":155560,"date":"2025-09-17T16:11:43","date_gmt":"2025-09-17T14:11:43","guid":{"rendered":"https:\/\/e326.greatsolution.dev\/?post_type=tribe_events&#038;p=155560"},"modified":"2025-09-17T16:11:43","modified_gmt":"2025-09-17T14:11:43","slug":"snap-zipped-2025-latelier-technologique-sap","status":"publish","type":"tribe_events","link":"https:\/\/e326.greatsolution.dev\/fr\/evenement\/snap-zipped-2025-latelier-technologique-sap\/","title":{"rendered":"snap zipped 2025 - L'atelier technologique SAP"},"content":{"rendered":"<p>Vivez une journ\u00e9e de transfert de connaissances avec un lien pratique autour des th\u00e8mes SAP KI et Clean Core. Des experts* exp\u00e9riment\u00e9s pr\u00e9senteront les d\u00e9veloppements actuels, montreront des solutions fond\u00e9es et transmettront un savoir-faire technologique sur mesure dans le cadre d'ateliers. Profitez de ces impulsions concr\u00e8tes et savourez cette journ\u00e9e informative \u00e0 Vienne, qui se terminera par un d\u00eener gastronomique en commun.<\/p>\n<p>\u00c9v\u00e9nement gratuit, inscription obligatoire.<\/p>\n<p>\u27a1<a href=\"https:\/\/www.snapconsult.com\/snap-zipped-2025?mtm_campaign=e3_eventpromo_2025&amp;mtm_source=e3_website#c3530\" target=\"_blank\" rel=\"noopener\">Vers l'inscription.<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Vivez une journ\u00e9e de transfert de connaissances avec un lien pratique autour des th\u00e8mes SAP KI et Clean Core. Des experts* exp\u00e9riment\u00e9s pr\u00e9senteront les d\u00e9veloppements actuels, montreront des solutions fond\u00e9es et transmettront un savoir-faire technologique sur mesure dans le cadre d'ateliers. Profitez de ces impulsions concr\u00e8tes et savourez cette journ\u00e9e informative \u00e0 Vienne, qui se terminera par un d\u00eener gastronomique en commun. Manifestation gratuite, inscription [...].<\/p>","protected":false},"author":2713,"featured_media":155562,"template":"","meta":{"_acf_changed":false,"pmpro_default_level":"","_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[42837],"coauthors":[43310],"class_list":["post-155560","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-sonstiges","pmpro-has-access","cat_sonstiges"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/09\/snap_zipped_2025.jpg",1200,676,false],"thumbnail":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/09\/snap_zipped_2025-150x150.jpg",150,150,true],"medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/09\/snap_zipped_2025-400x225.jpg",400,225,true],"medium_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/09\/snap_zipped_2025-768x433.jpg",768,433,true],"large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/09\/snap_zipped_2025.jpg",1200,676,false],"image-100":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/09\/snap_zipped_2025-100x56.jpg",100,56,true],"image-480":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/09\/snap_zipped_2025-480x270.jpg",480,270,true],"image-640":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/09\/snap_zipped_2025-640x361.jpg",640,361,true],"image-720":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/09\/snap_zipped_2025-720x406.jpg",720,406,true],"image-960":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/09\/snap_zipped_2025-960x541.jpg",960,541,true],"image-1168":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/09\/snap_zipped_2025-1168x658.jpg",1168,658,true],"image-1440":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/09\/snap_zipped_2025.jpg",1200,676,false],"image-1920":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/09\/snap_zipped_2025.jpg",1200,676,false],"1536x1536":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/09\/snap_zipped_2025.jpg",1200,676,false],"2048x2048":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/09\/snap_zipped_2025.jpg",1200,676,false],"trp-custom-language-flag":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/09\/snap_zipped_2025-18x10.jpg",18,10,true],"bricks_large_16x9":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/09\/snap_zipped_2025.jpg",1198,675,false],"bricks_large":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/09\/snap_zipped_2025.jpg",1200,676,false],"bricks_large_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/09\/snap_zipped_2025.jpg",1200,676,false],"bricks_medium":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/09\/snap_zipped_2025-600x338.jpg",600,338,true],"bricks_medium_square":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/09\/snap_zipped_2025-600x600.jpg",600,600,true],"profile_24":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/09\/snap_zipped_2025-24x24.jpg",24,24,true],"profile_48":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/09\/snap_zipped_2025-48x48.jpg",48,48,true],"profile_96":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/09\/snap_zipped_2025-96x96.jpg",96,96,true],"profile_150":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/09\/snap_zipped_2025-150x150.jpg",150,150,true],"profile_300":["https:\/\/e326.greatsolution.dev\/wp-content\/uploads\/2025\/09\/snap_zipped_2025-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Erleben Sie einen Tag lang Wissenstransfer mit Praxisbezug rund um die Themen SAP KI und Clean Core. Erfahrene Expert*innen pr\u00e4sentieren aktuelle Entwicklungen, zeigen fundierte L\u00f6sungen und vermitteln in Workshops ma\u00dfgeschneidertes Tech-Know-how. Profitieren Sie von den konkreten Impulsen und genie\u00dfen Sie diesen informativen Tag in Wien, der mit einem gemeinsamen Abendessen kulinarisch ausklingt. Kostenfreie Veranstaltung, Anmeldung erforderlich. \u27a1Zur Anmeldung.<\/p>\n","category_list_v2":"","author_info_v2":{"name":"Laura Cepeda","url":"https:\/\/e326.greatsolution.dev\/fr\/author\/laura-cepeda\/"},"comments_num_v2":"0 commentaire","_links":{"self":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/tribe_events\/155560","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/users\/2713"}],"version-history":[{"count":2,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/tribe_events\/155560\/revisions"}],"predecessor-version":[{"id":155568,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/tribe_events\/155560\/revisions\/155568"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/media\/155562"}],"wp:attachment":[{"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/media?parent=155560"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/tags?post=155560"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/tribe_events_cat?post=155560"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e326.greatsolution.dev\/fr\/wp-json\/wp\/v2\/coauthors?post=155560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}